{"id":241410,"date":"2022-07-08T21:41:48","date_gmt":"2022-07-08T19:41:48","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=241410&#038;preview=true&#038;preview_id=241410"},"modified":"2022-07-08T22:13:33","modified_gmt":"2022-07-08T20:13:33","slug":"euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/","title":{"rendered":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-championnat-deurope-feminin-de-basket-u20\/\">CHAMPIONNAT D&rsquo;EUROPE U20 F\u00c9MININ DE BASKET<\/a><b> &#8211; Apr\u00e8s 15 minutes de rodage, les Fran\u00e7aises ont pris l&rsquo;ascendant pour dominer les Pays-Bas (72-49). Une entame de qualit\u00e9 pour les Bleuettes, \u00e0 confirmer demain contre la R\u00e9publique Tch\u00e8que.<\/b><\/i><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est \u00e0 Sopron, en Hongrie, que les Bleuettes entamaient leur Euro. La France est d\u00e9j\u00e0 mont\u00e9e dix fois sur le podium de cette comp\u00e9tition par le pass\u00e9, et fait partie des favorites de la comp\u00e9tition. Les Pays-Bas n&rsquo;\u00e9taient cependant pas l&rsquo;adversaire id\u00e9al pour un premier match. Accrocheuses, les N\u00e9erlandaises ont tenu les Fran\u00e7aises en respect jusqu&rsquo;\u00e0 la moiti\u00e9 du deuxi\u00e8me quart-temps. Les Bleuettes ont alors acc\u00e9l\u00e9r\u00e9 pour rentrer aux vestiaires avec 14 points d&rsquo;avance (<strong>45-31<\/strong>), dans la foul\u00e9e d&rsquo;une <strong>Pauline Astier<\/strong> en jambes (14 points).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\"><a href=\"https:\/\/twitter.com\/hashtag\/EDFU20F?src=hash&amp;ref_src=twsrc%5Etfw\">#EDFU20F<\/a> &#x1f1eb;&#x1f1f7; \u2013 Entr\u00e9e en mati\u00e8re r\u00e9ussie pour nos Bleuettes face au Pays-Bas (72-49). <a href=\"https:\/\/t.co\/ASUEL5Lw4r\">pic.twitter.com\/ASUEL5Lw4r<\/a><\/p>\n<p>\u2014 FFBB (@ffbasketball) <a href=\"https:\/\/twitter.com\/ffbasketball\/status\/1545492985714032641?ref_src=twsrc%5Etfw\">July 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Dans le troisi\u00e8me quart-temps, les Fran\u00e7aises se sont quelque peu repos\u00e9es sur leurs lauriers. Elles ont multipli\u00e9 les mauvais choix et pertes de balles stupides. Les N\u00e9erlandaises n&rsquo;en ont profit\u00e9 qu&rsquo;\u00e0 moiti\u00e9, revenant \u00e0 dix points avant le dernier quart-temps (<strong>55-45<\/strong>). Les Bleuettes sont cependant rest\u00e9es concentr\u00e9es, et ont remis les gaz pour plier le match proprement, s&rsquo;imposant <strong>72-49<\/strong>. Trois joueuses terminent \u00e0 plus de 10 points, <strong>Louise Bussiere<\/strong> terminant meilleure marqueuse avec <strong>15 points.<\/strong> De plus, toute l&rsquo;\u00e9quipe s&rsquo;est envoy\u00e9e en d\u00e9fense. De bon augure avant le second match contre la R\u00e9publique Tch\u00e8que demain (19h45).<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNAT D&rsquo;EUROPE U20 F\u00c9MININ DE BASKET &#8211; Apr\u00e8s 15 minutes de rodage, les Fran\u00e7aises ont pris l&rsquo;ascendant pour dominer les Pays-Bas (72-49). Une entame de qualit\u00e9 pour les Bleuettes, \u00e0 confirmer demain contre la R\u00e9publique Tch\u00e8que.<\/p>\n","protected":false},"author":59,"featured_media":241431,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2305],"tags":[24441,24784,24786,24785],"class_list":["post-241410","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basketball-francais","tag-championnat-deurope-feminin-de-basket-u20","tag-euro-u20-basket-feminin","tag-france-basket-u20-filles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes<\/title>\n<meta name=\"description\" content=\"CHAMPIONNAT D&#039;EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l&#039;ascendant pour dominer les Pays-Bas\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNAT D&#039;EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l&#039;ascendant pour dominer les Pays-Bas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-08T19:41:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-08T20:13:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes\",\"datePublished\":\"2022-07-08T19:41:48+00:00\",\"dateModified\":\"2022-07-08T20:13:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/\"},\"wordCount\":288,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png\",\"keywords\":[\"Basketball fran\u00e7ais\",\"Championnat d'Europe f\u00e9minin de basket U20\",\"Euro U20 basket f\u00e9minin\",\"France basket U20 filles\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/\",\"name\":\"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png\",\"datePublished\":\"2022-07-08T19:41:48+00:00\",\"dateModified\":\"2022-07-08T20:13:33+00:00\",\"description\":\"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l'ascendant pour dominer les Pays-Bas\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png\",\"width\":800,\"height\":445,\"caption\":\"Euro U20 basket f\u00e9minin D\u00e9buts r\u00e9ussis pour les Bleuettes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes","description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l'ascendant pour dominer les Pays-Bas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes","og_description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l'ascendant pour dominer les Pays-Bas","og_url":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-07-08T19:41:48+00:00","article_modified_time":"2022-07-08T20:13:33+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes","datePublished":"2022-07-08T19:41:48+00:00","dateModified":"2022-07-08T20:13:33+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/"},"wordCount":288,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png","keywords":["Basketball fran\u00e7ais","Championnat d'Europe f\u00e9minin de basket U20","Euro U20 basket f\u00e9minin","France basket U20 filles"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/","url":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/","name":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png","datePublished":"2022-07-08T19:41:48+00:00","dateModified":"2022-07-08T20:13:33+00:00","description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET - Apr\u00e8s 15 minutes de rodage, les Bleuettes ont pris l'ascendant pour dominer les Pays-Bas","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Debuts-reussis-pour-les-Bleuettes.png","width":800,"height":445,"caption":"Euro U20 basket f\u00e9minin D\u00e9buts r\u00e9ussis pour les Bleuettes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-debuts-reussis-pour-les-bleuettes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro U20 basket f\u00e9minin : D\u00e9buts r\u00e9ussis pour les Bleuettes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241410","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=241410"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/241410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/241431"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=241410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=241410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=241410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}