{"id":24312,"date":"2018-08-21T19:56:29","date_gmt":"2018-08-21T17:56:29","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=24312"},"modified":"2018-08-21T20:02:54","modified_gmt":"2018-08-21T18:02:54","slug":"championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/","title":{"rendered":"Championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Berlin 2018 &#8211; Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">La Nouvelle-Cal\u00e9donie est \u00e0 la f\u00eate aujourd&rsquo;hui ! Apr\u00e8s l&rsquo;or d\u00e9croch\u00e9 par Pierre Fairbank, Rose Welepa, 32 ans, a remport\u00e9 la m\u00e9daille de bronze au javelot dans la cat\u00e9gorie F13 (d\u00e9ficients visuels). Le titre europ\u00e9en est revenu \u00e0 la grande favorite autrichienne Natalija Eder devant l&rsquo;Espagnole Laura Rus Martinez. Il s&rsquo;agit de la premi\u00e8re m\u00e9daille europ\u00e9enne pour Rose Welepa.<\/p>\n<p><strong><em>Flo Ostermann<br \/>\n<a href=\"https:\/\/www.facebook.com\/florent.ostermann\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/SportInsideMag\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin 2018 &#8211; Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.<\/p>\n","protected":false},"author":4,"featured_media":24318,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308,5753],"tags":[1265],"class_list":["post-24312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","category-handisport","tag-handisport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Championnats d&#039;Europe d&#039;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13<\/title>\n<meta name=\"description\" content=\"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Championnats d&#039;Europe d&#039;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13\" \/>\n<meta property=\"og:description\" content=\"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-21T17:56:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-21T18:02:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13\",\"datePublished\":\"2018-08-21T17:56:29+00:00\",\"dateModified\":\"2018-08-21T18:02:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\"},\"wordCount\":111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png\",\"keywords\":[\"handisport\"],\"articleSection\":[\"Athl\u00e9tisme\",\"Handisport\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\",\"name\":\"Championnats d'Europe d'athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png\",\"datePublished\":\"2018-08-21T17:56:29+00:00\",\"dateModified\":\"2018-08-21T18:02:54+00:00\",\"description\":\"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Championnats d'Europe d'athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13","description":"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/","og_locale":"fr_FR","og_type":"article","og_title":"Championnats d'Europe d'athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13","og_description":"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.","og_url":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2018-08-21T17:56:29+00:00","article_modified_time":"2018-08-21T18:02:54+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13","datePublished":"2018-08-21T17:56:29+00:00","dateModified":"2018-08-21T18:02:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/"},"wordCount":111,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png","keywords":["handisport"],"articleSection":["Athl\u00e9tisme","Handisport"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/","url":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/","name":"Championnats d'Europe d'athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png","datePublished":"2018-08-21T17:56:29+00:00","dateModified":"2018-08-21T18:02:54+00:00","description":"Berlin 2018 - Septi\u00e8me m\u00e9daille pour le clan tricolore en Allemagne, avec le bronze au javelot dans la cat\u00e9gorie F13 pour Rose Welepa.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/08\/Rose-Welepa-Javelot.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/championnats-europe-athletisme-handisport-rose-welepa-bronze-javelot-f13\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme handisport : Rose Welepa en bronze au javelot F13"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/24312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=24312"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/24312\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/24318"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=24312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=24312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=24312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}