{"id":243860,"date":"2022-07-16T19:42:19","date_gmt":"2022-07-16T17:42:19","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=243860&#038;preview=true&#038;preview_id=243860"},"modified":"2022-07-16T21:29:08","modified_gmt":"2022-07-16T19:29:08","slug":"euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/","title":{"rendered":"Euro U20 basket f\u00e9minin : Battues par l&rsquo;Italie, les Bleuettes \u00e9chouent au pied du podium"},"content":{"rendered":"<p style=\"text-align: justify;\"><i><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-championnat-deurope-feminin-de-basket-u20\/\">CHAMPIONNAT D&rsquo;EUROPE U20 F\u00c9MININ DE BASKET<\/a><b> &#8211; Handicap\u00e9es par une premi\u00e8re mi-temps rat\u00e9e, les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer la m\u00e9daille de bronze dans les mains des Italiennes (48-64).\u00a0<\/b><\/i><\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-les-bleuettes-eliminees-en-demi-finales-par-la-republique-tcheque\/\">Apr\u00e8s leur d\u00e9faite frustrante en demi-finale contre la R\u00e9publique Tch\u00e8que<\/a>, les Bleuettes avaient tout de m\u00eame l&rsquo;opportunit\u00e9 de finir sur une bonne note. Elles d\u00e9fiaient les Italiennes avec pour enjeu la m\u00e9daille de bronze. On attendait une belle performance des Tricolores, une r\u00e9compense internationale \u00e9tant tout de m\u00eame motivante. Mais on pouvait craindre une d\u00e9mobilisation de la part d&rsquo;une \u00e9quipe qui avait d\u00fb renoncer \u00e0 son objectif de titre.<\/p>\n<h2 style=\"text-align: justify;\">Les Italiennes en feu, les Bleuettes absentes<\/h2>\n<p style=\"text-align: justify;\">Le d\u00e9but de match est \u00e0 l&rsquo;apanage des Italiennes, men\u00e9es par une <strong>Giulia Natali<\/strong> infernale. La Transalpine inscrit 10 points dans le premier quart pour creuser un premier \u00e9cart (<strong>8-17<\/strong>). Une r\u00e9action permet aux Bleuettes de limiter la casse \u00e0 la fin du premier quart (<strong>12-17<\/strong>). Mais les Tricolores n&rsquo;y sont pas vraiment. Domin\u00e9es dans l&rsquo;engagement, elles subissent le <em>pick&rsquo;n&rsquo;roll<\/em> italien.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Panzera dropping 3&rsquo;s like it&rsquo;s nothing &#x1f4a3;<a href=\"https:\/\/twitter.com\/hashtag\/FIBAU20Europe?src=hash&amp;ref_src=twsrc%5Etfw\">#FIBAU20Europe<\/a> | <a href=\"https:\/\/twitter.com\/Italbasket?ref_src=twsrc%5Etfw\">@Italbasket<\/a> &#x1f1ee;&#x1f1f9; <a href=\"https:\/\/t.co\/3oFaDToxsI\">pic.twitter.com\/3oFaDToxsI<\/a><\/p>\n<p>\u2014 NextGen Hoops (@NextGenHoops) <a href=\"https:\/\/twitter.com\/NextGenHoops\/status\/1548349777208717315?ref_src=twsrc%5Etfw\">July 16, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\nJ\u00e9r\u00f4me Fournier se voit forc\u00e9 de prendre des temps morts pour tenter de r\u00e9veiller son \u00e9quipe. Mais globalement, les Bleuettes proposent une premi\u00e8re mi-temps d&rsquo;un pi\u00e8tre niveau. En face, <strong>Ilaria Panzera<\/strong> (15 points) fait du d\u00e9g\u00e2t dans la d\u00e9fense fran\u00e7aise. Et les Transalpines sont en feu longue distance, alors qu&rsquo;en face, les Tricolores sont indigentes \u00e0 trois points (<strong>1\/7<\/strong>). Seule <strong>Aminata Gueye<\/strong> (12 points) surnage dans le marasme. Les Bleuettes rentrent aux vestiaires men\u00e9es <strong>41-23<\/strong>, avec d\u00e9j\u00e0 un pied dans la tombe.<\/p>\n<h2 style=\"text-align: justify;\">Le r\u00e9veil fran\u00e7ais trop tardif<\/h2>\n<p style=\"text-align: justify;\">Les Italiennes reprennent l\u00e0 o\u00f9 elles s&rsquo;\u00e9taient arr\u00eat\u00e9es, et franchissent m\u00eame la barre des 20 points d&rsquo;avance. La paire <strong>Natali-Panzera<\/strong> est toujours aussi d\u00e9vastatrice. N\u00e9anmoins, les Bleuettes finissent par laisser entrevoir une r\u00e9action, notamment en d\u00e9fense. Elles n&rsquo;encaisseront que 3 points dans les 5 derni\u00e8res minutes du quart-temps. Cependant, la situation est toujours critique \u00e0 10 minutes de la fin, puisqu&rsquo;elles sont toujours men\u00e9es de 14 points (<strong>38-52<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Les Bleuettes montrent un bien meilleur visage dans cette seconde mi-temps. Elle grappillent leur retard, revenant \u00e0 sept points, mais pour leur malheur, cela n&rsquo;ira pas plus loin. L&rsquo;Italie serre le jeu, et marque les paniers qu&rsquo;il faut, men\u00e9e par les 43 points du duo magique <strong>Giulia Natali &#8211; Ilaria Panzera<\/strong>. Les 26 pertes de balles et le 4\/19 \u00e0 trois points auront fait \u00e9norm\u00e9ment de mal aux Fran\u00e7aises, qui s&rsquo;inclinent finalement <strong>48-64<\/strong>. Dommage, car elles ont montr\u00e9 de belles promesses durant la comp\u00e9tition. Mais leur manque de r\u00e9gularit\u00e9 leur aura certainement co\u00fbt\u00e9 un meilleur r\u00e9sultat. De quoi donner \u00e0 r\u00e9fl\u00e9chir \u00e0 ces jeunes joueuses bourr\u00e9es de talent, \u00e0 l&rsquo;image d&rsquo;<strong>Aminata Gueye<\/strong> (22 points, 12 rebonds dont 5 offensifs).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNAT D&rsquo;EUROPE U20 F\u00c9MININ DE BASKET &#8211; Handicap\u00e9es par une premi\u00e8re mi-temps rat\u00e9e, les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer la m\u00e9daille de bronze dans les mains des Italiennes (48-64).\u00a0<\/p>\n","protected":false},"author":59,"featured_media":243913,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2305],"tags":[24441,24784,24786,24785],"class_list":["post-243860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basketball-francais","tag-championnat-deurope-feminin-de-basket-u20","tag-euro-u20-basket-feminin","tag-france-basket-u20-filles"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Euro U20 basket f\u00e9minin : Battues par l&#039;Italie, les Bleuettes \u00e9chouent au pied du podium<\/title>\n<meta name=\"description\" content=\"CHAMPIONNAT D&#039;EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Euro U20 basket f\u00e9minin : Battues par l&#039;Italie, les Bleuettes \u00e9chouent au pied du podium\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNAT D&#039;EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-16T17:42:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-16T19:29:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Euro U20 basket f\u00e9minin : Battues par l&#039;Italie, les Bleuettes \u00e9chouent au pied du podium\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Euro U20 basket f\u00e9minin : Battues par l&rsquo;Italie, les Bleuettes \u00e9chouent au pied du podium\",\"datePublished\":\"2022-07-16T17:42:19+00:00\",\"dateModified\":\"2022-07-16T19:29:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png\",\"keywords\":[\"Basketball fran\u00e7ais\",\"Championnat d'Europe f\u00e9minin de basket U20\",\"Euro U20 basket f\u00e9minin\",\"France basket U20 filles\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/\",\"name\":\"Euro U20 basket f\u00e9minin : Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png\",\"datePublished\":\"2022-07-16T17:42:19+00:00\",\"dateModified\":\"2022-07-16T19:29:08+00:00\",\"description\":\"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png\",\"width\":800,\"height\":445,\"caption\":\"Euro U20 basket f\u00e9minin Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Euro U20 basket f\u00e9minin : Battues par l&rsquo;Italie, les Bleuettes \u00e9chouent au pied du podium\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Euro U20 basket f\u00e9minin : Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium","description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/","og_locale":"fr_FR","og_type":"article","og_title":"Euro U20 basket f\u00e9minin : Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium","og_description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)","og_url":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-07-16T17:42:19+00:00","article_modified_time":"2022-07-16T19:29:08+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Euro U20 basket f\u00e9minin : Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Euro U20 basket f\u00e9minin : Battues par l&rsquo;Italie, les Bleuettes \u00e9chouent au pied du podium","datePublished":"2022-07-16T17:42:19+00:00","dateModified":"2022-07-16T19:29:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png","keywords":["Basketball fran\u00e7ais","Championnat d'Europe f\u00e9minin de basket U20","Euro U20 basket f\u00e9minin","France basket U20 filles"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/","url":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/","name":"Euro U20 basket f\u00e9minin : Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png","datePublished":"2022-07-16T17:42:19+00:00","dateModified":"2022-07-16T19:29:08+00:00","description":"CHAMPIONNAT D'EUROPE U20 F\u00c9MININ DE BASKET -les Bleuettes ont d\u00fb se r\u00e9soudre \u00e0 laisser filer le bronze dans les mains des Italiennes (48-64)","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Euro-U20-basket-feminin-Battues-par-lItalie-les-Bleuettes-echouent-au-pied-du-podium.png","width":800,"height":445,"caption":"Euro U20 basket f\u00e9minin Battues par l'Italie, les Bleuettes \u00e9chouent au pied du podium"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euro-u20-basket-feminin-battues-par-litalie-les-bleuettes-echouent-au-pied-du-podium\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Euro U20 basket f\u00e9minin : Battues par l&rsquo;Italie, les Bleuettes \u00e9chouent au pied du podium"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/243860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=243860"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/243860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/243913"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=243860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=243860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=243860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}