{"id":245120,"date":"2022-07-20T17:23:14","date_gmt":"2022-07-20T15:23:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=245120&#038;preview=true&#038;preview_id=245120"},"modified":"2022-07-21T00:51:28","modified_gmt":"2022-07-20T22:51:28","slug":"tour-de-france-2022-nos-favoris-pour-la-18eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/","title":{"rendered":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b>PRONOSTIC <\/b><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/tour-de-france-2022\/\">TOUR DE FRANCE 2022<\/a><b> &#8211; Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e finale \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.<\/b><\/em><\/p>\n<h2 style=\"text-align: justify;\">Notre favori : Tadej Pogacar<\/h2>\n<p style=\"text-align: justify;\">C&rsquo;est sa derni\u00e8re chance de renverser le Tour. M\u00eame s&rsquo;il n&rsquo;a pas r\u00e9ussi \u00e0 distancer Jonas Vingegaard mercredi vers Peyragudes, il a remport\u00e9 l&rsquo;\u00e9tape. S&rsquo;il voit que le Danois est trop fort, il pourrait se concentrer sur le fait de lever les bras une quatri\u00e8me fois sur cette Grande Boucle.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"border-color: #ffffff; background-color: #404040; text-align: left; width: 650px;\"><span style=\"font-size: 12px; color: #ffffff;\"><span style=\"font-size: 12px; color: #ffffff;\"><span style=\"font-size: 12px; color: #ffffff;\"><span style=\"font-size: 12px; color: #ffffff;\">Tour de France &#8211; 18\u00e8me \u00e9tape &#8211; Jeudi 21 juillet<\/span><\/span><\/span><\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #525252; text-align: center; width: 150px;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border-color: #ffffff; background-color: #ffffff; text-align: justify; width: 650px;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Tadej Pogacar<br \/>\n<\/strong><\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #ffffff; text-align: center; width: 150px;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/1000023086?banid=33431\" class=\"su-button su-button-style-flat\" style=\"color:black;background-color:#ffed00;border-color:#ccbe00;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:black;padding:0px 16px;font-size:13px;line-height:26px;border-color:#fff34d;border-radius:5px;text-shadow:none\"> 3.50<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<hr \/>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-parcours-et-profil-18eme-etape\/\">Tour de France 2022 \u2013 Parcours et profil de la 18\u00e8me \u00e9tape<\/a><\/strong><\/li>\n<\/ul>\n<hr \/>\n<h2 style=\"text-align: justify;\">Notre coup \u00e0 tenter : Nick Schultz<\/h2>\n<p style=\"text-align: justify;\">Deuxi\u00e8me \u00e0 Meg\u00e8ve, il finit tr\u00e8s bien ce Tour de France en \u00e9tant souvent l&rsquo;un des derniers dans le groupe des favoris. Loin au g\u00e9n\u00e9ral, il pourrait faire mouche \u00e0 Hautacam s&rsquo;il prend l&rsquo;\u00e9chapp\u00e9e matinale.<\/p>\n<table style=\"width: 100%;\">\n<tbody>\n<tr style=\"height: 16px;\">\n<td style=\"border-color: #ffffff; background-color: #404040; text-align: left; width: 650px;\"><span style=\"font-size: 12px; color: #ffffff;\">Tour de France &#8211; 18\u00e8me \u00e9tape &#8211; Jeudi 21 juillet<\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #525252; text-align: center; width: 150px;\"><span style=\"font-size: 12px; color: #ffffff;\">1<\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px;\">\n<td style=\"border-color: #ffffff; background-color: #ffffff; text-align: justify; width: 650px;\"><span style=\"font-size: 14px; color: #000000;\"><strong>Nick Schultz<br \/>\n<\/strong><\/span><\/td>\n<td style=\"border-color: #ffffff; background-color: #ffffff; width: 150px; text-align: center;\"><span style=\"font-size: 10px;\"><a href=\"https:\/\/www.winamax.fr\/paris-sportifs\/match\/prelive\/1000023086?banid=33431\" class=\"su-button su-button-style-flat\" style=\"color:black;background-color:#ffed00;border-color:#ccbe00;border-radius:5px\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color:black;padding:0px 16px;font-size:13px;line-height:26px;border-color:#fff34d;border-radius:5px;text-shadow:none\"> 10<\/span><\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: justify;\">Tentez votre chance en misant jusqu\u2019\u00e0 100\u20ac gr\u00e2ce \u00e0 votre <a href=\"https:\/\/www.winamax.fr\/landing\/landing_leads.php?ldg=1er-pari-rembourse&amp;banid=33423\" target=\"_blank\" rel=\"nofollow noopener\">premier pari rembours\u00e9<\/a>.<\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/classement-general-tour-de-france-2022-maillot-jaune\/\"><strong>Classement g\u00e9n\u00e9ral du Tour de France 2022<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/toute-lactualite-du-tour-de-france-2022\/\" target=\"_blank\" rel=\"noopener\"><strong>Toute l\u2019actualit\u00e9 du Tour de France 2022<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-heure-et-chaine-de-la-18eme-etape\/\"><strong>Tour de France 2022 : Heure et cha\u00eene de la 18\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>PRONOSTIC TOUR DE FRANCE 2022 &#8211; Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e finale \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.<\/p>\n","protected":false},"author":1,"featured_media":245123,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46995],"tags":[1262],"class_list":["post-245120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-de-france","tag-tour-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-20T15:23:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-20T22:51:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape\",\"datePublished\":\"2022-07-20T15:23:14+00:00\",\"dateModified\":\"2022-07-20T22:51:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png\",\"keywords\":[\"Tour de France\"],\"articleSection\":[\"Tour de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\",\"name\":\"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png\",\"datePublished\":\"2022-07-20T15:23:14+00:00\",\"dateModified\":\"2022-07-20T22:51:28+00:00\",\"description\":\"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape","description":"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape","og_description":"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-07-20T15:23:14+00:00","article_modified_time":"2022-07-20T22:51:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape","datePublished":"2022-07-20T15:23:14+00:00","dateModified":"2022-07-20T22:51:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png","keywords":["Tour de France"],"articleSection":["Tour de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/","name":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png","datePublished":"2022-07-20T15:23:14+00:00","dateModified":"2022-07-20T22:51:28+00:00","description":"PRONOSTIC TOUR DE FRANCE 2022 - Derni\u00e8re \u00e9tape de montagne dans les Pyr\u00e9n\u00e9es avec une arriv\u00e9e \u00e0 Hautacam. Nos favoris pour la 18\u00e8me \u00e9tape.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Tour-de-France-2022-Nos-favoris-pour-la-18e\u0300me-e\u0301tape.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-france-2022-nos-favoris-pour-la-18eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de France 2022 : Nos favoris pour la 18\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/245120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=245120"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/245120\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/245123"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=245120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=245120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=245120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}