{"id":246998,"date":"2022-07-27T14:47:53","date_gmt":"2022-07-27T12:47:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=246998&#038;preview=true&#038;preview_id=246998"},"modified":"2022-07-27T19:02:47","modified_gmt":"2022-07-27T17:02:47","slug":"mercato-alexis-beka-beka-tout-proche-dun-retour-en-france","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/","title":{"rendered":"Mercato : Alexis Beka Beka tout proche d&rsquo;un retour en France"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>LIGUE 1 2022-2023 &#8211; Selon L&rsquo;\u00c9quipe, Alexis Beka Beka va s&rsquo;engager dans les prochaines heures avec l&rsquo;OGC Nice.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Un an apr\u00e8s son d\u00e9part au <strong>Lokomotiv Moscou<\/strong>, <strong>Alexis Beka Beka<\/strong> devrait faire son retour en France. Apr\u00e8s deux saisons de <strong>Ligue 2<\/strong> abouties avec Caen, il s&rsquo;\u00e9tait envol\u00e9 pour la Russie l&rsquo;\u00e9t\u00e9 dernier, contre la somme de 6 millions d&rsquo;euros. Le jeune milieu de terrain, international, espoir, veut rentrer en France et l&rsquo;<strong>OGC Nice<\/strong> s&rsquo;est positionn\u00e9 pour le recruter comme l&rsquo;\u00e9t\u00e9 dernier. S&rsquo;il y a un an, il avait refus\u00e9 la proposition des <strong>Aiglons<\/strong> pour signer au <strong>Lokomotiv<\/strong>, il veut aujourd&rsquo;hui rejoindre Nice. Un accord aurait \u00e9t\u00e9 trouv\u00e9 autour des 12 millions d&rsquo;euros et le club russe va donc faire une belle plus-value en seulement une saison.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L&rsquo;OGC Nice a intensifi\u00e9 les discussions pour faire venir Alexis Beka Beka (Lokomotiv Moscou) ces derni\u00e8res heures. Le milieu de terrain souhaite rejoindre la C\u00f4te d&rsquo;Azur. <a href=\"https:\/\/t.co\/5RI4AgQ3TZ\">https:\/\/t.co\/5RI4AgQ3TZ<\/a> <a href=\"https:\/\/t.co\/RKRaM32RjL\">pic.twitter.com\/RKRaM32RjL<\/a><\/p>\n<p>\u2014 L&rsquo;\u00c9QUIPE (@lequipe) <a href=\"https:\/\/twitter.com\/lequipe\/status\/1552241722398310400?ref_src=twsrc%5Etfw\">July 27, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2022-2023 &#8211; Selon L&rsquo;\u00c9quipe, Alexis Beka Beka va s&rsquo;engager dans les prochaines heures avec l&rsquo;OGC Nice.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":246999,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301,47045],"tags":[75,1554,460],"class_list":["post-246998","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-football","tag-ligue-1","tag-nice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mercato : Alexis Beka Beka tout proche d&#039;un retour en France<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2022-2023 - Selon L&#039;\u00c9quipe, Alexis Beka Beka va s&#039;engager dans les prochaines heures avec l&#039;OGC Nice.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato : Alexis Beka Beka tout proche d&#039;un retour en France\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2022-2023 - Selon L&#039;\u00c9quipe, Alexis Beka Beka va s&#039;engager dans les prochaines heures avec l&#039;OGC Nice.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-27T12:47:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-27T17:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mercato : Alexis Beka Beka tout proche d&#039;un retour en France\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Mercato : Alexis Beka Beka tout proche d&rsquo;un retour en France\",\"datePublished\":\"2022-07-27T12:47:53+00:00\",\"dateModified\":\"2022-07-27T17:02:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/\"},\"wordCount\":193,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png\",\"keywords\":[\"Football\",\"Ligue 1\",\"Nice\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/\",\"name\":\"Mercato : Alexis Beka Beka tout proche d'un retour en France\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png\",\"datePublished\":\"2022-07-27T12:47:53+00:00\",\"dateModified\":\"2022-07-27T17:02:47+00:00\",\"description\":\"LIGUE 1 2022-2023 - Selon L'\u00c9quipe, Alexis Beka Beka va s'engager dans les prochaines heures avec l'OGC Nice.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato : Alexis Beka Beka tout proche d&rsquo;un retour en France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mercato : Alexis Beka Beka tout proche d'un retour en France","description":"LIGUE 1 2022-2023 - Selon L'\u00c9quipe, Alexis Beka Beka va s'engager dans les prochaines heures avec l'OGC Nice.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercato : Alexis Beka Beka tout proche d'un retour en France","og_description":"LIGUE 1 2022-2023 - Selon L'\u00c9quipe, Alexis Beka Beka va s'engager dans les prochaines heures avec l'OGC Nice.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-07-27T12:47:53+00:00","article_modified_time":"2022-07-27T17:02:47+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Mercato : Alexis Beka Beka tout proche d'un retour en France","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Mercato : Alexis Beka Beka tout proche d&rsquo;un retour en France","datePublished":"2022-07-27T12:47:53+00:00","dateModified":"2022-07-27T17:02:47+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/"},"wordCount":193,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png","keywords":["Football","Ligue 1","Nice"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/","url":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/","name":"Mercato : Alexis Beka Beka tout proche d'un retour en France","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png","datePublished":"2022-07-27T12:47:53+00:00","dateModified":"2022-07-27T17:02:47+00:00","description":"LIGUE 1 2022-2023 - Selon L'\u00c9quipe, Alexis Beka Beka va s'engager dans les prochaines heures avec l'OGC Nice.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-Alexis-Beka-Beka-tout-proche-dun-retour-en-France.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alexis-beka-beka-tout-proche-dun-retour-en-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercato : Alexis Beka Beka tout proche d&rsquo;un retour en France"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/246998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=246998"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/246998\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/246999"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=246998"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=246998"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=246998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}