{"id":247946,"date":"2022-07-31T13:55:50","date_gmt":"2022-07-31T11:55:50","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=247946&#038;preview=true&#038;preview_id=247946"},"modified":"2022-07-31T14:04:26","modified_gmt":"2022-07-31T12:04:26","slug":"mercato-losc-lille-fonce-sur-ludovic-blas","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/","title":{"rendered":"Mercato LOSC : Lille fonce sur Ludovic Blas"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>LIGUE 1 2022-2023 &#8211; Selon Fabrizio Romano, le LOSC serait en passe de recruter le Nantais Ludovic Blas.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\"><strong>Ludovic Blas<\/strong>, milieu offensif de 24 ans, pourrait quitter le <strong>FC Nantes<\/strong> dans les prochains jours. Arriv\u00e9 \u00e0 l&rsquo;\u00e9t\u00e9 2019 chez les <strong>Canaris<\/strong>, il reste sur deux grosses saisons, avec notamment 25 buts marqu\u00e9s en 78 matchs disput\u00e9s toutes comp\u00e9titions confondues. Les dirigeants nantais ont accept\u00e9 de lui donner un bon de sortie en cas d&rsquo;offre int\u00e9ressante, et cela devrait \u00eatre le cas. Le <strong>LOSC<\/strong> veut renforcer son secteur offensif et aurait fait de l&rsquo;ancien joueur de <strong>Guingamp<\/strong> une priorit\u00e9. Les deux parties avancent sur le dossier et <strong>Ludovic Blas<\/strong> pourrait \u00eatre lillois dans les prochains jours.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Excl: Lille are in talks to sign Ludovic Blas from Nantes. Concrete interest and negotiations on as Fonseca now wants French player as new signing. &#x1f534;&#x1f1eb;&#x1f1f7; <a href=\"https:\/\/twitter.com\/hashtag\/transfers?src=hash&amp;ref_src=twsrc%5Etfw\">#transfers<\/a><\/p>\n<p>Clubs will open discussions to reach full agreement soon. <a href=\"https:\/\/t.co\/YmYKGaFZuS\">pic.twitter.com\/YmYKGaFZuS<\/a><\/p>\n<p>\u2014 Fabrizio Romano (@FabrizioRomano) <a href=\"https:\/\/twitter.com\/FabrizioRomano\/status\/1553666074079535104?ref_src=twsrc%5Etfw\">July 31, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <\/strong><a href=\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-tableau-des-transferts-2022-2023\/\" target=\"_blank\" rel=\"noopener\"><strong>Mercato LOSC Lille : Tableau des transferts 2022-2023<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2022-2023 &#8211; Selon Fabrizio Romano, le LOSC serait en passe de recruter le Nantais Ludovic Blas.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":247948,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301,47045],"tags":[75,2391,1272],"class_list":["post-247946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-football","tag-losc","tag-nantes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mercato LOSC : Lille fonce sur Ludovic Blas<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato LOSC : Lille fonce sur Ludovic Blas\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-31T11:55:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-31T12:04:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mercato LOSC : Lille fonce sur Ludovic Blas\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Mercato LOSC : Lille fonce sur Ludovic Blas\",\"datePublished\":\"2022-07-31T11:55:50+00:00\",\"dateModified\":\"2022-07-31T12:04:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\"},\"wordCount\":184,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png\",\"keywords\":[\"Football\",\"LOSC\",\"nantes\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\",\"name\":\"Mercato LOSC : Lille fonce sur Ludovic Blas\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png\",\"datePublished\":\"2022-07-31T11:55:50+00:00\",\"dateModified\":\"2022-07-31T12:04:26+00:00\",\"description\":\"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato LOSC : Lille fonce sur Ludovic Blas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mercato LOSC : Lille fonce sur Ludovic Blas","description":"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercato LOSC : Lille fonce sur Ludovic Blas","og_description":"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-07-31T11:55:50+00:00","article_modified_time":"2022-07-31T12:04:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Mercato LOSC : Lille fonce sur Ludovic Blas","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Mercato LOSC : Lille fonce sur Ludovic Blas","datePublished":"2022-07-31T11:55:50+00:00","dateModified":"2022-07-31T12:04:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/"},"wordCount":184,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png","keywords":["Football","LOSC","nantes"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/","url":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/","name":"Mercato LOSC : Lille fonce sur Ludovic Blas","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png","datePublished":"2022-07-31T11:55:50+00:00","dateModified":"2022-07-31T12:04:26+00:00","description":"LIGUE 1 2022-2023 - Selon Fabrizio Romano, le LOSC Lille serait en passe de recruter le Nantais Ludovic Blas.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/07\/Mercato-LOSC-Lille-fonce-sur-Ludovic-Blas.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mercato-losc-lille-fonce-sur-ludovic-blas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercato LOSC : Lille fonce sur Ludovic Blas"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/247946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=247946"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/247946\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/247948"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=247946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=247946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=247946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}