{"id":248286,"date":"2022-08-01T12:00:28","date_gmt":"2022-08-01T10:00:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=248286&#038;preview=true&#038;preview_id=248286"},"modified":"2022-08-01T12:07:45","modified_gmt":"2022-08-01T10:07:45","slug":"video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/","title":{"rendered":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>CYCLISME SUR PISTE &#8211; Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth, ce dimanche, lors de l&rsquo;\u00e9preuve du scratch de cyclisme sur piste.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Le pire a \u00e9t\u00e9 \u00e9vit\u00e9, mais les images sont impressionnantes ! Lors de l&rsquo;\u00e9preuve du scratch, <strong>Matt Walls<\/strong> est sorti de la piste et a heurt\u00e9 des spectateurs. Le <strong>Britannique<\/strong> \u00e9tait conscient au moment de son transport \u00e0 l&rsquo;h\u00f4pital, alors que les personnes du public touch\u00e9es n&rsquo;\u00e9taient pas bless\u00e9es.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">L&rsquo;\u00e9preuve du scratch lors des Jeux du Commonwealth dimanche a \u00e9t\u00e9 marqu\u00e9 par l&rsquo;incident de Matt Walls, pass\u00e9 par-dessus les barri\u00e8res en voulant \u00e9viter une chute. Transport\u00e9 \u00e0 l&rsquo;h\u00f4pital, le Britannique est conscient. Les 2 spectateurs touch\u00e9s vont bien. <a href=\"https:\/\/t.co\/g8j7IFRxnx\">pic.twitter.com\/g8j7IFRxnx<\/a><\/p>\n<p>\u2014 Le Gruppetto (@LeGruppetto) <a href=\"https:\/\/twitter.com\/LeGruppetto\/status\/1553752342821994496?ref_src=twsrc%5Etfw\">July 31, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR PISTE &#8211; Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth, ce dimanche, lors de l&rsquo;\u00e9preuve du scratch de cyclisme sur piste.<\/p>\n","protected":false},"author":1,"featured_media":248304,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[14089],"tags":[1664],"class_list":["post-248286","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-piste","tag-cyclisme-sur-piste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-01T10:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-01T10:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth\",\"datePublished\":\"2022-08-01T10:00:28+00:00\",\"dateModified\":\"2022-08-01T10:07:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\"},\"wordCount\":151,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png\",\"keywords\":[\"cyclisme sur piste\"],\"articleSection\":[\"Cyclisme sur piste\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\",\"name\":\"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png\",\"datePublished\":\"2022-08-01T10:00:28+00:00\",\"dateModified\":\"2022-08-01T10:07:45+00:00\",\"description\":\"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth","description":"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth","og_description":"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-08-01T10:00:28+00:00","article_modified_time":"2022-08-01T10:07:45+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth","datePublished":"2022-08-01T10:00:28+00:00","dateModified":"2022-08-01T10:07:45+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/"},"wordCount":151,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png","keywords":["cyclisme sur piste"],"articleSection":["Cyclisme sur piste"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/","url":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/","name":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png","datePublished":"2022-08-01T10:00:28+00:00","dateModified":"2022-08-01T10:07:45+00:00","description":"CYCLISME SUR PISTE - Matt Walls a \u00e9t\u00e9 impliqu\u00e9 dans une terrible chute lors des Jeux du Commonwealth dimanche. \u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Vide\u0301o-Cyclisme-sur-piste-La-terrible-chute-de-Matt-Walls-aux-Jeux-du-Commonwealth.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/video-cyclisme-sur-piste-la-terrible-chute-de-matt-walls-aux-jeux-du-commonwealth\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] Cyclisme sur piste : La terrible chute de Matt Walls aux Jeux du Commonwealth"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/248286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=248286"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/248286\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/248304"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=248286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=248286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=248286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}