{"id":251476,"date":"2022-08-21T19:00:28","date_gmt":"2022-08-21T17:00:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=251476&#038;preview=true&#038;preview_id=251476"},"modified":"2023-07-15T19:06:26","modified_gmt":"2023-07-15T17:06:26","slug":"tableau-des-medailles-des-championnats-deurope-de-natation-2022","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/","title":{"rendered":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><b><strong>CHAMPIONNATS D&rsquo;EUROPE DE NATATION 2022 &#8211; Les Championnats d&rsquo;Europe de natation 2022 se d\u00e9roulent du jeudi 11 au dimanche 21 ao\u00fbt \u00e0 Rome (Italie). <\/strong>Voici le tableau des m\u00e9dailles.<\/b><\/em><b style=\"font-size: 14px;\"><\/b><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s la onzi\u00e8me et derni\u00e8re journ\u00e9e des Championnats d&rsquo;Europe de Natation \u00e0 Rome, la <strong>France<\/strong> totalise 21 m\u00e9dailles dont 3 en or avec les titres de <a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-yohann-ndoye-brouard-en-or-sur-200-metres-dos\/\"><strong>Yohann Ndoye Brouard<\/strong><\/a> sur 200 m\u00e8tre dos, d&rsquo;<strong><a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-analia-pigree-en-or-sur-50-metres-dos\/\">Analia Pigr\u00e9e<\/a><\/strong> sur 50 m\u00e8tres dos et du <strong><a href=\"https:\/\/dicodusport.fr\/blog\/championnats-deurope-le-relais-4x100-metres-mixte-decroche-lor\/\">relais mixte 4&#215;100 m\u00e8tres nage libre<\/a><\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ff0000;\">Le 25km en eau libre hommes et femmes est annul\u00e9.<\/span><\/strong><\/p>\n<form><a id=\"choix\"><\/a><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#choix\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong><a id=\"tableau\"><\/a>Tableau mis \u00e0 jour le dimanche 21 ao\u00fbt \u00e0 19h00 (75\/75).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>24<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">24<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">19<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">67<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>10<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">27<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>10<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">17<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>6<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">15<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>5<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">16<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf1 PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>5<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf8\ud83c\uddea SU\u00c8DE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">10<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">21<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udded SUISSE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\uddf7 GR\u00c8CE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf1\ud83c\uddf9 LITUANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde7\ud83c\udde6 BOSNIE-HERZ\u00c9GOVINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf1 ISRA\u00cbL<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 AUTRICHE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf1 POLOGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddf0 DANEMARK<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddee FINLANDE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf9 PORTUGAL<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">21.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf8\ud83c\uddf0 SLOVAQUIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">22.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf8 SERBIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">22.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf9\ud83c\uddf7 TURQUIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p style=\"text-align: justify;\"><em><span style=\"font-size: 14px;\"><strong>Les disciplines pr\u00e9sentes \u00e0 Rome <\/strong>: Natation sportive, Natation artistique, Natation en eau libre, Plongeon et Plongeon de haut vol.<\/span><\/em><\/p>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-2022\/\"><strong>Le tableau des m\u00e9dailles des Championnats d&rsquo;Europe de Munich<\/strong><\/a><\/li>\n<\/ul>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natation\"><\/a>Tableau des m\u00e9dailles de la natation<\/h2>\n<p>&nbsp;<\/p>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#natation\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau mis \u00e0 jour le jeudi 18 ao\u00fbt \u00e0 19h04 (43\/43).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>13<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">13<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">9<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">35<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>5<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">15<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">15<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf1 PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">11<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf8\ud83c\uddea SUEDE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">13<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udded SUISSE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\uddf7 GR\u00c8CE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf1\ud83c\uddf9 LITUANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde7\ud83c\udde6 BOSNIE-HERZ\u00c9GOVINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf1 ISRA\u00cbL<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf1 POLOGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddf0 DANEMARK<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddee FINLANDE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 AUTRICHE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf9 PORTUGAL<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf9\ud83c\uddf7 TURQUIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natationartistique\"><\/a>Tableau des m\u00e9dailles de la natation artistique<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#natationartistique\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/#natation\">Natation<\/option><option value=\"#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau mis \u00e0 jour le jeudi 18 ao\u00fbt \u00e0 19h04 (12\/12).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>8<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">8<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddea\ud83c\uddf8 ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 AUTRICHE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 FRANCE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf8\ud83c\uddf0 SLOVAQUIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\uddf7 GR\u00c8CE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf8 SERBIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"natationeaulibre\"><\/a>Tableau des m\u00e9dailles de la natation en eau libre<\/h2>\n<p style=\"text-align: justify;\"><strong><span style=\"color: #ff0000;\">Le 25km en eau libre hommes et femmes est annul\u00e9.<\/span><\/strong><\/p>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#natationeaulibre\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/3\/#natationartistique\">Natation artistique<\/option><option value=\"#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/5\/#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau mis \u00e0 jour le dimanche 21 ao\u00fbt \u00e0 17h24 (5\/5).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\">\ud83c\uddee\ud83c\uddf9 <span style=\"font-size: 0.9em\"><strong>ITALIE<\/strong><\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>3<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">6<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>\ud83c\uddf3\ud83c\uddf1 <span style=\"font-size: 0.9em\">PAYS-BAS<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\">\ud83c\uddeb\ud83c\uddf7 <span style=\"font-size: 0.9em\"><strong>FRANCE<\/strong><\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">4<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>\ud83c\uddea\ud83c\uddf8 <span style=\"font-size: 0.9em\">ESPAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udded\ud83c\uddfa HONGRIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf5\ud83c\uddf9 PORTUGAL<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"plongeon\"><\/a>Tableau des m\u00e9dailles du plongeon<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#plongeon\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"#plongeon\">Plongeon<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/6\/#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau mis \u00e0 jour le dimanche 21 ao\u00fbt \u00e0 19h00 (13\/13).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddec\ud83c\udde7 GRANDE-BRETAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>6<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>4<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">12<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>2<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">3<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">5<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">7<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf8\ud83c\uddea SUEDE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde8\ud83c\udded SUISSE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<p><!--nextpage--><\/p>\n<h2 style=\"text-align: justify;\"><a id=\"plongeonhautvol\"><\/a>Tableau des m\u00e9dailles du plongeon de haut vol<\/h2>\n<form><select name=\"Tableauxmedailles\" size=\"1\" onchange=\"location.href=this.value\"><option value=\"#plongeonhautvol\">Choix du tableau des m\u00e9dailles<\/option><optgroup label=\"Tableau des m\u00e9dailles\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#tableau\">Championnats d&rsquo;Europe de natation<\/option><\/optgroup><optgroup label=\"Tableau des m\u00e9dailles par discipline\"><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/#natation\">Natation<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/3\/#natationartistique\">Natation artistique<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/4\/#natationeaulibre\">Natation en eau libre<\/option><option value=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/5\/#plongeon\">Plongeon<\/option><option value=\"#plongeonhautvol\">Plongeon de haut vol<\/option><\/optgroup><br \/>\n<\/select><\/form>\n<p style=\"text-align: justify;\"><span style=\"font-size: 14px;\"><em><strong>Tableau mis \u00e0 jour le samedi 20 ao\u00fbt \u00e0 19h00 (2\/2).<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 724px;border-collapse: collapse\">\n<tbody>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><strong>Rang<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong>Nations<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd47 Or<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd48 Argent<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle;background-color: #ffffff\"><strong>\ud83e\udd49 Bronze<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>Total<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddf7\ud83c\uddf4 ROUMANIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddea ALLEMAGNE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>1<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\udde6 UKRAINE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">1<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;width: 64px;border-color: #d9d9d9;border-style: solid;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 300px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddee\ud83c\uddf9 ITALIE<\/span><\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\"><strong>0<\/strong><\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">0<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<td style=\"text-align: center;border-color: #d9d9d9;border-style: solid;width: 90px;vertical-align: middle\">2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE DE NATATION 2022 &#8211; Les Championnats d&rsquo;Europe de natation 2022 se d\u00e9roulent du jeudi 11 au dimanche 21 ao\u00fbt \u00e0 Rome (Italie). Voici le tableau des m\u00e9dailles.<\/p>\n","protected":false},"author":2,"featured_media":251498,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2306],"tags":[5631],"class_list":["post-251476","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natation","tag-championnats-deurope-de-natation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022<\/title>\n<meta name=\"description\" content=\"Les Championnats d&#039;Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\" \/>\n<link rel=\"next\" href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022\" \/>\n<meta property=\"og:description\" content=\"Les Championnats d&#039;Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-21T17:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-15T17:06:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Benjamin Cots\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/BenjaminCots\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\"},\"author\":{\"name\":\"Benjamin Cots\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\"},\"headline\":\"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022\",\"datePublished\":\"2022-08-21T17:00:28+00:00\",\"dateModified\":\"2023-07-15T17:06:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\"},\"wordCount\":507,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png\",\"keywords\":[\"Championnats d'Europe de natation\"],\"articleSection\":[\"Natation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\",\"name\":\"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png\",\"datePublished\":\"2022-08-21T17:00:28+00:00\",\"dateModified\":\"2023-07-15T17:06:26+00:00\",\"description\":\"Les Championnats d'Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.\",\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png\",\"width\":1200,\"height\":670,\"caption\":\"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4\",\"name\":\"Benjamin Cots\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png\",\"caption\":\"Benjamin Cots\"},\"description\":\"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022","description":"Les Championnats d'Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/","next":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/2\/","og_locale":"fr_FR","og_type":"article","og_title":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022","og_description":"Les Championnats d'Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.","og_url":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-08-21T17:00:28+00:00","article_modified_time":"2023-07-15T17:06:26+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png","type":"image\/png"}],"author":"Benjamin Cots","twitter_card":"summary_large_image","twitter_title":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022","twitter_creator":"@https:\/\/twitter.com\/BenjaminCots","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/"},"author":{"name":"Benjamin Cots","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4"},"headline":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022","datePublished":"2022-08-21T17:00:28+00:00","dateModified":"2023-07-15T17:06:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/"},"wordCount":507,"commentCount":2,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png","keywords":["Championnats d'Europe de natation"],"articleSection":["Natation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/","url":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/","name":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png","datePublished":"2022-08-21T17:00:28+00:00","dateModified":"2023-07-15T17:06:26+00:00","description":"Les Championnats d'Europe de natation 2022 se d\u00e9roulent du 11 au 21 ao\u00fbt \u00e0 Rome. Voici le tableau des m\u00e9dailles.","inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-de-natation-2022\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tableau-des-medailles-des-Championnats-dEurope-de-natation-2022.png","width":1200,"height":670,"caption":"Tableau des m\u00e9dailles des Championnats d\u2019Europe de natation 2022"},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0c141de963d8493840348bb7df193da4","name":"Benjamin Cots","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/04\/Maillot-Benji-Dicodusport-150x150.png","caption":"Benjamin Cots"},"description":"Footballeur et fan des Girondins de Bordeaux depuis mon plus jeune \u00e2ge, le foot et le sport en g\u00e9n\u00e9ral ont rythm\u00e9 ma vie. Apr\u00e8s des \u00e9tudes en informatique, la cr\u00e9ation de Dicodusport \u00e9tait le parfait m\u00e9lange pour allier mes deux passions.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/BenjaminCots"],"url":"https:\/\/dicodusport.fr\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/251476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=251476"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/251476\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/251498"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=251476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=251476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=251476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}