{"id":252210,"date":"2022-08-16T21:56:01","date_gmt":"2022-08-16T19:56:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=252210&#038;preview=true&#038;preview_id=252210"},"modified":"2022-08-17T12:20:14","modified_gmt":"2022-08-17T10:20:14","slug":"athletisme-europe-2022-classement-du-decathlon","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/","title":{"rendered":"Athl\u00e9tisme Europe 2022 &#8211; Classement du d\u00e9cathlon"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a title=\"Calendrier et r\u00e9sultats Mondiaux d\u2019athl\u00e9tisme 2022\" href=\"https:\/\/dicodusport.fr\/blog\/programme-et-resultats-athletisme-championnats-deurope-2022\/\" target=\"_blank\" rel=\"noopener\">CHAMPIONNATS D&rsquo;EUROPE D&rsquo;ATHL\u00c9TISME 2022<\/a> &#8211; D\u00e9couvrez le classement (top 10) du d\u00e9cathlon des championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Incertain avant le d\u00e9but de la comp\u00e9tition, <a href=\"https:\/\/dicodusport.fr\/blog\/europe-2022-kevin-mayer-abandonne-des-le-100-metres\/\" target=\"_blank\" rel=\"noopener\">Kevin Mayer a abandonn\u00e9 d\u00e8s la premi\u00e8re \u00e9preuve<\/a> \u00e0 cause d&rsquo;une blessure \u00e0 la cuisse.<\/p>\n<p><span style=\"font-size: 14px;\"><em><strong>Classement mis \u00e0 jour apr\u00e8s le 1500 m\u00e8tres (10\/10).<br \/>\n<\/strong><\/em><\/span><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">&#x1f3c5;<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>D\u00c9CATHLONIENS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>POINTS<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1e9;&#x1f1ea; NIKLAS KAUL<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8545<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1e8;&#x1f1ed; SIMON EHAMMER<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8468<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1ea;&#x1f1ea; JANEK OIGLANE<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8346<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1f8;&#x1f1ea; MARCUS NILSSON<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8327<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1ea;&#x1f1ea; MAICEL UIBO<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8234<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1ee;&#x1f1f9; DARIO DESTER<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8218<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1f3;&#x1f1f4; SANDER SKOTHEIM<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8211<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1e9;&#x1f1ea; KAI KAZMIREK<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8151<\/strong><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<br \/>\n<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1eb;&#x1f1f7; BAPTISTE THIERY<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8057<\/strong><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle;font-size: 0.9em\"><strong>&#x1f1f3;&#x1f1f1; SVEN ROOSEN<\/strong><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle;font-size: 0.9em\"><strong>8021<\/strong><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a title=\"Tableau des m\u00e9dailles Championnats du monde d\u2019athl\u00e9tisme 2022\" href=\"https:\/\/results.mun.mev.atos.net\/ECM2022\/en\/results\/athletics\/summary-points-men-s-decathlon.htm\" target=\"_blank\" rel=\"noopener\"><strong>Le classement complet du d\u00e9cathlon<\/strong><\/a><\/li>\n<li><a title=\"Tableau des m\u00e9dailles Championnats du monde d\u2019athl\u00e9tisme 2022\" href=\"https:\/\/dicodusport.fr\/blog\/tableau-des-medailles-des-championnats-deurope-2022\/\" target=\"_blank\" rel=\"noopener\"><strong>Le tableau des m\u00e9dailles des Championnats d&rsquo;Europe de Munich<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CHAMPIONNATS D&rsquo;EUROPE D&rsquo;ATHL\u00c9TISME 2022 &#8211; D\u00e9couvrez le classement du d\u00e9cathlon des championnats d&rsquo;Europe d&rsquo;athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.<\/p>\n","protected":false},"author":1,"featured_media":252211,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2308],"tags":[143,1269],"class_list":["post-252210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-athletisme","tag-athletisme","tag-decathlon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon<\/title>\n<meta name=\"description\" content=\"CHAMPIONNATS D&#039;EUROPE D&#039;ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d&#039;Europe d&#039;athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon\" \/>\n<meta property=\"og:description\" content=\"CHAMPIONNATS D&#039;EUROPE D&#039;ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d&#039;Europe d&#039;athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-16T19:56:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-17T10:20:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Athl\u00e9tisme Europe 2022 &#8211; Classement du d\u00e9cathlon\",\"datePublished\":\"2022-08-16T19:56:01+00:00\",\"dateModified\":\"2022-08-17T10:20:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\"},\"wordCount\":180,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png\",\"keywords\":[\"Athl\u00e9tisme\",\"d\u00e9cathlon\"],\"articleSection\":[\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\",\"name\":\"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png\",\"datePublished\":\"2022-08-16T19:56:01+00:00\",\"dateModified\":\"2022-08-17T10:20:14+00:00\",\"description\":\"CHAMPIONNATS D'EUROPE D'ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d'Europe d'athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Athl\u00e9tisme Europe 2022 &#8211; Classement du d\u00e9cathlon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon","description":"CHAMPIONNATS D'EUROPE D'ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d'Europe d'athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/","og_locale":"fr_FR","og_type":"article","og_title":"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon","og_description":"CHAMPIONNATS D'EUROPE D'ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d'Europe d'athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.","og_url":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-08-16T19:56:01+00:00","article_modified_time":"2022-08-17T10:20:14+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Athl\u00e9tisme Europe 2022 &#8211; Classement du d\u00e9cathlon","datePublished":"2022-08-16T19:56:01+00:00","dateModified":"2022-08-17T10:20:14+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/"},"wordCount":180,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png","keywords":["Athl\u00e9tisme","d\u00e9cathlon"],"articleSection":["Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/","url":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/","name":"Athl\u00e9tisme Europe 2022 - Classement du d\u00e9cathlon","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png","datePublished":"2022-08-16T19:56:01+00:00","dateModified":"2022-08-17T10:20:14+00:00","description":"CHAMPIONNATS D'EUROPE D'ATHL\u00c9TISME 2022 - D\u00e9couvrez le classement du d\u00e9cathlon des championnats d'Europe d'athl\u00e9tisme, qui se d\u00e9roule du 15 au 16 ao\u00fbt.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Athle\u0301tisme-Europe-2022-Classement-du-de\u0301cathlon.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/athletisme-europe-2022-classement-du-decathlon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Athl\u00e9tisme Europe 2022 &#8211; Classement du d\u00e9cathlon"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/252210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=252210"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/252210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/252211"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=252210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=252210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=252210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}