{"id":252400,"date":"2022-08-29T10:07:28","date_gmt":"2022-08-29T08:07:28","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=252400&#038;preview=true&#038;preview_id=252400"},"modified":"2022-08-29T10:07:28","modified_gmt":"2022-08-29T08:07:28","slug":"tour-despagne-2022-parcours-et-profil-de-la-10eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/","title":{"rendered":"Tour d&rsquo;Espagne 2022 &#8211; Parcours et profil de la 10\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/tour-espagne-2022\/\">TOUR D&rsquo;ESPAGNE 2022<\/a> &#8211; <\/strong><\/em><em><strong><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">La 10\u00e8me \u00e9tape de la Vuelta a Espa\u00f1a sera un contre-la-montre individuel de 30,9 kilom\u00e8tres entre Elche et Alicante. Hormis une petite colline dans les 2 derniers kilom\u00e8tres, le parcours est pratiquement plat. <\/span> <span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Parcours et profil.<\/span><\/strong><\/em><\/p>\n<h2 style=\"text-align: justify;\">Le parcours de la 10\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022<\/h2>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">La premi\u00e8re moiti\u00e9 de la course devrait se d\u00e9rouler \u00e0 de fortes vitesses avec un faux-plat descendant de 16 kilom\u00e8tres depuis <strong>Elche<\/strong> jusqu&rsquo;\u00e0 <strong>L&rsquo;Altet<\/strong> pour rejoindre la c\u00f4te. Mise \u00e0 part quatre virages \u00e0 angle droit en sortant de la ville de d\u00e9part, il y aura de grandes lignes droites dans cette premi\u00e8re partie. <\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Puis, dans la seconde partie, la route sera plate et rectiligne jusqu&rsquo;\u00e0 <strong>Alicante<\/strong>. Les concurrents passeront par la <\/span><strong>Playa de los Saladares<\/strong>, la <strong>Playa de Agua Amarga<\/strong> et le <strong>Parc El Palmeral<\/strong>, un parc de loisir en bord de mer.<\/p>\n<p style=\"text-align: justify;\"><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">Habituellement, une arriv\u00e9e \u00e0 Alicante est une bonne nouvelle pour les sprinteurs. <\/span><span class=\"tojvnm2t a6sixzi8 abs2jz4q a8s20v7p t1p8iaqh k5wvi7nf q3lfd5jv pk4s997a bipmatt0 cebpdrjk qowsmv63 owwhemhu dp1hu0rb dhp61c6y iyyx5f41\">L&rsquo;an dernier, Arnaud D\u00e9mare avait remport\u00e9 un sprint sur le Tour de Valence dans la ville de la Costa Blanca. Le dernier sprint de la Vuelta a Espa\u00f1a \u00e0 Alicante a eu lieu en 2019 avec la victoire de Sam Bennett.<\/span><\/p>\n<div id=\"attachment_257369\" style=\"width: 750px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-257369\" class=\"size-large wp-image-257369\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022-948x1024.jpg\" alt=\"Carte du parcours de la 10\u00e8me \u00e9tape du Tour d'Espagne 2022\" width=\"740\" height=\"799\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022-948x1024.jpg 948w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022-278x300.jpg 278w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022-768x830.jpg 768w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Carte-du-parcours-de-la-10eme-etape-du-Tour-dEspagne-2022.jpg 960w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/a><p id=\"caption-attachment-257369\" class=\"wp-caption-text\">Carte du parcours de la 10\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022 &#8211; Via lavuelta.es<\/p><\/div>\n<h2 style=\"text-align: justify;\">Le profil de la 10\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022<\/h2>\n<div id=\"attachment_249875\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Profil-10eme-etape-Tour-dEspagne-2022.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-249875\" class=\"size-full wp-image-249875\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Profil-10eme-etape-Tour-dEspagne-2022.jpg\" alt=\"Profil 10\u00e8me \u00e9tape Tour d'Espagne 2022\" width=\"960\" height=\"349\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Profil-10eme-etape-Tour-dEspagne-2022.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Profil-10eme-etape-Tour-dEspagne-2022-300x109.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Profil-10eme-etape-Tour-dEspagne-2022-768x279.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a><p id=\"caption-attachment-249875\" class=\"wp-caption-text\">Profil 10\u00e8me \u00e9tape Tour d&rsquo;Espagne 2022 &#8211; Via Unipublic<\/p><\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-classement-general-maillot-rouge\/\"><strong>Classement g\u00e9n\u00e9ral du Tour d&rsquo;Espagne 2022<\/strong><\/a><strong>\u00a0<\/strong><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/le-profil-des-21-etapes-du-tour-d-espagne-2022\/\"><strong>Le profil des \u00e9tapes du Tour d&rsquo;Espagne 2022<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOUR D&rsquo;ESPAGNE 2022 &#8211; La 10\u00e8me \u00e9tape de la Vuelta a Espa\u00f1a sera un contre-la-montre individuel de 30,9 kilom\u00e8tres entre Elche et Alicante. Hormis une petite colline dans les 2 derniers kilom\u00e8tres, le parcours est pratiquement plat. Parcours et profil.<\/p>\n","protected":false},"author":48,"featured_media":257370,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47042],"tags":[3119],"class_list":["post-252400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-actualite-cyclisme"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR D&#039;ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR D&#039;ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-29T08:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"Tour d&rsquo;Espagne 2022 &#8211; Parcours et profil de la 10\u00e8me \u00e9tape\",\"datePublished\":\"2022-08-29T08:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\"},\"wordCount\":279,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png\",\"keywords\":[\"Actualit\u00e9 Cyclisme\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\",\"name\":\"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png\",\"datePublished\":\"2022-08-29T08:07:28+00:00\",\"description\":\"TOUR D'ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png\",\"width\":800,\"height\":445,\"caption\":\"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&rsquo;Espagne 2022 &#8211; Parcours et profil de la 10\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape","description":"TOUR D'ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape","og_description":"TOUR D'ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2022-08-29T08:07:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"Tour d&rsquo;Espagne 2022 &#8211; Parcours et profil de la 10\u00e8me \u00e9tape","datePublished":"2022-08-29T08:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/"},"wordCount":279,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png","keywords":["Actualit\u00e9 Cyclisme"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/","name":"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png","datePublished":"2022-08-29T08:07:28+00:00","description":"TOUR D'ESPAGNE 2022 - La 10\u00e8me \u00e9tape de la Vuelta sera un contre-la-montre de 30,9 kilom\u00e8tres entre Elche et Alicante. Parcours et profil.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-Parcours-et-profil-de-la-10eme-etape.png","width":800,"height":445,"caption":"Tour d'Espagne 2022 - Parcours et profil de la 10\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&rsquo;Espagne 2022 &#8211; Parcours et profil de la 10\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/252400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=252400"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/252400\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/257370"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=252400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=252400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=252400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}