{"id":255036,"date":"2022-08-24T09:00:49","date_gmt":"2022-08-24T07:00:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=255036&#038;preview=true&#038;preview_id=255036"},"modified":"2022-08-24T08:52:50","modified_gmt":"2022-08-24T06:52:50","slug":"pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/","title":{"rendered":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>PRO D2 2022\/2023 &#8211; Fin des vacances, la saison 2022\/2023 de Pro D2 d\u00e9bute ce jeudi soir par une opposition all\u00e9chante entre le Biarritz Olympique et Oyonnax. En amont de ce nouvel exercice, retrouvez nos avis concernant les \u00e9quipes amen\u00e9es \u00e0 jouer les premiers r\u00f4les, les formations qui devraient se m\u00ealer \u00e0 la lutte pour le maintien ainsi que les \u00e9quipes surprises de la saison.\u00a0<\/i><\/b><\/p>\n<h2 style=\"text-align: justify;\">Le favori<\/h2>\n<h3 style=\"text-align: justify;\">Oyonnax Rugby<\/h3>\n<p style=\"text-align: justify;\">Cinq ans apr\u00e8s leur rel\u00e9gation suite \u00e0 une d\u00e9faite en barrage d\u2019accession face \u00e0 Grenoble, les Oyonnaxiens font figure de favoris cette saison. Depuis qu\u2019ils sont en Pro D2, les joueurs du Haut-Bugey ont \u00e9t\u00e9 r\u00e9guliers au possible (battus par Perpignan en 2021 et par Bayonne en 2022 en phase finale). Cet \u00e9t\u00e9, <strong>Joe El Abd<\/strong> et son staff ont mis\u00e9 sur la continuit\u00e9 avec un effectif qui a peu \u00e9volu\u00e9, malgr\u00e9 les treize d\u00e9parts enregistr\u00e9s. Le pack s&rsquo;est renforc\u00e9 avec les arriv\u00e9es de <strong>Steve Mafi<\/strong> qui d\u00e9barque des London Irish, ou encore celui de <strong>Joe Ravouvou<\/strong>, intraitable l&rsquo;an dernier avec l&rsquo;Aviron Bayonnais, pour compenser les d\u00e9parts notamment de <strong>Lassalle<\/strong>, <strong>Leindekar<\/strong> ou d&rsquo;<strong>\u00c9tienne Herjean<\/strong>.<\/p>\n<p style=\"text-align: justify;\">La saison derni\u00e8re, Oyonnax \u00e9tait une \u00e9quipe difficile \u00e0 man\u0153uvrer, surtout gr\u00e2ce \u00e0 une d\u00e9fense tr\u00e8s herm\u00e9tique, o\u00f9 les gratteurs dans les <em>rucks<\/em> tels que <strong>Lebreton<\/strong> ou <strong>Hamilton<\/strong> ont fait des mis\u00e8res dans ce secteur. \u00c0 domicile, la pelouse synth\u00e9tique de Charles-Mathon permet de produire du jeu all\u00e9chant, tout en \u00e9tant efficace sur les ballons port\u00e9s, gr\u00e2ce auxquels le talonneur <strong>Benjamin G\u00e9l\u00e9dan<\/strong> a termin\u00e9 co-meilleur marqueur d&rsquo;essais la saison pass\u00e9e (14).<\/p>\n<h2 style=\"text-align: justify;\">La course au top 6<\/h2>\n<h3 style=\"text-align: justify;\">Biarritz Olympique<\/h3>\n<p style=\"text-align: justify;\">Biarritz redescend apr\u00e8s une saison dans l\u2019\u00e9lite. La premi\u00e8re partie de saison de Top 14 a \u00e9t\u00e9 bonne, mais sur la dur\u00e9e, l\u2019effectif, qui avait un d\u00e9ficit de qualit\u00e9 dans sa profondeur, n\u2019a pas tenu la longueur dans un championnat tr\u00e8s \u00e9nergivore sur le plan \u00e9nerg\u00e9tique. En parall\u00e8le, on a \u00e9galement longuement parl\u00e9 des frasques perp\u00e9tuelles entre le club de rugby et la mairie de la ville de Biarritz, beaucoup plus que le plan sportif. Cette saison, le club tentera de viser le Top 6, avec un effectif qui a vu partir pr\u00e8s de 20 joueurs, dont des cadres comme <strong>Cronin<\/strong>, <strong>Peyresblanques<\/strong>, <strong>Hirigoyen<\/strong>, <strong>Armitage<\/strong> ou <strong>Lucu,<\/strong> tout en recrutant des joueurs au profil lourd et imposant au sein de son pack. Derri\u00e8re, le centre du terrain a \u00e9t\u00e9 renforc\u00e9 suite aux arriv\u00e9es du Gallois <strong>Tyler Morgan<\/strong> et de l\u2019Australien <strong>Joe Tomane<\/strong>, et on rappellera que <strong>Francis Saili<\/strong> est toujours sous contrat avec le club basque.<\/p>\n<p style=\"text-align: justify;\">Sur le papier, le BO doit faire partie des six premiers \u00e0 la fin de la saison r\u00e9guli\u00e8re. Le staff a \u00e9t\u00e9 confort\u00e9 pour cette saison. Le joueur \u00e0 suivre du c\u00f4t\u00e9 d&rsquo;Aguilera sera<strong> Baptiste Germain<\/strong> : le demi de m\u00eal\u00e9e pr\u00eat\u00e9 par le Stade Toulousain a montr\u00e9 de belles dispositions en Top 14 la saison derni\u00e8re lorsqu&rsquo;il a remplac\u00e9 <strong>Antoine Dupont<\/strong>. En concurrence cette saison avec <strong>Barnab\u00e9 Couilloud<\/strong>, il sera un des \u00e9l\u00e9ments cl\u00e9s de ce BO version 2022\/2023.<\/p>\n<h3 style=\"text-align: justify;\"><span class=\"TextRun SCXW196731233 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW196731233 BCX8\">Provence Rugby <\/span><\/span><\/h3>\n<p style=\"text-align: justify;\">Cette ann\u00e9e, tous les yeux seront riv\u00e9s sur Provence Rugby, qui pr\u00e9sente un projet tr\u00e8s ambitieux. Et pour cause, avec le plus gros budget de la division (14.3 millions d&rsquo;euros), les Proven\u00e7aux sont des potentiels finalistes. Les infrastructures du club ne cessent d\u2019\u00e9voluer, le stade Maurice-David a accueilli des \u00e9v\u00e9nements de grande envergure (finale de barrage de la zone Afrique en Coupe du monde). Pour accompagner le tout, le staff a \u00e9t\u00e9 renforc\u00e9 avec <strong>Mauricio Reggiardo<\/strong> qui sera aux manettes, \u00e9paul\u00e9 par <strong>Jacques Delmas<\/strong>, ancien technicien du RCT, et de <strong>St\u00e9phane Glas<\/strong>, soit trois techniciens qui ont connu le tr\u00e8s haut niveau.<\/p>\n<p style=\"text-align: justify;\">Au niveau de l\u2019effectif, une grosse partie de celui-ci a \u00e9t\u00e9 conserv\u00e9, renforc\u00e9 par des arriv\u00e9es notables comme celles de <strong>Teimana Harrison<\/strong>, qui d\u00e9barque des Saints de Northampton ou encore celle de l&rsquo;ouvreur <strong>Johnny McPhillips<\/strong>, qui reste sur une tr\u00e8s bonne saison avec Carcassonne. Cet effectif semble avoir toutes les qualit\u00e9s requises pour jouer le haut de tableau, et l&rsquo;objectif d&rsquo;une place dans les six premiers semble atteignable.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Et vous&#8230; Quel <a href=\"https:\/\/twitter.com\/hashtag\/Proven%C3%A7alEtSupporter?src=hash&amp;ref_src=twsrc%5Etfw\">#Proven\u00e7alEtSupporter<\/a> \u00eates-vous ?<\/p>\n<p>Et si nous battions le record d&rsquo;abonn\u00e9s ? J-4 avant Agen&#8230; la campagne d&rsquo;abonnement bat toujours son plein ! <a href=\"https:\/\/t.co\/8udOcQOgL8\">https:\/\/t.co\/8udOcQOgL8<\/a><a href=\"https:\/\/twitter.com\/hashtag\/ProD2?src=hash&amp;ref_src=twsrc%5Etfw\">#ProD2<\/a> <a href=\"https:\/\/t.co\/SdUqSOYhho\">pic.twitter.com\/SdUqSOYhho<\/a><\/p>\n<p>\u2014 Provence Rugby &#x26ab;&#xfe0f; (@ProvenceRugby) <a href=\"https:\/\/twitter.com\/ProvenceRugby\/status\/1561649303793422336?ref_src=twsrc%5Etfw\">August 22, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"TextRun SCXW202804981 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW202804981 BCX8\">Mont-de-Marsan\u00a0<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\"><span class=\"TextRun SCXW202804981 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW202804981 BCX8\">Centurion en saison r\u00e9guli\u00e8re et finaliste l\u2019an pass\u00e9, le Stade Montois veut continuer de grandir en se qualifiant \u00e0 nouveau pour les phases finales. La plus grosse difficult\u00e9 sera d\u2019assumer ce nouveau statut d\u2019\u00e9quipe favorite pour la saison \u00e0 venir, et de voir si les t\u00eates sont fra\u00eeches et repos\u00e9es avec les deux d\u00e9faites face \u00e0 <a href=\"https:\/\/dicodusport.fr\/blog\/finale-pro-d2-bayonne-ecrase-le-stade-montois-et-valide-sa-place-en-top-14\/\">Bayonne en finale de Pro D2<\/a> et <a href=\"https:\/\/dicodusport.fr\/blog\/access-match-victorieux-a-mont-de-marsan-l-usap-se-maintient-en-top-14\/\">Perpignan en barrage d\u2019accession<\/a>. En misant sur la formation et sur un ancrage territorial fort, les Landais abordent ce nouvel exercice avec excitation, et un effectif qui est rest\u00e9 stable, m\u00eame si le club a vu partir <strong>L\u00e9o Coly<\/strong> \u00e0 Montpellier. <strong>Wame Naituvi<\/strong> a \u00e9t\u00e9 cibl\u00e9 par le Racing 92 durant l&rsquo;intersaison, mais le Fidjien est finalement rest\u00e9 au club et apportera de nouveau ses qualit\u00e9s de franchissement sur son aile. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\"><span class=\"TextRun SCXW202804981 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW202804981 BCX8\">Cette saison et comme l&rsquo;an dernier, <strong>L\u00e9o Banos<\/strong> sera une des pi\u00e8ces maitresses du collectif montois. Ce Landais pure souche peut \u00eatre consid\u00e9r\u00e9 comme un surclass\u00e9 dans cette division et pouvait partir en Top 14 \u00e0 l&rsquo;intersaison, car le Stade Toulousain ou Montpellier lui faisaient les yeux doux. Finalement, l&rsquo;international moins de 20 ans poursuivra son aventure avec son club de c\u0153ur, o\u00f9 il tentera de vivre une aventure humaine aussi forte que la saison derni\u00e8re.\u00a0<\/span><\/span><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"TextRun SCXW19151866 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW19151866 BCX8\">Colomiers <\/span><\/span><\/h3>\n<p style=\"text-align: justify;\">Chaque saison, lorsque l&rsquo;on \u00e9voque le club colum\u00e9rin, deux mots reviennent avec insistance : r\u00e9gularit\u00e9 et homog\u00e9n\u00e9it\u00e9. Le club \u00e0 la Colombe est un m\u00e9tronome de ce championnat, se positionnant r\u00e9guli\u00e8rement dans le haut du tableau (deux barrages sur les deux derni\u00e8res saisons). Les recettes de ce succ\u00e8s sont plut\u00f4t simples : on mise sur un effectif tr\u00e8s dense \u00e0 tous les postes, sans stars, avec une belle \u00e9mulation entre les joueurs et un recrutement tr\u00e8s bien orchestr\u00e9 par la direction sportive (<strong>Gori, Palisson, Campagnaro<\/strong>).<\/p>\n<p style=\"text-align: justify;\">Cette saison, les d\u00e9parts de l\u2019effectif ont \u00e9t\u00e9 combl\u00e9s par la promotion de joueurs du centre de formation, comme <strong>Robin <\/strong><strong>Bellemand<\/strong>, international des moins de 20 ans, ou du troisi\u00e8me ligne <strong>Wa\u00ebl <\/strong><strong>Ponpon<\/strong>. Pour assumer son statut d\u2019\u00e9quipe phare de ce championnat, les Colum\u00e9rins s\u2019appuieront sur une d\u00e9fense tr\u00e8s compacte, qui a fait la force du club ces derni\u00e8res saisons. Le club \u00e0 la Colombe devra jouer les premiers r\u00f4les dans ce championnat.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Rester s\u00e9rieux c&rsquo;est bien, mais pas trop longtemps pour nos Colum\u00e9rins &#8230;<\/p>\n<p>&#8211; &#8211; <a href=\"https:\/\/t.co\/9oga2de7TD\">pic.twitter.com\/9oga2de7TD<\/a><\/p>\n<p>\u2014 Colomiers Rugby (@ColomiersRugby) <a href=\"https:\/\/twitter.com\/ColomiersRugby\/status\/1560680610498129920?ref_src=twsrc%5Etfw\">August 19, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\"><span class=\"TextRun SCXW109879220 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW109879220 BCX8\">Nevers <\/span><\/span><\/h3>\n<p style=\"text-align: justify;\">Demi-finaliste l\u2019an dernier et souvent pr\u00e9sent\u00e9 comme un club ambitieux depuis sa mont\u00e9e de F\u00e9d\u00e9rale, l\u2019USON repart \u00e0 l\u2019abordage cette saison, avec des ambitions de Top 6. Pour un club qui entame sa cinqui\u00e8me saison en Pro D2, le club a toujours \u00e9t\u00e9 stabilis\u00e9 dans le haut du tableau, avec un budget cons\u00e9quent certes. Apr\u00e8s la demi-finale de l\u2019an dernier, le club r\u00eave plus grand. Au niveau du recrutement, les Nivernais ont pr\u00e9f\u00e9r\u00e9 miser sur des jeunes joueurs \u00e0 fort potentiel, ainsi que sur des \u00e9l\u00e9ments qui connaissent parfaitement le championnat.<\/p>\n<p style=\"text-align: justify;\">Pour esp\u00e9rer viser \u00e0 nouveau le haut du tableau, l\u2019USON d\u2019<strong>Hugues Bastide<\/strong> sera \u00e0 nouveau redoutable sur les ballons port\u00e9s, un exercice tr\u00e8s maitris\u00e9 par le pack nivernais. Le club a toutefois vu partir son supersonique talonneur <strong>Jannik Tarrit<\/strong>, qui a rejoint le Racing 92 \u00e0 l&rsquo;intersaison, ainsi que <strong>Joris Cazenave<\/strong>, s\u00e9duit par le projet d&rsquo;Aix-en-Provence. Cette saison, les supporters du Pr\u00e9-Fleuri devraient \u00eatre s\u00e9duits par <strong>Christiaan van der Merwe<\/strong>. Cette poutre de 2 m\u00e8tres et 115 kg a \u00e9t\u00e9 auteur de prestations XXL la saison derni\u00e8re sous le maillot carcassonnais.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Les outsiders au Top 6<\/h2>\n<h3 style=\"text-align: justify;\">Agen<\/h3>\n<p style=\"text-align: justify;\">Apr\u00e8s deux saisons tr\u00e8s difficiles sur le plan sportif, <strong>Bernard Goutta<\/strong> esp\u00e8re redonner le sourire aux supporters d&rsquo;Armandie. Dans le sport de haut niveau, les grands champions sont ceux qui ont la capacit\u00e9 mentale \u00e0 r\u00e9pondre \u00e0 toute forme d&rsquo;\u00e9preuve, et pour les Agenais, il faudra tourner la page de ces deux ann\u00e9es gal\u00e8res, o\u00f9 les joueurs donnaient parfois l&rsquo;impression d&rsquo;\u00eatre traumatis\u00e9s. Tout au long du marathon que repr\u00e9sente la Pro D2 (30 journ\u00e9es), le maintien fut l&rsquo;axe de bataille du club lot-et-garonnais, avec une premi\u00e8re victoire obtenue le 22 octobre face \u00e0 Aurillac.<\/p>\n<p style=\"text-align: justify;\">Pour cette saison et pour s&rsquo;\u00e9viter des sueurs froides, le pr\u00e9sident <strong>Fonteneau<\/strong> esp\u00e8re que le club assurera son maintien le plus rapidement possible avant de pourquoi pas, jouer le Top 6 en fin de saison. Dans cette optique, l&rsquo;effectif a \u00e9t\u00e9 revu avec 20 d\u00e9parts et 8 arriv\u00e9es, notamment des joueurs d&rsquo;exp\u00e9rience qui seront amen\u00e9s \u00e0 encadrer les jeunes troupes agenaises. On pense particuli\u00e8rement \u00e0 <strong>Richard Barrington<\/strong>, qui sort de plusieurs saisons disput\u00e9es sous le maillot des Saracens ou encore d&rsquo;<strong>Even Olmstead<\/strong>, le solide deuxi\u00e8me ligne canadien.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Pro D2. Jean-Fran\u00e7ois Fonteneau, pr\u00e9sident du SU Agen : \u00ab Le top 6 est une ambition raisonnable \u00bb <a href=\"https:\/\/t.co\/h9W8qykk0i\">https:\/\/t.co\/h9W8qykk0i<\/a> <a href=\"https:\/\/t.co\/P0hPpqASfl\">pic.twitter.com\/P0hPpqASfl<\/a><\/p>\n<p>\u2014 SO_Agen (@SO_47) <a href=\"https:\/\/twitter.com\/SO_47\/status\/1561389382514327552?ref_src=twsrc%5Etfw\">August 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW97415095 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW97415095 BCX8\">Vannes <\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">Il y a deux ans, les Bretons ont \u00e9t\u00e9 \u00e0 deux doigts d\u2019acc\u00e9der \u00e0 la finale de Pro D2, apr\u00e8s une d\u00e9faite en demi-finales face \u00e0 Biarritz. L\u2019an dernier, les six d\u00e9faites cons\u00e9cutives pour entamer la saison ont contrari\u00e9 les ambitions du club entra\u00een\u00e9 par <strong>Jean-No\u00ebl Spitzer<\/strong>, qui est pass\u00e9 d\u2019ambitions de Top 6 \u00e0 un objectif de maintien, obtenu durant les quatre derni\u00e8res journ\u00e9es. Cet \u00e9t\u00e9, le livre a \u00e9t\u00e9 ferm\u00e9 pour en ouvrir un nouveau, o\u00f9 les ambitions du club sont de nouveau \u00e9lev\u00e9es. Un coup de balai a \u00e9t\u00e9 effectu\u00e9 dans le club, avec pr\u00e8s de seize d\u00e9parts, dont des cadres de l\u2019an pass\u00e9 comme <strong>Curtis<\/strong>, <strong>Picault<\/strong>, <strong>Hilsenbeck<\/strong> ou encore <strong>Rodrigue Bruni<\/strong>, afin d&rsquo;entamer un nouveau cycle et ne plus regarder derri\u00e8re.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Les Vannetais s&rsquo;appuieront sur deux de leurs recrues majeures : <strong>Ben Afoa<\/strong> et <strong>Alapati Leaiua<\/strong> qui viennent de Bristol pour apporter toute leur exp\u00e9rience du tr\u00e8s haut niveau, \u00e0 un groupe jeune et avide d&rsquo;apprendre. Pour compenser le d\u00e9part d&rsquo;Ambrose Curtis \u00e0 Mont-de-Marsan, le <em>board<\/em> vannetais a jet\u00e9 son d\u00e9volu sur <strong>Nathana\u00ebl Hulleu<\/strong>, en provenance de l&rsquo;UBB. Cet espoir girondin cherchera \u00e0 encha\u00eener les matchs et confirmer les bonnes dispositions entrevues en Top 14 la saison derni\u00e8re (2 essais en 4 matchs).<\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW215037361 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW215037361 BCX8\">Grenoble\u00a0<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW215037361 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW215037361 BCX8\">Apr\u00e8s une saison pass\u00e9e catastrophique sur le plan sportif, le FCG entend retrouver le haut de tableau. Tout comme Vannes, le d\u00e9but de saison derni\u00e8re a compl\u00e8tement an\u00e9anti les ambitions du club, qui a d\u00fb changer son fusil d\u2019\u00e9paule en faisant confiance \u00e0 des jeunes espoirs du <\/span><span class=\"NormalTextRun SCXW215037361 BCX8\">club, qui seront sur le devant de la sc\u00e8ne cette saison. Cette ann\u00e9e,\u00a0le groupe est compos\u00e9 <\/span><span class=\"NormalTextRun SCXW215037361 BCX8\">avec pr\u00e8s de 40 %\u00a0de joueurs issus du centre de formation, une statistique qui fera plaisir \u00e0 plusieurs observateurs de ce jeu. Malgr\u00e9 le d\u00e9part d\u2019<strong>Ange <\/strong><\/span><strong><span class=\"NormalTextRun SpellingErrorV2Themed SCXW215037361 BCX8\">Capuozzo<\/span><\/strong><\/span><span class=\"TextRun SCXW215037361 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW215037361 BCX8\">, son\u00a0<\/span><span class=\"NormalTextRun SCXW215037361 BCX8\">X-Factor de la saison derni\u00e8re, vers Toulouse, plusieurs espoirs tels que <strong>Berruyer<\/strong> ou <\/span><strong><span class=\"NormalTextRun SpellingErrorV2Themed SCXW215037361 BCX8\">Sarragallet<\/span><\/strong><span class=\"NormalTextRun SCXW215037361 BCX8\"> ont \u00e9t\u00e9 prolong\u00e9s sur la dur\u00e9e, pour assurer l\u2019avenir \u00e0 long\u00a0terme d\u2019un club revanchard. <\/span><\/span><\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW215037361 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW215037361 BCX8\">Des joueurs revanchards sont arriv\u00e9s au club, comme\u00a0<strong>Erwan Dridi<\/strong>, qui cherche \u00e0\u00a0confirmer son potentiel aper\u00e7u lors des matchs de Top 14 avec le RCT, ou encore <strong>Sam Nixon<\/strong>, qui revient dans ce championnat apr\u00e8s un <\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW215037361 BCX8\">exercice<\/span><span class=\"NormalTextRun SCXW215037361 BCX8\"> contrari\u00e9 dans son pays. Pour esp\u00e9rer viser le Top 6 \u00e0 la fin de la saison, le FCG devra \u00eatre intraitable dans son stade des Alpes, o\u00f9 trop de points ont \u00e9t\u00e9 oubli\u00e9s \u00e0 domicile (7 d\u00e9faites la saison derni\u00e8re).\u00a0<\/span><\/span><\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW167782415 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW167782415 BCX8\">Aurillac\u00a0<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">Depuis six ans, les Cantalous n\u2019ont pas go\u00fbt\u00e9 au parfum des phases finales, et le dernier exercice en date leur donnera peut-\u00eatre des regrets (10\u1d49). En d\u00e9pit d\u2019une solidit\u00e9 \u00e0 domicile (13\u2009V, 2D l&rsquo;an dernier), les Aurillacois ont manqu\u00e9 le coche \u00e0 plusieurs reprises \u00e0 l\u2019ext\u00e9rieur (9 pts obtenus seulement), des points qui comptent lorsque la qualification se joue dans un mouchoir de poche. Depuis plusieurs saisons, cette \u00e9quipe est catalogu\u00e9e comme redoutable en hiver. Orchestr\u00e9s autour d\u2019un pack dense et de la meilleure m\u00eal\u00e9e du championnat, les Cantalous p\u00e8chent dans l\u2019animation et dans la cr\u00e9ation du jeu, les statistiques offensives de franchissements ne plaident pas en leur faveur. Pour ce nouvel exercice, le Stade Aurillacois va devoir composer avec un recrutement tr\u00e8s restreint, compte tenu du budget du club, o\u00f9 seules cinq recrues, dont deux pr\u00eats, sont venues renforcer les rangs de l\u2019effectif.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Toutefois, le club s\u2019appuiera \u00e9galement sur ses espoirs, qui ont \u00e9t\u00e9 champions de France l\u2019an dernier face au Stade Toulousain, avec un joueur comme <strong>Ronan Loughnane<\/strong> pour ne citer que lui. En conservant sa solidit\u00e9 \u00e0 domicile et en produisant davantage de jeu, Aurillac pourrait tr\u00e8s bien vivre la m\u00eame \u00e9pop\u00e9e que Carcassonne l&rsquo;an dernier, et jouer les troublions.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Sur les 21 saisons de Pro D2, le stade Aurillacois en a disput\u00e9 20. Une histoire d\u2019amour qui dure.<a href=\"https:\/\/t.co\/jasxwDOmD8\">https:\/\/t.co\/jasxwDOmD8<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1559169625526616070?ref_src=twsrc%5Etfw\">August 15, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW46171940 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW46171940 BCX8\">B\u00e9ziers\u00a0<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">D\u00e9cevants l\u2019an dernier, les Biterrois ont chang\u00e9 leur fusil d\u2019\u00e9paule \u00e0 l\u2019intersaison pour miser sur la continuit\u00e9. Plusieurs cadres ont \u00e9t\u00e9 prolong\u00e9s, tout comme des jeunes joueurs \u00e0 fort potentiel, notamment les trois-quarts qui ont \u00e9t\u00e9 tr\u00e8s sollicit\u00e9s l\u2019an dernier. Les le\u00e7ons du pass\u00e9 ont \u00e9t\u00e9 retenues, les recrutements catalogu\u00e9s Top 14, qui ont d\u00e9\u00e7u lors des saisons pr\u00e9c\u00e9dentes, ont \u00e9t\u00e9 mis de c\u00f4t\u00e9 pour faire place \u00e0 la p\u00e9rennit\u00e9. Pour miser sur une meilleure discipline, une des faiblesses de l\u2019\u00e9quipe la saison derni\u00e8re, l\u2019ASBH a, comme Toulon et Montpellier, engag\u00e9 un ancien arbitre. <strong>C\u00e9dric Marchat<\/strong>, jeune retrait\u00e9, posera donc ses valises \u00e0 B\u00e9ziers cette saison, un renfort attendu par les dirigeants.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Neuvi\u00e8mes l&rsquo;an dernier, les Biterrois esp\u00e8rent faire mieux avec un effectif qui, sur le papier, peut r\u00e9pondre aux moyens des ambitions des dirigeants. On esp\u00e8re toutefois que ce qui se passe en coulisses ne viendra pas perturber les performances sportives,<a href=\"https:\/\/dicodusport.fr\/blog\/la-ville-de-beziers-veut-revendre-asbh\/\"> la Ville, propri\u00e9taire du club, \u00e9tant \u00e0 la recherche d&rsquo;un repreneur<\/a>.<\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\">Montauban<\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">Aux portes de la qualification au printemps, le club a tr\u00e8s mal termin\u00e9 la saison, avec en t\u00eate le terrible drame qui a frapp\u00e9 toute une ville, <a href=\"https:\/\/dicodusport.fr\/blog\/deces-tragique-de-kelly-meafua-3eme-ligne-de-montauban\/\">le d\u00e9c\u00e8s de Kelly Meafua<\/a>. Il sera difficile de se remettre, de cet \u00e9pisode tragique mais pour cette saison 2022\/2023, les Montalbanais se sont promis de le faire pour <strong>Kelly Meafua<\/strong>. Pour cette saison, 30 \u00e0 40% de l&rsquo;effectif a \u00e9t\u00e9 remodel\u00e9 et les supporters attendent avec impatience les d\u00e9buts de <strong>Sema Rokodoguni<\/strong>, qui arrive tout droit de Bath en Angleterre, ainsi que les deux internationaux g\u00e9orgiens,\u00a0<strong>Tedo Abzhandadze<\/strong> et <strong>Otar Giorgadze<\/strong>, qui d\u00e9barquent en provenance du CA Brive. Le point d\u00e9terminant de cette saison sera la discipline, car l&rsquo;an dernier, Montauban a pris beaucoup trop de cartons pour pouvoir \u00eatre comp\u00e9titif sur 80 minutes. En tout cas, l&rsquo;optimisme est de mise du c\u00f4t\u00e9 de Sapiac, o\u00f9 on esp\u00e8re que la Cuvette r\u00e9sonnera de plus belle cette saison.<\/p>\n<blockquote class=\"twitter-tweet\"><p>3\/3 pour ces , un sans fautes! L&rsquo;\u00e9quipe est pr\u00eate pour affronter la Pro D2 cette saison. Et vous? RDV Vendredi prochain dans la cuvette&#8230; pleine \u00e0 craquer!<a href=\"https:\/\/twitter.com\/hashtag\/SST?src=hash&amp;ref_src=twsrc%5Etfw\">#SST<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Ibou?src=hash&amp;ref_src=twsrc%5Etfw\">#Ibou<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/USMCO?src=hash&amp;ref_src=twsrc%5Etfw\">#USMCO<\/a> <a href=\"https:\/\/t.co\/QirUQFSnZC\">pic.twitter.com\/QirUQFSnZC<\/a><\/p>\n<p>\u2014 USM Sapiac (@UsmSapiacRugby) <a href=\"https:\/\/twitter.com\/UsmSapiacRugby\/status\/1560707354747879432?ref_src=twsrc%5Etfw\">August 19, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">La lutte pour le maintien<\/h2>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW116159340 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW116159340 BCX8\">Carcassonne\u00a0<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">L\u2019an dernier, les Carcassonnais ont \u00e9t\u00e9 la grosse surprise de la saison, apr\u00e8s s\u2019\u00eatre qualifi\u00e9s dans le Top 6 au prix d\u2019une fin de saison termin\u00e9e en boulet de canon, le tout avec le plus petit budget du championnat. Cette ann\u00e9e et avec un effectif en grande partie renouvel\u00e9, l\u2019USCXV sera de nouveau pr\u00eat \u00e0 jouer les trouble-f\u00eates. Apr\u00e8s une belle ann\u00e9e sportive, le club a pay\u00e9 un lourd tribut \u00e0 cette r\u00e9ussite, puisque 50 % de l&rsquo;effectif de l\u2019an dernier a \u00e9t\u00e9 renouvel\u00e9. Exit les <strong>Clement Doumenc<\/strong>, <strong>Pierre Huguet<\/strong> ou encore <strong>Andrei Ursache<\/strong>, qui a pass\u00e9 pr\u00e8s de onze saisons dans l\u2019Aude, mais le public de Domec se familiarisera avec <strong>Simon Meka<\/strong>, joueur \u00e0 haut potentiel pr\u00eat\u00e9 par le Castres Olympique. Toutefois, cette saison, nous ne voyons pas l&rsquo;USCXV r\u00e9it\u00e9rer les exploits de la saison pass\u00e9e.<\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW29241765 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW29241765 BCX8\">Massy<\/span><\/span><\/h3>\n<p style=\"text-align: justify;\">Pour sa quatri\u00e8me saison \u00e0 l&rsquo;\u00e9chelon professionnel, les Massicois reviennent en Pro D2 avec de toutes nouvelles intentions. Tout d&rsquo;abord et par rapport aux saisons pr\u00e9c\u00e9dentes, les infrastructures du club ont \u00e9t\u00e9 am\u00e9lior\u00e9es, que ce soit sur et en dehors du terrain. L&rsquo;an dernier, Massy a roul\u00e9 sur la Nationale. Pour cette saison, 70% de l&rsquo;effectif a \u00e9t\u00e9 conserv\u00e9. On mise donc sur la continuit\u00e9, en gardant l&rsquo;ADN du club qui reste la formation. Mais on ne s&rsquo;est pas priv\u00e9 d&rsquo;effectuer de jolis coups sur le march\u00e9 des transferts, comme les recrutements de <strong>Marco Fuser<\/strong> (Newcastle), <strong>Dylan Lam<\/strong> et <strong>Cl\u00e9ment Lanen<\/strong>, les deux derniers \u00e9voluant en Top 14 la saison derni\u00e8re. Tout comme la saison pass\u00e9e, le plan de jeu devrait s&rsquo;appuyer autour d&rsquo;un pack mobile et tr\u00e8s performant sur les group\u00e9s p\u00e9n\u00e9trants, qui ont martyris\u00e9 plusieurs formations de Nationale l&rsquo;an dernier. Massy semble mieux arm\u00e9 que les saisons pr\u00e9c\u00e9dentes pour se maintenir \u00e0 la fin de saison.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Plus qu\u2019une petite semaine avant la reprise de la <a href=\"https:\/\/twitter.com\/rugbyprod2?ref_src=twsrc%5Etfw\">@rugbyprod2<\/a><\/p>\n<p>Vos abonnements pour la saison sont toujours disponibles <a href=\"https:\/\/t.co\/fTNvKn9UlL\">https:\/\/t.co\/fTNvKn9UlL<\/a><\/p>\n<p>ALLEZ MASSY ! &#x26ab;&#xfe0f;<a href=\"https:\/\/twitter.com\/hashtag\/R%C3%AAverFort?src=hash&amp;ref_src=twsrc%5Etfw\">#R\u00eaverFort<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/MadeInMassy?src=hash&amp;ref_src=twsrc%5Etfw\">#MadeInMassy<\/a> <a href=\"https:\/\/t.co\/AgqJTEInMX\">pic.twitter.com\/AgqJTEInMX<\/a><\/p>\n<p>\u2014 Rugby Club Massy Essonne (@RCME91) <a href=\"https:\/\/twitter.com\/RCME91\/status\/1561318201383964672?ref_src=twsrc%5Etfw\">August 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"TextRun SCXW103109339 BCX8\" lang=\"FR-FR\" xml:lang=\"FR-FR\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW103109339 BCX8\">Rouen <\/span><\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\">Les Rouennais ont eu tr\u00e8s chaud l\u2019an pass\u00e9, et le maintien ne s\u2019est jou\u00e9 que sur un fil. Cependant, malgr\u00e9 l\u2019\u00e9v\u00e9nement tragique qui a frapp\u00e9 le club en fin de saison derni\u00e8re, les joueurs de <strong>Nicolas Godignon<\/strong> ont maintenu le club au premier \u00e9chelon professionnel et souhaitent d\u00e9sormais viser plus haut. Cet \u00e9t\u00e9, les postes ont \u00e9t\u00e9 doubl\u00e9s, voire tripl\u00e9s, pour ne pas r\u00e9it\u00e9rer les erreurs de recrutement de l\u2019an pass\u00e9, o\u00f9 le club n\u2019avait pas anticip\u00e9 d\u2019\u00e9ventuelles blessures. Arriv\u00e9 sur le tard la saison pass\u00e9e, l\u2019ancien du CAB, <strong>Nicolas Godignon<\/strong>, a pu orchestrer la pr\u00e9paration \u00e0 son souhait et renforcer son groupe avec des joueurs hupp\u00e9s du championnat (<strong>Pourteau, Masilevu, Boughanmi<\/strong>).<\/p>\n<h3 style=\"text-align: justify;\" align=\"justify\"><span class=\"NormalTextRun SCXW33871998 BCX8\">Soyaux-<\/span><span class=\"NormalTextRun SpellingErrorV2Themed SCXW33871998 BCX8\">Angoul\u00e8me<\/span><\/h3>\n<p style=\"text-align: justify;\" align=\"justify\"><span class=\"NormalTextRun SCXW33871998 BCX8\">Rel\u00e9gu\u00e9s il y a deux saisons, les Charentais ne se sont pas \u00e9ternis\u00e9s en Nationale et sont vite remont\u00e9s \u00e0 l\u2019\u00e9tage sup\u00e9rieur. D\u00e9sormais, l\u2019objectif sera de p\u00e9renniser le club en Pro D2. Mais la t<\/span><span class=\"NormalTextRun SCXW33871998 BCX8\">\u00e2che s\u2019annonce ardue, sachant que les deux promus de la saison derni\u00e8re (Bourg-en-Bresse et Narbonne) ont \u00e9t\u00e9 rel\u00e9gu\u00e9s en fin d&rsquo;exercice. <\/span><span class=\"NormalTextRun SCXW33871998 BCX8\">Pour esp\u00e9rer se maintenir, le SA XV gardera les m\u00eames recettes que l\u2019an pass\u00e9 : un effectif stable, renforc\u00e9 seulement par plusieurs espoirs qui ont \u00e9t\u00e9 champions de France Accession l\u2019an dernier, <\/span><span class=\"NormalTextRun SCXW33871998 BCX8\">et un plan de jeu ambitieux, qui a permis notamment aux Angoumoisins d\u2019\u00eatre la meilleure attaque de Nationale l\u2019an pass\u00e9.\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Notre classement pour la saison<\/h2>\n<ol>\n<li style=\"text-align: justify;\">Oyonnax<\/li>\n<li style=\"text-align: justify;\">Colomiers<\/li>\n<li style=\"text-align: justify;\">Mont-de-Marsan<\/li>\n<li style=\"text-align: justify;\">Provence Rugby<\/li>\n<li style=\"text-align: justify;\">Biarritz<\/li>\n<li style=\"text-align: justify;\">Aurillac<\/li>\n<li>Grenoble<\/li>\n<li style=\"text-align: justify;\">Nevers<\/li>\n<li style=\"text-align: justify;\">Agen<\/li>\n<li style=\"text-align: justify;\">Vannes<\/li>\n<li style=\"text-align: justify;\">B\u00e9ziers<\/li>\n<li style=\"text-align: justify;\">Montauban<\/li>\n<li style=\"text-align: justify;\">Massy<\/li>\n<li style=\"text-align: justify;\">Carcassonne<\/li>\n<li style=\"text-align: justify;\">Rouen<\/li>\n<li style=\"text-align: justify;\">Soyaux-Angoul\u00eame<\/li>\n<\/ol>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>PRO D2 2022\/2023 &#8211; Fin des vacances, la saison 2022\/2023 de Pro D2 d\u00e9bute ce jeudi soir par une opposition all\u00e9chante entre le Biarritz Olympique et Oyonnax. En amont de ce nouvel exercice, retrouvez nos avis concernant les \u00e9quipes amen\u00e9es \u00e0 jouer les premiers r\u00f4les, les formations qui devraient se m\u00ealer \u00e0 la lutte pour le maintien ainsi que les \u00e9quipes surprises de la saison.\u00a0<\/p>\n","protected":false},"author":42,"featured_media":255467,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129],"tags":[1839,24],"class_list":["post-255036","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-pro-d2","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023<\/title>\n<meta name=\"description\" content=\"PRO D2 2022\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l&#039;\u00e9dition 2022\/2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023\" \/>\n<meta property=\"og:description\" content=\"PRO D2 2022\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l&#039;\u00e9dition 2022\/2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-24T07:00:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Mezine\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Lbiji13\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/\"},\"author\":{\"name\":\"Nicolas Mezine\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/99fcf31b3ee0d51fed53ade78139bbbf\"},\"headline\":\"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\\\/2023\",\"datePublished\":\"2022-08-24T07:00:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/\"},\"wordCount\":3389,\"commentCount\":1,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png\",\"keywords\":[\"Pro D2\",\"sport\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/\",\"name\":\"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\\\/2023\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png\",\"datePublished\":\"2022-08-24T07:00:49+00:00\",\"description\":\"PRO D2 2022\\\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l'\u00e9dition 2022\\\/2023.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/08\\\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png\",\"width\":800,\"height\":445,\"caption\":\"Pro D2 Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 20222023\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\\\/2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/99fcf31b3ee0d51fed53ade78139bbbf\",\"name\":\"Nicolas Mezine\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/IMG_4655-e1631787111223-150x150.jpg\",\"caption\":\"Nicolas Mezine\"},\"description\":\"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/nicolas-mezine-521380160\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Lbiji13\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/nicolas-m\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023","description":"PRO D2 2022\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l'\u00e9dition 2022\/2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/","og_locale":"fr_FR","og_type":"article","og_title":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023","og_description":"PRO D2 2022\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l'\u00e9dition 2022\/2023.","og_url":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-08-24T07:00:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png","type":"image\/png"}],"author":"Nicolas Mezine","twitter_card":"summary_large_image","twitter_title":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023","twitter_creator":"@https:\/\/twitter.com\/Lbiji13","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/"},"author":{"name":"Nicolas Mezine","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf"},"headline":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023","datePublished":"2022-08-24T07:00:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/"},"wordCount":3389,"commentCount":1,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png","keywords":["Pro D2","sport"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/","url":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/","name":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png","datePublished":"2022-08-24T07:00:49+00:00","description":"PRO D2 2022\/2023 - La saison d\u00e9marre ce jeudi, et il est temps de faire un focus sur les diff\u00e9rentes \u00e9quipes de l'\u00e9dition 2022\/2023.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Pro-D2-Favoris-course-a-la-montee-relegation-la-preview-de-la-saison-20222023.png","width":800,"height":445,"caption":"Pro D2 Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 20222023"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/pro-d2-favoris-course-a-la-montee-relegation-la-preview-de-la-saison-2022-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Pro D2 : Favoris, course \u00e0 la mont\u00e9e, rel\u00e9gation, la preview de la saison 2022\/2023"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/99fcf31b3ee0d51fed53ade78139bbbf","name":"Nicolas Mezine","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/IMG_4655-e1631787111223-150x150.jpg","caption":"Nicolas Mezine"},"description":"Passionn\u00e9 de sport, notamment de rugby dans toutes ses variantes (XV, XIII et VII). Fan du RC Toulon et de l'Olympique de Marseille.","sameAs":["https:\/\/www.linkedin.com\/in\/nicolas-mezine-521380160\/","https:\/\/x.com\/https:\/\/twitter.com\/Lbiji13"],"url":"https:\/\/dicodusport.fr\/blog\/author\/nicolas-m\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/255036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=255036"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/255036\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/255467"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=255036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=255036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=255036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}