{"id":25598,"date":"2018-09-13T16:00:23","date_gmt":"2018-09-13T14:00:23","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=25598"},"modified":"2018-09-13T16:25:09","modified_gmt":"2018-09-13T14:25:09","slug":"quelle-est-la-meilleure-affaire-du-mercato-estival","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/","title":{"rendered":"Quelle est la meilleure affaire du mercato estival ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Le Centre International de l\u2019\u00c9tude du Sport a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Selon l&rsquo;algorithme du CIES, c&rsquo;est le portier belge Thibaut Courtois qui est la meilleure affaire du dernier mercato estival. Pass\u00e9 de Chelsea au Real Madrid, le Diable Rouge valait 62,6 millions d&rsquo;euros selon l&rsquo;Observatoire du Football, soit 22 millions d&rsquo;euros de plus que le prix auquel les Blues l&rsquo;ont vendu aux Merengue. Le quintuple ballon d&rsquo;or Cristiano Ronaldo, qui a quitt\u00e9 la Maison Blanche pour rejoindre la Juventus, fait \u00e9galement partie du Top 10 des bonnes pioches : \u00e9valu\u00e9 \u00e0 116,5 millions d&rsquo;euros sur le papier, les Bianconeri en ont finalement d\u00e9pens\u00e9 11 de moins pour r\u00e9aliser le transfert de l&rsquo;\u00e9t\u00e9.<\/p>\n<p style=\"text-align: justify;\">Du c\u00f4t\u00e9 des mauvaises affaires, c&rsquo;est le rempla\u00e7ant de Thibaut Courtois \u00e0 Chelsea qui h\u00e9rite du titre de pire recrue sur le plan financier. En effet, Kepa Arrizabalaga, gardien espagnol de l&rsquo;Athletic Club, a \u00e9t\u00e9 vendu 80 millions d&rsquo;euros alors qu&rsquo;il n&rsquo;en valait que&#8230; 35,3 millions. M\u00eame son de cloche pour Javier Pastore. L&rsquo;Argentin a quitt\u00e9 le PSG cet \u00e9t\u00e9 pour rejoindre l&rsquo;AS Roma pour un montant de 24,7 millions d&rsquo;euros, pour une valeur r\u00e9elle de 7,6 millions.<\/p>\n<p style=\"text-align: justify;\">Retrouvez l&rsquo;\u00e9tude dans son int\u00e9gralit\u00e9 sur le site du <a href=\"http:\/\/www.football-observatory.com\/IMG\/sites\/b5wp\/2018\/232\/fr\/\" target=\"_blank\" rel=\"noopener\">CIES<\/a>.<\/p>\n<p><strong><em>Flo Ostermann<br \/>\n<a href=\"https:\/\/www.facebook.com\/florent.ostermann\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/SportInsideMag\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Centre International de l\u2019\u00c9tude du Sport a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.<\/p>\n","protected":false},"author":4,"featured_media":25606,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2,2301],"tags":[75,5963,2832],"class_list":["post-25598","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-football","tag-football","tag-mercato-estival","tag-transferts"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quelle est la meilleure affaire du mercato estival ?<\/title>\n<meta name=\"description\" content=\"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quelle est la meilleure affaire du mercato estival ?\" \/>\n<meta property=\"og:description\" content=\"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-13T14:00:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-13T14:25:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Quelle est la meilleure affaire du mercato estival ?\",\"datePublished\":\"2018-09-13T14:00:23+00:00\",\"dateModified\":\"2018-09-13T14:25:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png\",\"keywords\":[\"Football\",\"mercato estival\",\"transferts\"],\"articleSection\":[\"Actualit\u00e9s\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\",\"name\":\"Quelle est la meilleure affaire du mercato estival ?\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png\",\"datePublished\":\"2018-09-13T14:00:23+00:00\",\"dateModified\":\"2018-09-13T14:25:09+00:00\",\"description\":\"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Quelle est la meilleure affaire du mercato estival ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Quelle est la meilleure affaire du mercato estival ?","description":"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/","og_locale":"fr_FR","og_type":"article","og_title":"Quelle est la meilleure affaire du mercato estival ?","og_description":"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.","og_url":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2018-09-13T14:00:23+00:00","article_modified_time":"2018-09-13T14:25:09+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Quelle est la meilleure affaire du mercato estival ?","datePublished":"2018-09-13T14:00:23+00:00","dateModified":"2018-09-13T14:25:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png","keywords":["Football","mercato estival","transferts"],"articleSection":["Actualit\u00e9s","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/","url":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/","name":"Quelle est la meilleure affaire du mercato estival ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png","datePublished":"2018-09-13T14:00:23+00:00","dateModified":"2018-09-13T14:25:09+00:00","description":"Le CIES a d\u00e9voil\u00e9 les meilleures et les pires affaires du march\u00e9 des transferts cet \u00e9t\u00e9. Des donn\u00e9es surprenantes, ou presque.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Meilleures-affaires-mercato-\u00e9t\u00e9-2018.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/quelle-est-la-meilleure-affaire-du-mercato-estival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Quelle est la meilleure affaire du mercato estival ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/25598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=25598"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/25598\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/25606"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=25598"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=25598"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=25598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}