{"id":257549,"date":"2022-08-30T08:02:18","date_gmt":"2022-08-30T06:02:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=257549&#038;preview=true&#038;preview_id=257549"},"modified":"2022-08-30T10:06:39","modified_gmt":"2022-08-30T08:06:39","slug":"tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/","title":{"rendered":"Tour d&rsquo;Espagne 2022 &#8211; 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>TOUR D&rsquo;ESPAGNE 2022<\/strong> <b>&#8211; Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022, avec un contre-la-montre entre Elche et Alicante <\/b><\/em><strong><em>(30,9 km). Ordre et horaires de d\u00e9part des coureurs.<\/em><\/strong><\/p>\n<h2 style=\"text-align: justify;\">Ordre et horaires de d\u00e9part du contre-la-montre du Tour d&rsquo;Espagne 2022<\/h2>\n<table class=\"basic \" style=\"width: 810px; font-size: 0.9em;\">\n<tbody>\n<tr style=\"background-color: #000000;\">\n<td style=\"width: 10px; background-color: #ee2722; text-align: center; vertical-align: middle;\"><span style=\"color: #ffffff;\"><strong>#<\/strong><\/span><\/td>\n<td style=\"width: 90px; background-color: #ee2722; text-align: center; vertical-align: middle;\"><span style=\"color: #ffffff;\"><strong>Dossards<\/strong><\/span><\/td>\n<td style=\"width: 90px; background-color: #ee2722; vertical-align: middle; text-align: center;\"><span style=\"color: #ffffff;\"><strong>Heure<\/strong><\/span><\/td>\n<td style=\"width: 280px; background-color: #ee2722; text-align: center; vertical-align: middle;\"><span style=\"color: #ffffff;\"><strong>Coureurs<\/strong><\/span><\/td>\n<td style=\"width: 340px; background-color: #ee2722; text-align: center; vertical-align: middle;\"><span style=\"color: #ffffff;\"><strong>\u00c9quipes<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">1<\/td>\n<td style=\"width: 90px; text-align: center;\">182<\/td>\n<td style=\"width: 90px; text-align: center;\">13:52:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DE TIER<\/span>\u00a0Floris<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">2<\/td>\n<td style=\"width: 90px; text-align: center;\">98<\/td>\n<td style=\"width: 90px; text-align: center;\">13:53:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN POPPEL<\/span>\u00a0Boy<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">3<\/td>\n<td style=\"width: 90px; text-align: center;\">123<\/td>\n<td style=\"width: 90px; text-align: center;\">13:54:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MAS<\/span>\u00a0Llu\u00eds<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">4<\/td>\n<td style=\"width: 90px; text-align: center;\">93<\/td>\n<td style=\"width: 90px; text-align: center;\">13:55:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">JOHANSEN<\/span>\u00a0Julius<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">5<\/td>\n<td style=\"width: 90px; text-align: center;\">47<\/td>\n<td style=\"width: 90px; text-align: center;\">13:56:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MULLEN<\/span>\u00a0Ryan<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">6<\/td>\n<td style=\"width: 90px; text-align: center;\">53<\/td>\n<td style=\"width: 90px; text-align: center;\">13:57:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CIMOLAI<\/span>\u00a0Davide<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">7<\/td>\n<td style=\"width: 90px; text-align: center;\">181<\/td>\n<td style=\"width: 90px; text-align: center;\">13:58:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MERLIER<\/span>\u00a0Tim<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">8<\/td>\n<td style=\"width: 90px; text-align: center;\">186<\/td>\n<td style=\"width: 90px; text-align: center;\">13:59:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TAMINIAUX<\/span>\u00a0Lionel<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">9<\/td>\n<td style=\"width: 90px; text-align: center;\">173<\/td>\n<td style=\"width: 90px; text-align: center;\">14:00:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">OLIVEIRA<\/span>\u00a0Ivo<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">10<\/td>\n<td style=\"width: 90px; text-align: center;\">68<\/td>\n<td style=\"width: 90px; text-align: center;\">14:01:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN DEN BERG<\/span>\u00a0Julius<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">11<\/td>\n<td style=\"width: 90px; text-align: center;\">122<\/td>\n<td style=\"width: 90px; text-align: center;\">14:02:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">NORSGAARD<\/span>\u00a0Mathias<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">12<\/td>\n<td style=\"width: 90px; text-align: center;\">116<\/td>\n<td style=\"width: 90px; text-align: center;\">14:03:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MA\u0141ECKI<\/span>\u00a0Kamil<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">13<\/td>\n<td style=\"width: 90px; text-align: center;\">147<\/td>\n<td style=\"width: 90px; text-align: center;\">14:04:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">O&rsquo;BRIEN<\/span>\u00a0Kelland<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">14<\/td>\n<td style=\"width: 90px; text-align: center;\">8<\/td>\n<td style=\"width: 90px; text-align: center;\">14:05:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TEUNISSEN<\/span>\u00a0Mike<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">15<\/td>\n<td style=\"width: 90px; text-align: center;\">177<\/td>\n<td style=\"width: 90px; text-align: center;\">14:06:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MOLANO<\/span>\u00a0Juan Sebasti\u00e1n<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">16<\/td>\n<td style=\"width: 90px; text-align: center;\">73<\/td>\n<td style=\"width: 90px; text-align: center;\">14:07:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">LIENHARD<\/span>\u00a0Fabian<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">17<\/td>\n<td style=\"width: 90px; text-align: center;\">213<\/td>\n<td style=\"width: 90px; text-align: center;\">14:08:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">AZURMENDI<\/span>\u00a0Ibai<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">18<\/td>\n<td style=\"width: 90px; text-align: center;\">41<\/td>\n<td style=\"width: 90px; text-align: center;\">14:09:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BENNETT<\/span>\u00a0Sam<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">19<\/td>\n<td style=\"width: 90px; text-align: center;\">115<\/td>\n<td style=\"width: 90px; text-align: center;\">14:10:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DRIZNERS<\/span>\u00a0Jarrad<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">20<\/td>\n<td style=\"width: 90px; text-align: center;\">227<\/td>\n<td style=\"width: 90px; text-align: center;\">14:11:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">RUSSO<\/span>\u00a0Cl\u00e9ment<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">21<\/td>\n<td style=\"width: 90px; text-align: center;\">48<\/td>\n<td style=\"width: 90px; text-align: center;\">14:12:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN POPPEL<\/span>\u00a0Danny<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">22<\/td>\n<td style=\"width: 90px; text-align: center;\">216<\/td>\n<td style=\"width: 90px; text-align: center;\">14:13:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ITURRIA<\/span>\u00a0Mikel<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">23<\/td>\n<td style=\"width: 90px; text-align: center;\">154<\/td>\n<td style=\"width: 90px; text-align: center;\">14:14:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DEGENKOLB<\/span>\u00a0John<\/td>\n<td style=\"width: 340px; text-align: center;\">Team DSM<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">24<\/td>\n<td style=\"width: 90px; text-align: center;\">24<\/td>\n<td style=\"width: 90px; text-align: center;\">14:15:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">FEDOROV<\/span>\u00a0Yevgeniy<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">25<\/td>\n<td style=\"width: 90px; text-align: center;\">52<\/td>\n<td style=\"width: 90px; text-align: center;\">14:16:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">COQUARD<\/span>\u00a0Bryan<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">26<\/td>\n<td style=\"width: 90px; text-align: center;\">156<\/td>\n<td style=\"width: 90px; text-align: center;\">14:17:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HVIDEBERG<\/span>\u00a0Jonas Iversby<\/td>\n<td style=\"width: 340px; text-align: center;\">Team DSM<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">27<\/td>\n<td style=\"width: 90px; text-align: center;\">172<\/td>\n<td style=\"width: 90px; text-align: center;\">14:18:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ACKERMANN<\/span>\u00a0Pascal<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">28<\/td>\n<td style=\"width: 90px; text-align: center;\">112<\/td>\n<td style=\"width: 90px; text-align: center;\">14:19:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BEULLENS<\/span>\u00a0Cedric<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">29<\/td>\n<td style=\"width: 90px; text-align: center;\">157<\/td>\n<td style=\"width: 90px; text-align: center;\">14:20:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">NIEUWENHUIS<\/span>\u00a0Joris<\/td>\n<td style=\"width: 340px; text-align: center;\">Team DSM<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">30<\/td>\n<td style=\"width: 90px; text-align: center;\">168<\/td>\n<td style=\"width: 90px; text-align: center;\">14:21:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TIBERI<\/span>\u00a0Antonio<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">31<\/td>\n<td style=\"width: 90px; text-align: center;\">225<\/td>\n<td style=\"width: 90px; text-align: center;\">14:22:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MCLAY<\/span>\u00a0Daniel<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">32<\/td>\n<td style=\"width: 90px; text-align: center;\">67<\/td>\n<td style=\"width: 90px; text-align: center;\">14:23:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SHAW<\/span>\u00a0James<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">33<\/td>\n<td style=\"width: 90px; text-align: center;\">165<\/td>\n<td style=\"width: 90px; text-align: center;\">14:24:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">KIRSCH<\/span>\u00a0Alex<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">34<\/td>\n<td style=\"width: 90px; text-align: center;\">17<\/td>\n<td style=\"width: 90px; text-align: center;\">14:25:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">RAUGEL<\/span>\u00a0Antoine<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">35<\/td>\n<td style=\"width: 90px; text-align: center;\">105<\/td>\n<td style=\"width: 90px; text-align: center;\">14:26:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">FROOME<\/span>\u00a0Chris<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">36<\/td>\n<td style=\"width: 90px; text-align: center;\">146<\/td>\n<td style=\"width: 90px; text-align: center;\">14:27:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HEPBURN<\/span>\u00a0Michael<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">37<\/td>\n<td style=\"width: 90px; text-align: center;\">223<\/td>\n<td style=\"width: 90px; text-align: center;\">14:28:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GUERNALEC<\/span>\u00a0Thibault<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">38<\/td>\n<td style=\"width: 90px; text-align: center;\">162<\/td>\n<td style=\"width: 90px; text-align: center;\">14:29:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CATALDO<\/span>\u00a0Dario<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">39<\/td>\n<td style=\"width: 90px; text-align: center;\">103<\/td>\n<td style=\"width: 90px; text-align: center;\">14:30:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DE MARCHI<\/span>\u00a0Alessandro<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">40<\/td>\n<td style=\"width: 90px; text-align: center;\">36<\/td>\n<td style=\"width: 90px; text-align: center;\">14:31:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">S\u00dcTTERLIN<\/span>\u00a0Jasha<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">41<\/td>\n<td style=\"width: 90px; text-align: center;\">197<\/td>\n<td style=\"width: 90px; text-align: center;\">14:32:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">OKAMIKA<\/span>\u00a0Ander<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">42<\/td>\n<td style=\"width: 90px; text-align: center;\">54<\/td>\n<td style=\"width: 90px; text-align: center;\">14:33:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CHAMPION<\/span>\u00a0Thomas<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">43<\/td>\n<td style=\"width: 90px; text-align: center;\">77<\/td>\n<td style=\"width: 90px; text-align: center;\">14:34:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SCOTSON<\/span>\u00a0Miles<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">44<\/td>\n<td style=\"width: 90px; text-align: center;\">132<\/td>\n<td style=\"width: 90px; text-align: center;\">14:35:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CAVAGNA<\/span>\u00a0R\u00e9mi<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">45<\/td>\n<td style=\"width: 90px; text-align: center;\">144<\/td>\n<td style=\"width: 90px; text-align: center;\">14:36:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GROVES<\/span>\u00a0Kaden<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">46<\/td>\n<td style=\"width: 90px; text-align: center;\">204<\/td>\n<td style=\"width: 90px; text-align: center;\">14:37:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GALV\u00c1N<\/span>\u00a0Francisco<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">47<\/td>\n<td style=\"width: 90px; text-align: center;\">203<\/td>\n<td style=\"width: 90px; text-align: center;\">14:38:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CARRETERO<\/span>\u00a0H\u00e9ctor<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">48<\/td>\n<td style=\"width: 90px; text-align: center;\">46<\/td>\n<td style=\"width: 90px; text-align: center;\">14:39:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">KOCH<\/span>\u00a0Jonas<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">49<\/td>\n<td style=\"width: 90px; text-align: center;\">226<\/td>\n<td style=\"width: 90px; text-align: center;\">14:40:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">OWSIAN<\/span>\u00a0\u0141ukasz<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">50<\/td>\n<td style=\"width: 90px; text-align: center;\">2<\/td>\n<td style=\"width: 90px; text-align: center;\">14:41:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">AFFINI<\/span>\u00a0Edoardo<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">51<\/td>\n<td style=\"width: 90px; text-align: center;\">187<\/td>\n<td style=\"width: 90px; text-align: center;\">14:42:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VERMEERSCH<\/span>\u00a0Gianni<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">52<\/td>\n<td style=\"width: 90px; text-align: center;\">183<\/td>\n<td style=\"width: 90px; text-align: center;\">14:43:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">JANSSENS<\/span>\u00a0Jimmy<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">53<\/td>\n<td style=\"width: 90px; text-align: center;\">167<\/td>\n<td style=\"width: 90px; text-align: center;\">14:44:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PEDERSEN<\/span>\u00a0Mads<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">54<\/td>\n<td style=\"width: 90px; text-align: center;\">88<\/td>\n<td style=\"width: 90px; text-align: center;\">14:45:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TURNER<\/span>\u00a0Ben<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">55<\/td>\n<td style=\"width: 90px; text-align: center;\">28<\/td>\n<td style=\"width: 90px; text-align: center;\">14:46:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TEJADA<\/span>\u00a0Harold<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">56<\/td>\n<td style=\"width: 90px; text-align: center;\">191<\/td>\n<td style=\"width: 90px; text-align: center;\">14:47:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BOL<\/span>\u00a0Jetse<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">57<\/td>\n<td style=\"width: 90px; text-align: center;\">217<\/td>\n<td style=\"width: 90px; text-align: center;\">14:48:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MART\u00cdN<\/span>\u00a0Gotzon<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">58<\/td>\n<td style=\"width: 90px; text-align: center;\">153<\/td>\n<td style=\"width: 90px; text-align: center;\">14:49:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BRENNER<\/span>\u00a0Marco<\/td>\n<td style=\"width: 340px; text-align: center;\">Team DSM<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">59<\/td>\n<td style=\"width: 90px; text-align: center;\">108<\/td>\n<td style=\"width: 90px; text-align: center;\">14:50:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">IMPEY<\/span>\u00a0Daryl<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">60<\/td>\n<td style=\"width: 90px; text-align: center;\">133<\/td>\n<td style=\"width: 90px; text-align: center;\">14:51:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DEVENYNS<\/span>\u00a0Dries<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">61<\/td>\n<td style=\"width: 90px; text-align: center;\">102<\/td>\n<td style=\"width: 90px; text-align: center;\">14:52:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BEVIN<\/span>\u00a0Patrick<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">62<\/td>\n<td style=\"width: 90px; text-align: center;\">111<\/td>\n<td style=\"width: 90px; text-align: center;\">14:53:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DE GENDT<\/span>\u00a0Thomas<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">63<\/td>\n<td style=\"width: 90px; text-align: center;\">143<\/td>\n<td style=\"width: 90px; text-align: center;\">14:54:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DURBRIDGE<\/span>\u00a0Luke<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">64<\/td>\n<td style=\"width: 90px; text-align: center;\">25<\/td>\n<td style=\"width: 90px; text-align: center;\">14:55:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">LUTSENKO<\/span>\u00a0Alexey<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">65<\/td>\n<td style=\"width: 90px; text-align: center;\">215<\/td>\n<td style=\"width: 90px; text-align: center;\">14:56:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CANAL<\/span>\u00a0Carlos<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">66<\/td>\n<td style=\"width: 90px; text-align: center;\">212<\/td>\n<td style=\"width: 90px; text-align: center;\">14:57:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">AZPARREN<\/span>\u00a0Xabier Mikel<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">67<\/td>\n<td style=\"width: 90px; text-align: center;\">65<\/td>\n<td style=\"width: 90px; text-align: center;\">14:58:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">KUDUS<\/span>\u00a0Merhawi<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">68<\/td>\n<td style=\"width: 90px; text-align: center;\">113<\/td>\n<td style=\"width: 90px; text-align: center;\">14:59:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CONCA<\/span>\u00a0Filippo<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">69<\/td>\n<td style=\"width: 90px; text-align: center;\">205<\/td>\n<td style=\"width: 90px; text-align: center;\">15:00:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GARC\u00cdA PIERNA<\/span>\u00a0Ra\u00fal<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">70<\/td>\n<td style=\"width: 90px; text-align: center;\">214<\/td>\n<td style=\"width: 90px; text-align: center;\">15:01:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BOU<\/span>\u00a0Joan<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">71<\/td>\n<td style=\"width: 90px; text-align: center;\">16<\/td>\n<td style=\"width: 90px; text-align: center;\">15:02:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PRODHOMME<\/span>\u00a0Nicolas<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">72<\/td>\n<td style=\"width: 90px; text-align: center;\">206<\/td>\n<td style=\"width: 90px; text-align: center;\">15:03:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MIQUEL<\/span>\u00a0Pau<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">73<\/td>\n<td style=\"width: 90px; text-align: center;\">202<\/td>\n<td style=\"width: 90px; text-align: center;\">15:04:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BERRADE<\/span>\u00a0Urko<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">74<\/td>\n<td style=\"width: 90px; text-align: center;\">208<\/td>\n<td style=\"width: 90px; text-align: center;\">15:05:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">\u0158EPA<\/span>\u00a0Vojt\u011bch<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">75<\/td>\n<td style=\"width: 90px; text-align: center;\">118<\/td>\n<td style=\"width: 90px; text-align: center;\">15:06:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN GILS<\/span>\u00a0Maxim<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">76<\/td>\n<td style=\"width: 90px; text-align: center;\">117<\/td>\n<td style=\"width: 90px; text-align: center;\">15:07:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SWEENY<\/span>\u00a0Harry<\/td>\n<td style=\"width: 340px; text-align: center;\">Lotto Soudal<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">77<\/td>\n<td style=\"width: 90px; text-align: center;\">62<\/td>\n<td style=\"width: 90px; text-align: center;\">15:08:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CAICEDO<\/span>\u00a0Jonathan Klever<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">78<\/td>\n<td style=\"width: 90px; text-align: center;\">161<\/td>\n<td style=\"width: 90px; text-align: center;\">15:09:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BERNARD<\/span>\u00a0Julien<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">79<\/td>\n<td style=\"width: 90px; text-align: center;\">72<\/td>\n<td style=\"width: 90px; text-align: center;\">15:10:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ARMIRAIL<\/span>\u00a0Bruno<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">80<\/td>\n<td style=\"width: 90px; text-align: center;\">138<\/td>\n<td style=\"width: 90px; text-align: center;\">15:11:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VERVAEKE<\/span>\u00a0Louis<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">81<\/td>\n<td style=\"width: 90px; text-align: center;\">85<\/td>\n<td style=\"width: 90px; text-align: center;\">15:12:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PLAPP<\/span>\u00a0Luke<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">82<\/td>\n<td style=\"width: 90px; text-align: center;\">166<\/td>\n<td style=\"width: 90px; text-align: center;\">15:13:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">L\u00d3PEZ<\/span>\u00a0Juan Pedro<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">83<\/td>\n<td style=\"width: 90px; text-align: center;\">56<\/td>\n<td style=\"width: 90px; text-align: center;\">15:14:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HERRADA<\/span>\u00a0Jos\u00e9<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">84<\/td>\n<td style=\"width: 90px; text-align: center;\">201<\/td>\n<td style=\"width: 90px; text-align: center;\">15:15:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ADRI\u00c0<\/span>\u00a0Roger<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">85<\/td>\n<td style=\"width: 90px; text-align: center;\">15<\/td>\n<td style=\"width: 90px; text-align: center;\">15:16:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PETERS<\/span>\u00a0Nans<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">86<\/td>\n<td style=\"width: 90px; text-align: center;\">84<\/td>\n<td style=\"width: 90px; text-align: center;\">15:17:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HAYTER<\/span>\u00a0Ethan<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">87<\/td>\n<td style=\"width: 90px; text-align: center;\">14<\/td>\n<td style=\"width: 90px; text-align: center;\">15:18:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">JUNGELS<\/span>\u00a0Bob<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">88<\/td>\n<td style=\"width: 90px; text-align: center;\">176<\/td>\n<td style=\"width: 90px; text-align: center;\">15:19:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MCNULTY<\/span>\u00a0Brandon<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">89<\/td>\n<td style=\"width: 90px; text-align: center;\">3<\/td>\n<td style=\"width: 90px; text-align: center;\">15:20:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DENNIS<\/span>\u00a0Rohan<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">90<\/td>\n<td style=\"width: 90px; text-align: center;\">37<\/td>\n<td style=\"width: 90px; text-align: center;\">15:21:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">WRIGHT<\/span>\u00a0Fred<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">91<\/td>\n<td style=\"width: 90px; text-align: center;\">22<\/td>\n<td style=\"width: 90px; text-align: center;\">15:22:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BATTISTELLA<\/span>\u00a0Samuele<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">92<\/td>\n<td style=\"width: 90px; text-align: center;\">193<\/td>\n<td style=\"width: 90px; text-align: center;\">15:23:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">D\u00cdAZ<\/span>\u00a0Jos\u00e9 Manuel<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">93<\/td>\n<td style=\"width: 90px; text-align: center;\">224<\/td>\n<td style=\"width: 90px; text-align: center;\">15:24:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GUGLIELMI<\/span>\u00a0Simon<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">94<\/td>\n<td style=\"width: 90px; text-align: center;\">106<\/td>\n<td style=\"width: 90px; text-align: center;\">15:25:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GOLDSTEIN<\/span>\u00a0Omer<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">95<\/td>\n<td style=\"width: 90px; text-align: center;\">125<\/td>\n<td style=\"width: 90px; text-align: center;\">15:26:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">M\u00dcHLBERGER<\/span>\u00a0Gregor<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">96<\/td>\n<td style=\"width: 90px; text-align: center;\">221<\/td>\n<td style=\"width: 90px; text-align: center;\">15:27:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GESBERT<\/span>\u00a0\u00c9lie<\/td>\n<td style=\"width: 340px; text-align: center;\">Team Ark\u00e9a Samsic<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">97<\/td>\n<td style=\"width: 90px; text-align: center;\">196<\/td>\n<td style=\"width: 90px; text-align: center;\">15:28:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">NAVARRO<\/span>\u00a0Daniel<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">98<\/td>\n<td style=\"width: 90px; text-align: center;\">135<\/td>\n<td style=\"width: 90px; text-align: center;\">15:29:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MASNADA<\/span>\u00a0Fausto<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">99<\/td>\n<td style=\"width: 90px; text-align: center;\">185<\/td>\n<td style=\"width: 90px; text-align: center;\">15:30:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">STANNARD<\/span>\u00a0Robert<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">100<\/td>\n<td style=\"width: 90px; text-align: center;\">218<\/td>\n<td style=\"width: 90px; text-align: center;\">15:31:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MAT\u00c9<\/span>\u00a0Luis \u00c1ngel<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">101<\/td>\n<td style=\"width: 90px; text-align: center;\">82<\/td>\n<td style=\"width: 90px; text-align: center;\">15:32:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN BAARLE<\/span>\u00a0Dylan<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">102<\/td>\n<td style=\"width: 90px; text-align: center;\">51<\/td>\n<td style=\"width: 90px; text-align: center;\">15:33:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HERRADA<\/span>\u00a0Jes\u00fas<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">103<\/td>\n<td style=\"width: 90px; text-align: center;\">194<\/td>\n<td style=\"width: 90px; text-align: center;\">15:34:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">EZQUERRA<\/span>\u00a0Jes\u00fas<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">104<\/td>\n<td style=\"width: 90px; text-align: center;\">27<\/td>\n<td style=\"width: 90px; text-align: center;\">15:35:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PRONSKIY<\/span>\u00a0Vadim<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">105<\/td>\n<td style=\"width: 90px; text-align: center;\">4<\/td>\n<td style=\"width: 90px; text-align: center;\">15:36:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GESINK<\/span>\u00a0Robert<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">106<\/td>\n<td style=\"width: 90px; text-align: center;\">142<\/td>\n<td style=\"width: 90px; text-align: center;\">15:37:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CRADDOCK<\/span>\u00a0Lawson<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">107<\/td>\n<td style=\"width: 90px; text-align: center;\">42<\/td>\n<td style=\"width: 90px; text-align: center;\">15:38:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">FABBRO<\/span>\u00a0Matteo<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">108<\/td>\n<td style=\"width: 90px; text-align: center;\">107<\/td>\n<td style=\"width: 90px; text-align: center;\">15:39:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HAGEN<\/span>\u00a0Carl Fredrik<\/td>\n<td style=\"width: 340px; text-align: center;\">Israel &#8211; Premier Tech<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">109<\/td>\n<td style=\"width: 90px; text-align: center;\">184<\/td>\n<td style=\"width: 90px; text-align: center;\">15:40:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MEURISSE<\/span>\u00a0Xandro<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">110<\/td>\n<td style=\"width: 90px; text-align: center;\">145<\/td>\n<td style=\"width: 90px; text-align: center;\">15:41:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HAMILTON<\/span>\u00a0Lucas<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">111<\/td>\n<td style=\"width: 90px; text-align: center;\">127<\/td>\n<td style=\"width: 90px; text-align: center;\">15:42:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ROJAS<\/span>\u00a0Jos\u00e9 Joaqu\u00edn<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">112<\/td>\n<td style=\"width: 90px; text-align: center;\">26<\/td>\n<td style=\"width: 90px; text-align: center;\">15:43:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">NIBALI<\/span>\u00a0Vincenzo<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">113<\/td>\n<td style=\"width: 90px; text-align: center;\">131<\/td>\n<td style=\"width: 90px; text-align: center;\">15:44:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ALAPHILIPPE<\/span>\u00a0Julian<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">114<\/td>\n<td style=\"width: 90px; text-align: center;\">64<\/td>\n<td style=\"width: 90px; text-align: center;\">15:45:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CHAVES<\/span>\u00a0Esteban<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">115<\/td>\n<td style=\"width: 90px; text-align: center;\">38<\/td>\n<td style=\"width: 90px; text-align: center;\">15:46:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ZAMBANINI<\/span>\u00a0Edoardo<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">116<\/td>\n<td style=\"width: 90px; text-align: center;\">148<\/td>\n<td style=\"width: 90px; text-align: center;\">15:47:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SCOTSON<\/span>\u00a0Callum<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">117<\/td>\n<td style=\"width: 90px; text-align: center;\">137<\/td>\n<td style=\"width: 90px; text-align: center;\">15:48:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VAN WILDER<\/span>\u00a0Ilan<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">118<\/td>\n<td style=\"width: 90px; text-align: center;\">171<\/td>\n<td style=\"width: 90px; text-align: center;\">15:49:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SOLER<\/span>\u00a0Marc<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">119<\/td>\n<td style=\"width: 90px; text-align: center;\">55<\/td>\n<td style=\"width: 90px; text-align: center;\">15:50:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">FERN\u00c1NDEZ<\/span>\u00a0Rub\u00e9n<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">120<\/td>\n<td style=\"width: 90px; text-align: center;\">32<\/td>\n<td style=\"width: 90px; text-align: center;\">15:51:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BUITRAGO<\/span>\u00a0Santiago<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">121<\/td>\n<td style=\"width: 90px; text-align: center;\">12<\/td>\n<td style=\"width: 90px; text-align: center;\">15:52:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CHAMPOUSSIN<\/span>\u00a0Cl\u00e9ment<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">122<\/td>\n<td style=\"width: 90px; text-align: center;\">163<\/td>\n<td style=\"width: 90px; text-align: center;\">15:53:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ELISSONDE<\/span>\u00a0Kenny<\/td>\n<td style=\"width: 340px; text-align: center;\">Trek &#8211; Segafredo<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">123<\/td>\n<td style=\"width: 90px; text-align: center;\">58<\/td>\n<td style=\"width: 90px; text-align: center;\">15:54:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VILLELLA<\/span>\u00a0Davide<\/td>\n<td style=\"width: 340px; text-align: center;\">Cofidis<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">124<\/td>\n<td style=\"width: 90px; text-align: center;\">211<\/td>\n<td style=\"width: 90px; text-align: center;\">15:55:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BIZKARRA<\/span>\u00a0Mikel<\/td>\n<td style=\"width: 340px; text-align: center;\">Euskaltel &#8211; Euskadi<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">125<\/td>\n<td style=\"width: 90px; text-align: center;\">75<\/td>\n<td style=\"width: 90px; text-align: center;\">15:56:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PACHER<\/span>\u00a0Quentin<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">126<\/td>\n<td style=\"width: 90px; text-align: center;\">126<\/td>\n<td style=\"width: 90px; text-align: center;\">15:57:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">OLIVEIRA<\/span>\u00a0Nelson<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">127<\/td>\n<td style=\"width: 90px; text-align: center;\">128<\/td>\n<td style=\"width: 90px; text-align: center;\">15:58:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VERONA<\/span>\u00a0Carlos<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">128<\/td>\n<td style=\"width: 90px; text-align: center;\">96<\/td>\n<td style=\"width: 90px; text-align: center;\">15:59:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">TAARAM\u00c4E<\/span>\u00a0Rein<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">129<\/td>\n<td style=\"width: 90px; text-align: center;\">5<\/td>\n<td style=\"width: 90px; text-align: center;\">16:00:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HARPER<\/span>\u00a0Chris<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">130<\/td>\n<td style=\"width: 90px; text-align: center;\">7<\/td>\n<td style=\"width: 90px; text-align: center;\">16:01:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">OOMEN<\/span>\u00a0Sam<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">131<\/td>\n<td style=\"width: 90px; text-align: center;\">76<\/td>\n<td style=\"width: 90px; text-align: center;\">16:02:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">REICHENBACH<\/span>\u00a0S\u00e9bastien<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">132<\/td>\n<td style=\"width: 90px; text-align: center;\">71<\/td>\n<td style=\"width: 90px; text-align: center;\">16:03:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PINOT<\/span>\u00a0Thibaut<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">133<\/td>\n<td style=\"width: 90px; text-align: center;\">207<\/td>\n<td style=\"width: 90px; text-align: center;\">16:04:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PARRA<\/span>\u00a0Jos\u00e9 F\u00e9lix<\/td>\n<td style=\"width: 340px; text-align: center;\">Equipo Kern Pharma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">134<\/td>\n<td style=\"width: 90px; text-align: center;\">91<\/td>\n<td style=\"width: 90px; text-align: center;\">16:05:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">BAKELANTS<\/span>\u00a0Jan<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">135<\/td>\n<td style=\"width: 90px; text-align: center;\">188<\/td>\n<td style=\"width: 90px; text-align: center;\">16:06:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VINE<\/span>\u00a0Jay<\/td>\n<td style=\"width: 340px; text-align: center;\">Alpecin-Deceuninck<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">136<\/td>\n<td style=\"width: 90px; text-align: center;\">74<\/td>\n<td style=\"width: 90px; text-align: center;\">16:07:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MOLARD<\/span>\u00a0Rudy<\/td>\n<td style=\"width: 340px; text-align: center;\">Groupama &#8211; FDJ<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">137<\/td>\n<td style=\"width: 90px; text-align: center;\">31<\/td>\n<td style=\"width: 90px; text-align: center;\">16:08:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">LANDA<\/span>\u00a0Mikel<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">138<\/td>\n<td style=\"width: 90px; text-align: center;\">192<\/td>\n<td style=\"width: 90px; text-align: center;\">16:09:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CABEDO<\/span>\u00a0\u00d3scar<\/td>\n<td style=\"width: 340px; text-align: center;\">Burgos-BH<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">139<\/td>\n<td style=\"width: 90px; text-align: center;\">81<\/td>\n<td style=\"width: 90px; text-align: center;\">16:10:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CARAPAZ<\/span>\u00a0Richard<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">140<\/td>\n<td style=\"width: 90px; text-align: center;\">178<\/td>\n<td style=\"width: 90px; text-align: center;\">16:11:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">POLANC<\/span>\u00a0Jan<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">141<\/td>\n<td style=\"width: 90px; text-align: center;\">35<\/td>\n<td style=\"width: 90px; text-align: center;\">16:12:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">S\u00c1NCHEZ<\/span>\u00a0Luis Le\u00f3n<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">142<\/td>\n<td style=\"width: 90px; text-align: center;\">45<\/td>\n<td style=\"width: 90px; text-align: center;\">16:13:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">KELDERMAN<\/span>\u00a0Wilco<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">143<\/td>\n<td style=\"width: 90px; text-align: center;\">95<\/td>\n<td style=\"width: 90px; text-align: center;\">16:14:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">POZZOVIVO<\/span>\u00a0Domenico<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">144<\/td>\n<td style=\"width: 90px; text-align: center;\">43<\/td>\n<td style=\"width: 90px; text-align: center;\">16:15:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HIGUITA<\/span>\u00a0Sergio<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">145<\/td>\n<td style=\"width: 90px; text-align: center;\">61<\/td>\n<td style=\"width: 90px; text-align: center;\">16:17:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">UR\u00c1N<\/span>\u00a0Rigoberto<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">146<\/td>\n<td style=\"width: 90px; text-align: center;\">33<\/td>\n<td style=\"width: 90px; text-align: center;\">16:19:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">M\u00c4DER<\/span>\u00a0Gino<\/td>\n<td style=\"width: 340px; text-align: center;\">Bahrain &#8211; Victorious<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">147<\/td>\n<td style=\"width: 90px; text-align: center;\">23<\/td>\n<td style=\"width: 90px; text-align: center;\">16:21:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">DE LA CRUZ<\/span>\u00a0David<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">148<\/td>\n<td style=\"width: 90px; text-align: center;\">66<\/td>\n<td style=\"width: 90px; text-align: center;\">16:23:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">PADUN<\/span>\u00a0Mark<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">149<\/td>\n<td style=\"width: 90px; text-align: center;\">94<\/td>\n<td style=\"width: 90px; text-align: center;\">16:25:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MEINTJES<\/span>\u00a0Louis<\/td>\n<td style=\"width: 340px; text-align: center;\">Intermarch\u00e9 &#8211; Wanty &#8211; Gobert Mat\u00e9riaux<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">150<\/td>\n<td style=\"width: 90px; text-align: center;\">63<\/td>\n<td style=\"width: 90px; text-align: center;\">16:27:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">CARTHY<\/span>\u00a0Hugh<\/td>\n<td style=\"width: 340px; text-align: center;\">EF Education-EasyPost<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">151<\/td>\n<td style=\"width: 90px; text-align: center;\">121<\/td>\n<td style=\"width: 90px; text-align: center;\">16:29:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">VALVERDE<\/span>\u00a0Alejandro<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">152<\/td>\n<td style=\"width: 90px; text-align: center;\">11<\/td>\n<td style=\"width: 90px; text-align: center;\">16:31:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">O&rsquo;CONNOR<\/span>\u00a0Ben<\/td>\n<td style=\"width: 340px; text-align: center;\">AG2R Citro\u00ebn Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">153<\/td>\n<td style=\"width: 90px; text-align: center;\">83<\/td>\n<td style=\"width: 90px; text-align: center;\">16:33:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">GEOGHEGAN HART<\/span>\u00a0Tao<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">154<\/td>\n<td style=\"width: 90px; text-align: center;\">151<\/td>\n<td style=\"width: 90px; text-align: center;\">16:35:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ARENSMAN<\/span>\u00a0Thymen<\/td>\n<td style=\"width: 340px; text-align: center;\">Team DSM<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">155<\/td>\n<td style=\"width: 90px; text-align: center;\">87<\/td>\n<td style=\"width: 90px; text-align: center;\">16:37:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">SIVAKOV<\/span>\u00a0Pavel<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">156<\/td>\n<td style=\"width: 90px; text-align: center;\">44<\/td>\n<td style=\"width: 90px; text-align: center;\">16:39:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">HINDLEY<\/span>\u00a0Jai<\/td>\n<td style=\"width: 340px; text-align: center;\">BORA &#8211; hansgrohe<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">157<\/td>\n<td style=\"width: 90px; text-align: center;\">21<\/td>\n<td style=\"width: 90px; text-align: center;\">16:41:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">L\u00d3PEZ<\/span>\u00a0Miguel \u00c1ngel<\/td>\n<td style=\"width: 340px; text-align: center;\">Astana Qazaqstan Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">158<\/td>\n<td style=\"width: 90px; text-align: center;\">175<\/td>\n<td style=\"width: 90px; text-align: center;\">16:43:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ALMEIDA<\/span>\u00a0Jo\u00e3o<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">159<\/td>\n<td style=\"width: 90px; text-align: center;\">141<\/td>\n<td style=\"width: 90px; text-align: center;\">16:45:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">YATES<\/span>\u00a0Simon<\/td>\n<td style=\"width: 340px; text-align: center;\">Team BikeExchange &#8211; Jayco<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">160<\/td>\n<td style=\"width: 90px; text-align: center;\">174<\/td>\n<td style=\"width: 90px; text-align: center;\">16:47:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">AYUSO<\/span>\u00a0Juan<\/td>\n<td style=\"width: 340px; text-align: center;\">UAE Team Emirates<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">161<\/td>\n<td style=\"width: 90px; text-align: center;\">86<\/td>\n<td style=\"width: 90px; text-align: center;\">16:49:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">RODR\u00cdGUEZ<\/span>\u00a0Carlos<\/td>\n<td style=\"width: 340px; text-align: center;\">INEOS Grenadiers<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">162<\/td>\n<td style=\"width: 90px; text-align: center;\">1<\/td>\n<td style=\"width: 90px; text-align: center;\">16:51:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">ROGLI\u010c<\/span>\u00a0Primo\u017e<\/td>\n<td style=\"width: 340px; text-align: center;\">Jumbo-Visma<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">163<\/td>\n<td style=\"width: 90px; text-align: center;\">124<\/td>\n<td style=\"width: 90px; text-align: center;\">16:53:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">MAS<\/span>\u00a0Enric<\/td>\n<td style=\"width: 340px; text-align: center;\">Movistar Team<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 10px; text-align: center;\">164<\/td>\n<td style=\"width: 90px; text-align: center;\">134<\/td>\n<td style=\"width: 90px; text-align: center;\">16:55:00<\/td>\n<td style=\"width: 280px; text-align: center;\">\u00a0<span class=\"uppercase\">EVENEPOEL<\/span>\u00a0Remco<\/td>\n<td style=\"width: 340px; text-align: center;\">Quick-Step Alpha Vinyl Team<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<h2>\u00c0 lire aussi<\/h2>\n<ul>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/le-profil-des-21-etapes-du-tour-d-espagne-2022\/\" target=\"_blank\" rel=\"noopener\"><b>Le profil des \u00e9tapes du Tour d\u2019Espagne 2022<\/b><\/a><\/li>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-parcours-et-profil-de-la-10eme-etape\/\" target=\"_blank\" rel=\"noopener\"><strong>Tour d\u2019Espagne 2022 \u2013 Parcours et profil de la 10\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-classement-general-maillot-rouge\/\"><strong>Classement g\u00e9n\u00e9ral du Tour d\u2019Espagne 2022<\/strong><\/a><strong>\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.<\/p>\n","protected":false},"author":1,"featured_media":257551,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47042],"tags":[1671],"class_list":["post-257549","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-tour-despagne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part<\/title>\n<meta name=\"description\" content=\"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d&#039;Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part\" \/>\n<meta property=\"og:description\" content=\"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d&#039;Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-30T06:02:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-30T08:06:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Tour d&rsquo;Espagne 2022 &#8211; 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part\",\"datePublished\":\"2022-08-30T06:02:18+00:00\",\"dateModified\":\"2022-08-30T08:06:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\"},\"wordCount\":936,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png\",\"keywords\":[\"Tour d'Espagne\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\",\"name\":\"Tour d'Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png\",\"datePublished\":\"2022-08-30T06:02:18+00:00\",\"dateModified\":\"2022-08-30T08:06:39+00:00\",\"description\":\"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d'Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&rsquo;Espagne 2022 &#8211; 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part","description":"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d'Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part","og_description":"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d'Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-08-30T06:02:18+00:00","article_modified_time":"2022-08-30T08:06:39+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Tour d&rsquo;Espagne 2022 &#8211; 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part","datePublished":"2022-08-30T06:02:18+00:00","dateModified":"2022-08-30T08:06:39+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/"},"wordCount":936,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png","keywords":["Tour d'Espagne"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/","name":"Tour d'Espagne 2022 - 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png","datePublished":"2022-08-30T06:02:18+00:00","dateModified":"2022-08-30T08:06:39+00:00","description":"Ce mardi, place \u00e0 la 10\u00e8me \u00e9tape du Tour d'Espagne 2022, avec un contre-la-montre entre Elche et Alicante (30,9 km). Ordre et horaires de d\u00e9part des coureurs.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/08\/Tour-dEspagne-2022-10e\u0300me-e\u0301tape-Ordre-et-horaires-de-de\u0301part.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-10eme-etape-ordre-et-horaires-de-depart\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&rsquo;Espagne 2022 &#8211; 10\u00e8me \u00e9tape : Ordre et horaires de d\u00e9part"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/257549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=257549"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/257549\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/257551"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=257549"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=257549"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=257549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}