{"id":260000,"date":"2022-09-08T17:13:01","date_gmt":"2022-09-08T15:13:01","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=260000&#038;preview=true&#038;preview_id=260000"},"modified":"2022-09-08T19:42:46","modified_gmt":"2022-09-08T17:42:46","slug":"tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/","title":{"rendered":"Tour d&rsquo;Espagne 2022 : Remco Evenepoel s&rsquo;impose en patron sur la 18\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/tour-espagne-2022\/\">TOUR D&rsquo;ESPAGNE 2022<\/a> &#8211; Imp\u00e9rial dans le final face \u00e0 Enric Mas (Movistar), Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l&rsquo;Alto del Piornal. Le Belge conforte son maillot rouge de leader, \u00e0 trois jours de l&rsquo;arriv\u00e9e \u00e0 Madrid.<\/strong><\/em><span class=\"f7rl1if4 adechonz f6oz4yja dahkl6ri axrg9lpx rufpak1n qtovjlwq qbmienfq rfyhaz4c rdmi1yqr ohrdq8us nswx41af fawcizw8 l1aqi3e3 sdu1flz4\"><br \/>\n<\/span><\/p>\n<p style=\"text-align: justify;\">Remco taille patron ! Ce jeudi, le Belge <strong>Remco Evenepoel<\/strong> a sans doute enfonc\u00e9 le clou sur la <strong>Vuelta 2022<\/strong>. Le leader de la Quick-Step Alpha Vinyl, maillot rouge depuis 13 jours, a enlev\u00e9 la <strong>18\u00e8me \u00e9tape de ce Tour d&rsquo;Espagne<\/strong>, au sommet de l&rsquo;Alto del Piornal, au terme d&rsquo;une \u00e9tape longue 192 km.<\/p>\n<h2 style=\"text-align: justify;\">Evenepoel proche du sacre<\/h2>\n<p style=\"text-align: justify;\">Pour glaner sa premi\u00e8re \u00e9tape en ligne sur un Grand Tour, <strong>Evenepoel<\/strong> a frustr\u00e9 son plus grand rival depuis l&rsquo;abandon de <strong>Primoz Roglic<\/strong> (Jumbo-Visma), <strong>Enric Mas<\/strong> (Movistar). Le duo belgo-espagnol s&rsquo;est en effet extirp\u00e9 du groupe des cadors peu avant la flamme rouge, avant de fondre sur le dernier rescap\u00e9 de l&rsquo;\u00e9chapp\u00e9e du jour, <strong>Robert Gesink<\/strong> (Jumbo-Visma). Le N\u00e9erlandais, lib\u00e9r\u00e9 de son r\u00f4le de lieutenent aupr\u00e8s de Roglic, s&rsquo;est montr\u00e9 le plus fort d&rsquo;un groupe de 40 coureurs, au sein duquel on retrouvait \u00e9galement <strong>Thibaut Pinot<\/strong> (Groupama-FDJ) et <strong>Richard Carapaz<\/strong> (INEOS Grenadiers).<\/p>\n<p style=\"text-align: justify;\">Finalement, dans les 150 derniers m\u00e8tres, <strong>Remco Evenepoel<\/strong> a fait parler sa puissance pour s&rsquo;imposer une deuxi\u00e8me fois sur cette Vuelta, apr\u00e8s avoir remport\u00e9 le chrono de la 10\u00e8me \u00e9tape \u00e0 Alicante, laissant Mas constater les d\u00e9g\u00e2ts. \u00c0 3 jours de l&rsquo;arriv\u00e9e \u00e0 Madrid, le natif d&rsquo;Alost, 22 ans, dispose d&rsquo;une avance de 2:07 sur <strong>Enric Mas<\/strong>, avec une derni\u00e8re \u00e9tape compliqu\u00e9e samedi, vers le Puerto de Navacerrada. Autant dire que le petit prince belge touche au but.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">! &#x26a1;&#xfe0f;<\/p>\n<p>Le maillot rouge s&rsquo;offre la 18e \u00e9tape devant Mas et Gesink et fait un (tr\u00e8s) grand pas vers la victoire finale <a href=\"https:\/\/twitter.com\/hashtag\/LaVuelta22?src=hash&amp;ref_src=twsrc%5Etfw\">#LaVuelta22<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/LesRP?src=hash&amp;ref_src=twsrc%5Etfw\">#LesRP<\/a> <a href=\"https:\/\/t.co\/uDM1LDcP8v\">pic.twitter.com\/uDM1LDcP8v<\/a><\/p>\n<p>\u2014 Eurosport France (@Eurosport_FR) <a href=\"https:\/\/twitter.com\/Eurosport_FR\/status\/1567893376841748481?ref_src=twsrc%5Etfw\">September 8, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-classement-18eme-etape\/\"><strong>Le classement de la 18\u00e8me \u00e9tape du Tour d&rsquo;Espagne 2022<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-classement-general-maillot-rouge\/\"><strong>Le classement g\u00e9n\u00e9ral du Tour d&rsquo;Espagne 2022<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOUR D&rsquo;ESPAGNE 2022 &#8211; Imp\u00e9rial dans le final face \u00e0 Enric Mas (Movistar), Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l&rsquo;Alto del Piornal. Le Belge conforte son maillot rouge de leader, \u00e0 trois jours de l&rsquo;arriv\u00e9e \u00e0 Madrid.<\/p>\n","protected":false},"author":4,"featured_media":260090,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47042],"tags":[574,24],"class_list":["post-260000","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tour-d-espagne","tag-cyclisme","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour d&#039;Espagne 2022 : Remco Evenepoel s&#039;impose en patron sur la 18\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR D&#039;ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l&#039;Alto del Piornal.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour d&#039;Espagne 2022 : Remco Evenepoel s&#039;impose en patron sur la 18\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR D&#039;ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l&#039;Alto del Piornal.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-08T15:13:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-08T17:42:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour d&#039;Espagne 2022 : Remco Evenepoel s&#039;impose en patron sur la 18\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour d&rsquo;Espagne 2022 : Remco Evenepoel s&rsquo;impose en patron sur la 18\u00e8me \u00e9tape\",\"datePublished\":\"2022-09-08T15:13:01+00:00\",\"dateModified\":\"2022-09-08T17:42:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\"},\"wordCount\":363,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png\",\"keywords\":[\"Cyclisme\",\"sport\"],\"articleSection\":[\"Tour d'Espagne\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\",\"name\":\"Tour d'Espagne 2022 : Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png\",\"datePublished\":\"2022-09-08T15:13:01+00:00\",\"dateModified\":\"2022-09-08T17:42:46+00:00\",\"description\":\"TOUR D'ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l'Alto del Piornal.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png\",\"width\":800,\"height\":445,\"caption\":\"Tour d'Espagne 2022 Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour d&rsquo;Espagne 2022 : Remco Evenepoel s&rsquo;impose en patron sur la 18\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour d'Espagne 2022 : Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape","description":"TOUR D'ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l'Alto del Piornal.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour d'Espagne 2022 : Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape","og_description":"TOUR D'ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l'Alto del Piornal.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-09-08T15:13:01+00:00","article_modified_time":"2022-09-08T17:42:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour d'Espagne 2022 : Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour d&rsquo;Espagne 2022 : Remco Evenepoel s&rsquo;impose en patron sur la 18\u00e8me \u00e9tape","datePublished":"2022-09-08T15:13:01+00:00","dateModified":"2022-09-08T17:42:46+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/"},"wordCount":363,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png","keywords":["Cyclisme","sport"],"articleSection":["Tour d'Espagne"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/","name":"Tour d'Espagne 2022 : Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png","datePublished":"2022-09-08T15:13:01+00:00","dateModified":"2022-09-08T17:42:46+00:00","description":"TOUR D'ESPAGNE 2022 - Remco Evenepoel (Quick-Step Alpha Vinyl) a remport\u00e9 la 18\u00e8me \u00e9tape de la Vuelta ce jeudi, \u00e0 l'Alto del Piornal.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Tour-dEspagne-2022-Remco-Evenepoel-simpose-en-patron-sur-la-18eme-etape.png","width":800,"height":445,"caption":"Tour d'Espagne 2022 Remco Evenepoel s'impose en patron sur la 18\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-despagne-2022-remco-evenepoel-remporte-la-18eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour d&rsquo;Espagne 2022 : Remco Evenepoel s&rsquo;impose en patron sur la 18\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/260000","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=260000"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/260000\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/260090"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=260000"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=260000"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=260000"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}