{"id":26104,"date":"2018-09-23T09:15:59","date_gmt":"2018-09-23T07:15:59","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=26104"},"modified":"2018-09-23T14:02:23","modified_gmt":"2018-09-23T12:02:23","slug":"yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/","title":{"rendered":"Yvan Mendy est-il la victime de l&rsquo;un des plus grands scandales de l&rsquo;histoire de la boxe ?"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Pour la revanche de leur combat d&rsquo;il y a presque trois ans, c&rsquo;est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges. Cette d\u00e9cision a beau fait parler, le Fran\u00e7ais est-il la victime d&rsquo;un des plus gros scandales de l&rsquo;histoire ?\u00a0<\/strong><\/em><\/p>\n<h4 style=\"text-align: justify;\">Oui, Brahim Asloum et\u00a0Samyr Hamoudi ont raison<\/h4>\n<p style=\"text-align: justify;\">Avant la d\u00e9cision, les deux commentateurs fran\u00e7ais sont confiants et pensent que l&rsquo;arbitre va lever le poing de Mendy. M\u00eame si Brahim Asloum est aussi son promoteur, l&rsquo;ancien champion olympique et son acolyte affirment que m\u00eame en \u00e9tant pessimiste, le boxeur fran\u00e7ais est devant. La d\u00e9cision des juges est sans appel et les deux commentateurs fran\u00e7ais ainsi que toute la communaut\u00e9 fran\u00e7aise qui a suivi le combat crient au scandale du si\u00e8cle, pensant que leur poulain devait gagner et surtout ne pas perdre de 10 points comme l&rsquo;a d\u00e9cid\u00e9 un juge.<\/p>\n<h4 style=\"text-align: justify;\">Non, seul l&rsquo;\u00e9cart de 10 points d&rsquo;un juge est illogique<\/h4>\n<p style=\"text-align: justify;\">Si en France tout le monde voyait Mendy vainqueur, chez les observateurs \u00e9trangers, la tr\u00e8s grande majorit\u00e9,\u00a0Sugar Ray Leonard compris, donnaient l&rsquo;Anglais gagnant, mais d&rsquo;une courte t\u00eate. Ils s&rsquo;accordent tous \u00e0 dire que les 10 points d&rsquo;\u00e9cart donn\u00e9s par le premier juge (119-109) est effectivement une aberration mais que Campbell a \u00e9t\u00e9 plus chirurgical sur ce combat face au Fran\u00e7ais.<\/p>\n<div class=\"dem-poll-shortcode\">\n<style id=\"democracy-poll-css\">.democracy:after{content:'';display:table;clear:both}.democracy ul li,.democracy ul{background:0 0;padding:0;margin:0}.democracy ul li:before{display:none}.democracy input[type=radio],.democracy input[type=checkbox]{margin:0;vertical-align:middle}.democracy input[type=radio]:focus,.democracy input[type=checkbox]:focus{outline:none}.democracy ul{list-style:none !important;border:none !important}.democracy ul li{list-style:none !important}input[type=submit].dem-button,a.dem-button,.dem-button{position:relative;display:inline-block;text-decoration:none;line-height:1;border:0;margin:0;padding:0;cursor:pointer;white-space:nowrap;-webkit-user-select:none;-moz-user-select:none;-ms-user-select:none;user-select:none}input[type=submit].dem-button:focus,a.dem-button:focus,.dem-button:focus{outline:none}input[type=submit].dem-button:disabled,a.dem-button:disabled,.dem-button:disabled{opacity:.6;cursor:not-allowed}a.dem-button:hover{text-decoration:none !important}.democracy{position:relative;margin:0 auto}.democracy input[type=radio],.democracy input[type=checkbox]{margin-right:.2em}.dem-screen{position:relative;line-height:1.3}.democracy ul.dem-vote{margin-bottom:1em}.democracy ul.dem-vote li{padding-bottom:0;margin-bottom:0}.democracy ul.dem-vote li>*{margin-bottom:.6em}.democracy ul.dem-answers li{padding-bottom:1em}.dem-answers .dem-label{margin-bottom:.2em;line-height:1.2}.dem-graph{position:relative;color:#555;color:rgba(0,0,0,.6);box-sizing:content-box;width:100%;display:table;height:1.2em;line-height:1.2em}.dem-fill{position:absolute;top:0;left:0;height:100%;background-color:#7cb4dd}.dem-voted-this .dem-fill{background-color:#ffc45a}.dem-votes-txt,.dem-percent-txt{position:relative;display:table-cell;padding-left:.3em;vertical-align:middle;font-size:90%}.dem-poll-info{padding-bottom:1em}.dem-poll-info:after{content:'';display:table;clear:both}.dem-poll-info>*{font-size:85%;display:block;float:right;clear:both;text-align:right;opacity:.7;line-height:1.3}.dem-vote label{float:none;display:block}.dem-results-link{display:inline-block;line-height:1;margin:.8em 1em}.dem-vote .dem-disabled{opacity:.5}.democracy .dem-bottom{padding-bottom:1em}.dem-bottom{text-align:center}.dem-bottom:after{content:'';display:table;clear:both}.dem-poll-title{display:block;margin-bottom:1.5em;margin-top:1.2em;font-size:120%}.dem-notice{z-index:10;position:absolute;top:0;border-radius:2px;width:100%;padding:1.5em 2em;text-align:center;background:rgba(247,241,212,.8);color:#6d6214}.dem-notice-close{position:absolute;top:0;right:0;padding:5px;cursor:pointer;line-height:.6;font-size:150%}.dem-notice-close:hover{color:#d26616}.dem-star{font-size:90%;vertical-align:baseline;padding-left:.3em;color:#ff4e00}.dem-poll-note{font-size:90%;padding:.5em;opacity:.8;line-height:1.3}.democracy .dem-copyright{position:absolute;bottom:-1em;right:0;text-decoration:none;border-bottom:0;color:#b2b2b2;opacity:.5;line-height:1}.democracy .dem-copyright:hover{opacity:1}.dem-add-answer{position:relative}.dem-add-answer>*{display:block}.dem-add-answer a{display:inline-block}input.dem-add-answer-txt{width:100%;box-sizing:border-box}.dem-add-answer-close{position:absolute;right:0;padding:0 .7em;cursor:pointer;color:#333}.dem-add-answer-close:hover{color:#ff2700}.dem-edit-link{display:block;position:absolute;top:0;right:0;line-height:1;text-decoration:none !important;border:none !important}.dem-edit-link svg{width:1.2em!important;fill:#6c6c6c}.dem-edit-link:hover svg{fill:#35a91d}.dem-loader{display:none;position:absolute;top:0;left:0;width:100%;height:100%}.dem-loader>*{display:table-cell;vertical-align:middle;text-align:center}.dem-loader svg{width:20%;max-width:100px;min-width:80px;margin-bottom:15%}.dem-loader [class^=dem-]{margin-bottom:15%!important}.dem__collapser{display:block;cursor:pointer;text-align:center;font-size:150%;line-height:1}.dem__collapser:hover{color:#f31;background:rgba(255,255,255,.3)}.dem__collapser.expanded{position:relative;height:1em}.dem__collapser.collapsed{position:absolute;top:0;bottom:0;right:0;left:0}.dem__collapser .arr{display:block;position:absolute;bottom:0;width:100%}.dem__collapser.collapsed .arr:before{content:\"\u25be\"}.dem__collapser.expanded .arr:before{content:\"\u25b4\"}.dem-poll-shortcode{margin-bottom:1.5em}.dem-archives .dem-elem-wrap{margin-bottom:2em;padding-bottom:20px;border-bottom:1px dashed rgba(0,0,0,.1)}.dem-archives .dem-archive-link{display:none}.dem-paging{text-align:center;margin:1.5em auto}.dem-paging>*{display:inline-block;padding:.3em .8em;border-radius:.2em;background:#e2e2e2;color:#333;text-decoration:none;text-transform:lowercase;user-select:none}.dem-paging>a{color:#333}.dem-paging>a:hover{background:#ccc;color:#333;text-decoration:none}.dem-paging .current{background:#656565;color:#fff}.dem-paging .dots{background:0 0}.democracy{border-color:#ccc;border:1px solid rgba(0,0,0,.1);background-color:#eee;background-color:rgba(0,0,0,.1);background-image:-webkit-linear-gradient(bottom,rgba(0,0,0,.05),transparent);background-image:linear-gradient(to top,rgba(0,0,0,.05),transparent);padding:1em;padding-bottom:.5em;margin-bottom:1em}.dem-poll-title{margin:0;font-size:115%;margin:-.9em;margin-bottom:1em;text-align:center;padding:1em;border-bottom:1px solid rgba(0,0,0,.1)}.dem-percent-txt,.dem-label-percent-txt{display:none}.dem-votes-txt-percent:before{content:'- ';display:inline}.dem-revote-button:before{content:'\u25c2 '}.dem-graph{background-color:rgba(255,255,255,.8)}.dem-results-link{margin-bottom:0}.dem__checkbox,.dem__radio{display:none !important}.dem__checkbox_label,.dem__radio_label{position:relative;box-sizing:content-box}.dem__checkbox_label .dem__spot{border-radius:3px}.dem__radio_label .dem__spot{border-radius:50%}.dem__checkbox_label .dem__spot,.dem__radio_label .dem__spot{position:relative;display:inline-block;vertical-align:baseline;width:.9em;height:.9em;margin-right:.3em;cursor:pointer;background:#fff;border:1px solid #ccc}.dem__checkbox_label .dem__spot:after{width:.9em;height:.32em;top:-.1em;left:.145em;border:.17em solid #333;border-top:none;border-right:none;-webkit-transform:rotate(-45deg);transform:rotate(-45deg);background:0 0}.dem__radio_label .dem__spot:after{width:.5em;height:.5em;border-radius:50%;top:50%;left:50%;-webkit-transform:translate(-50%,-50%);transform:translate(-50%,-50%);background:#333}.dem__checkbox_label .dem__spot:after,.dem__radio_label .dem__spot:after{content:'';position:absolute;opacity:0}.dem__checkbox_label:hover .dem__spot:after,.dem__radio_label:hover .dem__spot:after{opacity:.2}.dem__checkbox:checked+.dem__spot,.dem__radio:checked+.dem__spot{border-color:#999}.dem__checkbox:checked+.dem__spot:after,.dem__radio:checked+.dem__spot:after{opacity:1}.dem__checkbox:disabled+.dem__spot,.dem__radio:disabled+.dem__spot{opacity:.5}.dem__checkbox:not(:checked):disabled+.dem__spot:after,.dem__radio:not(:checked):disabled+.dem__spot:after{opacity:0}input[type=submit].dem-button,a.dem-button,.dem-button{font-size:90%;font-family:tahoma,arial,sans-serif;padding:.8em 1.6em !important;color:#fff;background:#61a9de;text-transform:uppercase}input[type=submit].dem-button:hover,a.dem-button:hover,.dem-button:hover{color:#fff;background:#3b8bc6}a.dem-button:visited{color:#fff}.dem-loader .fill{fill:#0248ed !important}.dem-loader .css-fill{background-color:#0248ed !important}.dem-loader .stroke{stroke:#0248ed !important}.dem-graph{background:#a5a5a5 !important}.dem-fill{background-color:#1c62ed !important}.dem-voted-this .dem-fill{background-color:#30a82a !important}.dem-graph{height:25px;line-height:25px}.dem-button{background-color:#f71339 !important}.dem-button{color:#efefef !important}.democracy{background-color:#fff;color:#000}.dem-poll-info{color:#000}.dem-votes-txt,.dem-percent-txt{color:#fff}<\/style>\n\n<div class=\"dem-loader dem_loader_js\"><div><style type=\"text\/css\">\n.dem-circle {\n  width:100%;\n  height:100%;\n  min-width:40px;\n  min-height:40px;\n  max-width:70px;\n  max-height:70px;\n\n  position: relative;\n  margin: 0 auto;\n}\n\n.double-bounce1, .double-bounce2 {\n  width: 100%;\n  height: 100%;\n  border-radius: 50%;\n  background-color: var(--dem-loader-color, #226ec6);\n  opacity: 0.6;\n  position: absolute;\n  top: 0;\n  left: 0;\n  animation: bounce 2.0s infinite ease-in-out;\n}\n\n.double-bounce2 {\n  animation-delay: -1.0s;\n}\n\n@keyframes bounce {\n  0%, 100% { \n    transform: scale(0.0);\n  } 50% { \n    transform: scale(1.0);\n  }\n}<\/style>\n\n<div class=\"dem-circle\">\n  <div class=\"double-bounce1 css-fill\"><\/div>\n  <div class=\"double-bounce2 css-fill\"><\/div>\n<\/div><\/div><\/div>\n<template class=\"dem_notice_template_js\">\n\t<div class=\"dem-notice dem_notice_js\">\n\t\t<button type=\"button\" class=\"dem-notice-close dem_notice_close_js\" aria-label=\"Fermer\">&times;<\/button>\n\t\t<div class=\"dem-notice-message dem_notice_message_js\"><\/div>\n\t<\/div>\n<\/template>\n<div id=\"democracy-181\" class=\"democracy democracy_js\" data-opts='{&quot;pid&quot;:181,&quot;max_answs&quot;:0,&quot;answs_max_height&quot;:&quot;&quot;}' >\n\t<strong class=\"dem-poll-title\">La d\u00e9faite d'Yvan Mendy est-elle un scandale ?<\/strong>\n\t<div class=\"dem-screen voted dem_screen_js\"><ul class=\"dem-answers dem_answers_list_js\" data-voted_txt=\"Votre vote.\">\n\t<li  class=\"dem-winner\" title=\"190 voix - 85% des votes\" data-aid=\"666\">\n\t<div class=\"dem-label\">\n\t\tOui, il devait gagner \n\t\t<span class=\"dem-label-percent-txt\">85%, 190 <span class=\"votxt\">voix<\/span><\/span>\n\t<\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill dem_fill_js\" data-width=\"100%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">190 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">85%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">190 voix - 85% des votes<\/div>\n\t<\/div>\n<\/li><li  title=\"29 voix - 13% des votes\" data-aid=\"667\">\n\t<div class=\"dem-label\">\n\t\tNon, mais il ne devait pas perdre de 10 points \n\t\t<span class=\"dem-label-percent-txt\">13%, 29 <span class=\"votxt\">voix<\/span><\/span>\n\t<\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill dem_fill_js\" data-width=\"15%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">29 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">13%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">29 voix - 13% des votes<\/div>\n\t<\/div>\n<\/li><li  title=\"5 voix - 2% des votes\" data-aid=\"668\">\n\t<div class=\"dem-label\">\n\t\tNon, l'Anglais a \u00e9t\u00e9 meilleur \n\t\t<span class=\"dem-label-percent-txt\">2%, 5 <span class=\"votxt\">voix<\/span><\/span>\n\t<\/div>\n\t<div class=\"dem-graph\">\n\t\t<div class=\"dem-fill dem_fill_js\" data-width=\"3%\"><\/div>\n\t\t<div class=\"dem-votes-txt\">\n\t\t\t<span class=\"dem-votes-txt-votes\">5 <span class=\"votxt\">voix<\/span><\/span>\n\t\t\t<span class=\"dem-votes-txt-percent\">2%<\/span>\n\t\t<\/div>\n\t\t<div class=\"dem-percent-txt\">5 voix - 2% des votes<\/div>\n\t<\/div>\n<\/li>\n<\/ul>\n<div class=\"dem-bottom dem-results-bottom\">\n\t<div class=\"dem-poll-info\">\n\t\t<div class=\"dem-total-votes\">Total des votes : 224<\/div>\n\t\t\n\t\t<div class=\"dem-date\" title=\"D\u00e9but\">\n\t\t\t<span class=\"dem-begin-date\">23 septembre 2018<\/span> - <span class=\"dem-end-date\" title=\"Fin\">12 ao\u00fbt 2021<\/span>\n\t\t<\/div>\n\t\t\n\t\t<div>Les votes sont clos<\/div>\n\t\t\n\t<\/div>\n\t\n<\/div><!--\/dem-bottom--><\/div>\n<\/div><!--democracy-->\n<\/div>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<\/strong><br \/>\n<\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour la revanche de leur combat d&rsquo;il y a presque trois ans, c&rsquo;est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges. <\/p>\n","protected":false},"author":1,"featured_media":26110,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,2310],"tags":[622],"class_list":["post-26104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-sports-de-combat","tag-boxe"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Yvan Mendy est-il la victime de l&#039;un des plus grands scandales de l&#039;histoire de la boxe ?<\/title>\n<meta name=\"description\" content=\"Pour la revanche de leur combat d&#039;il y a presque trois ans, c&#039;est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yvan Mendy est-il la victime de l&#039;un des plus grands scandales de l&#039;histoire de la boxe ?\" \/>\n<meta property=\"og:description\" content=\"Pour la revanche de leur combat d&#039;il y a presque trois ans, c&#039;est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-23T07:15:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-23T12:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Yvan Mendy est-il la victime de l&rsquo;un des plus grands scandales de l&rsquo;histoire de la boxe ?\",\"datePublished\":\"2018-09-23T07:15:59+00:00\",\"dateModified\":\"2018-09-23T12:02:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/\"},\"wordCount\":261,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Yvan-Mendy-Luke-Campbell.png\",\"keywords\":[\"boxe\"],\"articleSection\":[\"Actualit\u00e9s\",\"Sports de combat\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#respond\"]}],\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/\",\"name\":\"Yvan Mendy est-il la victime de l'un des plus grands scandales de l'histoire de la boxe ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Yvan-Mendy-Luke-Campbell.png\",\"datePublished\":\"2018-09-23T07:15:59+00:00\",\"dateModified\":\"2018-09-23T12:02:23+00:00\",\"description\":\"Pour la revanche de leur combat d'il y a presque trois ans, c'est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Yvan-Mendy-Luke-Campbell.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2018\\\/09\\\/Yvan-Mendy-Luke-Campbell.png\",\"width\":1200,\"height\":670},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yvan Mendy est-il la victime de l&rsquo;un des plus grands scandales de l&rsquo;histoire de la boxe ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Yvan Mendy est-il la victime de l'un des plus grands scandales de l'histoire de la boxe ?","description":"Pour la revanche de leur combat d'il y a presque trois ans, c'est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/","og_locale":"fr_FR","og_type":"article","og_title":"Yvan Mendy est-il la victime de l'un des plus grands scandales de l'histoire de la boxe ?","og_description":"Pour la revanche de leur combat d'il y a presque trois ans, c'est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.","og_url":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2018-09-23T07:15:59+00:00","article_modified_time":"2018-09-23T12:02:23+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Yvan Mendy est-il la victime de l&rsquo;un des plus grands scandales de l&rsquo;histoire de la boxe ?","datePublished":"2018-09-23T07:15:59+00:00","dateModified":"2018-09-23T12:02:23+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/"},"wordCount":261,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png","keywords":["boxe"],"articleSection":["Actualit\u00e9s","Sports de combat"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#respond"]}],"copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/","url":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/","name":"Yvan Mendy est-il la victime de l'un des plus grands scandales de l'histoire de la boxe ?","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png","datePublished":"2018-09-23T07:15:59+00:00","dateModified":"2018-09-23T12:02:23+00:00","description":"Pour la revanche de leur combat d'il y a presque trois ans, c'est Luke Campbell qui a battu Yvan Mendy par d\u00e9cision unanime des juges.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Yvan-Mendy-Luke-Campbell.png","width":1200,"height":670},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/yvan-mendy-est-il-la-victime-d-un-des-plus-grands-scandales-de-lhistoire-de-la-boxe\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Yvan Mendy est-il la victime de l&rsquo;un des plus grands scandales de l&rsquo;histoire de la boxe ?"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/26104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=26104"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/26104\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/26110"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=26104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=26104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=26104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}