{"id":262192,"date":"2022-09-15T13:41:18","date_gmt":"2022-09-15T11:41:18","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=262192&#038;preview=true&#038;preview_id=262192"},"modified":"2022-09-15T14:12:08","modified_gmt":"2022-09-15T12:12:08","slug":"wta-fin-de-saison-pour-simona-halep","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/","title":{"rendered":"WTA : Fin de saison pour Simona Halep"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>SAISON WTA 2022 &#8211; L&rsquo;ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, a subi une intervention chirurgicale, et se voit contrainte de mettre un terme \u00e0 sa saison.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Ce fut l&rsquo;une des grosses surprises du dernier US Open. Parmi les outsiders l\u00e9gitimes du tournoi, <strong>Simona Halep<\/strong> <a href=\"https:\/\/dicodusport.fr\/blog\/us-open-2022-simona-halep-prend-deja-la-porte\/\">avait chut\u00e9 d\u00e8s le premier tour<\/a> contre l&rsquo;inconnue ukrainienne <strong>Daria Snigur<\/strong>. Apr\u00e8s ce couac, la Roumaine pouvait tout de m\u00eame envisager une qualification pour les prochaines WTA Finals (\u00e9quivalent des Masters). Mais il n&rsquo;en sera rien, puisqu&rsquo;elle vient d&rsquo;annoncer avoir subi une op\u00e9ration destin\u00e9e \u00e0 corriger des probl\u00e8mes respiratoires de longue date. L&rsquo;intervention a \u00e9t\u00e9 un succ\u00e8s, mais la voil\u00e0 contrainte de mettre fin \u00e0 sa saison.<\/p>\n<p style=\"text-align: justify;\">Une saison cependant r\u00e9ussie, puisqu&rsquo;apr\u00e8s une ann\u00e9e 2021 g\u00e2ch\u00e9e par une blessure au mollet, l&rsquo;ancienne n\u00b01 mondiale a retrouv\u00e9 le chemin du top 10, et notamment d\u00e9croch\u00e9 <a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-feminin-de-toronto-simona-halep-revient-au-sommet-au-canada\/\">le titre au WTA 1000 de Toronto<\/a>. On la reverra probablement lors de la tourn\u00e9e australienne en janvier.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Hi everyone &#x1f44b; <a href=\"https:\/\/t.co\/wfUe7Outym\">pic.twitter.com\/wfUe7Outym<\/a><\/p>\n<p>\u2014 Simona Halep (@Simona_Halep) <a href=\"https:\/\/twitter.com\/Simona_Halep\/status\/1570370209504198656?ref_src=twsrc%5Etfw\">September 15, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SAISON WTA 2022 &#8211; L&rsquo;ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, a subi une intervention chirurgicale, et se voit contrainte de mettre un terme \u00e0 sa saison.\u00a0<\/p>\n","protected":false},"author":59,"featured_media":262197,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[3539],"class_list":["post-262192","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-simona-halep"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>WTA : Fin de saison pour Simona Halep<\/title>\n<meta name=\"description\" content=\"SAISON WTA 2022 - L&#039;ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WTA : Fin de saison pour Simona Halep\" \/>\n<meta property=\"og:description\" content=\"SAISON WTA 2022 - L&#039;ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T11:41:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-15T12:12:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"WTA : Fin de saison pour Simona Halep\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"WTA : Fin de saison pour Simona Halep\",\"datePublished\":\"2022-09-15T11:41:18+00:00\",\"dateModified\":\"2022-09-15T12:12:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\"},\"wordCount\":201,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png\",\"keywords\":[\"Simona Halep\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\",\"name\":\"WTA : Fin de saison pour Simona Halep\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png\",\"datePublished\":\"2022-09-15T11:41:18+00:00\",\"dateModified\":\"2022-09-15T12:12:08+00:00\",\"description\":\"SAISON WTA 2022 - L'ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png\",\"width\":800,\"height\":445,\"caption\":\"WTA Fin de saison pour Simona Halep\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"WTA : Fin de saison pour Simona Halep\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"WTA : Fin de saison pour Simona Halep","description":"SAISON WTA 2022 - L'ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/","og_locale":"fr_FR","og_type":"article","og_title":"WTA : Fin de saison pour Simona Halep","og_description":"SAISON WTA 2022 - L'ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison","og_url":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-09-15T11:41:18+00:00","article_modified_time":"2022-09-15T12:12:08+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"WTA : Fin de saison pour Simona Halep","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"WTA : Fin de saison pour Simona Halep","datePublished":"2022-09-15T11:41:18+00:00","dateModified":"2022-09-15T12:12:08+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/"},"wordCount":201,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png","keywords":["Simona Halep"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/","url":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/","name":"WTA : Fin de saison pour Simona Halep","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png","datePublished":"2022-09-15T11:41:18+00:00","dateModified":"2022-09-15T12:12:08+00:00","description":"SAISON WTA 2022 - L'ancienne n\u00b01 mondiale Simona Halep, apr\u00e8s un US Open d\u00e9cevant, se voit contrainte de mettre un terme \u00e0 sa saison","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/WTA-Fin-de-saison-pour-Simona-Halep.png","width":800,"height":445,"caption":"WTA Fin de saison pour Simona Halep"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/wta-fin-de-saison-pour-simona-halep\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"WTA : Fin de saison pour Simona Halep"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/262192","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=262192"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/262192\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/262197"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=262192"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=262192"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=262192"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}