{"id":262401,"date":"2022-09-15T23:01:30","date_gmt":"2022-09-15T21:01:30","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=262401&#038;preview=true&#038;preview_id=262401"},"modified":"2022-09-16T08:34:55","modified_gmt":"2022-09-16T06:34:55","slug":"ligue-europa-rennes-et-le-fenerbahce-se-neutralisent","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/","title":{"rendered":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>LIGUE EUROPA 2022\/2023 &#8211; Apr\u00e8s avoir men\u00e9 2-0, les Rennais ont conc\u00e9d\u00e9 le match nul face au Fenerbah\u00e7e. R\u00e9duits \u00e0 10 dans les quinze derni\u00e8res minutes, c\u2019est un penalty dans le temps additionnel qui permet aux Stambouliotes d&rsquo;\u00e9galiser.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s <a href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-le-stade-rennais-lemporte-dans-les-dernieres-secondes\/\">leur victoire in extremis face \u00e0 l\u2019AEK Larnaca<\/a>, les Rennais recevaient le <strong>Fenerbah\u00e7e<\/strong> pour un gros choc. Dans un match class\u00e9 \u00e0 risque en raison du d\u00e9placement des supporters turcs, les deux \u00e9quipes avaient n\u00e9anmoins la possibilit\u00e9 de prendre provisoirement la premi\u00e8re place du groupe B. Quelques fumig\u00e8nes pour f\u00eater la seconde journ\u00e9e d\u2019Europa League -on va dire \u00e7a comme \u00e7a- et Mr Kubalkov pouvait siffler le coup d\u2019envoi.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x23f1; C&rsquo;est parti au Roazhon Park.<\/p>\n<p>ALLEZ LES ROUGE ET NOIR ! &#x1f525;<a href=\"https:\/\/twitter.com\/hashtag\/SRFCFEN?src=hash&amp;ref_src=twsrc%5Etfw\">#SRFCFEN<\/a> 0-0 <a href=\"https:\/\/t.co\/2fyL7XnyAx\">pic.twitter.com\/2fyL7XnyAx<\/a><\/p>\n<p>\u2014 Stade Rennais F.C. (@staderennais) <a href=\"https:\/\/twitter.com\/staderennais\/status\/1570488307016142850?ref_src=twsrc%5Etfw\">September 15, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">De l\u2019intensit\u00e9 mais peu d\u2019occasions<\/h2>\n<p style=\"text-align: justify;\"><strong>Priv\u00e9 de 10\u00a0000 spectateurs<\/strong>, le Roazhon Park n\u2019a pourtant pas tra\u00een\u00e9 pour pousser ses joueurs. Et ces derniers ont rapidement r\u00e9pondu pr\u00e9sent notamment sur la r\u00e9cup\u00e9ration du ballon. Un pressing tout terrain qui permettait aux Rennais de reprendre la possession. Mais pour en faire quoi\u00a0? Car <strong>les Bretons ont manqu\u00e9 de r\u00e9ussite en premi\u00e8re p\u00e9riode <\/strong>et ont vite rendu la balle. Un contr\u00f4le, une passe, il manquait toujours le dernier geste afin de s\u2019offrir une occasion nette.<\/p>\n<p style=\"text-align: justify;\">Les plus franches des 45 premi\u00e8res minutes sont \u00e0 mettre au cr\u00e9dit des Stambouliotes. Michy Batshuayi butait sur Steve Mandanda (7\u2019) et <strong>le but d\u2019Irfan Can Kahveci \u00e9tait refus\u00e9 pour une position de hors-jeu <\/strong>(25\u2019). La premi\u00e8re frappe rennaise a vu le jour \u00e0 la 23<sup>\u00e8me<\/sup> minute pour trois tentatives au total avant la pause dont aucune cadr\u00e9e, trop peu pour inqui\u00e9ter le Fenerbah\u00e7e.<\/p>\n<h2 style=\"text-align: justify;\">Rennes tenait la victoire\u2026 jusqu\u2019au temps additionnel<\/h2>\n<p style=\"text-align: justify;\">Alors que la r\u00e9alisation s\u2019attardait sur un ralenti d\u2019une glissade d\u2019Osayi-Samuel dans la surface rennaise, Mandanda avait rapidement relanc\u00e9 \u00e0 la main sur Lovro Majer. Le Croate servait en profondeur <strong>Martin Terrier qui se retrouvait seul face \u00e0 Bayindir et ouvrait le score<\/strong>. On jouait alors la 52<sup>\u00e8me<\/sup> minute. \u00c0 la 54<sup>\u00e8me<\/sup>, les Bretons menaient 2-0. \u00c0 peine le temps de f\u00eater le premier but que Terrier se retrouvait passeur, Majer se transformait en buteur pour une <strong>copie conforme du but pr\u00e9c\u00e9dent<\/strong>. Les ardeurs du stade sont vite redescendues lorsque Kahveci, d\u2019une frappe lointaine, a r\u00e9duit la marque \u00e0 l\u2019heure de jeu. Pire encore, \u00e0 dix minutes du terme, <strong>Traor\u00e9 se faisait exclure suite \u00e0 un mauvais geste sur ce m\u00eame Kahveci<\/strong>.<\/p>\n<p style=\"text-align: justify;\">\u00c0 onze contre dix, les efforts turcs ont \u00e9t\u00e9 plus intenses, et ont fini par payer. <strong>Une faute de Benjamin Bourigeaud dans la surface offrait la balle d\u2019\u00e9galisation \u00e0 Enner Valencia<\/strong> qui ne se faisait pas prier pour transformer le penalty (90+2). Cruel pour le capitaine du Stade Rennais et ses co\u00e9quipiers, mais c\u2019est tout de m\u00eame un bon point de pris alors que la premi\u00e8re place du groupe se joue toujours entre ces deux clubs.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3c1; C&rsquo;est termin\u00e9.<\/p>\n<p>Au terme d&rsquo;une fin de match cruelle, nos Rouge et Noir sont tenus en \u00e9chec par Fenerbah\u00e7e. <a href=\"https:\/\/twitter.com\/hashtag\/SRFCFEN?src=hash&amp;ref_src=twsrc%5Etfw\">#SRFCFEN<\/a> 2-2 <a href=\"https:\/\/t.co\/4gKBu37dUb\">pic.twitter.com\/4gKBu37dUb<\/a><\/p>\n<p>\u2014 Stade Rennais F.C. (@staderennais) <a href=\"https:\/\/twitter.com\/staderennais\/status\/1570517550798180354?ref_src=twsrc%5Etfw\">September 15, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>LIGUE EUROPA 2022\/2023 &#8211; Apr\u00e8s avoir men\u00e9 2-0, les Rennais ont conc\u00e9d\u00e9 le match nul face au Fenerbah\u00e7e. R\u00e9duits \u00e0 10 dans les quinze derni\u00e8res minutes, c\u2019est un penalty dans le temps additionnel qui permet aux Stambouliotes d&rsquo;\u00e9galiser.<\/p>\n","protected":false},"author":18,"featured_media":262424,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[4897,75,4437,1840,24],"class_list":["post-262401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-fenerbahce","tag-football","tag-ligue-europa","tag-rennes","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-15T21:01:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-16T06:34:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent\",\"datePublished\":\"2022-09-15T21:01:30+00:00\",\"dateModified\":\"2022-09-16T06:34:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/\"},\"wordCount\":568,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png\",\"keywords\":[\"Fenerbah\u00e7e\",\"Football\",\"Ligue Europa\",\"Rennes\",\"sport\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/\",\"name\":\"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png\",\"datePublished\":\"2022-09-15T21:01:30+00:00\",\"dateModified\":\"2022-09-16T06:34:55+00:00\",\"description\":\"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue Europa Rennes et le Fenerbah\u00e7e se neutralisent\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent","description":"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent","og_description":"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2022-09-15T21:01:30+00:00","article_modified_time":"2022-09-16T06:34:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent","datePublished":"2022-09-15T21:01:30+00:00","dateModified":"2022-09-16T06:34:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/"},"wordCount":568,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png","keywords":["Fenerbah\u00e7e","Football","Ligue Europa","Rennes","sport"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/","name":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png","datePublished":"2022-09-15T21:01:30+00:00","dateModified":"2022-09-16T06:34:55+00:00","description":"Apr\u00e8s avoir men\u00e9 2-0, Rennes conc\u00e8de finalement le nul face \u00e0 Fenerbah\u00e7e suite \u00e0 un penalty siffl\u00e9 dans le temps additionnel.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Ligue-Europa-Rennes-et-le-Fenerbahce-se-neutralisent.png","width":800,"height":445,"caption":"Ligue Europa Rennes et le Fenerbah\u00e7e se neutralisent"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-et-le-fenerbahce-se-neutralisent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue Europa : Rennes et le Fenerbah\u00e7e se neutralisent"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/262401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=262401"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/262401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/262424"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=262401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=262401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=262401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}