{"id":263066,"date":"2022-09-18T07:40:42","date_gmt":"2022-09-18T05:40:42","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=263066"},"modified":"2022-09-18T09:09:28","modified_gmt":"2022-09-18T07:09:28","slug":"boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/","title":{"rendered":"Boxe : Saul Canelo Alvarez s&rsquo;adjuge la trilogie face \u00e0 Golovkin !"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>BOXE &#8211; POIDS SUPER-MOYENS &#8211; La trilogie revient au Mexicain ! Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin. Au terme d&rsquo;un match ma\u00eetris\u00e9, Canelo conserve l&rsquo;int\u00e9gralit\u00e9 des ceintures chez les poids super-moyens, dont il est le roi incontest\u00e9 depuis un an.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Quatre ans apr\u00e8s leur dernier combat, <em>Canelo<\/em> et <em>GGG<\/em> se sont retrouv\u00e9s pour une derni\u00e8re danse. Apr\u00e8s deux combats l\u00e9gendaires, cet ultime face \u00e0 face fut certainement le moins spectaculaire et le plus d\u00e9s\u00e9quilibr\u00e9. En effet, \u00e0 32 ans, <strong>Saul Alvarez<\/strong>, <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-mi-lourds-dmitry-bivol-renverse-saul-alvarez\/\">m\u00eame s&rsquo;il restait sur une d\u00e9faite contre <strong>Dmitrii Bivol<\/strong><\/a>, est au sommet de son art, surtout dans sa cat\u00e9gorie f\u00e9tiche des poids super-moyens. En face, la l\u00e9gende kazakhe <strong>Gennady Golovkin<\/strong>, du haut de ses 40 ans, faisait figure d&rsquo;outsider.<\/p>\n<h2 style=\"text-align: justify;\">La fin d&rsquo;une grande rivalit\u00e9<\/h2>\n<p style=\"text-align: justify;\">La premi\u00e8re partie du combat fut \u00e0 sens unique. En total ma\u00eetrise, le Mexicain a distribu\u00e9 des coups puissants \u00e0 son rival, qui n&rsquo;a jamais mis en danger son adversaire. Ce dernier s&rsquo;est r\u00e9veill\u00e9 sur la seconde partie du match, pour faire douter les observateurs quant \u00e0 l&rsquo;issue du combat. Finalement, la bataille est all\u00e9e jusqu&rsquo;au bout et <em>Canelo<\/em>, qui avait pris beaucoup d&rsquo;avance, s&rsquo;est adjug\u00e9 la victoire (116-112, 115-113, 115-113).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">After 36 rounds&#8230; The respect is there &#x1f91d;<a href=\"https:\/\/twitter.com\/hashtag\/CaneloGGG3?src=hash&amp;ref_src=twsrc%5Etfw\">#CaneloGGG3<\/a> <a href=\"https:\/\/t.co\/DVEZ12m9U9\">pic.twitter.com\/DVEZ12m9U9<\/a><\/p>\n<p>\u2014 Matchroom Boxing (@MatchroomBoxing) <a href=\"https:\/\/twitter.com\/MatchroomBoxing\/status\/1571356585053802497?ref_src=twsrc%5Etfw\">September 18, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Sur ce dernier combat, la diff\u00e9rence physique s&rsquo;est clairement fait ressentir entre les deux hommes. Beaucoup plus rapide et puissant, le Mexicain a pu rapidement marquer le combat de son empreinte. Apr\u00e8s cela, <em>GGG<\/em> a s\u00fbrement profit\u00e9 de la fatigue de son adversaire pour trouver davantage d&rsquo;ouverture, m\u00eame si cela fut loin d&rsquo;\u00eatre suffisant. Toutefois, les deux hommes sont rest\u00e9s fid\u00e8les \u00e0 leur r\u00e9putation de boxeurs solides. En effet, au cours des trois combats, aucun des deux hommes n&rsquo;a subi de voyage au tapis !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE &#8211; POIDS SUPER-MOYENS &#8211; La trilogie revient au Mexicain ! Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin. Au terme d&rsquo;un match ma\u00eetris\u00e9, Canelo conserve l&rsquo;int\u00e9gralit\u00e9 des ceintures chez les poids super-moyens, dont il est le roi incontest\u00e9 depuis un an.\u00a0<\/p>\n","protected":false},"author":45,"featured_media":263071,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[8672],"tags":[1696],"class_list":["post-263066","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe-anglaise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Boxe : Saul Canelo Alvarez s&#039;adjuge la trilogie face \u00e0 Golovkin !<\/title>\n<meta name=\"description\" content=\"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boxe : Saul Canelo Alvarez s&#039;adjuge la trilogie face \u00e0 Golovkin !\" \/>\n<meta property=\"og:description\" content=\"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T05:40:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-18T07:09:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Alexandre Jeffroy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Boxe : Saul Canelo Alvarez s&#039;adjuge la trilogie face \u00e0 Golovkin !\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/smokinalexjoe\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\"},\"author\":{\"name\":\"Alexandre Jeffroy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\"},\"headline\":\"Boxe : Saul Canelo Alvarez s&rsquo;adjuge la trilogie face \u00e0 Golovkin !\",\"datePublished\":\"2022-09-18T05:40:42+00:00\",\"dateModified\":\"2022-09-18T07:09:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\"},\"wordCount\":350,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png\",\"keywords\":[\"boxe anglaise\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\",\"name\":\"Boxe : Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png\",\"datePublished\":\"2022-09-18T05:40:42+00:00\",\"dateModified\":\"2022-09-18T07:09:28+00:00\",\"description\":\"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png\",\"width\":800,\"height\":445,\"caption\":\"Boxe Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boxe : Saul Canelo Alvarez s&rsquo;adjuge la trilogie face \u00e0 Golovkin !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0\",\"name\":\"Alexandre Jeffroy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg\",\"caption\":\"Alexandre Jeffroy\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.\",\"sameAs\":[\"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Boxe : Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !","description":"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/","og_locale":"fr_FR","og_type":"article","og_title":"Boxe : Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !","og_description":"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.","og_url":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","article_published_time":"2022-09-18T05:40:42+00:00","article_modified_time":"2022-09-18T07:09:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png","type":"image\/png"}],"author":"Alexandre Jeffroy","twitter_card":"summary_large_image","twitter_title":"Boxe : Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !","twitter_creator":"@https:\/\/twitter.com\/smokinalexjoe","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/"},"author":{"name":"Alexandre Jeffroy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0"},"headline":"Boxe : Saul Canelo Alvarez s&rsquo;adjuge la trilogie face \u00e0 Golovkin !","datePublished":"2022-09-18T05:40:42+00:00","dateModified":"2022-09-18T07:09:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/"},"wordCount":350,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png","keywords":["boxe anglaise"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/","url":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/","name":"Boxe : Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png","datePublished":"2022-09-18T05:40:42+00:00","dateModified":"2022-09-18T07:09:28+00:00","description":"BOXE - POIDS SUPER-MOYENS - Cette nuit, \u00e0 Las Vegas, Saul Alvarez est parvenu \u00e0 triompher de son grand rival Gennady Golovkin.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Boxe-Saul-Canelo-Alvarez-sadjuge-la-trilogie-face-a-Golovkin-.png","width":800,"height":445,"caption":"Boxe Saul Canelo Alvarez s'adjuge la trilogie face \u00e0 Golovkin !"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/boxe-saul-canelo-alvarez-sadjuge-la-trilogie-face-a-golovkin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Boxe : Saul Canelo Alvarez s&rsquo;adjuge la trilogie face \u00e0 Golovkin !"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0e50be5ee9a0e6705846ac950257c4a0","name":"Alexandre Jeffroy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Alexandre-Jeffroy-150x150.jpg","caption":"Alexandre Jeffroy"},"description":"Journaliste\/R\u00e9dacteur depuis octobre 2020 - Bolt qui foudroie le record du monde du 100 m\u00e8tres, les derniers essais de Dominici, les premi\u00e8res charges d\u00e9vastatrices de Bastarocket... de beaux souvenirs pour une grande passion, celle du sport. L\u2019histoire du sport aussi. Comprendre le r\u00f4le qu\u2019il a eu, celui qu\u2019il a et celui qu\u2019il aura dans notre soci\u00e9t\u00e9. Le sport au pass\u00e9, au pr\u00e9sent, au futur. Le sport tous les jours, matin, midi et soir. A d\u00e9faut d\u2019\u00eatre un grand sportif, je suis et je raconte l\u2019actualit\u00e9 et l\u2019histoire des championnes et des champions qui savent se d\u00e9passer pour accomplir des merveilles.","sameAs":["https:\/\/www.facebook.com\/alexandre.jeffroy.3\/","https:\/\/x.com\/https:\/\/twitter.com\/smokinalexjoe"],"url":"https:\/\/dicodusport.fr\/blog\/author\/alexandrejeffroy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/263066","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/45"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=263066"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/263066\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/263071"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=263066"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=263066"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=263066"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}