{"id":263256,"date":"2022-09-18T15:49:46","date_gmt":"2022-09-18T13:49:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=263256&#038;preview=true&#038;preview_id=263256"},"modified":"2022-09-18T16:11:54","modified_gmt":"2022-09-18T14:11:54","slug":"jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/","title":{"rendered":"[Vid\u00e9o] Jean-Clair Todibo prend l&rsquo;un des cartons rouges les plus rapides de l&rsquo;histoire"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>LIGUE 1 2022-2023 &#8211; Jean-Clair Todibo (OGC Nice) a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu face \u00e0 Angers ce dimanche, et a probablement pris un des cartons rouges les plus rapides de l&rsquo;histoire.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Le d\u00e9fenseur de <strong>Nice<\/strong> fait faute \u00e0 la septi\u00e8me seconde et l&rsquo;arbitre sort le rouge \u00e0 la neuvi\u00e8me seconde. Probablement le carton rouge le plus rapide de l&rsquo;histoire, mais c&rsquo;est dur d&rsquo;en avoir la certitude. Par exemple, en 2017, un Argentin avait fait un tacle assassin \u00e0 la neuvi\u00e8me seconde et l&rsquo;arbitre avait brandi le rouge \u00e0 la dix-septi\u00e8me seconde. Ce qui est s\u00fbr, c&rsquo;est que <strong>Jean-Clair Todibo<\/strong> a re\u00e7u le carton rouge le plus rapide de l&rsquo;histoire de la <strong>Ligue 1<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Jean-Clair Todibo devient le joueur recevant un carton rouge le plus rapidement dans un match de Ligue 1 apr\u00e8s seulement 9 secondes.<\/p>\n<p>oui, oui 9 secondes de jeu ! <a href=\"https:\/\/t.co\/5sFJdk0ksF\">pic.twitter.com\/5sFJdk0ksF<\/a><\/p>\n<p>\u2014 FOOTBALL-TIME&#x2b50; (@Footballtime___) <a href=\"https:\/\/twitter.com\/Footballtime___\/status\/1571488047249735680?ref_src=twsrc%5Etfw\">September 18, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE 1 2022-2023 &#8211; Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l&rsquo;histoire.<\/p>\n","protected":false},"author":1,"featured_media":263263,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301,47045],"tags":[75,460],"class_list":["post-263256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","category-ligue-1","tag-football","tag-nice"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>[Vid\u00e9o] Jean-Clair Todibo prend l&#039;un des cartons rouges les plus rapides de l&#039;histoire<\/title>\n<meta name=\"description\" content=\"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l&#039;histoire.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[Vid\u00e9o] Jean-Clair Todibo prend l&#039;un des cartons rouges les plus rapides de l&#039;histoire\" \/>\n<meta property=\"og:description\" content=\"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l&#039;histoire.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-18T13:49:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-18T14:11:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"[Vid\u00e9o] Jean-Clair Todibo prend l&#039;un des cartons rouges les plus rapides de l&#039;histoire\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"[Vid\u00e9o] Jean-Clair Todibo prend l&rsquo;un des cartons rouges les plus rapides de l&rsquo;histoire\",\"datePublished\":\"2022-09-18T13:49:46+00:00\",\"dateModified\":\"2022-09-18T14:11:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/\"},\"wordCount\":176,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png\",\"keywords\":[\"Football\",\"Nice\"],\"articleSection\":[\"Football\",\"Ligue 1\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/\",\"name\":\"[Vid\u00e9o] Jean-Clair Todibo prend l'un des cartons rouges les plus rapides de l'histoire\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png\",\"datePublished\":\"2022-09-18T13:49:46+00:00\",\"dateModified\":\"2022-09-18T14:11:54+00:00\",\"description\":\"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l'histoire.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"[Vid\u00e9o] Jean-Clair Todibo prend l&rsquo;un des cartons rouges les plus rapides de l&rsquo;histoire\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"[Vid\u00e9o] Jean-Clair Todibo prend l'un des cartons rouges les plus rapides de l'histoire","description":"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l'histoire.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/","og_locale":"fr_FR","og_type":"article","og_title":"[Vid\u00e9o] Jean-Clair Todibo prend l'un des cartons rouges les plus rapides de l'histoire","og_description":"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l'histoire.","og_url":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-09-18T13:49:46+00:00","article_modified_time":"2022-09-18T14:11:54+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"[Vid\u00e9o] Jean-Clair Todibo prend l'un des cartons rouges les plus rapides de l'histoire","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"[Vid\u00e9o] Jean-Clair Todibo prend l&rsquo;un des cartons rouges les plus rapides de l&rsquo;histoire","datePublished":"2022-09-18T13:49:46+00:00","dateModified":"2022-09-18T14:11:54+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/"},"wordCount":176,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png","keywords":["Football","Nice"],"articleSection":["Football","Ligue 1"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/","url":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/","name":"[Vid\u00e9o] Jean-Clair Todibo prend l'un des cartons rouges les plus rapides de l'histoire","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png","datePublished":"2022-09-18T13:49:46+00:00","dateModified":"2022-09-18T14:11:54+00:00","description":"LIGUE 1 2022-2023 - Jean-Clair Todibo a \u00e9t\u00e9 expuls\u00e9 apr\u00e8s seulement 9 secondes de jeu et a probablement pris un des cartons rouges les plus rapides de l'histoire.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Jean-Clair-Todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/jean-clair-todibo-prend-lun-des-cartons-rouges-les-plus-rapides-de-lhistoire\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"[Vid\u00e9o] Jean-Clair Todibo prend l&rsquo;un des cartons rouges les plus rapides de l&rsquo;histoire"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/263256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=263256"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/263256\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/263263"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=263256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=263256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=263256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}