{"id":265558,"date":"2022-09-28T13:45:25","date_gmt":"2022-09-28T11:45:25","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=265558&#038;preview=true&#038;preview_id=265558"},"modified":"2022-09-28T15:59:36","modified_gmt":"2022-09-28T13:59:36","slug":"stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/","title":{"rendered":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>TOP 14 2022-2023 &#8211; Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Comme <strong>Julien Marchand<\/strong> et <strong>Matthis Lebel<\/strong> face \u00e0 <strong>la Section Paloise<\/strong>, <strong>Ugo Mola<\/strong> devrait mettre au repos trois autres internationaux pour le d\u00e9placement \u00e0 <strong>Montpellier<\/strong> : <strong>Antoine Dupont<\/strong>, <strong>Peato Mauvaka<\/strong> et <strong>Anthony Jelonch<\/strong>. Les trois internationaux n&rsquo;\u00e9taient pas pr\u00e9sents lors de la reprise de l&rsquo;entra\u00eenement du Stade Toulousain ce mercredi et devraient donc \u00eatre au repos face au <strong>MHR<\/strong>.<\/p>\n<p style=\"text-align: justify;\"><strong>Toulouse<\/strong> sait que ses internationaux vont encore \u00eatre tr\u00e8s sollicit\u00e9s cette saison avec la Coupe du monde dans un an en point de mire, et veut donc prendre le moins de risques possibles pour leur sant\u00e9. <strong>Ugo Mola<\/strong> pourra compter sur les retours \u00e0 la comp\u00e9tition de <strong>Yannick Youyoutte<\/strong> et<strong> Lucas Tauzin <\/strong>pour le choc face au<strong> champion de France 2022.\u00a0<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Toulouse : Dupont, Mauvaka et Jelonch au repos <a href=\"https:\/\/t.co\/DNjMuQFkq9\">https:\/\/t.co\/DNjMuQFkq9<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Rugby?src=hash&amp;ref_src=twsrc%5Etfw\">#Rugby<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Top14?src=hash&amp;ref_src=twsrc%5Etfw\">#Top14<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/StadeToulousain?src=hash&amp;ref_src=twsrc%5Etfw\">#StadeToulousain<\/a> <a href=\"https:\/\/twitter.com\/RugbyramaFR?ref_src=twsrc%5Etfw\">@RugbyramaFR<\/a> <a href=\"https:\/\/t.co\/mB1ggfuvHO\">pic.twitter.com\/mB1ggfuvHO<\/a><\/p>\n<p>\u2014 Rugby&rsquo;O&rsquo;Top (@rugbyotop) <a href=\"https:\/\/twitter.com\/rugbyotop\/status\/1575084045905842176?ref_src=twsrc%5Etfw\">September 28, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":265559,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[2373,4008,463],"class_list":["post-265558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-antoine-dupont","tag-stade-toulousain","tag-toulouse"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-09-28T11:45:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-09-28T13:59:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier\",\"datePublished\":\"2022-09-28T11:45:25+00:00\",\"dateModified\":\"2022-09-28T13:59:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/\"},\"wordCount\":178,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png\",\"keywords\":[\"Antoine Dupont\",\"Stade Toulousain\",\"Toulouse\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/\",\"name\":\"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png\",\"datePublished\":\"2022-09-28T11:45:25+00:00\",\"dateModified\":\"2022-09-28T13:59:36+00:00\",\"description\":\"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier","description":"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/","og_locale":"fr_FR","og_type":"article","og_title":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier","og_description":"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-09-28T11:45:25+00:00","article_modified_time":"2022-09-28T13:59:36+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier","datePublished":"2022-09-28T11:45:25+00:00","dateModified":"2022-09-28T13:59:36+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/"},"wordCount":178,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png","keywords":["Antoine Dupont","Stade Toulousain","Toulouse"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/","url":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/","name":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png","datePublished":"2022-09-28T11:45:25+00:00","dateModified":"2022-09-28T13:59:36+00:00","description":"TOP 14 2022-2023 - Selon nos confr\u00e8res de Rugbyrama, trois internationaux du Stade Toulousain devraient \u00eatre au repos face \u00e0 Montpellier.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/09\/Stade-Toulousain-Trois-internationaux-devraient-e\u0302tre-au-repos-face-a\u0300-Montpellier.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/stade-toulousain-trois-internationaux-devraient-etre-au-repos-face-a-montpellier\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Stade Toulousain : Trois internationaux devraient \u00eatre au repos face \u00e0 Montpellier"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/265558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=265558"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/265558\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/265559"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=265558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=265558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=265558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}