{"id":267690,"date":"2022-10-06T17:04:47","date_gmt":"2022-10-06T15:04:47","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=267690&#038;preview=true&#038;preview_id=267690"},"modified":"2022-10-06T17:21:13","modified_gmt":"2022-10-06T15:21:13","slug":"paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/","title":{"rendered":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/cyclisme\/cyclisme-sur-route-2022\/\">CYCLISME SUR ROUTE 2022<\/a> &#8211; Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges. Il a devanc\u00e9 au sprint les Fran\u00e7ais Arnaud D\u00e9mare (Groupama-FDJ) et Bryan Coquard (Cofidis).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Neuvi\u00e8me victoire de la saison pour <strong>Jasper Philipsen<\/strong> (Alpecin-Deceuninck). Le Belge a remport\u00e9 ce jeudi Paris-Bourges, au terme des 198 km de course. Comme de coutume, la victoire s&rsquo;est jou\u00e9e au sprint dans les rues de la cit\u00e9 berruy\u00e8re. Lanc\u00e9 \u00e0 plus de 200 m\u00e8tres par son train,<strong> Arnaud D\u00e9mare<\/strong> (Groupama-FDJ) a sans doute produit son effort de trop loin pour esp\u00e9rer s&rsquo;imposer. Le Picard a en effet \u00e9t\u00e9 d\u00e9bord\u00e9 dans les 50 derniers m\u00e8tres par un <strong>Jasper Philipsen<\/strong> surpuissant. <strong>D\u00e9mare<\/strong> prend la deuxi\u00e8me place, et ce pour la 8\u00e8me fois de la saison. <strong>Bryan Coquard<\/strong> compl\u00e8te quant \u00e0 lui le podium. Cit\u00e9 parmi les grands favoris du jour, <strong>Arnaud De Lie<\/strong> (Lotto-Soudal) n&rsquo;a pas r\u00e9ussi \u00e0 prendre la bonne roue, et doit se contenter de la 6\u00e8me place.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f3c6; Victoire de <a href=\"https:\/\/twitter.com\/JasperPhilipsen?ref_src=twsrc%5Etfw\">@JasperPhilipsen<\/a> !<a href=\"https:\/\/twitter.com\/hashtag\/ParisBourges?src=hash&amp;ref_src=twsrc%5Etfw\">#ParisBourges<\/a> <a href=\"https:\/\/t.co\/gRZc1cC0HL\">pic.twitter.com\/gRZc1cC0HL<\/a><\/p>\n<p>\u2014 Paris-Gien-Bourges (@parisbourges) <a href=\"https:\/\/twitter.com\/parisbourges\/status\/1578037061075943424?ref_src=twsrc%5Etfw\">October 6, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/classement-paris-bourges-2022\/\">Le classement de Paris-Bourges 2022<\/a>\u00a0<\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE 2022 &#8211; Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges. Il a devanc\u00e9 au sprint les Fran\u00e7ais Arnaud D\u00e9mare (Groupama-FDJ) et Bryan Coquard (Cofidis).<\/p>\n","protected":false},"author":4,"featured_media":267703,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[19736,24],"class_list":["post-267690","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-paris-bourges","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T15:04:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T15:21:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\",\"datePublished\":\"2022-10-06T15:04:47+00:00\",\"dateModified\":\"2022-10-06T15:21:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\"},\"wordCount\":204,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png\",\"keywords\":[\"Paris-Bourges\",\"sport\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\",\"name\":\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png\",\"datePublished\":\"2022-10-06T15:04:47+00:00\",\"dateModified\":\"2022-10-06T15:21:13+00:00\",\"description\":\"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png\",\"width\":800,\"height\":445,\"caption\":\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard","description":"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/","og_locale":"fr_FR","og_type":"article","og_title":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard","og_description":"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.","og_url":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2022-10-06T15:04:47+00:00","article_modified_time":"2022-10-06T15:21:13+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard","datePublished":"2022-10-06T15:04:47+00:00","dateModified":"2022-10-06T15:21:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/"},"wordCount":204,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png","keywords":["Paris-Bourges","sport"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/","url":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/","name":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png","datePublished":"2022-10-06T15:04:47+00:00","dateModified":"2022-10-06T15:21:13+00:00","description":"CYCLISME SUR ROUTE 2022 - Le Belge Jasper Philipsen (Alpecin-Deceuninck) a remport\u00e9 ce jeudi la 72\u00e8me \u00e9dition de Paris-Bourges.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Paris-Bourges-2022-Jasper-Philipsen-devance-Arnaud-Demare-et-Bryan-Coquard.png","width":800,"height":445,"caption":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/paris-bourges-2022-jasper-philipsen-devance-arnaud-demare-et-bryan-coquard\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Paris-Bourges 2022 : Jasper Philipsen devance Arnaud D\u00e9mare et Bryan Coquard"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/267690","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=267690"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/267690\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/267703"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=267690"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=267690"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=267690"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}