{"id":267788,"date":"2022-10-06T22:57:14","date_gmt":"2022-10-06T20:57:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=267788&#038;preview=true&#038;preview_id=267788"},"modified":"2022-10-06T23:31:41","modified_gmt":"2022-10-06T21:31:41","slug":"ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/","title":{"rendered":"Ligue Europa (J3) : Rennes s&rsquo;impose au finish contre le Dynamo Kiev"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>LIGUE EUROPA 2022\/2023 &#8211; Belle r\u00e9compense pour les Rennais. Apr\u00e8s l\u2019ouverture du score de Martin Terrier en premi\u00e8re p\u00e9riode, le Dynamo Kiev est rapidement revenu au score. Sans rien l\u00e2cher, les Bretons sont all\u00e9s chercher la victoire dans la derni\u00e8re minute du temps r\u00e9glementaire gr\u00e2ce \u00e0 une r\u00e9alisation de D\u00e9sir\u00e9 Dou\u00e9 (2-1).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Pour la troisi\u00e8me journ\u00e9e de Ligue Europa, Rennes recevait le Dynamo Kiev. Le Roazhon Park avait retrouv\u00e9 l\u2019int\u00e9gralit\u00e9 de ses supporters et les Rennais tr\u00f4naient alors en t\u00eate du groupe, \u00e0 \u00e9galit\u00e9 de points avec le Fenerbah\u00e7e. Sur une s\u00e9rie de sept rencontres sans d\u00e9faite, les Rouge et Noir pouvaient creuser un peu plus l\u2019\u00e9cart sur l\u2019AEK Larcana et le club ukrainien en vue des huiti\u00e8mes de finale.<\/p>\n<h2 style=\"text-align: justify;\">Rennes \u00e0 l\u2019attaque<\/h2>\n<p style=\"text-align: justify;\">Les Rennais auraient pu mener facilement 2-0 \u00e0 la pause. Port\u00e9s par <strong>Benjamin Bourigeaud<\/strong>, ils ont monopolis\u00e9 le ballon et le camp adverse lors des 25 premi\u00e8res minutes. A la 8<sup>\u00e8me<\/sup> minute, aid\u00e9 par le pressing breton, le capitaine r\u00e9cup\u00e9rait le cuir d\u2019une mauvaise relance de <strong>Denys Boyko<\/strong> mais la frappe de <strong>Lovro Majer<\/strong> passait \u00e0 c\u00f4t\u00e9. Quelques instants plus tard, <strong>Bourigeaud<\/strong> lui-m\u00eame pla\u00e7ait un tir puissant, cette fois-ci pouss\u00e9 en corner par le gardien adverse. Au quart d\u2019heure de jeu, c\u2019est\u00a0<strong>Martin Terrier<\/strong> qui tentait sa chance apr\u00e8s une superbe talonnade de <strong>Flavien Tait<\/strong> mais le cadre fuyait l\u2019attaquant rennais. Ce dernier a finalement trouv\u00e9 la mire \u00e0 la 23<sup>\u00e8me<\/sup> minute suite \u00e0 une passe dans le dos dans la d\u00e9fense d\u2019<strong>Amine Gouiri<\/strong>.<\/p>\n<p style=\"text-align: justify;\">Le Stade Rennais menait alors logiquement 1-0, les visiteurs ayant beaucoup de mal \u00e0 s\u2019approcher de la surface de r\u00e9paration rennaise. Il n\u2019a cependant pas fallu beaucoup d\u2019occasions au Dynamo Kiev pour \u00e9galiser. Une premi\u00e8re fois mis en \u00e9chec par <strong>Steve Mandanda<\/strong>, <strong>Viktor Tsygankov<\/strong> suivait sa frappe et trompait l\u2019ancien gardien marseillais (33\u2019). Cette \u00e9galisation relan\u00e7ait l\u2019attaque rennaise pour les derniers instants de la premi\u00e8re p\u00e9riode, en vain. Un partout balle au centre au moment de retourner aux vestiaires, tout \u00e9tait \u00e0 refaire.<\/p>\n<h2 style=\"text-align: justify;\">Une victoire m\u00e9rit\u00e9e<\/h2>\n<p style=\"text-align: justify;\">Toujours tr\u00e8s haut, Rennes a de nouveau multipli\u00e9 les occasions dans le deuxi\u00e8me acte. Au four et au moulin, <strong>Bourigeaud<\/strong> r\u00e9cup\u00e9rait une nouvelle fois la gonfle pr\u00e8s des cages adverses mais son centre passait devant ses co\u00e9quipiers et la d\u00e9fense ukrainienne sans \u00eatre touch\u00e9. <strong>Amine Gouiri<\/strong>, <strong>Flavien Tait<\/strong> ou encore <strong>Lorenz Assignon<\/strong> tentaient \u00e9galement leur chance mais la tour de contr\u00f4le <strong>Boyko<\/strong> tenait bon.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s 19 tentatives, la 20<sup>\u00e8me<\/sup> a \u00e9t\u00e9 la bonne pour les Rouge et Noir. A la 89<sup>\u00e8me<\/sup>, <strong>Dou\u00e9<\/strong>, entr\u00e9 en jeu vingt minutes plus t\u00f4t, r\u00e9cup\u00e9rait un ballon mal d\u00e9gag\u00e9 par la d\u00e9fense et offrait la victoire \u00e0 Rennes (2-1). Une victoire m\u00e9rit\u00e9e car si vous n\u2019avez pas entendu parler du Dynamo Kiev, c\u2019est que <strong>Steve Mandanda<\/strong> a pass\u00e9 une soir\u00e9e vraiment tr\u00e8s calme mis \u00e0 part ce but encaiss\u00e9 en premi\u00e8re mi-temps.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&lsquo; \u0301 !<\/p>\n<p>Gr\u00e2ce \u00e0 un but de \u0301\u0301 \u0301 dans les ultimes instants, les Rouge et Noir arrachent la victoire contre le <a href=\"https:\/\/twitter.com\/DynamoKyiv?ref_src=twsrc%5Etfw\">@DynamoKyiv<\/a>. <a href=\"https:\/\/twitter.com\/hashtag\/SRFCFCDK?src=hash&amp;ref_src=twsrc%5Etfw\">#SRFCFCDK<\/a> 2-1 <a href=\"https:\/\/t.co\/W96rsEjiLy\">pic.twitter.com\/W96rsEjiLy<\/a><\/p>\n<p>\u2014 Stade Rennais F.C. (@staderennais) <a href=\"https:\/\/twitter.com\/staderennais\/status\/1578126366624870400?ref_src=twsrc%5Etfw\">October 6, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Pendant ce temps, Fenerbah\u00e7e a remport\u00e9 son match contre l\u2019AEK Lacarna et prend provisoirement la t\u00eate du groupe devant Rennes, \u00e0 \u00e9galit\u00e9 de points mais avec un petit but de plus.<\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>LIGUE EUROPA 2022\/2023 &#8211; Belle r\u00e9compense pour les Rennais. Apr\u00e8s l\u2019ouverture du score de Martin Terrier en premi\u00e8re p\u00e9riode, le Dynamo Kiev est rapidement revenu au score. Sans rien l\u00e2cher, les Bretons sont all\u00e9s chercher la victoire dans la derni\u00e8re minute du temps r\u00e9glementaire gr\u00e2ce \u00e0 une r\u00e9alisation de D\u00e9sir\u00e9 Dou\u00e9 (2-1).<\/p>\n","protected":false},"author":18,"featured_media":267829,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2301],"tags":[12382,75,4437,1840,24],"class_list":["post-267788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-dynamo-kiev","tag-football","tag-ligue-europa","tag-rennes","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ligue Europa (J3) : Rennes s&#039;impose au finish contre le Dynamo Kiev<\/title>\n<meta name=\"description\" content=\"LIGUE EUROPA 2022\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue Europa (J3) : Rennes s&#039;impose au finish contre le Dynamo Kiev\" \/>\n<meta property=\"og:description\" content=\"LIGUE EUROPA 2022\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/soocube\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-06T20:57:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-06T21:31:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Sophie Clapier\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue Europa (J3) : Rennes s&#039;impose au finish contre le Dynamo Kiev\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/soocube\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/\"},\"author\":{\"name\":\"Sophie Clapier\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\"},\"headline\":\"Ligue Europa (J3) : Rennes s&rsquo;impose au finish contre le Dynamo Kiev\",\"datePublished\":\"2022-10-06T20:57:14+00:00\",\"dateModified\":\"2022-10-06T21:31:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/\"},\"wordCount\":604,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png\",\"keywords\":[\"Dynamo Kiev\",\"Football\",\"Ligue Europa\",\"Rennes\",\"sport\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/\",\"name\":\"Ligue Europa (J3) : Rennes s'impose au finish contre le Dynamo Kiev\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png\",\"datePublished\":\"2022-10-06T20:57:14+00:00\",\"dateModified\":\"2022-10-06T21:31:41+00:00\",\"description\":\"LIGUE EUROPA 2022\\\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/10\\\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue Europa (J3) Rennes s\u2019impose au finish contre le Dynamo Kiev\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue Europa (J3) : Rennes s&rsquo;impose au finish contre le Dynamo Kiev\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/416c975648aca9da8839bdfe333a21c9\",\"name\":\"Sophie Clapier\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Sophie-Clapier-150x150.jpg\",\"caption\":\"Sophie Clapier\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\\\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/soocube\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/soocube\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sophie\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue Europa (J3) : Rennes s'impose au finish contre le Dynamo Kiev","description":"LIGUE EUROPA 2022\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue Europa (J3) : Rennes s'impose au finish contre le Dynamo Kiev","og_description":"LIGUE EUROPA 2022\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/soocube","article_published_time":"2022-10-06T20:57:14+00:00","article_modified_time":"2022-10-06T21:31:41+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png","type":"image\/png"}],"author":"Sophie Clapier","twitter_card":"summary_large_image","twitter_title":"Ligue Europa (J3) : Rennes s'impose au finish contre le Dynamo Kiev","twitter_creator":"@https:\/\/twitter.com\/soocube","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/"},"author":{"name":"Sophie Clapier","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9"},"headline":"Ligue Europa (J3) : Rennes s&rsquo;impose au finish contre le Dynamo Kiev","datePublished":"2022-10-06T20:57:14+00:00","dateModified":"2022-10-06T21:31:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/"},"wordCount":604,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png","keywords":["Dynamo Kiev","Football","Ligue Europa","Rennes","sport"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/","name":"Ligue Europa (J3) : Rennes s'impose au finish contre le Dynamo Kiev","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png","datePublished":"2022-10-06T20:57:14+00:00","dateModified":"2022-10-06T21:31:41+00:00","description":"LIGUE EUROPA 2022\/2023 - Rennes a arrach\u00e9 un succ\u00e8s pr\u00e9cieux face au Dynamo Kiev ce jeudi soir (2-1). Une victoire \u00f4 combien importante !","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Ligue-Europa-J3-Rennes-simpose-au-finish-contre-le-Dynamo-Kiev.png","width":800,"height":445,"caption":"Ligue Europa (J3) Rennes s\u2019impose au finish contre le Dynamo Kiev"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-europa-rennes-s-impose-au-finish-contre-le-dynamo-kiev\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue Europa (J3) : Rennes s&rsquo;impose au finish contre le Dynamo Kiev"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/416c975648aca9da8839bdfe333a21c9","name":"Sophie Clapier","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Sophie-Clapier-150x150.jpg","caption":"Sophie Clapier"},"description":"Journaliste\/r\u00e9dactrice depuis janvier 2016 - Passionn\u00e9e de sport depuis toujours, j\u2019en ai pratiqu\u00e9 quelques-uns. Judo, football, handball ou encore tennis, je n\u2019ai jamais pu me mettre d\u2019accord sur un en particulier. Mais \u00e7a, c\u2019\u00e9tait avant de d\u00e9couvrir le basket, devenu mon sport de pr\u00e9dilection. Les actions NBA, le All-Star Week-end, la fureur des Game 7 pendant les playoffs ou mieux, lors des Finals, this is why we play. Team Spurs T.P, je m\u2019accroche encore \u00e0 Gregg Popovich (don\u2019t leave !). Team chef Curry, je souhaite qu\u2019il finisse aux Warriors (staaaay !). Non, il n\u2019y a pas qu\u2019eux, des petits nouveaux -et des petites nouvelles \u00e9videmment- arrivent chaque jour dans toutes les disciplines et cr\u00e9ent de nouveaux exploits. Alors pour les grands \u00e9v\u00e9nements et comp\u00e9titions internationales, vive les pulsations 240\/minutes et le d\u00e9fibrillateur pas loin, et allez les Bleu(e)s ! C\u2019est s\u00fbr, j\u2019aurai plus vu ma vie sur un terrain de sport, mais \u00e0 d\u00e9faut d\u2019en faire en haut niveau, je le partage avec vous.","sameAs":["https:\/\/www.facebook.com\/soocube","https:\/\/x.com\/https:\/\/twitter.com\/soocube","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/sophie\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/267788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=267788"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/267788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/267829"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=267788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=267788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=267788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}