{"id":270868,"date":"2022-10-17T11:56:11","date_gmt":"2022-10-17T09:56:11","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=270868&#038;preview=true&#038;preview_id=270868"},"modified":"2022-10-17T12:07:28","modified_gmt":"2022-10-17T10:07:28","slug":"plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/","title":{"rendered":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>PLONGEON DE HAUT VOL &#8211; Coupe du monde de la sp\u00e9cialit\u00e9, les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt, le deuxi\u00e8me sous les couleurs de la France.<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">Les ann\u00e9es passent, et <strong>Gary Hunt<\/strong> reste le ma\u00eetre incontest\u00e9 du plongeon de haut vol. Si en bassin, il n&rsquo;a pas r\u00e9ussi \u00e0 d\u00e9crocher une m\u00e9daille lors des derniers Championnats d&rsquo;Europe, il est incontestablement \u00e0 l&rsquo;aise en ext\u00e9rieur. Ce week-end, il s&rsquo;est adjug\u00e9 pour la dixi\u00e8me fois les <em>Red Bull Cliff Diving World Series<\/em>, comp\u00e9tition spectaculaire qui est la Coupe du monde de sp\u00e9cialit\u00e9.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Plongeon Extr\u00eame : Gary Hunt plonge \u00e0 27 m\u00e8tres vers son 10\u00e8me titre Mondial, samedi 15 octobre \u00e0 Sidney en Australie. Anglais d&rsquo;origine devenu fran\u00e7ais en 2020. <a href=\"https:\/\/twitter.com\/hashtag\/garyhunt?src=hash&amp;ref_src=twsrc%5Etfw\">#garyhunt<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/plongeon?src=hash&amp;ref_src=twsrc%5Etfw\">#plongeon<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/natation?src=hash&amp;ref_src=twsrc%5Etfw\">#natation<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/extreme?src=hash&amp;ref_src=twsrc%5Etfw\">#extreme<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/championdumonde?src=hash&amp;ref_src=twsrc%5Etfw\">#championdumonde<\/a> <a href=\"https:\/\/t.co\/tFlQOx18I1\">https:\/\/t.co\/tFlQOx18I1<\/a> <a href=\"https:\/\/t.co\/IN3b8htf0Y\">pic.twitter.com\/IN3b8htf0Y<\/a><\/p>\n<p>\u2014 Championdumonde (@championmondefr) <a href=\"https:\/\/twitter.com\/championmondefr\/status\/1581700319804739584?ref_src=twsrc%5Etfw\">October 16, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Mais c&rsquo;est surtout son deuxi\u00e8me sacre (apr\u00e8s 2021) sous les couleurs de la France, lui qui a \u00e9t\u00e9 naturalis\u00e9 en 2020. Il a empoch\u00e9 le morceau en remportant la derni\u00e8re manche ce week-end \u00e0 Sydney (Australie). R\u00e9sultat, le voil\u00e0 \u00e0 nouveau sacr\u00e9 dans cette comp\u00e9tition devant <strong>Aidan Heslop<\/strong><span class=\"inline-paragraph__text\"> et <\/span><strong>Catalin Preda<\/strong>. \u00c0 38 ans, <strong>Gary Hunt<\/strong> est toujours au sommet de son art, et sa domination n&rsquo;est pas pr\u00eate de s&rsquo;arr\u00eater.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PLONGEON DE HAUT VOL &#8211; Coupe du monde de la sp\u00e9cialit\u00e9, les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt, le deuxi\u00e8me sous les couleurs de la France.<\/p>\n","protected":false},"author":59,"featured_media":270878,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2306],"tags":[],"class_list":["post-270868","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-natation"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois<\/title>\n<meta name=\"description\" content=\"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\" \/>\n<meta property=\"og:description\" content=\"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-17T09:56:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-17T10:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\",\"datePublished\":\"2022-10-17T09:56:11+00:00\",\"dateModified\":\"2022-10-17T10:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\"},\"wordCount\":253,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png\",\"articleSection\":[\"Natation\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\",\"name\":\"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png\",\"datePublished\":\"2022-10-17T09:56:11+00:00\",\"dateModified\":\"2022-10-17T10:07:28+00:00\",\"description\":\"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png\",\"width\":800,\"height\":445,\"caption\":\"Plongeon Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois","description":"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/","og_locale":"fr_FR","og_type":"article","og_title":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois","og_description":"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.","og_url":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2022-10-17T09:56:11+00:00","article_modified_time":"2022-10-17T10:07:28+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois","datePublished":"2022-10-17T09:56:11+00:00","dateModified":"2022-10-17T10:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/"},"wordCount":253,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png","articleSection":["Natation"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/","url":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/","name":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png","datePublished":"2022-10-17T09:56:11+00:00","dateModified":"2022-10-17T10:07:28+00:00","description":"PLONGEON DE HAUT VOL - Les Red Bull Cliff Diving World Series se sont achev\u00e9es ce week-end par le dixi\u00e8me sacre de Gary Hunt.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/10\/Plongeon-Gary-Hunt-remporte-les-Red-Bull-Cliff-Diving-World-Series-pour-la-dixieme-fois.png","width":800,"height":445,"caption":"Plongeon Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/plongeon-gary-hunt-remporte-les-red-bull-cliff-diving-world-series-pour-la-dixieme-fois\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Plongeon : Gary Hunt remporte les Red Bull Cliff Diving World Series pour la dixi\u00e8me fois"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/270868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=270868"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/270868\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/270878"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=270868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=270868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=270868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}