{"id":277962,"date":"2022-11-11T23:11:05","date_gmt":"2022-11-11T22:11:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=277962&#038;preview=true&#038;preview_id=277962"},"modified":"2022-11-11T23:17:13","modified_gmt":"2022-11-11T22:17:13","slug":"euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/","title":{"rendered":"EuroLigue (J7) : Un pi\u00e8tre Monaco s&rsquo;incline logiquement d&rsquo;un souffle \u00e0 Valence"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/?s=euroligue\">EUROLIGUE 2022-2023<\/a> &#8211; Comme les femmes plus t\u00f4t dans la semaine, les \u00e9quipes fran\u00e7aises masculines ont accumul\u00e9 les d\u00e9faites. En d\u00e9placement \u00e0 Valence, l&rsquo;AS Monaco a logiquement \u00e9t\u00e9 battue apr\u00e8s avoir livr\u00e9 une prestation insipide, contrastant avec la coh\u00e9rence collective des Espagnols sublim\u00e9e par l&rsquo;ancien Lyonnais Chris Jones. Au bout d&rsquo;un money-time totalement d\u00e9li\u00e9, la Roca Team a c\u00e9d\u00e9 89-84.\u00a0<\/em><\/strong><\/p>\n<p align=\"justify\">Au lendemain de la d\u00e9faite de l\u2019ASVEL, l\u2019<b>AS Monaco <\/b>effectuait un d\u00e9placement du c\u00f4t\u00e9 de Valence avec l\u2019objectif de poursuivre son d\u00e9but de saison quasi parfait (6V-1D). Face \u00e0 un collectif bien r\u00f4d\u00e9 qui reste sur deux victoires de rang malgr\u00e9 l\u2019absence de l\u2019excellent <b>Jasiel Rivero<\/b>, la Roca Team souhaitait conserver sa dynamique.<\/p>\n<h2 align=\"justify\">Monaco tient le coup miraculeusement malgr\u00e9 la folie Chris Jones<\/h2>\n<p align=\"justify\">Toutefois, le d\u00e9but de match est compliqu\u00e9, la faute \u00e0 l\u2019ancien lyonnais <b>Chris Jones.<\/b> Sur un nuage, il claque 13 points dans les cinq premi\u00e8res minutes en profitant d\u2019une d\u00e9fense hors de position. Face \u00e0 l\u2019incandescence du meneur am\u00e9ricain, l\u2019ASM limite l\u2019\u00e9clat gr\u00e2ce \u00e0 l\u2019adresse de <b>Jordan Loyd <\/b><b>(24 points<\/b>), sans trouver sa coh\u00e9rence habituelle (17-12). Cela contraste avec un collectif valencian bien en place qui d\u00e9roule son basket avec fluidit\u00e9. Mais la sortie de Jones enraye la dynamique d\u2019une \u00e9quipe encha\u00eenant alors les pertes de balle (8 dans le QT1!). Les Mon\u00e9gasques en profitent imm\u00e9diatement avec des paniers faciles en contre-attaque (20-20).<\/p>\n<p align=\"justify\">Malgr\u00e9 tout, le collectif espagnol ne sombre pas, et son jeu de passe bien r\u00f4d\u00e9 offre des shoots ouverts derri\u00e8re l\u2019arc pour des tireurs adroits comme <b>Victor Claver<\/b> ou <b>Xabier Lopez-Arestegui<\/b>. L\u2019ASM maintient l\u2019\u00e9cart en prenant progressivement le contr\u00f4le du rebond, mais sans cr\u00e9er de r\u00e9elle dynamique. <b>Chris Jones<\/b> continue lui \u00e0 enfiler les paniers comme les perles tout en d\u00e9livrant les caviars. En toute logique, Valence cr\u00e9e un \u00e9cart cons\u00e9quent suite \u00e0 deux filoches ext\u00e9rieures (29-39).<\/p>\n<p align=\"justify\">Gr\u00e2ce au talent individuel de <strong>Jordan Loyd<\/strong> et <b>Mike James<\/b>, les hommes de <b>Sasa Obradovic<\/b> terminent fort la premi\u00e8re p\u00e9riode. En l\u2019espace de trois minutes, ils claquent un terrible 11-2 leur permettant de revenir quasiment \u00e0 \u00e9galit\u00e9 (39-40). Un miracle absolu au vu de la pauvret\u00e9 du jeu propos\u00e9 par la <em>Roca Team<\/em>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">This is beautiful basketball&#8230;<a href=\"https:\/\/twitter.com\/valenciabasket?ref_src=twsrc%5Etfw\">@valenciabasket<\/a> <a href=\"https:\/\/t.co\/lc7NwzFnjZ\">pic.twitter.com\/lc7NwzFnjZ<\/a><\/p>\n<p>\u2014 Turkish Airlines EuroLeague (@EuroLeague) <a href=\"https:\/\/twitter.com\/EuroLeague\/status\/1591170737620254722?ref_src=twsrc%5Etfw\">November 11, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 align=\"justify\">James Webb assassine une Roca Team inconsistante<\/h2>\n<p align=\"justify\">Au retour des vestiaires, les intentions mon\u00e9gasques dans le jeu sont diff\u00e9rentes. Tout le monde est impliqu\u00e9, la gonfle tourne mieux, et cela se ressent. Fantomatique en d\u00e9but de match, <b>Donatas Motiejunas<\/b> est relanc\u00e9 avec succ\u00e8s, et offre un combat de titans avec son vis-\u00e0-vis mont\u00e9n\u00e9grin <b>Bojan Dubljevic<\/b>. Malgr\u00e9 ce l\u00e9ger mieux, la Roca Team est en gal\u00e8re pour scorer face \u00e0 une d\u00e9fense dure n\u2019offrant aucun panier facile. Seuls les lancers francs leur font tenir la cadence d\u2019Espagnols infernaux sur jeu rapide et qui verrouillent le rebond. A force de se faire pilonner, la d\u00e9fense mon\u00e9gasque plie, et se retrouve de nouveau \u00e0 dix points \u00e0 l\u2019aube du dernier quart (54-64).<\/p>\n<p align=\"justify\">Puis treize sur un shoot lointain de <b>Jared Harper<\/b>. Le match en main, Valence conna\u00eet un nouveau coup de mou. Sans briller, Monaco profite de cette apathie pour recoller progressivement. Jusque l\u00e0 en grande difficult\u00e9, <b>\u00c9lie Okobo<\/b> inscrit ses premiers points pour remettre les siens \u00e0 seulement deux possessions dans un match devenu hach\u00e9 par des fautes incessantes (63-69). Au d\u00e9but du money-time, les deux \u00e9quipes sont dans la p\u00e9nalit\u00e9. Encore une fois, Valence tremble et encha\u00eene les erreurs. Les lancers s\u2019encha\u00eenent pour les Mon\u00e9gasques (31\/38!), et <strong>Okobo<\/strong> arrache l\u2019\u00e9galisation derri\u00e8re l\u2019arc (73-73) !<\/p>\n<p align=\"justify\">Mais ce match \u00e9tait le <b>Chris Jones<\/b> (27 points) <em>game<\/em>. L\u2019ancien lyonnais \u00e9gale son record en EuroLigue, et inscrit des points d\u00e9cisifs. Puis, <b>James Webb<\/b> (15 points, 8 rebonds) se charge de planter deux poignards derri\u00e8re l\u2019arc pour d\u00e9finitivement doucher les espoirs tricolores. En toute logique, Valence l\u2019emporte<strong> 89-84<\/strong>, et provoque la deuxi\u00e8me d\u00e9faite de la <em>Roca Team<\/em> cette saison.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">ISO Chris Jones and La Fonteta goes crazy&#x1f525;<a href=\"https:\/\/twitter.com\/valenciabasket?ref_src=twsrc%5Etfw\">@valenciabasket<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/7DAYSMagicMoment?src=hash&amp;ref_src=twsrc%5Etfw\">#7DAYSMagicMoment<\/a> <a href=\"https:\/\/t.co\/xSvw6XSMcR\">pic.twitter.com\/xSvw6XSMcR<\/a><\/p>\n<p>\u2014 Turkish Airlines EuroLeague (@EuroLeague) <a href=\"https:\/\/twitter.com\/EuroLeague\/status\/1591188722225418240?ref_src=twsrc%5Etfw\">November 11, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE 2022-2023 &#8211; Comme les femmes plus t\u00f4t dans la semaine, les \u00e9quipes fran\u00e7aises masculines ont accumul\u00e9 les d\u00e9faites. En d\u00e9placement \u00e0 Valence, l&rsquo;AS Monaco a logiquement \u00e9t\u00e9 battue apr\u00e8s avoir livr\u00e9 une prestation insipide, contrastant avec la coh\u00e9rence collective des Espagnols sublim\u00e9e par l&rsquo;ancien Lyonnais Chris Jones. Au bout d&rsquo;un money-time totalement d\u00e9li\u00e9, la Roca Team a c\u00e9d\u00e9 89-84.\u00a0<\/p>\n","protected":false},"author":55,"featured_media":278008,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47001],"tags":[1691,181,25103,24,2100],"class_list":["post-277962","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-as-monaco","tag-euroligue","tag-jordan-loyd","tag-sport","tag-valence"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroLigue (J7) : Un pi\u00e8tre Monaco s&#039;incline logiquement d&#039;un souffle \u00e0 Valence<\/title>\n<meta name=\"description\" content=\"L&#039;AS Monaco s&#039;est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d&#039;EuroLigue, 89-84.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue (J7) : Un pi\u00e8tre Monaco s&#039;incline logiquement d&#039;un souffle \u00e0 Valence\" \/>\n<meta property=\"og:description\" content=\"L&#039;AS Monaco s&#039;est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d&#039;EuroLigue, 89-84.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-11T22:11:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-11T22:17:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue (J7) : Un pi\u00e8tre Monaco s&#039;incline logiquement d&#039;un souffle \u00e0 Valence\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"EuroLigue (J7) : Un pi\u00e8tre Monaco s&rsquo;incline logiquement d&rsquo;un souffle \u00e0 Valence\",\"datePublished\":\"2022-11-11T22:11:05+00:00\",\"dateModified\":\"2022-11-11T22:17:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\"},\"wordCount\":748,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png\",\"keywords\":[\"AS Monaco\",\"Euroligue\",\"Jordan Loyd\",\"sport\",\"valence\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\",\"name\":\"EuroLigue (J7) : Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png\",\"datePublished\":\"2022-11-11T22:11:05+00:00\",\"dateModified\":\"2022-11-11T22:17:13+00:00\",\"description\":\"L'AS Monaco s'est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d'EuroLigue, 89-84.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png\",\"width\":800,\"height\":445,\"caption\":\"EuroLigue (J7) Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue (J7) : Un pi\u00e8tre Monaco s&rsquo;incline logiquement d&rsquo;un souffle \u00e0 Valence\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue (J7) : Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence","description":"L'AS Monaco s'est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d'EuroLigue, 89-84.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue (J7) : Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence","og_description":"L'AS Monaco s'est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d'EuroLigue, 89-84.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-11-11T22:11:05+00:00","article_modified_time":"2022-11-11T22:17:13+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"EuroLigue (J7) : Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"EuroLigue (J7) : Un pi\u00e8tre Monaco s&rsquo;incline logiquement d&rsquo;un souffle \u00e0 Valence","datePublished":"2022-11-11T22:11:05+00:00","dateModified":"2022-11-11T22:17:13+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/"},"wordCount":748,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png","keywords":["AS Monaco","Euroligue","Jordan Loyd","sport","valence"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/","name":"EuroLigue (J7) : Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png","datePublished":"2022-11-11T22:11:05+00:00","dateModified":"2022-11-11T22:17:13+00:00","description":"L'AS Monaco s'est inclin\u00e9e logiquement sur le parquet de Valence dans le cadre de la 7e journ\u00e9e d'EuroLigue, 89-84.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/EuroLigue-J7-Un-pietre-Monaco-sincline-logiquement-dun-souffle-a-Valence.png","width":800,"height":445,"caption":"EuroLigue (J7) Un pi\u00e8tre Monaco s'incline logiquement d'un souffle \u00e0 Valence"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j7-un-pietre-monaco-sincline-logiquement-dun-souffle-a-valence\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue (J7) : Un pi\u00e8tre Monaco s&rsquo;incline logiquement d&rsquo;un souffle \u00e0 Valence"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/277962","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=277962"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/277962\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/278008"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=277962"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=277962"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=277962"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}