{"id":278948,"date":"2022-11-14T15:28:23","date_gmt":"2022-11-14T14:28:23","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=278948&#038;preview=true&#038;preview_id=278948"},"modified":"2022-11-15T16:34:20","modified_gmt":"2022-11-15T15:34:20","slug":"xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/","title":{"rendered":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/xv-de-france\/\">XV DE FRANCE<\/a> &#8211; Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d&rsquo;automne 2022 face au Japon, qui se d\u00e9roule ce dimanche (14h), \u00e0 Toulouse.\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">En plus des 25 joueurs encore pr\u00e9sents avec le groupe France, <strong>Fabien<\/strong> <strong>Galthi\u00e9<\/strong> a convoqu\u00e9 17 joueurs pour faire le groupe de 42. <strong>Antoine<\/strong> <strong>Dupont<\/strong>, suspendu, <strong>Cyril<\/strong> <strong>Baille<\/strong> et <strong>Thibaud<\/strong> <strong>Flament<\/strong>, forfaits, sont les trois joueurs qui quittent le rassemblement des <strong>Bleus<\/strong>. <strong>Nolann<\/strong> <strong>Le<\/strong> <strong>Garrec<\/strong> est convoqu\u00e9 pour remplacer le capitaine de l&rsquo;\u00e9quipe de France alors qu&rsquo;<strong>Antony<\/strong> <strong>Bouthier<\/strong> est aussi rappel\u00e9.<\/p>\n<h2 style=\"text-align: justify;\">Les avants<\/h2>\n<p style=\"text-align: justify;\">ALLDRITT Gr\u00e9gory (Stade Rochelais),<br \/>\nATONIO Uini (Stade Rochelais),<br \/>\nBECOGNEE Alexandre (Montpellier H\u00e9rault Rugby),<br \/>\nBOURGARIT Pierre (Stade Rochelais),<br \/>\nCASTETS Cl\u00e9ment (Stade Fran\u00e7ais Paris),<br \/>\nCHALUREAU Bastien (Montpellier H\u00e9rault Rugby),<br \/>\nCRETIN Dylan (Lyon OU Rugby),<br \/>\nFALATEA Sipili (Union Bordeaux B\u00e8gles),<br \/>\nHAOUAS Mohamed (Montpellier H\u00e9rault Rugby),<br \/>\nJELONCH Anthony (Stade Toulousain),<br \/>\nJOSEPH Jordan (Section Paloise),<br \/>\nLAVAULT Thomas (Stade Rochelais),<br \/>\nMACALOU Sekou (Stade Fran\u00e7ais Paris),<br \/>\nMARCHAND Julien (Stade Toulousain),<br \/>\nMAUVAKA Peato (Stade Toulousain),<br \/>\nOLLIVON Charles (RC Toulon),<br \/>\nPRISO Dany (RC Toulon),<br \/>\nTANGA Yoan (Stade Rochelais),<br \/>\nTAOFIFENUA Romain (Lyon OU Rugby),<br \/>\nVANVERBERGHE Florent (Castres Olympique),<br \/>\nWARDI R\u00e9da (Stade Rochelais),<br \/>\nWOKI Cameron (Racing 92)<\/p>\n<h2 style=\"text-align: justify;\">Les arri\u00e8res<\/h2>\n<p style=\"text-align: justify;\">BARASSI Pierre-Louis (Stade Toulousain),<br \/>\nBERDEU L\u00e9o (Lyon OU Rugby),<br \/>\nBOUDEHENT Pierre (Stade Rochelais),<br \/>\nBOUTHIER Anthony (Montpellier H\u00e9rault Rugby),<br \/>\nCOUILLOUD Baptiste (Lyon OU Rugby),<br \/>\nDANTY Jonathan (Stade Rochelais),<br \/>\nDUMORTIER Ethan (Lyon OU Rugby),<br \/>\nEZEALA Samuel (AS Clermont Auvergne),<br \/>\nFICKOU Ga\u00ebl (Racing 92),<br \/>\nGAILLETON Emilien (Section Paloise)<br \/>\nJALIBERT Matthieu (Union Bordeaux B\u00e8gles),<br \/>\nLEBEL Matthis (Stade Toulousain),<br \/>\nLE GARREC Nolann (Racing 92)<br \/>\nLUCU Maxime (Union Bordeaux B\u00e8gles),<br \/>\nMOEFANA Yoram (Union Bordeaux B\u00e8gles),<br \/>\nNTAMACK Romain (Stade Toulousain),<br \/>\nPENAUD Damian (ASM Clermont Auvergne),<br \/>\nRAKA Alivereti (ASM Clermont Auvergne),<br \/>\nRAMOS Thomas (Stade Toulousain),<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x1f4e3; L\u2019encadrement du <a href=\"https:\/\/twitter.com\/hashtag\/XVdeFrance?src=hash&amp;ref_src=twsrc%5Etfw\">#XVdeFrance<\/a> a communiqu\u00e9 la liste des joueurs s\u00e9lectionn\u00e9s pour pr\u00e9parer le troisi\u00e8me et dernier match des <a href=\"https:\/\/twitter.com\/autumnnations?ref_src=twsrc%5Etfw\">@autumnnations<\/a> 2022 face au Japon, dimanche \u00e0 14h au Stadium de Toulouse.<a href=\"https:\/\/twitter.com\/hashtag\/FRAJAP?src=hash&amp;ref_src=twsrc%5Etfw\">#FRAJAP<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/NeFaisonsXV?src=hash&amp;ref_src=twsrc%5Etfw\">#NeFaisonsXV<\/a><a href=\"https:\/\/t.co\/9ibnVvqr3K\">https:\/\/t.co\/9ibnVvqr3K<\/a><\/p>\n<p>\u2014 France Rugby (@FranceRugby) <a href=\"https:\/\/twitter.com\/FranceRugby\/status\/1592164580637421569?ref_src=twsrc%5Etfw\">November 14, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>XV DE FRANCE &#8211; Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d&rsquo;automne face au Japon.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":279039,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,19951],"tags":[30,318,1638],"class_list":["post-278948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-xv-de-france","tag-france","tag-japon","tag-xv-de-france"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon<\/title>\n<meta name=\"description\" content=\"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d&#039;automne face au Japon.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon\" \/>\n<meta property=\"og:description\" content=\"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d&#039;automne face au Japon.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-14T14:28:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-15T15:34:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon\",\"datePublished\":\"2022-11-14T14:28:23+00:00\",\"dateModified\":\"2022-11-15T15:34:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png\",\"keywords\":[\"France\",\"Japon\",\"XV de France\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"XV de France\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/\",\"name\":\"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png\",\"datePublished\":\"2022-11-14T14:28:23+00:00\",\"dateModified\":\"2022-11-15T15:34:20+00:00\",\"description\":\"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d'automne face au Japon.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2022\\\/11\\\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon","description":"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d'automne face au Japon.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/","og_locale":"fr_FR","og_type":"article","og_title":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon","og_description":"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d'automne face au Japon.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-11-14T14:28:23+00:00","article_modified_time":"2022-11-15T15:34:20+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon","datePublished":"2022-11-14T14:28:23+00:00","dateModified":"2022-11-15T15:34:20+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png","keywords":["France","Japon","XV de France"],"articleSection":["Rugby \u00e0 XV","XV de France"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/","url":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/","name":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png","datePublished":"2022-11-14T14:28:23+00:00","dateModified":"2022-11-15T15:34:20+00:00","description":"XV DE FRANCE - Le staff du XV de France a d\u00e9voil\u00e9 le groupe de 42 joueurs pour pr\u00e9parer le troisi\u00e8me match de la tourn\u00e9e d'automne face au Japon.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/XV-de-France-Le-groupe-de-42-joueurs-pour-pre\u0301parer-le-Japon-1.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/xv-de-france-le-groupe-de-42-joueurs-pour-preparer-le-japon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"XV de France : Le groupe de 42 joueurs pour pr\u00e9parer le Japon"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/278948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=278948"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/278948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/279039"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=278948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=278948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=278948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}