{"id":281105,"date":"2022-11-21T16:17:10","date_gmt":"2022-11-21T15:17:10","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=281105&#038;preview=true&#038;preview_id=281105"},"modified":"2022-11-21T16:38:59","modified_gmt":"2022-11-21T15:38:59","slug":"coupe-du-monde-de-football-l-angleterre-desosse-l-iran","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/","title":{"rendered":"Coupe du monde de football : L&rsquo;Angleterre d\u00e9sosse l&rsquo;Iran"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/coupe-du-monde-de-football-2022\/\">COUPE DU MONDE DE FOOTBALL 2022<\/a> &#8211; La Coupe du monde de l&rsquo;Angleterre commence sur les chapeaux de roues. Face \u00e0 l&rsquo;Iran, les hommes de Gareth Southgate ont surclass\u00e9 un adversaire extr\u00eamement d\u00e9cevant, 6-2. Meilleurs dans tous les domaines, et port\u00e9s par une animation offensive tr\u00e8s int\u00e9ressante, les Three Lions ont brill\u00e9. Bukayo Saka s&rsquo;offre un doubl\u00e9, et rejoint Enner Valencia en t\u00eate du <a href=\"https:\/\/dicodusport.fr\/blog\/classement-meilleurs-buteurs-coupe-du-monde-de-football\/\">classement des buteurs<\/a>.<\/i><\/b><\/p>\n<p align=\"justify\">Quatre ans apr\u00e8s les espoirs n\u00e9s d\u2019une campagne en Russie termin\u00e9e \u00e0 la 4<sup>e<\/sup> place, et finaliste de l&rsquo;Euro 2020 entre-temps, l\u2019<b>Angleterre<\/b> faisait ses grands d\u00e9buts au Khalifa International Stadium de <strong>Doha<\/strong> face \u00e0 l\u2019<b>Iran,<\/b> au sein d&rsquo;un Groupe B o\u00f9 elle fait figure d&rsquo;\u00e9pouvantail. Face \u00e0 un adversaire \u00e0 ne pas sous-estimer, les Anglais se devaient de partir sur de bonnes bases afin d\u2019affirmer leurs ambitions. Avant le coup d&rsquo;envoi, ces m\u00eames Iraniens ont envoy\u00e9 un message fort en restant muets lors de l&rsquo;hymne national, ce qui fait \u00e9cho aux tensions \u00e9maillant le pays et son r\u00e9gime politique autoritaire depuis plusieurs semaines.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Outre la d\u00e9route de l&rsquo;Iran &#x1f1ee;&#x1f1f7; face \u00e0 l&rsquo;Angleterre&#x1f3f4;&#xe0067;&#xe0062;&#xe0065;&#xe006e;&#xe0067;&#xe007f; (0-3), on retiendra surtout que les joueurs de la \u00ab\u00a0Team Melli\u00a0\u00bb n&rsquo;ont pas chant\u00e9 leur hymne, siffl\u00e9 par le stade, en soutien aux manifestations dans leur pays. <a href=\"https:\/\/twitter.com\/hashtag\/ENGIRN?src=hash&amp;ref_src=twsrc%5Etfw\">#ENGIRN<\/a><\/p>\n<p>D\u00e9cryptage sous ce tweet &#x2935;<a href=\"https:\/\/t.co\/y8HgdMmZzW\">pic.twitter.com\/y8HgdMmZzW<\/a><\/p>\n<p>\u2014 FC Geopolitics (@FCGeopolitics) <a href=\"https:\/\/twitter.com\/FCGeopolitics\/status\/1594692773722181633?ref_src=twsrc%5Etfw\">November 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Le collectif anglais surclasse une Iran inoffensive<\/h2>\n<p align=\"justify\">Comme attendu, les hommes de <b>Gareth Southgate <\/b>mettent imm\u00e9diatement le pied sur le ballon, et m\u00e8nent des premi\u00e8res perc\u00e9es int\u00e9ressantes sur les ailes, gr\u00e2ce aux options propos\u00e9es par les lat\u00e9raux <b>Kieran Trippier<\/b> et <b>Luke Shaw<\/b>. Les Iraniens sont retranch\u00e9s dans leur camp, incapables de ressortir le moindre ballon, et subissent la perte de leur gardien. Violemment touch\u00e9 suite \u00e0 un choc avec son d\u00e9fenseur, <b>Alireza Beiranvand<\/b> est finalement remplac\u00e9 suite \u00e0 dix minutes d\u2019imbroglio concernant sa capacit\u00e9 \u00e0 continuer. Cela n\u2019enraye pas la bonne dynamique de <em>Three Lions<\/em> bien organis\u00e9s, et de plus en plus dangereux.<\/p>\n<p align=\"justify\">A la demi-heure de jeu, une reprise de <b>Mason Mount<\/b> termine dans le petit filet, puis <b>Harry Maguire<\/b> claque ensuite une t\u00eate surpuissante finissant sa course sur la transversale. Mais c\u2019est finalement le benjamin du groupe qui va d\u00e9livrer les Anglais. <b>Jude Bellingham <\/b>b\u00e9n\u00e9ficie d\u2019un magnifique jeu d\u00e9velopp\u00e9 \u00e0 trois sur l\u2019aile gauche pour venir claquer une t\u00eate d\u00e9crois\u00e9e gagnante (1-0, 36e). Irr\u00e9sistibles face \u00e0 une \u00e9quipe iranienne qui se cantonne \u00e0 d\u00e9fendre dans ses 35 derniers m\u00e8tres, les Anglais vont tuer le match avant la pause.<\/p>\n<p align=\"justify\"><b>Bukayo Saka<\/b> profite d\u2019une d\u00e9viation de <b>Harry Maguire<\/b> pour d\u00e9clencher une frappe monstrueuse sous la barre (2-0, 43e). Puis \u00e0 peine deux minutes plus tard, <b>Harry Kane<\/b> offre un caviar \u00e0<b> Raheem Sterling<\/b>, lanc\u00e9 \u00e0 pleine vitesse pour crucifier le malheureux <b>Hossein Hosseini <\/b>(3-0, 45e). Les Anglais d\u00e9roulent leur football et rentrent aux vestiaires avec trois buts d\u2019avance, 81 % de possession, et aucun tir conc\u00e9d\u00e9. \u00c0 sens unique.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">What a finish from saka &#x1f525;&#x1f525;&#x1f525;<a href=\"https:\/\/t.co\/jIl1o38wE0\">pic.twitter.com\/jIl1o38wE0<\/a><\/p>\n<p>\u2014 999 IQ moment in football (@TBackfooty) <a href=\"https:\/\/twitter.com\/TBackfooty\/status\/1594688279127130112?ref_src=twsrc%5Etfw\">November 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Dix minutes de folie, l&rsquo;Angleterre en gestion<\/h2>\n<p style=\"text-align: justify;\">D\u00e8s la reprise, le s\u00e9lectionneur portugais de l&rsquo;Iran <strong>Carlos Queiroz<\/strong> d\u00e9cide logiquement de bouleverser son effectif en apportant trois changements. Deux crans au-dessus, les Anglais g\u00e8rent sans difficult\u00e9 malgr\u00e9 un pressing iranien plus consistant.\u00a0Il faut attendre l&rsquo;heure de jeu pour voir une premi\u00e8re frappe iranienne anecdotique sign\u00e9e <strong>Saeid Ezatolahi<\/strong>. Mais dans la foul\u00e9e, un nouveau coup de poignard vient les frapper. <strong>Bukayo Saka<\/strong> s&rsquo;offre un doubl\u00e9 en mystifiant des Iraniens passifs (4-0, 62e). Alors que Southgate pr\u00e9pare une vague de changements, Taremi profite sa toute premi\u00e8re opportunit\u00e9 sur un service d&rsquo;<strong>Ali Gholizadeh<\/strong> pour crucifier Pickford (4-1, 65e), et offrir un but inesp\u00e9r\u00e9 aux siens !<\/p>\n<p style=\"text-align: justify;\">Mais cette deuxi\u00e8me mi-temps est totalement d\u00e9brid\u00e9e, et les d\u00e9fenses de plus en plus permissives. A peine entr\u00e9 en jeu, <strong>Marcus Rashford<\/strong> est lanc\u00e9 par <strong>Harry Kane<\/strong>, \u00e9limine facilement un d\u00e9fenseur iranien, et offre un cinqui\u00e8me but aux siens (5-1, 71e). La folie totale qui s&rsquo;\u00e9tait empar\u00e9e de la rencontre retombe progressivement au fil des minutes. Les Anglais continuent \u00e0 se cr\u00e9er de grosses occasions, notamment par le biais d&rsquo;un Rashford tr\u00e8s incisif. Histoire de clore le spectacle en beaut\u00e9, les rempla\u00e7ants offrent le feu d&rsquo;artifice final. <strong>Callum Wilson<\/strong> est lanc\u00e9 dans le dos de la d\u00e9fense, et se montre altruiste en offrant \u00e0<strong> Jack Grealish<\/strong> le sixi\u00e8me but (6-1, 90e).<\/p>\n<p style=\"text-align: justify;\">Toutefois, au terme de dix minutes (!) d&rsquo;arr\u00eats de jeu, l&rsquo;Iran se montre. <strong>Sardar Azmoun<\/strong> frappe la barre, puis <strong>Mehdi Taremi<\/strong> devient le premier joueur iranien \u00e0 s&rsquo;offrir un doubl\u00e9 en transformant un penalty tardif (6-2, 90+12e). Une petite t\u00e2che dans un match finalement largement ma\u00eetris\u00e9, l&rsquo;Angleterre l&#8217;emporte 6-2 au bout d&rsquo;un match fou, et interminable (26 minutes de temps additionnel en cumul\u00e9 !).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">Scorers in the second half &#x1f60e; <a href=\"https:\/\/t.co\/HyWWJ0IMxT\">pic.twitter.com\/HyWWJ0IMxT<\/a><\/p>\n<p>\u2014 England (@England) <a href=\"https:\/\/twitter.com\/England\/status\/1594706562139963393?ref_src=twsrc%5Etfw\">November 21, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Homme du match : Bukayo Saka<\/h2>\n<p style=\"text-align: justify;\">Depuis son \u00e9chec lors de <a href=\"https:\/\/dicodusport.fr\/blog\/euro-2020-italie-sur-le-toit-europe\/\">la s\u00e9ance de tirs aux buts de la finale de l&rsquo;Euro 2020<\/a>, <strong>Bukayo Saka<\/strong> n&rsquo;a cess\u00e9 d&rsquo;\u00e9voluer pour devenir cette saison un cadre incontournable du leader de Premier League, Arsenal. Face \u00e0 cet Iran passif d\u00e9fensivement, le Gunner a \u00e9t\u00e9 insaisissable. Multipliant les bons appels de balle, il a percut\u00e9 avec sa vitesse sur les ailes, mais a \u00e9galement ouvert le couloir \u00e0 son lat\u00e9ral afin d&rsquo;apporter plus de pr\u00e9sence dans l&rsquo;axe. En premi\u00e8re p\u00e9riode,<strong> il a permis aux Three Lions de doubler la mise d&rsquo;une reprise de vol\u00e9e splendide<\/strong>. Puis, en deuxi\u00e8me p\u00e9riode, il s&rsquo;est offert le doubl\u00e9 en faisant danser ses vis-\u00e0-vis, avant de glisser d\u00e9licatement le cuir dans les filets. Propre, actif, disponible, efficace\u2026 Saka a r\u00e9alis\u00e9 un match \u00e9norme au sein d&rsquo;un dispositif offensif huil\u00e9. A la 70e minute, <strong>Marcus Rashford<\/strong> le remplace, mettant fin \u00e0 une partition de premier choix.<\/p>\n<div id=\"attachment_281152\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Bukayo-Saka-sest-amuse-face-a-lIran-1.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-281152\" class=\"size-full wp-image-281152\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Bukayo-Saka-sest-amuse-face-a-lIran-1.png\" alt=\"Bukayo Saka s'est amus\u00e9 face \u00e0 l'Iran\" width=\"800\" height=\"445\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Bukayo-Saka-sest-amuse-face-a-lIran-1.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Bukayo-Saka-sest-amuse-face-a-lIran-1-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Bukayo-Saka-sest-amuse-face-a-lIran-1-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p id=\"caption-attachment-281152\" class=\"wp-caption-text\">Bukayo Saka s&rsquo;est amus\u00e9 face \u00e0 l&rsquo;Iran &#8211; Photo Icon Sport<\/p><\/div>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-groupe-b-coupe-du-monde-de-football\/\"><strong>Calendrier et r\u00e9sultats du groupe B de la Coupe du monde 2022<\/strong><\/a><\/li>\n<\/ul>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE FOOTBALL 2022 &#8211; La Coupe du monde de l&rsquo;Angleterre commence sur les chapeaux de roues. Face \u00e0 l&rsquo;Iran, les hommes de Gareth Southgate ont surclass\u00e9 un adversaire extr\u00eamement d\u00e9cevant, 6-2. Meilleurs dans tous les domaines, et port\u00e9s par une animation offensive tr\u00e8s int\u00e9ressante, les Three Lions ont brill\u00e9. Bukayo Saka s&rsquo;offre un doubl\u00e9, et rejoint Enner Valencia en t\u00eate du classement des buteurs.<\/p>\n","protected":false},"author":55,"featured_media":281153,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47043,2301],"tags":[51,5095,75,5002,15470],"class_list":["post-281105","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","category-football","tag-angleterre","tag-coupe-du-monde-de-football","tag-football","tag-iran","tag-jude-bellingham"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde de football : L&#039;Angleterre d\u00e9sosse l&#039;Iran<\/title>\n<meta name=\"description\" content=\"L&#039;Angleterre a surclass\u00e9 l&#039;Iran, l&#039;emportant 6-2, \u00e0 l&#039;occasion du premier match du Groupe B de la Coupe du monde 2022 de football.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde de football : L&#039;Angleterre d\u00e9sosse l&#039;Iran\" \/>\n<meta property=\"og:description\" content=\"L&#039;Angleterre a surclass\u00e9 l&#039;Iran, l&#039;emportant 6-2, \u00e0 l&#039;occasion du premier match du Groupe B de la Coupe du monde 2022 de football.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-21T15:17:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-21T15:38:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde de football : L&#039;Angleterre d\u00e9sosse l&#039;Iran\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Coupe du monde de football : L&rsquo;Angleterre d\u00e9sosse l&rsquo;Iran\",\"datePublished\":\"2022-11-21T15:17:10+00:00\",\"dateModified\":\"2022-11-21T15:38:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\"},\"wordCount\":1111,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png\",\"keywords\":[\"Angleterre\",\"coupe du monde de football\",\"Football\",\"Iran\",\"Jude Bellingham\"],\"articleSection\":[\"Coupe du monde de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\",\"name\":\"Coupe du monde de football : L'Angleterre d\u00e9sosse l'Iran\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png\",\"datePublished\":\"2022-11-21T15:17:10+00:00\",\"dateModified\":\"2022-11-21T15:38:59+00:00\",\"description\":\"L'Angleterre a surclass\u00e9 l'Iran, l'emportant 6-2, \u00e0 l'occasion du premier match du Groupe B de la Coupe du monde 2022 de football.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde de football L\u2019Angleterre d\u00e9sosse l'Iran\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde de football : L&rsquo;Angleterre d\u00e9sosse l&rsquo;Iran\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde de football : L'Angleterre d\u00e9sosse l'Iran","description":"L'Angleterre a surclass\u00e9 l'Iran, l'emportant 6-2, \u00e0 l'occasion du premier match du Groupe B de la Coupe du monde 2022 de football.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde de football : L'Angleterre d\u00e9sosse l'Iran","og_description":"L'Angleterre a surclass\u00e9 l'Iran, l'emportant 6-2, \u00e0 l'occasion du premier match du Groupe B de la Coupe du monde 2022 de football.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-11-21T15:17:10+00:00","article_modified_time":"2022-11-21T15:38:59+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Coupe du monde de football : L'Angleterre d\u00e9sosse l'Iran","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Coupe du monde de football : L&rsquo;Angleterre d\u00e9sosse l&rsquo;Iran","datePublished":"2022-11-21T15:17:10+00:00","dateModified":"2022-11-21T15:38:59+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/"},"wordCount":1111,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png","keywords":["Angleterre","coupe du monde de football","Football","Iran","Jude Bellingham"],"articleSection":["Coupe du monde de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/","name":"Coupe du monde de football : L'Angleterre d\u00e9sosse l'Iran","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png","datePublished":"2022-11-21T15:17:10+00:00","dateModified":"2022-11-21T15:38:59+00:00","description":"L'Angleterre a surclass\u00e9 l'Iran, l'emportant 6-2, \u00e0 l'occasion du premier match du Groupe B de la Coupe du monde 2022 de football.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-LAngleterre-desosse-lIran.png","width":800,"height":445,"caption":"Coupe du monde de football L\u2019Angleterre d\u00e9sosse l'Iran"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-l-angleterre-desosse-l-iran\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde de football : L&rsquo;Angleterre d\u00e9sosse l&rsquo;Iran"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/281105","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=281105"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/281105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/281153"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=281105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=281105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=281105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}