{"id":281464,"date":"2022-11-22T18:59:53","date_gmt":"2022-11-22T17:59:53","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=281464&#038;preview=true&#038;preview_id=281464"},"modified":"2022-11-22T19:21:02","modified_gmt":"2022-11-22T18:21:02","slug":"coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/","title":{"rendered":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/coupe-du-monde-de-football-2022\/\">COUPE DU MONDE DE FOOTBALL 2022<\/a> &#8211; Le Mexique peut remercier son gardien Guillermo Ochoa. En repoussant le penalty de Robert Lewandowski, l&rsquo;ancien gardien de l&rsquo;AC Ajaccio a permis \u00e0 son pays de conserver le match nul face \u00e0 la Pologne (0-0).<\/i><\/b><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">\u00c0 quelques instants de leur match contre l&rsquo;Australie, les Bleus n&rsquo;ont sans doute pas regard\u00e9 cette rencontre entre Mexicains et Polonais. Pourtant, l&rsquo;une de ces deux nations pourrait \u00eatre l&rsquo;un des adversaires de la France en huiti\u00e8mes de finale. Avec <a href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-larabie-saoudite-signe-un-exploit-monumental-contre-largentine\/\">la chute surprise de l&rsquo;Argentine<\/a> de <\/span><b>Leo Messi<\/b> face \u00e0 l&rsquo;Arabie Saoudite<span style=\"font-weight: 400;\">, le Mexique et la Pologne esp\u00e8rent en profiter dans ce groupe C. Ni l&rsquo;une, ni l&rsquo;autre nation ne r\u00e9ussira \u00e0 marquer. Un point chacun dans une rencontre o\u00f9 les deux pays auraient pu s&rsquo;imposer.<\/span><\/p>\n<h2 style=\"text-align: justify;\">Le Mexique tente de cr\u00e9er<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le d\u00e9but de partie n&rsquo;a pas offert une kyrielle d&rsquo;occasions de but, mais c&rsquo;est aussi parce que les d\u00e9fenseurs des deux nations se sont bagarr\u00e9s pour garder le ballon en-dehors de leur surface. <\/span><i><span style=\"font-weight: 400;\">El Tri<\/span><\/i><span style=\"font-weight: 400;\"> a bien tent\u00e9 de monopoliser la balle et planter la tente dans le camp adverse, mais sans r\u00e9el succ\u00e8s. Il fallait s&rsquo;y attendre, le match est pour le moins \u00e9quilibr\u00e9 et aucune des deux formations ne prend le dessus sur l&rsquo;autre. Les fans polonais en tribunes ou devant leur t\u00e9l\u00e9 vont subir un premier double coup de chaud (26e, 28e). <\/span><b>Vega<\/b><span style=\"font-weight: 400;\"> de la t\u00eate puis <\/span><b>Gallardo<\/b><span style=\"font-weight: 400;\"> sont proches de placer leur s\u00e9lection devant au score.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Apr\u00e8s 45 minutes jou\u00e9es, le score est nul et vierge. Pourtant, la rencontre est incontestablement rythm\u00e9e avec peu de temps mort. La preuve, pour la premi\u00e8re fois de la comp\u00e9tition, seulement deux minutes de temps additionnel sur une p\u00e9riode. Pour poser un bilan \u00e0 la mi-temps, le Mexique a \u00e9t\u00e9 plus avenant tandis que la Pologne a eu plus de difficult\u00e9s offensivement. Non pas que <\/span><b>Guillermo Ochoa<\/b><span style=\"font-weight: 400;\"> a \u00e9t\u00e9 dans un transat, mais l&rsquo;ex-gardien ajaccien n&rsquo;a pas non plus \u00e9t\u00e9 d\u00e9rang\u00e9 par <\/span><b>Robert Lewandowski <\/b><span style=\"font-weight: 400;\">et compagnie.<\/span><\/p>\n<h2 style=\"text-align: justify;\">Ochoa plus solide que Lewandowski<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">En parlant d&rsquo;<\/span><b>Ochoa<\/b><span style=\"font-weight: 400;\">\u2026 Tout supporter de football conna\u00eet le niveau du portier mexicain lors des Coupes du monde qu&rsquo;il a disput\u00e9es. Avant l&rsquo;heure de jeu, <\/span><b>Lewandowski <\/b><span style=\"font-weight: 400;\">et <\/span><b>Hector Herrera<\/b><span style=\"font-weight: 400;\"> s&rsquo;accrochent dans la surface. L&rsquo;arbitre australien d\u00e9signe le point de penalty apr\u00e8s utilisation de la VAR. Mais l&rsquo;attaquant du FC Barcelone va voir son tir stopp\u00e9 par le gardien et reste toujours muet dans la plus grande des comp\u00e9titions. Toujours 0-0 alors que les tribunes sont de plus en plus bouillantes.<\/span><\/p>\n<div id=\"attachment_281537\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Robert-Lewandowski-bute-sur-Guillermo-Ochoa.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-281537\" class=\"size-full wp-image-281537\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Robert-Lewandowski-bute-sur-Guillermo-Ochoa.png\" alt=\"Robert Lewandowski bute sur Guillermo Ochoa\" width=\"800\" height=\"445\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Robert-Lewandowski-bute-sur-Guillermo-Ochoa.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Robert-Lewandowski-bute-sur-Guillermo-Ochoa-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Robert-Lewandowski-bute-sur-Guillermo-Ochoa-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p id=\"caption-attachment-281537\" class=\"wp-caption-text\">Robert Lewandowski bute sur Guillermo Ochoa &#8211; Photo Icon Sport<\/p><\/div>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Comme en premi\u00e8re p\u00e9riode, les d\u00e9bats s&rsquo;\u00e9quilibrent dans la deuxi\u00e8me partie du match. Par contre, le jeu est plus hach\u00e9. Les chevilles souffrent vu le nombre de semelles subit par les joueurs, aussi bien Mexicains que Polonais. <\/span><i><span style=\"font-weight: 400;\">El Tri <\/span><\/i><span style=\"font-weight: 400;\">continue de pousser pour aller chercher trois points importants mais ce sera sans le succ\u00e8s escompt\u00e9. La Pologne pourra avoir un seul regret : le penalty arr\u00eat\u00e9 par <\/span><b><em>Memo<\/em> Ochoa<\/b><span style=\"font-weight: 400;\">. Sur le reste de la partie, les co\u00e9quipiers de <\/span><b>Wojciech Szczesny <\/b><span style=\"font-weight: 400;\">n&rsquo;ont pas \u00e9t\u00e9 assez dangereux pour pr\u00e9tendre \u00e0 la victoire. Le groupe C a donc un leader inattendu apr\u00e8s une journ\u00e9e avec l&rsquo;Arabie Saoudite.<\/span><\/p>\n<h2 style=\"text-align: justify;\">L&rsquo;homme du match : Guillermo Ochoa<\/h2>\n<p style=\"text-align: justify;\"><b>Alexis Vega<\/b><span style=\"font-weight: 400;\"> aurait pu \u00eatre notre homme du match tant le joueur de Guadalajara a apport\u00e9 gr\u00e2ce \u00e0 ses courses, sa cr\u00e9ation et sa combativit\u00e9. Mais l&rsquo;homme qui sauve un point ce soir est bien <\/span><b>Guillermo Ochoa<\/b><span style=\"font-weight: 400;\">. Peu attaqu\u00e9 sur l&rsquo;ensemble de la rencontre, le gardien de 37 ans a r\u00e9pondu pr\u00e9sent en repoussant le penalty de l&rsquo;un des meilleurs buteurs de la plan\u00e8te, <\/span><b>Robert Lewandowski<\/b><span style=\"font-weight: 400;\">. Une action d\u00e9cisive apportant joie et soulagement \u00e0 sa patrie.<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Ochoa en temps normal. \/ Ochoa quand c&rsquo;est un match de Coupe du Monde. <a href=\"https:\/\/twitter.com\/hashtag\/MEXPOL?src=hash&amp;ref_src=twsrc%5Etfw\">#MEXPOL<\/a> <a href=\"https:\/\/t.co\/G1NLdtsZ6v\">pic.twitter.com\/G1NLdtsZ6v<\/a><\/p>\n<p>\u2014 Winamax Sport &#x1f51e; (@WinamaxSport) <a href=\"https:\/\/twitter.com\/WinamaxSport\/status\/1595104903927578626?ref_src=twsrc%5Etfw\">November 22, 2022<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<ul>\n<li style=\"text-align: justify;\"><strong>\u00c0 lire aussi &#8211; <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-groupe-c-coupe-du-monde-de-football\/\">Calendrier et r\u00e9sultats Groupe C de la Coupe du monde de football<\/a><\/strong><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE FOOTBALL 2022 &#8211; Le Mexique peut remercier son gardien Guillermo Ochoa. En repoussant le penalty de Robert Lewandowski, l&rsquo;ancien gardien de l&rsquo;AC Ajaccio a permis \u00e0 son pays de conserver le match nul face \u00e0 la Pologne (0-0).<\/p>\n","protected":false},"author":61,"featured_media":281524,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47043,2301],"tags":[5095,75,4356,356],"class_list":["post-281464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","category-football","tag-coupe-du-monde-de-football","tag-football","tag-mexique","tag-pologne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n&#039;ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n&#039;ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-22T17:59:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-22T18:21:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne\",\"datePublished\":\"2022-11-22T17:59:53+00:00\",\"dateModified\":\"2022-11-22T18:21:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\"},\"wordCount\":733,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png\",\"keywords\":[\"coupe du monde de football\",\"Football\",\"mexique\",\"Pologne\"],\"articleSection\":[\"Coupe du monde de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\",\"name\":\"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png\",\"datePublished\":\"2022-11-22T17:59:53+00:00\",\"dateModified\":\"2022-11-22T18:21:02+00:00\",\"description\":\"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n'ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde de football Pas de vainqueur entre le Mexique et la Pologne\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne","description":"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n'ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne","og_description":"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n'ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-11-22T17:59:53+00:00","article_modified_time":"2022-11-22T18:21:02+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne","datePublished":"2022-11-22T17:59:53+00:00","dateModified":"2022-11-22T18:21:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/"},"wordCount":733,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png","keywords":["coupe du monde de football","Football","mexique","Pologne"],"articleSection":["Coupe du monde de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/","name":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png","datePublished":"2022-11-22T17:59:53+00:00","dateModified":"2022-11-22T18:21:02+00:00","description":"COUPE DU MONDE DE FOOTBALL 2022 - Le Mexique et la Pologne n'ont pu se d\u00e9partager ce mardi soir dans le groupe C (0-0).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-Pas-de-vainqueur-entre-le-Mexique-et-la-Pologne.png","width":800,"height":445,"caption":"Coupe du monde de football Pas de vainqueur entre le Mexique et la Pologne"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-pas-de-vainqueur-entre-le-mexique-et-la-pologne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde de football : Pas de vainqueur entre le Mexique et la Pologne"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/281464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=281464"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/281464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/281524"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=281464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=281464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=281464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}