{"id":282611,"date":"2022-11-26T16:07:08","date_gmt":"2022-11-26T15:07:08","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=282611&#038;preview=true&#038;preview_id=282611"},"modified":"2022-11-26T23:29:26","modified_gmt":"2022-11-26T22:29:26","slug":"coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/","title":{"rendered":"Coupe du monde de football : La Pologne fait craquer l&rsquo;Arabie Saoudite"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/football\/coupe-du-monde-de-football-2022\/\">COUPE DU MONDE DE FOOTBALL 2022<\/a> &#8211;\u00a0 Apr\u00e8s un nul sans saveur pour leur premier match face au Mexique, les Polonais prennent la t\u00eate du <a href=\"https:\/\/dicodusport.fr\/blog\/calendrier-et-resultats-groupe-c-coupe-du-monde-de-football\/\">groupe C<\/a>, en s&rsquo;imposant face \u00e0 la surprenante Arabie Saoudite 2 \u00e0 0, \u00e0 quelques heures du match entre l&rsquo;Argentine et le Mexique.\u00a0<\/i><\/b><\/p>\n<h2 style=\"text-align: justify;\">Les Verts enflamment le stade<\/h2>\n<p style=\"text-align: justify;\">Sur le terrain comme dans les tribunes, les Saoudiens enflamment le match. Apr\u00e8s leur exploit face \u00e0 l\u2019Argentine, ils veulent le r\u00e9it\u00e9rer afin de se qualifier en 8\u00e8mes de finale de Coupe du monde. Ils prennent le match par le bon bout et dominent en premi\u00e8re p\u00e9riode. Malgr\u00e9 cela, ils ne trouvent pas d\u2019ouverture mais provoquent beaucoup de cartons jaunes polonais. \u00c0 la 39\u2019, la Pologne ouvre le score gr\u00e2ce \u00e0 <strong>Zielinski<\/strong>, contre le cours du jeu, et \u00e9teint les tribunes majoritairement saoudiennes.<\/p>\n<p style=\"text-align: justify;\">Mais quelques minutes plus tard, contact dans la surface entre <strong>Bielik<\/strong> et <strong>Saleh Al-Shehri<\/strong>, l\u2019arbitre visionne la VAR et donne le penalty. Malheureusement pour l&rsquo;Arabie Saoudite, le cyborg <strong>Szcz\u0119sny<\/strong> s\u2019impose face \u00e0 <strong>Salem<\/strong> sur le penalty. Les pieds du gardien n\u2019\u00e9taient pourtant pas sur la ligne, mais l\u2019arbitre ne fait pas retirer le penalty. La pause intervient donc \u00e0 1-0 pour les Polonais.<\/p>\n<h2 style=\"text-align: justify;\">Les Saoudiens maladroits<\/h2>\n<p style=\"text-align: justify;\">Dans la seconde p\u00e9riode, c\u2019est le m\u00eame sc\u00e9nario que la premi\u00e8re, les Saoudiens tiennent le ballon et les Polonais proc\u00e8dent par contre-attaque. <strong>Szcz\u0119sny<\/strong>\u00a0est encore en feu et r\u00e9alise des arr\u00eats d\u2019un autre monde. Le tournant de la seconde mi-temps, c\u2019est bien la barre de <strong>Milik<\/strong> et \u00e0 la 82\u2019, sur une erreur de relance saoudienne. Ensuite, <strong>Lewandowski<\/strong> r\u00e9cup\u00e8re le ballon dans les pieds du d\u00e9fenseur et trompe le gardien en un contre un. L&rsquo;attaquant du FC Barcelone aggrave le score et marque son 1<sup>er<\/sup> but dans ce Mondial (2-0).<\/p>\n<p style=\"text-align: justify;\">Lewandowski aura marqu\u00e9 des buts dans toutes les comp\u00e9titions possibles et entre encore un peu plus dans la l\u00e9gende du football polonais. L\u2019\u00e9quipe d\u2019<strong>Herv\u00e9 Renard<\/strong> aura appris que dans les grandes comp\u00e9titions, sans r\u00e9alisme, on se fait punir. Il y aura donc un match des plus importants pour l&rsquo;\u00e9quipe de Renard contre le Mexique, pour se qualifier en 8\u00e8me de finale.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">&#x23f1; TERMIN\u00c9 !<\/p>\n<p>POLOGNE &#x1f1f5;&#x1f1f1; 2-0 &#x1f1f8;&#x1f1e6; ARABIE<\/p>\n<p>&#x26bd;&#xfe0f; Zielinski<br \/>\n&#x26bd;&#xfe0f; Lewandowski<\/p>\n<p>Ultra-r\u00e9aliste, la Pologne bat l&rsquo;Arabie saoudite et prend la t\u00eate du groupe C, en attendant le bouillant Argentine-Mexique ce soir. <a href=\"https:\/\/twitter.com\/hashtag\/FIFAWorldCup?src=hash&amp;ref_src=twsrc%5Etfw\">#FIFAWorldCup<\/a> <a href=\"https:\/\/t.co\/klHoTHEySg\">pic.twitter.com\/klHoTHEySg<\/a><\/p>\n<p>\u2014 Actu Foot (@ActuFoot_) <a href=\"https:\/\/twitter.com\/ActuFoot_\/status\/1596519795620552705?ref_src=twsrc%5Etfw\">November 26, 2022<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">Homme du match : Wojciech Szcz\u0119sny<\/h2>\n<p style=\"text-align: justify;\">Le gardien polonais a fait le match parfait contre les Faucons. Il a sorti une premi\u00e8re balle de but \u00e0 0-0, puis un penalty qui permet \u00e0 la Pologne de maintenir l\u2019avantage. Puis en d\u00e9but de seconde p\u00e9riode, il a \u00e9teint le feu dans la surface face <strong>Salem Al-Dawsari<\/strong>. Le gardien des Aigles a \u00e9t\u00e9 le joueur le plus d\u00e9cisif du match.<\/p>\n<div id=\"attachment_282666\" style=\"width: 810px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Wojciech-Szczesny-Pologne.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-282666\" class=\"size-full wp-image-282666\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Wojciech-Szczesny-Pologne.png\" alt=\"Wojciech Szczesny - Pologne\" width=\"800\" height=\"445\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Wojciech-Szczesny-Pologne.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Wojciech-Szczesny-Pologne-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Wojciech-Szczesny-Pologne-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><p id=\"caption-attachment-282666\" class=\"wp-caption-text\">Wojciech Szczesny &#8211; Pologne &#8211; Photo Icon Sport<\/p><\/div>\n","protected":false},"excerpt":{"rendered":"<p>COUPE DU MONDE DE FOOTBALL 2022 &#8211;\u00a0 Apr\u00e8s un nul sans saveur pour leur premier match face au Mexique, les Polonais prennent la t\u00eate du groupe C, en s&rsquo;imposant face \u00e0 la surprenante Arabie Saoudite 2 \u00e0 0, \u00e0 quelques heures du match entre l&rsquo;Argentine et le Mexique.\u00a0<\/p>\n","protected":false},"author":74,"featured_media":282653,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47043,2301],"tags":[4973,5095,75,356],"class_list":["post-282611","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-coupe-du-monde-de-football","category-football","tag-arabie-saoudite","tag-coupe-du-monde-de-football","tag-football","tag-pologne"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Coupe du monde de football : La Pologne fait craquer l&#039;Arabie Saoudite<\/title>\n<meta name=\"description\" content=\"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s&#039;impose face \u00e0 l&#039;Arabie Saoudite 2 \u00e0 0.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coupe du monde de football : La Pologne fait craquer l&#039;Arabie Saoudite\" \/>\n<meta property=\"og:description\" content=\"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s&#039;impose face \u00e0 l&#039;Arabie Saoudite 2 \u00e0 0.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-26T15:07:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-26T22:29:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julien Guillaume\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Coupe du monde de football : La Pologne fait craquer l&#039;Arabie Saoudite\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\"},\"author\":{\"name\":\"Julien Guillaume\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fbc076c7537570c66101729bae63c6a3\"},\"headline\":\"Coupe du monde de football : La Pologne fait craquer l&rsquo;Arabie Saoudite\",\"datePublished\":\"2022-11-26T15:07:08+00:00\",\"dateModified\":\"2022-11-26T22:29:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\"},\"wordCount\":537,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png\",\"keywords\":[\"Arabie Saoudite\",\"coupe du monde de football\",\"Football\",\"Pologne\"],\"articleSection\":[\"Coupe du monde de football\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#respond\"]}],\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\",\"name\":\"Coupe du monde de football : La Pologne fait craquer l'Arabie Saoudite\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png\",\"datePublished\":\"2022-11-26T15:07:08+00:00\",\"dateModified\":\"2022-11-26T22:29:26+00:00\",\"description\":\"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s'impose face \u00e0 l'Arabie Saoudite 2 \u00e0 0.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png\",\"width\":800,\"height\":445,\"caption\":\"Coupe du monde de football La Pologne fait craquer l'Arabie Saoudite\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coupe du monde de football : La Pologne fait craquer l&rsquo;Arabie Saoudite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fbc076c7537570c66101729bae63c6a3\",\"name\":\"Julien Guillaume\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png\",\"caption\":\"Julien Guillaume\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/julien-guillaume\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coupe du monde de football : La Pologne fait craquer l'Arabie Saoudite","description":"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s'impose face \u00e0 l'Arabie Saoudite 2 \u00e0 0.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/","og_locale":"fr_FR","og_type":"article","og_title":"Coupe du monde de football : La Pologne fait craquer l'Arabie Saoudite","og_description":"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s'impose face \u00e0 l'Arabie Saoudite 2 \u00e0 0.","og_url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2022-11-26T15:07:08+00:00","article_modified_time":"2022-11-26T22:29:26+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png","type":"image\/png"}],"author":"Julien Guillaume","twitter_card":"summary_large_image","twitter_title":"Coupe du monde de football : La Pologne fait craquer l'Arabie Saoudite","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/"},"author":{"name":"Julien Guillaume","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fbc076c7537570c66101729bae63c6a3"},"headline":"Coupe du monde de football : La Pologne fait craquer l&rsquo;Arabie Saoudite","datePublished":"2022-11-26T15:07:08+00:00","dateModified":"2022-11-26T22:29:26+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/"},"wordCount":537,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png","keywords":["Arabie Saoudite","coupe du monde de football","Football","Pologne"],"articleSection":["Coupe du monde de football","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#respond"]}],"copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/","url":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/","name":"Coupe du monde de football : La Pologne fait craquer l'Arabie Saoudite","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png","datePublished":"2022-11-26T15:07:08+00:00","dateModified":"2022-11-26T22:29:26+00:00","description":"COUPE DU MONDE DE FOOTBALL 2022 -\u00a0 Apr\u00e8s un nul sans saveur face au Mexique, la Pologne s'impose face \u00e0 l'Arabie Saoudite 2 \u00e0 0.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Coupe-du-monde-de-football-La-Pologne-fait-craquer-lArabie-Saoudite.png","width":800,"height":445,"caption":"Coupe du monde de football La Pologne fait craquer l'Arabie Saoudite"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/coupe-du-monde-de-football-la-pologne-fait-craquer-l-arabie-saoudite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Coupe du monde de football : La Pologne fait craquer l&rsquo;Arabie Saoudite"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/fbc076c7537570c66101729bae63c6a3","name":"Julien Guillaume","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE-150x150.png","caption":"Julien Guillaume"},"url":"https:\/\/dicodusport.fr\/blog\/author\/julien-guillaume\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/282611","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/74"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=282611"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/282611\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/282653"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=282611"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=282611"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=282611"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}