{"id":32999,"date":"2019-02-06T09:47:12","date_gmt":"2019-02-06T08:47:12","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=32999"},"modified":"2019-02-08T09:07:57","modified_gmt":"2019-02-08T08:07:57","slug":"7-marathon-en-7-jours-stephanie-gicquel-touche-au-but","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/","title":{"rendered":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em>Jeudi dernier, l&rsquo;athl\u00e8te fran\u00e7aise de l&rsquo;extr\u00eame St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge en Antarctique. Le but ? Courir 7 marathons en 7 jours.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">C&rsquo;est un d\u00e9fi fou dans lequel s&rsquo;est lanc\u00e9e St\u00e9phanie Gicquel. Athl\u00e8te de l&rsquo;extr\u00eame et avocate dans la vie de tous les jours, cette Carcassonnaise de 36 ans a pris le d\u00e9part jeudi dernier du World Marathon Challenge. Le concept ? Courir un marathon par jour pendant sept jours, soit 295km en une semaine, et ce sur les sept continents, l&rsquo;Am\u00e9rique du Nord et l&rsquo;Am\u00e9rique du Sud \u00e9tant compt\u00e9s comme deux continents bien distincts dans ce Challenge. Celle qui d\u00e9tient le record du plus long raid \u00e0 ski d&rsquo;une femme en Antarctique depuis 2015 (2045 km en 74 jours parcourus avec son mari J\u00e9r\u00e9mie) touche donc au but, apr\u00e8s avoir boucl\u00e9 le sixi\u00e8me de ces sept marathons il y a quelques heures.<\/p>\n<h1 style=\"text-align: justify;\">\u00ab Un m\u00e9lange d\u2019aventure et de performance\u00a0\u00bb<\/h1>\n<p style=\"text-align: justify;\">L&rsquo;aventure a d\u00e9but\u00e9 jeudi dernier, en Antarctique. Apr\u00e8s des \u00e9tapes en Afrique du Sud, en Australie, \u00e0 Duba\u00ef et en Espagne, St\u00e9phanie Gicquel et les 41 autres participant(e)s au World Marathon Challenge ont fait escale hier au Chili pour leur avant-dernier p\u00e9riple de 42,195 km, avant de terminer en beaut\u00e9 \u00e0 Miami. Interrog\u00e9e par <a href=\"http:\/\/www.leparisien.fr\/sports\/le-defi-fou-de-stephanie-gicquel-courir-7-marathons-en-7-jours-sur-7-continents-05-02-2019-8004384.php\" target=\"_blank\" rel=\"noopener\">Le Parisien<\/a> lundi dernier avant l&rsquo;\u00e9tape \u00e0 Madrid, cette avocate au barreau de Paris confiait que cette aventure avait plusieurs buts : <em>\u00ab Un m\u00e9lange d\u2019aventure et de performance. Je fais \u00e7a pour me d\u00e9passer, pour battre le record.\u00a0\u00bb <\/em>Un record d\u00e9tenu par l\u2019Am\u00e9ricaine Becca Pizzi, qui avait couru 295 km en 27h26 en 2016, soit une moyenne de 3h55 par marathon. Un challenge \u00e9galement motiv\u00e9 par son soutien \u00e0 l&rsquo;Association Petits Princes, pour laquelle l&rsquo;athl\u00e8te collecte des fonds afin de venir en aide aux enfants malades.<\/p>\n<p style=\"text-align: justify;\">Et \u00e0 moins de 24h de l&rsquo;arriv\u00e9e finale \u00e0 Miami, St\u00e9phanie Gicquel pointe \u00e0 la troisi\u00e8me place du classement g\u00e9n\u00e9ral, en 22h08. Avec une moyenne de 3h40 par marathon, la Fran\u00e7aise, championne de France des 24h en 2018, est donc en passe d&rsquo;atteindre son objectif, apr\u00e8s avoir brav\u00e9 les conditions extr\u00eames aux quatre coins du monde, entre le froid glacial de l&rsquo;Antarctique, la forte humidit\u00e9 de Duba\u00ef et la chaleur de l&rsquo;Australie et du Chili.<\/p>\n<p><strong><em>Flo Ostermann<br \/>\n<a href=\"https:\/\/www.facebook.com\/florent.ostermann\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" sizes=\"auto, (max-width: 40px) 100vw, 40px\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png 150w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-300x300.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook.png 400w\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/SportInsideMag\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeudi dernier, l&rsquo;athl\u00e8te fran\u00e7aise de l&rsquo;extr\u00eame St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge en Antarctique. Le but ? Courir 7 marathons en 7 jours.<\/p>\n","protected":false},"author":4,"featured_media":33004,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,2308],"tags":[1013],"class_list":["post-32999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-athletisme","tag-marathon"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but<\/title>\n<meta name=\"description\" content=\"Jeudi dernier, l&#039;athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but\" \/>\n<meta property=\"og:description\" content=\"Jeudi dernier, l&#039;athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-06T08:47:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-08T08:07:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but\",\"datePublished\":\"2019-02-06T08:47:12+00:00\",\"dateModified\":\"2019-02-08T08:07:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png\",\"keywords\":[\"marathon\"],\"articleSection\":[\"Actualit\u00e9s\",\"Athl\u00e9tisme\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/\",\"name\":\"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png\",\"datePublished\":\"2019-02-06T08:47:12+00:00\",\"dateModified\":\"2019-02-08T08:07:57+00:00\",\"description\":\"Jeudi dernier, l'athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but","description":"Jeudi dernier, l'athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/","og_locale":"fr_FR","og_type":"article","og_title":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but","og_description":"Jeudi dernier, l'athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.","og_url":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2019-02-06T08:47:12+00:00","article_modified_time":"2019-02-08T08:07:57+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but","datePublished":"2019-02-06T08:47:12+00:00","dateModified":"2019-02-08T08:07:57+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png","keywords":["marathon"],"articleSection":["Actualit\u00e9s","Athl\u00e9tisme"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/","url":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/","name":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png","datePublished":"2019-02-06T08:47:12+00:00","dateModified":"2019-02-08T08:07:57+00:00","description":"Jeudi dernier, l'athl\u00e8te fran\u00e7aise St\u00e9phanie Gicquel, 36 ans, a pris le d\u00e9part du World Marathon Challenge. Le but ? Courir 7 marathons en 7 jours.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/St\u00e9phanie-Gicquel-World-Marathon-Challenge-2019.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/7-marathon-en-7-jours-stephanie-gicquel-touche-au-but\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"7 marathons en 7 jours : St\u00e9phanie Gicquel touche au but"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/32999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=32999"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/32999\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/33004"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=32999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=32999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=32999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}