{"id":341022,"date":"2023-01-03T14:59:14","date_gmt":"2023-01-03T13:59:14","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=341022&#038;preview=true&#038;preview_id=341022"},"modified":"2023-01-03T16:42:09","modified_gmt":"2023-01-03T15:42:09","slug":"united-cup-2023-la-france-eliminee-par-la-croatie","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/","title":{"rendered":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a title=\"United Cup 2023 : La France men\u00e9e 0-2 par la Croatie\" href=\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-menee-0-2-par-la-croatie\/\" target=\"_blank\" rel=\"noopener\">UNITED CUP<\/a> &#8211; Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n&rsquo;est pas parvenue \u00e0 inverser la tendance, s&rsquo;inclinant face \u00e0 la Croatie.<br \/>\n<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">En mauvaise posture et men\u00e9e 0-2, la <strong>France<\/strong> abordait cette deuxi\u00e8me journ\u00e9e face \u00e0 la <strong>Croatie<\/strong> dos au mur. Cependant, sur le papier, la France pouvait avoir l&rsquo;avantage sur les deux simples du jour. Encore fallait-il le confirmer sur le terrain.<\/p>\n<h2>Garcia garde la France en vie<\/h2>\n<p style=\"text-align: justify;\">Le premier jeu a \u00e9t\u00e9 accroch\u00e9. Apr\u00e8s avoir sauv\u00e9 une balle de break, <strong>Caroline Garcia<\/strong> a fini par remporter le jeu apr\u00e8s 7 minutes. <strong>Petra Martic<\/strong> quant \u00e0 elle, a facilement remport\u00e9 son engagement, solide au service. La Fran\u00e7aise lui a ensuite r\u00e9pondu avec elle aussi un jeu blanc. Les serveuses ont ensuite tenu leurs engagements avec une balle de break \u00e0 sauver \u00e0 4-4 pour Garcia.\u00a0 D&rsquo;un superbe passing en retour, Garcia a \u00e9galis\u00e9 \u00e0 30-30, \u00e0 deux points du set mais Martic a resserr\u00e9 la vis en retour. La manche s&rsquo;est donc d\u00e9cid\u00e9e au tie-break.<\/p>\n<p style=\"text-align: justify;\">La Fran\u00e7aise a r\u00e9alis\u00e9 le premier <strong>mini-break<\/strong> avec un bon retour une nouvelle fois. Mais sur une faute directe en coup droit, elle a perdu son avantage. Elle a ensuite pouss\u00e9 son adversaire \u00e0 la faute pour s&rsquo;offrir 2 balles de set dont la premi\u00e8re sur le service de la Croate (6-4). Elles ont \u00e9t\u00e9 sauv\u00e9es par un service et retour gagnants. En panne de <strong>premi\u00e8re balle<\/strong>, Garcia a conc\u00e9d\u00e9 une balle de set sur le service adverse. Agressive au retour, la Fran\u00e7aise est parvenue \u00e0 la sauver et \u00e0 se procurer une nouvelle balle de set, sur son service. Elle a r\u00e9alis\u00e9 un tr\u00e8s bon service ext\u00e9rieur mais fait ensuite une grosse faute en coup droit (8-8). Nouvelle balle de set pour la Fran\u00e7aise mais cette fois sur le service de Martic. Une nouvelle fois agressive en retour, Garcia s&rsquo;est procur\u00e9e une <strong>5e balle de set<\/strong>. Et sur son engagement la Fran\u00e7aise a conclu la premi\u00e8re manche apr\u00e8s 1h07 de jeu : 7-6[9].<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83c\uddeb\ud83c\uddf7 <a href=\"https:\/\/twitter.com\/CaroGarcia?ref_src=twsrc%5Etfw\">@CaroGarcia<\/a> takes the first set 7-6 vs. Martic!<a href=\"https:\/\/twitter.com\/hashtag\/UnitedCup?src=hash&amp;ref_src=twsrc%5Etfw\">#UnitedCup<\/a> <a href=\"https:\/\/t.co\/PEIcCwjEdj\">pic.twitter.com\/PEIcCwjEdj<\/a><\/p>\n<p>\u2014 United Cup (@UnitedCupTennis) <a href=\"https:\/\/twitter.com\/UnitedCupTennis\/status\/1610213412243640322?ref_src=twsrc%5Etfw\">January 3, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La Fran\u00e7aise a ensuite bien d\u00e9but\u00e9 sur le service adverse mais Martic remporte son engagement et se procure 2 balles de break (15-40). Mais Garcia les sauve avec deux points gagnants. Et la frustration a chang\u00e9 de camp puisqu&rsquo;apr\u00e8s avoir remport\u00e9 son jeu, Garcia s&rsquo;est \u00e9galement procur\u00e9e <strong>3 balles de break<\/strong> (0-40). D&rsquo;un superbe passing au filet, aid\u00e9e par le filet, la Fran\u00e7aise a r\u00e9alis\u00e9 le premier break du match pour mener 2-1. Avec ce break acquis, la Fran\u00e7aise a ensuite d\u00e9roul\u00e9 pour s&rsquo;imposer 7-6[9] 6-4.<\/p>\n<h2>Bojo s&rsquo;offre Mannarino<\/h2>\n<p style=\"text-align: justify;\">Comme lors du premier match, le premier set s&rsquo;est jou\u00e9 au tie-break, les serveurs ne laissant que peu d&rsquo;opportunit\u00e9s au retour. Et <strong>Adrian Mannarino<\/strong> a \u00e9t\u00e9 le premier \u00e0 conc\u00e9der un mini-break \u00e0<strong> Borna Gojo<\/strong> (3-4). Mais le Fran\u00e7ais est parvenu \u00e0 le r\u00e9cup\u00e9rer. Seulement, bis repetita avec un retour en coup droit gagnant sur deuxi\u00e8me balle pour cette fois-ci s&rsquo;offrir une balle de set. Convertie sur un 6e ace pour faire la course en t\u00eate pour le Croate. Si Gojo rend 98 places au classement ATP \u00e0 Mannarino, il sait se transcender lors des matchs par \u00e9quipes comme lors de la campagne de Coupe Davis 2021.<\/p>\n<p style=\"text-align: justify;\">Dans la deuxi\u00e8me manche, <strong>Mannarino<\/strong> a cette fois fait la course en t\u00eate. Et pour la premi\u00e8re fois, il a pos\u00e9 probl\u00e8me \u00e0 son adversaire sur son engagement avec deux \u00e9galit\u00e9s et une balle de break. Et finalement, le Fran\u00e7ais est parvenu \u00e0 <strong>breaker<\/strong> sur une faute directe adverse pour mener 2-0. Mais derri\u00e8re, dans un long \u00e9change (40 coups) qui a fait mal, Mannarino a c\u00e9d\u00e9 et Gojo s&rsquo;est procur\u00e9 2 balles de d\u00e9break (15-40). Et le d\u00e9break a \u00e9t\u00e9 imm\u00e9diat. Le Fran\u00e7ais a eu une occasion d&rsquo;aller chercher quelque chose \u00e0 3-2. Apr\u00e8s 10 minutes de jeu et une balle de break sauv\u00e9e par Gojo, celui-ci a commis sa deuxi\u00e8me double faute pour conc\u00e9der une nouvelle balle de break. Et Mannarino s&rsquo;est engouffr\u00e9 sur la deuxi\u00e8me balle pour aller chercher le break (4-2). Le Croate \u00e9tait clairement \u00e0 la peine physiquement mais le Fran\u00e7ais ne devait pas commettre la m\u00eame erreur qu&rsquo;il y a quelques jeux. Finalement, le Fran\u00e7ais a tenu pour \u00e9galiser une manche partout 6-7[5] 6-3.<\/p>\n<h3>Mannarino craque en fin de match<\/h3>\n<p style=\"text-align: justify;\"><strong>Mannarino<\/strong> a bien d\u00e9but\u00e9 la derni\u00e8re manche en r\u00e9alisant le break sur la premi\u00e8re de ses 3 balles de break \u00e0 1-1. Et comme Garcia, le Fran\u00e7ais a tenu jusqu&rsquo;\u00e0 5-4. Sauf qu&rsquo;au moment de conclure, les jambes ont encore un peu trembl\u00e9 et il s&rsquo;est trouv\u00e9 men\u00e9 15-40. Totalement lib\u00e9r\u00e9, <strong>Gojo<\/strong> a distribu\u00e9 et l\u00e2ch\u00e9 ses coups droit qui a refait son retard pour revenir \u00e0 5-5. Le <strong>momentum<\/strong> a chang\u00e9 de camp, la Croatie n&rsquo;\u00e9tant plus qu&rsquo;\u00e0 2 jeux du match et de la rencontre. Sur une grosse faute directe du Fran\u00e7ais, Gojo s&rsquo;est procur\u00e9 2 balles de match sur service adverse (15-40). Les deux ont \u00e9t\u00e9 sauv\u00e9es mais Gojo a continu\u00e9 \u00e0 aller chercher le revers de son adversaire pour se procurer une 3e balle de match. Sur un deuxi\u00e8me service, Mannarino a touch\u00e9 les lignes pour s&rsquo;ouvrir le court et rester dans le match. Dans un nouveau rallye au cours duquel Gojo a touch\u00e9 deux fois la bande du filet, Mannarino s&rsquo;est procur\u00e9 une balle de jeu d\u00e9cisif, convertie.<\/p>\n<p style=\"text-align: justify;\">Dans le tie-break, Gojo a poursuivi son sans-faute au service et est parti chercher directement le mini-break. Et le Croate a poursuivi son travail de d\u00e9molition pour mener 5-1. Mannarino a recoll\u00e9 \u00e0 5-6 en sauvant 2 balles de match mais la 3e \u00e9tait sur le service de Gojo. Et il ne s&rsquo;est pas priv\u00e9 pour la convertir celle-l\u00e0.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">SCENESSSS \ud83c\udded\ud83c\uddf7<\/p>\n<p>Borna Gojo defeats Mannarino 7-6 3-6 7-6 after a WILD final set to secure Croatia&rsquo;s spot in the Perth city final!<a href=\"https:\/\/twitter.com\/hashtag\/UnitedCup?src=hash&amp;ref_src=twsrc%5Etfw\">#UnitedCup<\/a> <a href=\"https:\/\/t.co\/mPhbf1QPQp\">pic.twitter.com\/mPhbf1QPQp<\/a><\/p>\n<p>\u2014 Tennis TV (@TennisTV) <a href=\"https:\/\/twitter.com\/TennisTV\/status\/1610272861813633026?ref_src=twsrc%5Etfw\">January 3, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Dans un match qui ne comptait pas, le capitaine <strong>\u00c9douard Roger-Vasselin<\/strong> et <strong>Jessika Ponchet<\/strong> se sont impos\u00e9s 6-4 6-4 face \u00e0 <strong>Matija Pecotic<\/strong> et <strong>Petra Marcinko<\/strong>.<\/p>\n<p style=\"text-align: justify;\">C&rsquo;est une d\u00e9ception pour la France qui avait les moyens de faire mieux face \u00e0 cette Croatie. Celle-ci affrontera donc la Gr\u00e8ce demain dans la finale de Perth.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>UNITED CUP &#8211; Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n&rsquo;est pas parvenue \u00e0 inverser la tendance, s&rsquo;inclinant face \u00e0 la Croatie.<\/p>\n","protected":false},"author":12,"featured_media":341094,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2302],"tags":[2000],"class_list":["post-341022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-caroline-garcia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie<\/title>\n<meta name=\"description\" content=\"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n&#039;est pas parvenue \u00e0 inverser la tendance, s&#039;inclinant face \u00e0 la Croatie.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie\" \/>\n<meta property=\"og:description\" content=\"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n&#039;est pas parvenue \u00e0 inverser la tendance, s&#039;inclinant face \u00e0 la Croatie.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-03T13:59:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-03T15:42:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie\",\"datePublished\":\"2023-01-03T13:59:14+00:00\",\"dateModified\":\"2023-01-03T15:42:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\"},\"wordCount\":1116,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg\",\"keywords\":[\"Caroline Garcia\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\",\"name\":\"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg\",\"datePublished\":\"2023-01-03T13:59:14+00:00\",\"dateModified\":\"2023-01-03T15:42:09+00:00\",\"description\":\"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n'est pas parvenue \u00e0 inverser la tendance, s'inclinant face \u00e0 la Croatie.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg\",\"width\":800,\"height\":445,\"caption\":\"United Cup 2023 La France \u00e9limin\u00e9e par la Croatie\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/arlette\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie","description":"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n'est pas parvenue \u00e0 inverser la tendance, s'inclinant face \u00e0 la Croatie.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/","og_locale":"fr_FR","og_type":"article","og_title":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie","og_description":"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n'est pas parvenue \u00e0 inverser la tendance, s'inclinant face \u00e0 la Croatie.","og_url":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-03T13:59:14+00:00","article_modified_time":"2023-01-03T15:42:09+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg","type":"image\/jpeg"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie","datePublished":"2023-01-03T13:59:14+00:00","dateModified":"2023-01-03T15:42:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/"},"wordCount":1116,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg","keywords":["Caroline Garcia"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/","url":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/","name":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg","datePublished":"2023-01-03T13:59:14+00:00","dateModified":"2023-01-03T15:42:09+00:00","description":"UNITED CUP - Apr\u00e8s 2 matchs perdus hier, la France \u00e9tait dos au mur. Et elle n'est pas parvenue \u00e0 inverser la tendance, s'inclinant face \u00e0 la Croatie.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/United-Cup-2023-La-France-eliminee-par-la-Croatie.jpg","width":800,"height":445,"caption":"United Cup 2023 La France \u00e9limin\u00e9e par la Croatie"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/united-cup-2023-la-france-eliminee-par-la-croatie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"United Cup 2023 : La France \u00e9limin\u00e9e par la Croatie"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/dca4a6239e6d708e46c45d60e160de6c?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/341022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=341022"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/341022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/341094"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=341022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=341022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=341022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}