{"id":343236,"date":"2023-01-10T20:54:05","date_gmt":"2023-01-10T19:54:05","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=343236&#038;preview=true&#038;preview_id=343236"},"modified":"2023-01-10T23:16:34","modified_gmt":"2023-01-10T22:16:34","slug":"basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/","title":{"rendered":"Basket Ligue des Champions : La JDA Dijon grille un joker en s&rsquo;inclinant \u00e0 Peristeri"},"content":{"rendered":"<p align=\"justify\"><i><b><a href=\"https:\/\/dicodusport.fr\/blog\/?s=basket+ligue+des+champions\">BASKET LIGUE DES CHAMPIONS 2022-2023<\/a> &#8211; Une semaine apr\u00e8s avoir pris les devants, la JDA Dijon a laiss\u00e9 filer une belle occasion d&rsquo;acc\u00e9der au Top 16 d\u00e8s ce mardi. A Peristeri, les Dijonnais ont c\u00e9d\u00e9 au bout des prolongations, 92-88, face aux Grecs au terme d&rsquo;une passe d&rsquo;armes intense. La JDA devra donc disputer un match d&rsquo;appui d\u00e9cisif .<\/b><\/i><\/p>\n<p align=\"justify\">Vainqueur du match aller au Palais des Sports (89-80), la <b>JDA Dijon<\/b> devait terminer le boulot en Gr\u00e8ce. Face au <b>Peristari<\/b> de <b>Sylvain Francisco<\/b>, les Tricolores disposaient d\u2019une occasion en or pour s\u2019\u00e9viter un match d\u2019appui la semaine prochaine.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Un deuxi\u00e8me quart renversant<\/h2>\n<p align=\"justify\">D\u2019entr\u00e9e de jeu, les Dijonnais montrent qu\u2019ils ont envie de bien faire les choses en d\u00e9roulant un basket int\u00e9ressant pour r\u00e9pondre \u00e0 la fougue grecque. Ce sont eux qui prennent les devants apr\u00e8s des premi\u00e8res minutes serr\u00e9es. La d\u00e9fense est parfaitement en place tandis que pour s\u2019occuper du scoring, <b>Gregor Hrovat<\/b> et <b>Markis McDuffie<\/b> (20 points, 8 rebonds) sont sur un nuage. Les deux hommes claquent dix-huit des vingt premiers points bourguignons ! Derri\u00e8re ce duo infernal, la JDA prend une avance confortable d\u00e8s le premier quart (20-12).<\/p>\n<p align=\"justify\">Appliqu\u00e9e et concentr\u00e9e, cette derni\u00e8re ne rel\u00e2che pas l\u2019\u00e9treinte et prend plus de dix points d\u2019avance suite \u00e0 une \u00e9norme action \u00e0 quatre points de l\u2019in\u00e9vitable McDuffie. Les Grecs ont la t\u00eate sous l\u2019eau. Ces derniers n\u2019inscrivent pas un point durant plus de cinq minutes, la faute \u00e0 des choix offensifs hasardeux, et conc\u00e8dent au passage un terrible 14-0 (25-12) ! Toutefois, avec l\u2019appui de leur public et un <b>Sylvain Francisco<\/b> en feu derri\u00e8re l\u2019arc, ils reviennent en seulement quatre minutes \u00e0 \u00e9galit\u00e9 (28-28). Cela lance une fin de quart totalement folle o\u00f9 les deux \u00e9quipes se r\u00e9pondent du tac au tac. Juste avant la pause, <b>Robin Ducot\u00e9 <\/b>claque une ogive au buzzer pour r\u00e9pondre \u00e0 Francisco, et maintenir la JDA en t\u00eate (40-37).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">How do you say \u00ab\u00a0\ud835\udde6\ud835\uddee\ud835\uddfb \ud835\uddd9\ud835\uddff\ud835\uddee\ud835\uddfb\ud835\uddf0\ud835\uddf6\ud835\ude00\ud835\uddf0\ud835\uddfc\u00a0\u00bb in Greek? Asking for a friend \ud83d\ude2c<a href=\"https:\/\/twitter.com\/hashtag\/BasketballCL?src=hash&amp;ref_src=twsrc%5Etfw\">#BasketballCL<\/a> I <a href=\"https:\/\/twitter.com\/S_CISCO_2?ref_src=twsrc%5Etfw\">@S_CISCO_2<\/a> x <a href=\"https:\/\/twitter.com\/peristeribc?ref_src=twsrc%5Etfw\">@peristeribc<\/a> <a href=\"https:\/\/t.co\/nGbwJuYNIm\">pic.twitter.com\/nGbwJuYNIm<\/a><\/p>\n<p>\u2014 Basketball Champions League (@BasketballCL) <a href=\"https:\/\/twitter.com\/BasketballCL\/status\/1612876313848852482?ref_src=twsrc%5Etfw\">January 10, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">La JDA c\u00e8de dans une fin de match insoutenable<\/h2>\n<p align=\"justify\">Les deux \u00e9quipes restent \u00e0 une possession \u00e0 la reprise, mais la JDA n\u2019arrive plus \u00e0 encha\u00eener les stops, la faute notamment \u00e0 un <b>Dimitris Agr<\/b><b>a<\/b><b>vanis<\/b> incandescent, et perd un nombre excessif de ballons. Dans une salle bouillante, les Grecs d\u00e9sossent la d\u00e9fense dijonnaise sur transition. \u00c0 la baguette, <b>Sylvain Francisco<\/b> (19 points, 8 passes) distribue les offrandes, et les hommes de<b> Nenad Markovic<\/b> vacillent (54-61). Ils parviennent \u00e0 rapidement rectifier le tir pour recoller en d\u00e9but de dernier quart avec un <b>Robin Ducot\u00e9<\/b> (21 points) ultra productif au scoring.<\/p>\n<p align=\"justify\">L&rsquo;\u00e9tau se resserre \u00e0 l&rsquo;approche du money time, les fautes s&rsquo;encha\u00eenant. Les Dijonnais s&rsquo;accrochent gr\u00e2ce \u00e0 leur domination au rebond, mais se reposent trop sur leur adresse ext\u00e9rieure. Heureusement pour eux, Ducot\u00e9 est totalement en feu. Le jeune arri\u00e8re tricolore d\u00e9coche sa cinqui\u00e8me ogive de la soir\u00e9e pour \u00e9galiser \u00e0 cinq minutes du buzzer (71-71). Cela lance un money time totalement \u00e9touffant o\u00f9 chaque point vaut son pesant d&rsquo;or. <strong>Marcus Denmon<\/strong> donne quatre points d&rsquo;avance \u00e0 <strong>Peristeri<\/strong>, mais les Grecs g\u00e8rent mal leur fin de rencontre en offrant de nombreux lancers \u00e0 la JDA. Cette derni\u00e8re en profite pour grappiller son retard avant que <strong>Gavin Ware<\/strong> n&rsquo;\u00e9galise \u00e0 13 secondes du buzzer (81-81).<\/p>\n<p align=\"justify\">En prolongations, ce duel infernal se poursuit. Les Grecs prennent la t\u00eate, mais la JDA revient progressivement gr\u00e2ce au gros impact de Gavin Ware encore. Aucun shoot n&rsquo;est laiss\u00e9 et c&rsquo;est sur la ligne que la diff\u00e9rence va \u00eatre faite. Les mains tremblent des deux c\u00f4t\u00e9s, et c&rsquo;est finalement Peristeri qui commet le moins d&rsquo;erreurs pour arracher une victoire pr\u00e9cieuse, 92-88. Les deux \u00e9quipes se retrouveront donc afin de disputer <strong>un match d&rsquo;appui d\u00e9cisif dont le vainqueur obtiendra le ticket pour le Top 16 de cette Ligue des Champions.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83d\udea8 <a href=\"https:\/\/twitter.com\/BigWare_20?ref_src=twsrc%5Etfw\">@BigWare_20<\/a> ties it and sends it to OT! <a href=\"https:\/\/twitter.com\/hashtag\/BasketballCL?src=hash&amp;ref_src=twsrc%5Etfw\">#BasketballCL<\/a> I <a href=\"https:\/\/twitter.com\/jdadijonbasket?ref_src=twsrc%5Etfw\">@jdadijonbasket<\/a> <a href=\"https:\/\/t.co\/kLJsCN1Vcn\">pic.twitter.com\/kLJsCN1Vcn<\/a><\/p>\n<p>\u2014 Basketball Champions League (@BasketballCL) <a href=\"https:\/\/twitter.com\/BasketballCL\/status\/1612894525764300801?ref_src=twsrc%5Etfw\">January 10, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p align=\"justify\">\n","protected":false},"excerpt":{"rendered":"<p>BASKET LIGUE DES CHAMPIONS 2022-2023 &#8211; Une semaine apr\u00e8s avoir pris les devants, la JDA Dijon a laiss\u00e9 filer une belle occasion d&rsquo;acc\u00e9der au Top 16 d\u00e8s ce mardi. A Peristeri, les Dijonnais ont c\u00e9d\u00e9 au bout des prolongations, 92-88, face aux Grecs au terme d&rsquo;une passe d&rsquo;armes intense. La JDA devra donc disputer un match d&rsquo;appui d\u00e9cisif .<\/p>\n","protected":false},"author":55,"featured_media":343282,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[24256,19698,419,27599,21341],"class_list":["post-343236","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-gregor-hrovat","tag-jda-dijon","tag-ligue-des-champions","tag-markis-mcduffie","tag-sylvain-francisco"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Basket Ligue des Champions : La JDA Dijon grille un joker en s&#039;inclinant \u00e0 Peristeri<\/title>\n<meta name=\"description\" content=\"La JDA Dijon s&#039;est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d&#039;accession au Top 16 de la Ligue des Champions de basket.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Basket Ligue des Champions : La JDA Dijon grille un joker en s&#039;inclinant \u00e0 Peristeri\" \/>\n<meta property=\"og:description\" content=\"La JDA Dijon s&#039;est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d&#039;accession au Top 16 de la Ligue des Champions de basket.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-10T19:54:05+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-10T22:16:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Basket Ligue des Champions : La JDA Dijon grille un joker en s&#039;inclinant \u00e0 Peristeri\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"Basket Ligue des Champions : La JDA Dijon grille un joker en s&rsquo;inclinant \u00e0 Peristeri\",\"datePublished\":\"2023-01-10T19:54:05+00:00\",\"dateModified\":\"2023-01-10T22:16:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\"},\"wordCount\":727,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png\",\"keywords\":[\"Gregor Hrovat\",\"JDA Dijon\",\"Ligue des champions\",\"Markis McDuffie\",\"Sylvain francisco\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\",\"name\":\"Basket Ligue des Champions : La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png\",\"datePublished\":\"2023-01-10T19:54:05+00:00\",\"dateModified\":\"2023-01-10T22:16:34+00:00\",\"description\":\"La JDA Dijon s'est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d'accession au Top 16 de la Ligue des Champions de basket.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png\",\"width\":800,\"height\":445,\"caption\":\"Basket Ligue des Champions La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Basket Ligue des Champions : La JDA Dijon grille un joker en s&rsquo;inclinant \u00e0 Peristeri\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/maximec\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Basket Ligue des Champions : La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri","description":"La JDA Dijon s'est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d'accession au Top 16 de la Ligue des Champions de basket.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/","og_locale":"fr_FR","og_type":"article","og_title":"Basket Ligue des Champions : La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri","og_description":"La JDA Dijon s'est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d'accession au Top 16 de la Ligue des Champions de basket.","og_url":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-10T19:54:05+00:00","article_modified_time":"2023-01-10T22:16:34+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"Basket Ligue des Champions : La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"Basket Ligue des Champions : La JDA Dijon grille un joker en s&rsquo;inclinant \u00e0 Peristeri","datePublished":"2023-01-10T19:54:05+00:00","dateModified":"2023-01-10T22:16:34+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/"},"wordCount":727,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png","keywords":["Gregor Hrovat","JDA Dijon","Ligue des champions","Markis McDuffie","Sylvain francisco"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/","url":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/","name":"Basket Ligue des Champions : La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png","datePublished":"2023-01-10T19:54:05+00:00","dateModified":"2023-01-10T22:16:34+00:00","description":"La JDA Dijon s'est inclin\u00e9e en Gr\u00e8ce face \u00e0 Peristeri, 92-88, en barrages d'accession au Top 16 de la Ligue des Champions de basket.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Basket-Ligue-des-Champions-La-JDA-Dijon-grille-un-joker-en-sinclinant-a-Peristeri.png","width":800,"height":445,"caption":"Basket Ligue des Champions La JDA Dijon grille un joker en s'inclinant \u00e0 Peristeri"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/basket-ligue-des-champions-la-jda-dijon-grille-un-joker-en-sinclinant-a-peristeri\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Basket Ligue des Champions : La JDA Dijon grille un joker en s&rsquo;inclinant \u00e0 Peristeri"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/343236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=343236"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/343236\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/343282"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=343236"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=343236"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=343236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}