{"id":34360,"date":"2019-02-28T14:10:08","date_gmt":"2019-02-28T13:10:08","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=34360"},"modified":"2019-02-28T14:31:27","modified_gmt":"2019-02-28T13:31:27","slug":"atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/","title":{"rendered":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien\u00a0Berankis en quart de finale.<br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Une premi\u00e8re manche rondement men\u00e9e avec un Fran\u00e7ais ultra-concentr\u00e9 et dominateur qui n&rsquo;a laiss\u00e9 aucune solution \u00e0 son adversaire du jour. Le Parisien empochait ainsi la premi\u00e8re manche 6-1, et on se disait alors que le match \u00e9tait d\u00e9j\u00e0 pli\u00e9.<\/p>\n<p style=\"text-align: justify;\">Mais avec <em>La Monf,<\/em> rien ne se passe comme pr\u00e9vu. Un break conc\u00e9d\u00e9 en milieu de deuxi\u00e8me manche avant de r\u00e9agir pour d\u00e9breaker et m\u00eame prendre \u00e0 nouveau le service de son adversaire dans la foul\u00e9e. A 5-4, le Tricolore servait pour le match, mais il se faisait de nouveau breaker par le Lituanien, qui remportait finalement ce set au jeu d\u00e9cisif.<\/p>\n<p style=\"text-align: justify;\">Le d\u00e9but de troisi\u00e8me set \u00e9tait inqui\u00e9tant pour le Tricolore qui continuait dans ses travers et se retrouvait rapidement break\u00e9. C&rsquo;est une fois dos au mur qu&rsquo;il retrouvait la qualit\u00e9 entrevue lors de la premi\u00e8re manche pour finalement s&rsquo;imposer 6-2. Il retrouvera demain en demi-finale le vainqueur de la rencontre qui oppose Tsitsipas \u00e0 Hurkacz.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<br \/>\n<\/strong><\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale. <\/p>\n","protected":false},"author":1,"featured_media":34361,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,2365,2302],"tags":[156,7349,2804,158,3831],"class_list":["post-34360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-sports-de-raquette","category-tennis","tag-atp","tag-dubai","tag-gael-monfils","tag-monfils","tag-rotterdam"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales<\/title>\n<meta name=\"description\" content=\"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales\" \/>\n<meta property=\"og:description\" content=\"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-28T13:10:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-28T13:31:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales\",\"datePublished\":\"2019-02-28T13:10:08+00:00\",\"dateModified\":\"2019-02-28T13:31:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/\"},\"wordCount\":219,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Gael-Monfils-Dubai\u0308.png\",\"keywords\":[\"ATP\",\"Duba\u00ef\",\"Ga\u00ebl Monfils\",\"monfils\",\"Rotterdam\"],\"articleSection\":[\"Actualit\u00e9s\",\"Sports de raquette\",\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/\",\"name\":\"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Gael-Monfils-Dubai\u0308.png\",\"datePublished\":\"2019-02-28T13:10:08+00:00\",\"dateModified\":\"2019-02-28T13:31:27+00:00\",\"description\":\"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Gael-Monfils-Dubai\u0308.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/02\\\/Gael-Monfils-Dubai\u0308.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales","description":"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/","og_locale":"fr_FR","og_type":"article","og_title":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales","og_description":"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.","og_url":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2019-02-28T13:10:08+00:00","article_modified_time":"2019-02-28T13:31:27+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales","datePublished":"2019-02-28T13:10:08+00:00","dateModified":"2019-02-28T13:31:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/"},"wordCount":219,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png","keywords":["ATP","Duba\u00ef","Ga\u00ebl Monfils","monfils","Rotterdam"],"articleSection":["Actualit\u00e9s","Sports de raquette","Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/","url":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/","name":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png","datePublished":"2019-02-28T13:10:08+00:00","dateModified":"2019-02-28T13:31:27+00:00","description":"Apr\u00e8s deux premiers tours bien ma\u00eetris\u00e9s dont un gros combat face \u00e0 Marin Cilic, Ga\u00ebl Monfils \u00e9tait oppos\u00e9 au Lituanien Berankis en quart de finale.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/02\/Gael-Monfils-Dubai\u0308.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/atp-dubai-gael-monfils-se-complique-la-tache-mais-rallie-les-demi-finales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"ATP Duba\u00ef : Ga\u00ebl Monfils se complique la t\u00e2che mais rallie les demi-finales"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/34360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=34360"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/34360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/34361"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=34360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=34360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=34360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}