{"id":345920,"date":"2023-01-18T18:49:59","date_gmt":"2023-01-18T17:49:59","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=345920&#038;preview=true&#038;preview_id=345920"},"modified":"2023-01-18T19:18:06","modified_gmt":"2023-01-18T18:18:06","slug":"euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/","title":{"rendered":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&rsquo;armada am\u00e9ricaine de \u00c7ukurova"},"content":{"rendered":"<p align=\"justify\"><em><strong>EUROLIGUE FEMMES 2022\/23 &#8211; Ce n&rsquo;\u00e9tait pas le bon match pour relancer une dynamique. Avant-derni\u00e8res de leur groupe d&rsquo;EuroLigue, les joueuses du Basket Landes avaient fort \u00e0 faire face au club turc de \u00c7ukurova et ses stars de la WNBA. Les Fran\u00e7aises ont souffert d&rsquo;un d\u00e9ficit athl\u00e9tique pendant tout le match, et s&rsquo;inclinent finalement 75-69.<\/strong><\/em><\/p>\n<p align=\"justify\">68 sur 75. C&rsquo;est la part des points marqu\u00e9s par <strong>cinq joueuses de \u00c7ukurova ce soir, toutes am\u00e9ricaines (ou naturalis\u00e9es) et pensionnaires de la WNBA<\/strong>. Face \u00e0 cette armada, les joueuses du Basket Landes ont eu bien du mal \u00e0 rivaliser. Les int\u00e9rieures <strong>Tiffany Hayes<\/strong> (21 points) et <strong>Elizabeth Williams<\/strong> (12 points, 7 rebonds) ont notamment encha\u00een\u00e9 les post-ups, sans qu&rsquo;aucune landaise ne puisse les d\u00e9fendre. La meneuse <strong>Chelsea Gray<\/strong>, tout juste <a href=\"https:\/\/dicodusport.fr\/blog\/iliana-rupert-troisieme-championne-wnba-francaise-de-lhistoire\/\">championne WNBA avec les Las Vegas Aces<\/a>, s&rsquo;est quant \u00e0 elle appliqu\u00e9e \u00e0 les servir (16 points, 8 passes). De mani\u00e8re g\u00e9n\u00e9rale, il y avait une classe d&rsquo;\u00e9cart au niveau athl\u00e9tique entre les deux \u00e9quipes. Ce qui a fait souffrir les Fran\u00e7aises des deux c\u00f4t\u00e9s du terrain.<\/p>\n<p align=\"justify\">C\u00f4t\u00e9 Basket Landes, l&rsquo;\u00e9ternelle <strong>C\u00e9line Dumerc<\/strong> a tout de m\u00eame r\u00e9ussi \u00e0 survoler les d\u00e9bats (14 points). C&rsquo;est la seule joueuse de son \u00e9quipe qui termine avec un plus\/minus positif. L&rsquo;int\u00e9rieure <strong>Regan Magarity<\/strong> a elle livr\u00e9 une belle bataille dans la raquette (14 points, 11 rebonds). <strong>Marine Fauthoux<\/strong>, enfin, signe une de ses pires prestations de la saison, bien g\u00ean\u00e9e par la d\u00e9fense adverse. L&rsquo;arri\u00e8re internationale termine avec 8 points \u00e0 3\/9 au tir, mais surtout 7 pertes de balle. Une prestation en contraste avec son dernier match, o\u00f9<a href=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j9-fauthoux-porte-un-basket-landes-renversant-bourges-costaud-face-a-bologne\/\"> elle avait offert la victoire aux siennes avec 25 points<\/a>. Cette d\u00e9faite marque <strong>la cinqui\u00e8me sur les six derniers matchs<\/strong> toutes comp\u00e9titions confondues pour Basket Landes. Une r\u00e9action sera attendue lors d&rsquo;un match de championnat capital face \u00e0 l&rsquo;ASVEL, dimanche soir.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83e\udd1d \ud835\udc13\ud835\udc1e\ud835\udc1a\ud835\udc26\ud835\udc30\ud835\udc28\ud835\udc2b\ud835\udc24<a href=\"https:\/\/twitter.com\/hashtag\/EuroLeagueWomen?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroLeagueWomen<\/a> | <a href=\"https:\/\/twitter.com\/BasketLandes?ref_src=twsrc%5Etfw\">@BasketLandes<\/a> <a href=\"https:\/\/t.co\/gkTEdBsVCy\">pic.twitter.com\/gkTEdBsVCy<\/a><\/p>\n<p>\u2014 EuroLeague Women (@EuroLeagueWomen) <a href=\"https:\/\/twitter.com\/EuroLeagueWomen\/status\/1615760832184610816?ref_src=twsrc%5Etfw\">January 18, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROLIGUE FEMMES 2022\/23 &#8211; Ce n&rsquo;\u00e9tait pas le bon match pour relancer une dynamique. Avant-derni\u00e8res de leur groupe d&rsquo;EuroLigue, les joueuses du Basket Landes avaient fort \u00e0 faire face au club turc de \u00c7ukurova et ses stars de la WNBA. Les Fran\u00e7aises ont souffert d&rsquo;un d\u00e9ficit athl\u00e9tique pendant tout le match, et s&rsquo;inclinent finalement 75-69. [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":345943,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2305],"tags":[13487,5424,27824],"class_list":["post-345920","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basket-landes","tag-celine-dumerc","tag-euroligue-femmes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&#039;armada am\u00e9ricaine de \u00c7ukurova<\/title>\n<meta name=\"description\" content=\"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n&#039;ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&#039;armada am\u00e9ricaine de \u00c7ukurova\" \/>\n<meta property=\"og:description\" content=\"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n&#039;ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-18T17:49:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-18T18:18:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tom Compayrot\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&#039;armada am\u00e9ricaine de \u00c7ukurova\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Tom_Cprt\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\"},\"author\":{\"name\":\"Tom Compayrot\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7\"},\"headline\":\"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&rsquo;armada am\u00e9ricaine de \u00c7ukurova\",\"datePublished\":\"2023-01-18T17:49:59+00:00\",\"dateModified\":\"2023-01-18T18:18:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\"},\"wordCount\":353,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png\",\"keywords\":[\"Basket Landes\",\"C\u00e9line Dumerc\",\"EuroLigue Femmes\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\",\"name\":\"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l'armada am\u00e9ricaine de \u00c7ukurova\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png\",\"datePublished\":\"2023-01-18T17:49:59+00:00\",\"dateModified\":\"2023-01-18T18:18:06+00:00\",\"description\":\"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n'ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&rsquo;armada am\u00e9ricaine de \u00c7ukurova\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7\",\"name\":\"Tom Compayrot\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg\",\"caption\":\"Tom Compayrot\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/Tom_Cprt\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/tom\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l'armada am\u00e9ricaine de \u00c7ukurova","description":"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n'ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l'armada am\u00e9ricaine de \u00c7ukurova","og_description":"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n'ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-18T17:49:59+00:00","article_modified_time":"2023-01-18T18:18:06+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png","type":"image\/png"}],"author":"Tom Compayrot","twitter_card":"summary_large_image","twitter_title":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l'armada am\u00e9ricaine de \u00c7ukurova","twitter_creator":"@https:\/\/twitter.com\/Tom_Cprt","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/"},"author":{"name":"Tom Compayrot","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7"},"headline":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&rsquo;armada am\u00e9ricaine de \u00c7ukurova","datePublished":"2023-01-18T17:49:59+00:00","dateModified":"2023-01-18T18:18:06+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/"},"wordCount":353,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png","keywords":["Basket Landes","C\u00e9line Dumerc","EuroLigue Femmes"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/","name":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l'armada am\u00e9ricaine de \u00c7ukurova","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png","datePublished":"2023-01-18T17:49:59+00:00","dateModified":"2023-01-18T18:18:06+00:00","description":"En difficult\u00e9 cette saison en EuroLigue, les joueuses du Basket Landes n'ont pas r\u00e9ussi \u00e0 se relancer en Turquie, sur le parquet de \u00c7ukurova.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-femmes-j10-basket-landes-prend-la-foudre-par-larmada-americaine-de-cukurova\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue Femmes (J10) : Basket Landes prend la foudre par l&rsquo;armada am\u00e9ricaine de \u00c7ukurova"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/bf1e4f404e108bd2be5b447b16bde9a7","name":"Tom Compayrot","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Tom-Compayrot-150x150.jpg","caption":"Tom Compayrot"},"description":"Journaliste\/r\u00e9dacteur depuis mars 2017 - Amoureux de la petite balle jaune et du gros ballon orange qui tra\u00eene sa carcasse sur Dicodusport depuis 2017. Rafael Nadal et LeBron James sont les meilleurs joueurs de l'histoire.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Tom_Cprt"],"url":"https:\/\/dicodusport.fr\/blog\/author\/tom\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/345920","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=345920"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/345920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/345943"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=345920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=345920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=345920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}