{"id":346254,"date":"2023-01-19T16:28:54","date_gmt":"2023-01-19T15:28:54","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=346254&#038;preview=true&#038;preview_id=346254"},"modified":"2023-01-19T17:27:41","modified_gmt":"2023-01-19T16:27:41","slug":"mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/","title":{"rendered":"Mercato : Alex Arrate se rapproche finalement de la Pro D2"},"content":{"rendered":"<p align=\"justify\"><em><strong>TOP 14 2022-2023 &#8211; Selon le Midi Olympique, Alex Arrate (Stade Fran\u00e7aos) devrait finalement s&rsquo;engager avec Vannes pour la saison prochaine.\u00a0<\/strong><\/em><\/p>\n<p align=\"justify\">Le centre de 25 ans arrive en fin de contrat avec le <strong>Stade Fran\u00e7ais Paris<\/strong> et ne devrait pas \u00eatre conserv\u00e9. Le club parisien a d\u00e9j\u00e0 recrut\u00e9 \u00e0 ce poste et <strong>Alex<\/strong> <strong>Arrate<\/strong> va donc devoir trouver un nouveau challenge. Alors qu&rsquo;il \u00e9tait en contact avanc\u00e9 avec le <strong>Castres<\/strong> <strong>Olympique<\/strong>, l&rsquo;op\u00e9ration est finalement tomb\u00e9e \u00e0 l&rsquo;eau. L&rsquo;ancien joueur du Biarritz Olympique devrait finalement rebondir en <strong>Pro<\/strong> <strong>D2<\/strong>, en Bretagne, selon nos confr\u00e8res.<\/p>\n<p align=\"justify\"><strong>Alex<\/strong> <strong>Arrate<\/strong> a visit\u00e9 les installations de Vannes il y a peu de temps et un accord contractuel serait proche entre les deux parties. La formation de <strong>Pro<\/strong> <strong>D2<\/strong> voulait se renforcer au centre puisque plusieurs de ses joueurs \u00e0 ce poste sont en fin de contrat. C&rsquo;est le cas pour <strong>Sacha<\/strong> <strong>Valleau<\/strong>, <strong>Dan<\/strong> <strong>Hollinshead<\/strong> et <strong>K\u00e9vin<\/strong> <strong>Burgand<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Le centre du Stade fran\u00e7ais, Alex Arrat\u00e9 (25 ans), un temps pressenti \u00e0 Castres, ne rejoindra finalement pas le Tarn. Selon nos informations, il a r\u00e9cemment visit\u00e9 les installations vannetaises.<a href=\"https:\/\/t.co\/cOMj1B39Hx\">https:\/\/t.co\/cOMj1B39Hx<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1616037882895925248?ref_src=twsrc%5Etfw\">January 19, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; Selon le Midi Olympique, Alex Arrate (Stade Fran\u00e7aos) devrait finalement s&rsquo;engager avec Vannes pour la saison prochaine.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":346257,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[3076,8584],"class_list":["post-346254","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-stade-francais","tag-vannes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mercato : Alex Arrate se rapproche finalement de la Pro D2<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s&#039;engager avec Vannes pour la saison prochaine.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mercato : Alex Arrate se rapproche finalement de la Pro D2\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s&#039;engager avec Vannes pour la saison prochaine.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T15:28:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-19T16:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mercato : Alex Arrate se rapproche finalement de la Pro D2\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Mercato : Alex Arrate se rapproche finalement de la Pro D2\",\"datePublished\":\"2023-01-19T15:28:54+00:00\",\"dateModified\":\"2023-01-19T16:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png\",\"keywords\":[\"Stade Fran\u00e7ais\",\"Vannes\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/\",\"name\":\"Mercato : Alex Arrate se rapproche finalement de la Pro D2\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png\",\"datePublished\":\"2023-01-19T15:28:54+00:00\",\"dateModified\":\"2023-01-19T16:27:41+00:00\",\"description\":\"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s'engager avec Vannes pour la saison prochaine.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mercato : Alex Arrate se rapproche finalement de la Pro D2\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mercato : Alex Arrate se rapproche finalement de la Pro D2","description":"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s'engager avec Vannes pour la saison prochaine.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/","og_locale":"fr_FR","og_type":"article","og_title":"Mercato : Alex Arrate se rapproche finalement de la Pro D2","og_description":"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s'engager avec Vannes pour la saison prochaine.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-19T15:28:54+00:00","article_modified_time":"2023-01-19T16:27:41+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Mercato : Alex Arrate se rapproche finalement de la Pro D2","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Mercato : Alex Arrate se rapproche finalement de la Pro D2","datePublished":"2023-01-19T15:28:54+00:00","dateModified":"2023-01-19T16:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png","keywords":["Stade Fran\u00e7ais","Vannes"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/","url":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/","name":"Mercato : Alex Arrate se rapproche finalement de la Pro D2","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png","datePublished":"2023-01-19T15:28:54+00:00","dateModified":"2023-01-19T16:27:41+00:00","description":"TOP 14 2022-2023 - Selon le Midi Olympique, Alex Arrate devrait finalement s'engager avec Vannes pour la saison prochaine.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Mercato-Alex-Arrate-se-rapproche-finalement-de-la-Pro-D2.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mercato-alex-arrate-se-rapproche-finalement-de-la-pro-d2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mercato : Alex Arrate se rapproche finalement de la Pro D2"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/346254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=346254"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/346254\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/346257"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=346254"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=346254"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=346254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}