{"id":346318,"date":"2023-01-19T21:20:25","date_gmt":"2023-01-19T20:20:25","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=346318&#038;preview=true&#038;preview_id=346318"},"modified":"2023-01-20T02:54:09","modified_gmt":"2023-01-20T01:54:09","slug":"euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/","title":{"rendered":"EuroLigue (J20) : L&rsquo;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e"},"content":{"rendered":"<p align=\"justify\"><em><a style=\"font-weight: bold;\" href=\"https:\/\/dicodusport.fr\/blog\/?s=euroligue\">EUROLIGUE 2022-2023<\/a><b> &#8211; L&rsquo;AS Monaco n&rsquo;y arrive toujours pas \u00e0 l&rsquo;ext\u00e9rieur. La Roca Team a conc\u00e9d\u00e9 sa quatri\u00e8me d\u00e9faite de suite hors de ses bases sur le parquet du Fenerbah\u00e7e, 98-94. Au terme d&rsquo;un final haletant, les Mon\u00e9gasques ont \u00e9chou\u00e9 \u00e0 renverser le club stambouliote. Avec un bilan de 12 victoires pour 8 d\u00e9faites, la Roca Team glisse au 5e rang du classement.<\/b><\/em><\/p>\n<p align=\"justify\">D\u2019entr\u00e9e, l\u2019<a href=\"https:\/\/dicodusport.fr\/blog\/euroligue-las-monaco-est-elle-equipee-pour-aller-chercher-le-titre\/\"><b>AS Monaco<\/b><\/a> prend le bouillon dans une salle incandescente. Les Turcs se montrent extr\u00eamement adroits et creusent un r\u00e9el \u00e9cart (17-8). Dominateurs au rebond et dans le sillage d\u2019un <b>Donatas Motiejunas<\/b> efficace, les Mon\u00e9gasques parviennent \u00e0 calmer progressivement les ardeurs adverses en recollant d\u00e8s la fin du premier quart (20-20).<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">John Brown arrache une \u00e9galisation miraculeuse&#8230;<\/h2>\n<p align=\"justify\">Si les Turcs repartent fort dans la foul\u00e9e, <b>Yacouba Ouattara<\/b> r\u00e9pond en claquant les deux premiers shoots ext\u00e9rieurs de la Roca Team. Inarr\u00eatable, il en plante un troisi\u00e8me quelques minutes plus tard, participant grandement \u00e0 l\u2019\u00e9norme run effectu\u00e9 (20-6) pour prendre plus de dix points d\u2019avance (42-30). \u00c0 la baguette, <b>Mike James<\/b> shoote peu, mais grappille des lancers, capte des rebonds et distille des passes. Le meneur am\u00e9ricain est sur un quasi triple-double de moyenne \u00e0 la pause (10 points, 6 rebonds, 4 passes), alors que l\u2019ASM m\u00e8ne en Turquie (47-39).<\/p>\n<p align=\"justify\">Malheureusement, cet avantage va fondre comme neige au soleil au fil du troisi\u00e8me quart. <strong>Scottie Wilbekin<\/strong> (19 points) se montre percutant alors que l&rsquo;attaque mon\u00e9gasque envoie des briques sur le cercle. Les Turcs ont totalement pris l&rsquo;ascendant au rebond, et retrouvent une adresse infernale. Les hommes de Sasa Obradovic abordent la derni\u00e8re p\u00e9riode sur un fil, et ne se rassurent pas en accumulant les pertes de balle. Pouss\u00e9 par son public, le <em>Fener<\/em> creuse petit \u00e0 petit l&rsquo;\u00e9cart et compte sept points d&rsquo;avance \u00e0 l&rsquo;aube du money time. Entre <strong>Marko Guduric<\/strong>, <strong>Nigel Hayes-Davis<\/strong> et <strong>Johnathan Motley<\/strong> (16 points, 8 rebonds), l&rsquo;ASM n&rsquo;arrive plus \u00e0 cadenasser une attaque trouvant des solutions \u00e0 foison.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">John Brown forces to overtime at the Ulker Arena!<\/p>\n<p>Another five minutes between Fenerbah\u00e7e Beko Istanbul and AS Monaco in one of the best EuroLeague game of the season.<a href=\"https:\/\/twitter.com\/hashtag\/basketball?src=hash&amp;ref_src=twsrc%5Etfw\">#basketball<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Baloncesto?src=hash&amp;ref_src=twsrc%5Etfw\">#Baloncesto<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/EuroLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroLeague<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Fenerbahce?src=hash&amp;ref_src=twsrc%5Etfw\">#Fenerbahce<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FenerbahceBeko?src=hash&amp;ref_src=twsrc%5Etfw\">#FenerbahceBeko<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ASMonaco?src=hash&amp;ref_src=twsrc%5Etfw\">#ASMonaco<\/a> <a href=\"https:\/\/t.co\/XAijD7k3KC\">pic.twitter.com\/XAijD7k3KC<\/a><\/p>\n<p>\u2014 Matteo Andreani (@matty_vanpersie) <a href=\"https:\/\/twitter.com\/matty_vanpersie\/status\/1616163234330853382?ref_src=twsrc%5Etfw\">January 19, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">&#8230; mais les Turcs font la diff\u00e9rence<\/h2>\n<p align=\"justify\"><strong>Nick Calathes<\/strong> pense alors tuer le match en claquant trois paniers cons\u00e9cutifs. Mais au bout d&rsquo;un come-back \u00e0 l&rsquo;arrach\u00e9e, <strong>John Brown<\/strong> \u00e9galise \u00e0 la derni\u00e8re seconde en r\u00e9cup\u00e9rant une tentative \u00e9chou\u00e9e de James (84-84) ! Malgr\u00e9 tout, l&rsquo;adresse ne sera pas suffisante pour mettre en danger les Turcs men\u00e9s par un Wilbekin d\u00e9terminant.<strong> Mike James<\/strong> va \u00e9chouer \u00e0 deux reprises pour recoller au score. Un triste symbole de sa soir\u00e9e au tir (5\/17). Au final, les Stambouliotes l&#8217;emportent sur le score de 98-94, et passent l&rsquo;ASM au classement.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u2694\ufe0f La <a href=\"https:\/\/twitter.com\/hashtag\/RocaTeam?src=hash&amp;ref_src=twsrc%5Etfw\">#RocaTeam<\/a> s\u2019est battue jusqu\u2019au bout mais s\u2019incline \ud83c\udd9a <a href=\"https:\/\/twitter.com\/FBBasketbol?ref_src=twsrc%5Etfw\">@FBBasketbol<\/a> \ud83c\uddf9\ud83c\uddf7 Nos Roca Boys ont r\u00e9alis\u00e9 un match de haut niveau \ud83d\udc4f <a href=\"https:\/\/t.co\/JIpOhjPEXb\">pic.twitter.com\/JIpOhjPEXb<\/a><\/p>\n<p>\u2014 AS Monaco Basket \ud83c\uddf2\ud83c\udde8 (@ASMonaco_Basket) <a href=\"https:\/\/twitter.com\/ASMonaco_Basket\/status\/1616167493063806976?ref_src=twsrc%5Etfw\">January 19, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>UROLIGUE 2022-2023 &#8211; L&rsquo;AS Monaco n&rsquo;y arrive toujours pas \u00e0 l&rsquo;ext\u00e9rieur. La Roca Team a conc\u00e9d\u00e9 sa quatri\u00e8me d\u00e9faite de suite hors de ses bases sur le parquet du Fenerbah\u00e7e, 98-94. Au terme d&rsquo;un final haletant, les Mon\u00e9gasques ont \u00e9chou\u00e9 \u00e0 renverser le club stambouliote. Avec un bilan de 12 victoires pour 8 d\u00e9faites, la Roca Team glisse au 5e rang du classement.<\/p>\n","protected":false},"author":55,"featured_media":346345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[47001],"tags":[1691,181,4897,19252,24],"class_list":["post-346318","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-euroligue","tag-as-monaco","tag-euroligue","tag-fenerbahce","tag-mike-james","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>EuroLigue (J20) : L&#039;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e<\/title>\n<meta name=\"description\" content=\"L&#039;AS Monaco s&#039;est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d&#039;EuroLigue.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EuroLigue (J20) : L&#039;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\" \/>\n<meta property=\"og:description\" content=\"L&#039;AS Monaco s&#039;est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d&#039;EuroLigue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-19T20:20:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-20T01:54:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Maxime Cazenave\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"EuroLigue (J20) : L&#039;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Maxime_Caze\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/\"},\"author\":{\"name\":\"Maxime Cazenave\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\"},\"headline\":\"EuroLigue (J20) : L&rsquo;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\",\"datePublished\":\"2023-01-19T20:20:25+00:00\",\"dateModified\":\"2023-01-20T01:54:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png\",\"keywords\":[\"AS Monaco\",\"Euroligue\",\"Fenerbah\u00e7e\",\"Mike James\",\"sport\"],\"articleSection\":[\"EuroLigue\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/\",\"name\":\"EuroLigue (J20) : L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png\",\"datePublished\":\"2023-01-19T20:20:25+00:00\",\"dateModified\":\"2023-01-20T01:54:09+00:00\",\"description\":\"L'AS Monaco s'est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d'EuroLigue.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/01\\\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png\",\"width\":800,\"height\":445,\"caption\":\"EuroLigue (J20) L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EuroLigue (J20) : L&rsquo;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/37def232098a7a5cbab3974a3690abb0\",\"name\":\"Maxime Cazenave\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Maxime-Cazenave-150x150.jpg\",\"caption\":\"Maxime Cazenave\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Maxime_Caze\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/maximec\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"EuroLigue (J20) : L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e","description":"L'AS Monaco s'est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d'EuroLigue.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/","og_locale":"fr_FR","og_type":"article","og_title":"EuroLigue (J20) : L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e","og_description":"L'AS Monaco s'est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d'EuroLigue.","og_url":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-19T20:20:25+00:00","article_modified_time":"2023-01-20T01:54:09+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png","type":"image\/png"}],"author":"Maxime Cazenave","twitter_card":"summary_large_image","twitter_title":"EuroLigue (J20) : L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e","twitter_creator":"@https:\/\/twitter.com\/Maxime_Caze","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/"},"author":{"name":"Maxime Cazenave","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0"},"headline":"EuroLigue (J20) : L&rsquo;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e","datePublished":"2023-01-19T20:20:25+00:00","dateModified":"2023-01-20T01:54:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png","keywords":["AS Monaco","Euroligue","Fenerbah\u00e7e","Mike James","sport"],"articleSection":["EuroLigue"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/","url":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/","name":"EuroLigue (J20) : L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png","datePublished":"2023-01-19T20:20:25+00:00","dateModified":"2023-01-20T01:54:09+00:00","description":"L'AS Monaco s'est inclin\u00e9e \u00e0 Istanbul sur le parquet du Fenerbah\u00e7e dans le cadre de la 20e journ\u00e9e d'EuroLigue.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/EuroLigue-J20-LAS-Monaco-cede-sur-le-parquet-du-Fenerbahce.png","width":800,"height":445,"caption":"EuroLigue (J20) L'AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/euroligue-j20-l-as-monaco-cede-sur-le-parquet-du-fenerbahce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"EuroLigue (J20) : L&rsquo;AS Monaco c\u00e8de sur le parquet du Fenerbah\u00e7e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/37def232098a7a5cbab3974a3690abb0","name":"Maxime Cazenave","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Maxime-Cazenave-150x150.jpg","caption":"Maxime Cazenave"},"description":"Journaliste\/R\u00e9dacteur depuis 2012 - Berc\u00e9 par l\u2019amour des Girondins de Bordeaux, les \u00e9checs de Christophe Moreau sur le Tour de France sous l'\u00e8re Lance Armstrong et le fade-away l\u00e9tal de Dirk Nowitzki, ma passion d\u00e9vorante pour le sport a toujours \u00e9t\u00e9 un pan incontournable de ma vie. Transmettre ma passion \u00e0 l\u2019\u00e9crit a \u00e9t\u00e9 une transition naturelle. Suiveur assidu de basket et de hockey sur glace, je garde toujours un peu de place pour suivre le cyclisme, le football et le maximum de performances fran\u00e7aises.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Maxime_Caze"],"url":"https:\/\/dicodusport.fr\/blog\/author\/maximec\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/346318","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=346318"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/346318\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/346345"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=346318"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=346318"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=346318"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}