{"id":348443,"date":"2023-01-25T13:51:29","date_gmt":"2023-01-25T12:51:29","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=348443&#038;preview=true&#038;preview_id=348443"},"modified":"2023-01-25T13:51:29","modified_gmt":"2023-01-25T12:51:29","slug":"ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/","title":{"rendered":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France"},"content":{"rendered":"<p align=\"justify\"><em><strong>SKI FREERIDE &#8211; Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.<\/strong><\/em><\/p>\n<p align=\"justify\">La France empoche un nouveau titre mondial en freeride. \u00c0 17 ans,\u00a0<strong>Zo\u00e9 Delzoppo\u00a0<\/strong>est sacr\u00e9e championne du monde juniors en ski. Sur les pentes raides de Kappl, en Autriche, la rideuse de la Clusaz a montr\u00e9 de la fluidit\u00e9 et un contr\u00f4le certain de ses mouvements. Un run technique avec tr\u00e8s peu d&rsquo;h\u00e9sitations. Elle obtient un score de 1 300 points.<\/p>\n<p align=\"justify\">Les skieuses tricolores ont assur\u00e9 en r\u00e9alisant le doubl\u00e9 sur l&rsquo;\u00e9preuve dames.\u00a0<strong>Mila De Le Rue<\/strong>, fille de\u00a0<strong>Xavier,<\/strong> a pris la deuxi\u00e8me place avec une note atteignant aussi les 1 000 (1 020). L&rsquo;Am\u00e9ricaine <strong>Tia Schenk<\/strong> termine \u00e0 la 3e place et un score de 840 points. Chez les hommes, le Canadien\u00a0<strong>Marcus Goguen\u00a0<\/strong>a impressionn\u00e9 et remporte ces championnats du monde juniors avec le m\u00eame total que\u00a0<strong>Zo\u00e9 Delzoppo.<\/strong><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La rideuse de la Clusaz Zo\u00e9 Delzoppo est devenue championne du monde juniors de freeride en ski ! Un titre qui revient souvent \u00e0 la France ces derni\u00e8res ann\u00e9es. <a href=\"https:\/\/twitter.com\/hashtag\/FWJ?src=hash&amp;ref_src=twsrc%5Etfw\">#FWJ<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/FWT?src=hash&amp;ref_src=twsrc%5Etfw\">#FWT<\/a><\/p>\n<p>\u2014 Pierre Gorce (@pierregorce12) <a href=\"https:\/\/twitter.com\/pierregorce12\/status\/1618209760918253570?ref_src=twsrc%5Etfw\">January 25, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SKI FREERIDE &#8211; Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.<\/p>\n","protected":false},"author":61,"featured_media":348459,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9217],"tags":[],"class_list":["post-348443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France<\/title>\n<meta name=\"description\" content=\"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\" \/>\n<meta property=\"og:description\" content=\"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-01-25T12:51:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Pierre Gorce\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/pierregorce12\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\"},\"author\":{\"name\":\"Pierre Gorce\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\"},\"headline\":\"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\",\"datePublished\":\"2023-01-25T12:51:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\"},\"wordCount\":208,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png\",\"articleSection\":[\"Ski\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\",\"name\":\"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png\",\"datePublished\":\"2023-01-25T12:51:29+00:00\",\"description\":\"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png\",\"width\":800,\"height\":445,\"caption\":\"Ski freeride Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018\",\"name\":\"Pierre Gorce\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg\",\"caption\":\"Pierre Gorce\"},\"description\":\"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.\",\"sameAs\":[\"https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12\"],\"birthDate\":\"1999-08-29\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France","description":"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France","og_description":"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.","og_url":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-01-25T12:51:29+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png","type":"image\/png"}],"author":"Pierre Gorce","twitter_card":"summary_large_image","twitter_title":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France","twitter_creator":"@https:\/\/twitter.com\/pierregorce12","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/"},"author":{"name":"Pierre Gorce","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018"},"headline":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France","datePublished":"2023-01-25T12:51:29+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/"},"wordCount":208,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png","articleSection":["Ski"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/","url":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/","name":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png","datePublished":"2023-01-25T12:51:29+00:00","description":"Aux championnats du monde juniors de freeride en Autriche, Zo\u00e9 Delzoppo a d\u00e9croch\u00e9 le titre devant sa jeune compatriote Mila De Le Rue.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/01\/Ski-freeride-Zoe-Delzoppo-championne-du-monde-juniors-double-pour-la-France.png","width":800,"height":445,"caption":"Ski freeride Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ski-freeride-zoe-delzoppo-championne-du-monde-juniors-double-pour-la-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ski freeride : Zo\u00e9 Delzoppo championne du monde juniors, doubl\u00e9 pour la France"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0eaf70b33d703a1a66b1155ac1bda018","name":"Pierre Gorce","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/IMG_20211214_233053_722-150x150.jpg","caption":"Pierre Gorce"},"description":"Couteau suisse venant tout droit de Haute-Savoie. Habitu\u00e9 \u00e0 regarder du sport depuis petit, j'en ai maintenant fait mon m\u00e9tier. Des sports d'hiver au surf, en passant par le tennis, la F1, le handball et l'athl\u00e9tisme, j'essaie d'avoir mes yeux sur l'enti\u00e8ret\u00e9 de l'actualit\u00e9. Jeune homme berc\u00e9 par les exploits de Jean-Baptiste Grange, Sebastian Vettel et des Experts. Membre de la g\u00e9n\u00e9ration 1999 comme Luka Doncic, Sydney McLaughlin, Lando Norris et Loana Lecomte, mais avec beaucoup moins de talent qu'eux.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/pierregorce12"],"birthDate":"1999-08-29","url":"https:\/\/dicodusport.fr\/blog\/author\/pierreg\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/348443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=348443"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/348443\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/348459"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=348443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=348443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=348443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}