{"id":350824,"date":"2023-02-01T16:36:40","date_gmt":"2023-02-01T15:36:40","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=350824&#038;preview=true&#038;preview_id=350824"},"modified":"2023-02-01T18:29:42","modified_gmt":"2023-02-01T17:29:42","slug":"etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/","title":{"rendered":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><b><i>CYCLISME SUR ROUTE 2023 &#8211; Apr\u00e8s une journ\u00e9e marqu\u00e9e par les bordures, Arnaud De Lie (Lotto-Dstny) a gagn\u00e9 la premi\u00e8re \u00e9tape de l&rsquo;\u00c9toile de Bess\u00e8ges \u00e0 Bellegarde, ce mercredi. Il a devanc\u00e9 Mads Pedersen (Trek Segafredo) et Beno\u00eet Cosnefroy (AG2R Citro\u00ebn).\u00a0<\/i><\/b><\/p>\n<p style=\"text-align: justify;\">D&rsquo;abord, un trio s&rsquo;est rapidement constitu\u00e9 \u00e0 l&rsquo;avant de la course avec <strong>Ayco Bastiaens<\/strong> (Alpecin-Deceuninck), <strong>Jean-Louis Le Ny<\/strong> (Nice M\u00e9tropole C\u00f4te d&rsquo;Azur) et <strong>Simon Pellaud<\/strong> (Tudor Pro Cycling Team). L&rsquo;avance est mont\u00e9e jusqu&rsquo;\u00e0 un peu moins de six minutes, avant que le peloton ne se mette \u00e0 rouler fort en file indienne.<\/p>\n<h2 style=\"text-align: justify;\">Le vent anime la course<\/h2>\n<p style=\"text-align: justify;\">Ensuite, plusieurs \u00e9ventails se sont form\u00e9s \u00e0 cause du vent \u00e0 70 kilom\u00e8tres du terme. Dans un premier peloton, <strong>Mads Pedersen<\/strong> (Trek-Segafredo), <strong>Michal Kwiatkowski, Ben Turner<\/strong> (INEOS Grenadiers), <strong>Beno\u00eet Cosnefroy<\/strong> (AG2R Citro\u00ebn) ou encore <a href=\"https:\/\/dicodusport.fr\/blog\/arnaud-de-lie-bien-plus-quun-sprinteur\/\"><strong>Arnaud De Lie<\/strong><\/a> (Lotto-Dstny) \u00e9taient pr\u00e9sents, alors que le tenant du titre <strong>Benjamin Thomas<\/strong> (Cofidis), le vainqueur du <a href=\"https:\/\/dicodusport.fr\/blog\/classement-grand-prix-la-marseillaise-2023\/\">Grand Prix La Marseillaise<\/a> <strong>Neilson Powless<\/strong> (EF Education EasyPost) ainsi que <strong>Thibaut Pinot<\/strong> (Groupama FDJ) et <strong>Magnus Cort Nielsen<\/strong> (EF Education EasyPost) ont \u00e9t\u00e9 pi\u00e9g\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s avoir distanc\u00e9 <strong>Jean-Louis Le Ny<\/strong> (Nice M\u00e9tropole C\u00f4te d&rsquo;Azur), <strong>Ayco Bastiaens<\/strong> (Alpecin-Deceuninck) et <strong>Simon Pellaud<\/strong> (Tudor Pro Cycling Team) ont \u00e9t\u00e9 aval\u00e9s par le premier peloton \u00e0 37 kilom\u00e8tres de l&rsquo;arriv\u00e9e. N\u00e9anmoins, apr\u00e8s un gros travail de leurs co\u00e9quipiers et apr\u00e8s avoir accus\u00e9 une minute de retard, <strong>Benjamin Thomas<\/strong> (Cofidis), <strong>Neilson Powless<\/strong> et <strong>Magnus Cort<\/strong> (EF Education EasyPost), entre autres, ont \u00e9t\u00e9 ramen\u00e9s \u00e0 10 kilom\u00e8tres de l&rsquo;arriv\u00e9e dans le premier peloton.<\/p>\n<p style=\"text-align: justify;\">Puis, <strong>Jasper De Buyst<\/strong> (Lotto-Dstny) a effectu\u00e9 un gros travail au pied de la bosse finale, longue de 700 m\u00e8tres \u00e0 8 % de moyenne, avant que <strong>Mads Pedersen<\/strong> (Trek Segafredo) ne produise son effort dans les plus forts pourcentages. Seuls <strong>Arnaud De Lie<\/strong> (Lotto Dstny) et <strong>Beno\u00eet Cosnefroy<\/strong> (AG2R Citro\u00ebn) ont suivi le Danois. Pour rappel, Pedersen s&rsquo;\u00e9tait impos\u00e9 l&rsquo;an dernier \u00e0 Bellegarde.<\/p>\n<h2 style=\"text-align: justify;\">Arnaud De Lie en patron<\/h2>\n<p style=\"text-align: justify;\">Finalement, <strong>Arnaud De Lie<\/strong> (Lotto-Dstny) a d\u00e9bord\u00e9 <strong>Mads Pedersen<\/strong> (Trek Segafredo) avant l&rsquo;entame de la derni\u00e8re ligne droite pour d\u00e9crocher le deuxi\u00e8me bouquet de la saison apr\u00e8s la <a href=\"https:\/\/dicodusport.fr\/blog\/classement-classique-de-la-communaute-de-valence-2023\/\">Classique de Valence<\/a>. Il a devanc\u00e9 <strong>Mads Pedersen<\/strong> (Trek Segafredo) et <strong>Beno\u00eet Cosnefroy<\/strong> (AG2R Citro\u00ebn). <strong>Dylan Teuns<\/strong> (Israel Premier Tech) a pris la quatri\u00e8me place \u00e0 trois secondes devant <strong>Andrea Piccolo<\/strong> (EF Education EasyPost) et <strong>Mattias Skjelmose Jensen<\/strong> (Trek Segafredo).<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La victoire pour Arnaud De Lie !<\/p>\n<p>Le jeune Belge devance Mads Pedersen et Beno\u00eet Cosnefroy dans le final en bosse de la premi\u00e8re \u00e9tape de l\u2019\u00c9toile de Bess\u00e8ges. <a href=\"https:\/\/twitter.com\/hashtag\/lequipeVELO?src=hash&amp;ref_src=twsrc%5Etfw\">#lequipeVELO<\/a> <a href=\"https:\/\/t.co\/YeGZVUtO1f\">pic.twitter.com\/YeGZVUtO1f<\/a><\/p>\n<p>\u2014 la chaine L&rsquo;\u00c9quipe (@lachainelequipe) <a href=\"https:\/\/twitter.com\/lachainelequipe\/status\/1620807948267044864?ref_src=twsrc%5Etfw\">February 1, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><b><a href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-classement-1ere-etape\/\">Le classement de la 1\u00e8re \u00e9tape de l&rsquo;\u00c9toile de Bess\u00e8ges<\/a>\u00a0<\/b><\/li>\n<li style=\"text-align: justify;\"><strong><a href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-classement-general\/\">Le classement g\u00e9n\u00e9ral de l&rsquo;\u00c9toile de Bess\u00e8ges<\/a>\u00a0<\/strong><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-profil-des-etapes\/\" target=\"_blank\" rel=\"noopener\"><strong>\u00c9toile de Bess\u00e8ges 2023 : le profil des \u00e9tapes<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>CYCLISME SUR ROUTE 2023 &#8211; Apr\u00e8s une journ\u00e9e marqu\u00e9e par les bordures, Arnaud De Lie (Lotto Dstny) a gagn\u00e9 la premi\u00e8re \u00e9tape de l&rsquo;\u00c9toile de Bess\u00e8ges \u00e0 Bellegarde, ce mercredi. Il a devanc\u00e9 Mads Pedersen (Trek Segafredo) et Beno\u00eet Cosnefroy (AG2R Citro\u00ebn).\u00a0<\/p>\n","protected":false},"author":48,"featured_media":350972,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[574,11197,3645,24],"class_list":["post-350824","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-cyclisme","tag-cyclisme-sur-route","tag-etoile-de-besseges","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape<\/title>\n<meta name=\"description\" content=\"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s&#039;est impos\u00e9 sur la premi\u00e8re \u00e9tape de l&#039;\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s&#039;est impos\u00e9 sur la premi\u00e8re \u00e9tape de l&#039;\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-01T15:36:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-01T17:29:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Emilien Descampiaux\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/LRoisDuPeloton\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\"},\"author\":{\"name\":\"Emilien Descampiaux\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\"},\"headline\":\"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape\",\"datePublished\":\"2023-02-01T15:36:40+00:00\",\"dateModified\":\"2023-02-01T17:29:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png\",\"keywords\":[\"Cyclisme\",\"Cyclisme sur route\",\"Etoile de Bess\u00e8ges\",\"sport\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\",\"name\":\"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png\",\"datePublished\":\"2023-02-01T15:36:40+00:00\",\"dateModified\":\"2023-02-01T17:29:42+00:00\",\"description\":\"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s'est impos\u00e9 sur la premi\u00e8re \u00e9tape de l'\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png\",\"width\":800,\"height\":445,\"caption\":\"Arnaud De Lie, l'\u00e9nigme - Photo Icon Sport\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7\",\"name\":\"Emilien Descampiaux\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg\",\"caption\":\"Emilien Descampiaux\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.\",\"sameAs\":[\"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton\",\"https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape","description":"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s'est impos\u00e9 sur la premi\u00e8re \u00e9tape de l'\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape","og_description":"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s'est impos\u00e9 sur la premi\u00e8re \u00e9tape de l'\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.","og_url":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","article_published_time":"2023-02-01T15:36:40+00:00","article_modified_time":"2023-02-01T17:29:42+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png","type":"image\/png"}],"author":"Emilien Descampiaux","twitter_card":"summary_large_image","twitter_title":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/LRoisDuPeloton","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/"},"author":{"name":"Emilien Descampiaux","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7"},"headline":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape","datePublished":"2023-02-01T15:36:40+00:00","dateModified":"2023-02-01T17:29:42+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png","keywords":["Cyclisme","Cyclisme sur route","Etoile de Bess\u00e8ges","sport"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/","url":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/","name":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png","datePublished":"2023-02-01T15:36:40+00:00","dateModified":"2023-02-01T17:29:42+00:00","description":"CYCLISME SUR ROUTE 2023 - Arnaud De Lie s'est impos\u00e9 sur la premi\u00e8re \u00e9tape de l'\u00c9toile de Bess\u00e8ges ce mercredi \u00e0 Bellegarde.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Etoile-de-Besseges-2023-Arnaud-De-Lie-remporte-la-1ere-etape-1.png","width":800,"height":445,"caption":"Arnaud De Lie, l'\u00e9nigme - Photo Icon Sport"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/etoile-de-besseges-2023-arnaud-de-lie-remporte-la-1ere-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00c9toile de Bess\u00e8ges 2023 : Arnaud De Lie remporte la 1\u00e8re \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/6db4bae06b171592211be385b32876a7","name":"Emilien Descampiaux","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Emilien-Descampiaux-150x150.jpg","caption":"Emilien Descampiaux"},"description":"Journaliste\/r\u00e9dacteur depuis 2014 - Fan de la classe de Frank Vandenbroucke, je vis cyclisme (et de ses paysages) depuis plus de 20 ans. Je suis tr\u00e8s impliqu\u00e9 sur mes diff\u00e9rents r\u00e9seaux sociaux pour partager ma passion sur le monde et l'Histoire de la bicyclette avec ma voix sur les images en noir et blanc du succ\u00e8s de Rik Van Steenbergen lors du Ronde sur le V\u00e9lodrome de Gand.","sameAs":["https:\/\/www.facebook.com\/groups\/LesRoisDuPeloton","https:\/\/x.com\/https:\/\/twitter.com\/LRoisDuPeloton"],"url":"https:\/\/dicodusport.fr\/blog\/author\/emiliend\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/350824","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=350824"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/350824\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/350972"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=350824"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=350824"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=350824"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}