{"id":355151,"date":"2023-02-13T07:57:46","date_gmt":"2023-02-13T06:57:46","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=355151&#038;preview=true&#038;preview_id=355151"},"modified":"2023-02-13T08:42:55","modified_gmt":"2023-02-13T07:42:55","slug":"lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/","title":{"rendered":"L&rsquo;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e"},"content":{"rendered":"<p align=\"justify\"><em><strong>TOP 14 2022-2023 &#8211; Selon le Midi Olympique, l&rsquo;ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0<\/strong><\/em><\/p>\n<p align=\"justify\">L&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/asm-clermont-auvergne-une-periode-delicate-et-inquietante\/\"><strong>ASM Clermont<\/strong><\/a> serait entr\u00e9e en m\u00e9diation avec le salary cap manager de la <strong>LNR<\/strong>,<strong> Samuel Gauthier<\/strong>, d\u00e8s le mois d&rsquo;avril 2022, pour trouver un accord financier. Pour la saison 202-2023, l&rsquo;<strong>ASM<\/strong> <strong>Clermont<\/strong> aurait donc d\u00e9pass\u00e9 le salary cap de pas moins de 320 000 euros. Deux raisons principales \u00e0 cela : la baisse du salary cap ces derni\u00e8res ann\u00e9es, de 300 000 euros environ, m\u00eame s&rsquo;il ne bougera plus par exemple pour la saison prochaine. Mais aussi la baisse du nombre d&rsquo;internationaux \u00e0 l&rsquo;<strong>ASM Clermont<\/strong>, puisque chaque club re\u00e7oit un cr\u00e9dit suppl\u00e9mentaire de 180 000 euros par joueur convoqu\u00e9.<\/p>\n<p align=\"justify\">Comme l&rsquo;<strong>ASM Clermont<\/strong> s&rsquo;est signal\u00e9e pour son probl\u00e8me, elle ne risque rien sportivement, mais va trouver un accord financier avec <strong>Samuel<\/strong> <strong>Gauthier<\/strong>, salary cap manager de la <strong>LNR<\/strong>, pour mettre fin \u00e0 ce litige. Ce n&rsquo;est pas le premier club qui en vient \u00e0 une m\u00e9diation pour son salary cap, puisque le <strong>Stade<\/strong> <strong>Fran\u00e7ais<\/strong> et <strong>Montpellier<\/strong> sont d\u00e9j\u00e0 pass\u00e9s par l\u00e0 par le pass\u00e9.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Trop verts en Une de Midi Olympique !<\/p>\n<p>Pour lire le journal &gt; <a href=\"https:\/\/t.co\/hO2HfN5zfm\">https:\/\/t.co\/hO2HfN5zfm<\/a> <a href=\"https:\/\/t.co\/SnOhaVvidM\">pic.twitter.com\/SnOhaVvidM<\/a><\/p>\n<p>\u2014 RUGBYRAMA (@RugbyramaFR) <a href=\"https:\/\/twitter.com\/RugbyramaFR\/status\/1624873241868177410?ref_src=twsrc%5Etfw\">February 12, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; Selon le Midi Olympique, l&rsquo;ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0\u00a0<\/p>\n","protected":false},"author":1,"featured_media":275470,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,47050],"tags":[1208,16878,1183,111],"class_list":["post-355151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-asm-clermont","tag-breve","tag-clermont","tag-top-14"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>L&#039;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - Selon le Midi Olympique, l&#039;ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - Selon le Midi Olympique, l&#039;ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-13T06:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T07:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"L&#039;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"L&rsquo;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e\",\"datePublished\":\"2023-02-13T06:57:46+00:00\",\"dateModified\":\"2023-02-13T07:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\"},\"wordCount\":237,\"commentCount\":3,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png\",\"keywords\":[\"ASM Clermont\",\"br\u00e8ve\",\"clermont\",\"Top 14\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\",\"name\":\"L'ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png\",\"datePublished\":\"2023-02-13T06:57:46+00:00\",\"dateModified\":\"2023-02-13T07:42:55+00:00\",\"description\":\"TOP 14 2022-2023 - Selon le Midi Olympique, l'ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&rsquo;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"L'ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e","description":"TOP 14 2022-2023 - Selon le Midi Olympique, l'ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/","og_locale":"fr_FR","og_type":"article","og_title":"L'ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e","og_description":"TOP 14 2022-2023 - Selon le Midi Olympique, l'ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-02-13T06:57:46+00:00","article_modified_time":"2023-02-13T07:42:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"L'ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"L&rsquo;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e","datePublished":"2023-02-13T06:57:46+00:00","dateModified":"2023-02-13T07:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/"},"wordCount":237,"commentCount":3,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png","keywords":["ASM Clermont","br\u00e8ve","clermont","Top 14"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/","url":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/","name":"L'ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png","datePublished":"2023-02-13T06:57:46+00:00","dateModified":"2023-02-13T07:42:55+00:00","description":"TOP 14 2022-2023 - Selon le Midi Olympique, l'ASM Clermont a d\u00e9pass\u00e9 de 320 000 euros le salary cap de la saison 2022-2023.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/11\/Mercato-Damian-Penaud-entre-Toulouse-et-Clermont-1.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/lasm-clermont-a-largement-depasse-le-salary-cap-la-saison-passee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"L&rsquo;ASM Clermont a largement d\u00e9pass\u00e9 le salary cap la saison pass\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/355151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=355151"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/355151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/275470"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=355151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=355151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=355151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}