{"id":358086,"date":"2023-02-21T22:59:24","date_gmt":"2023-02-21T21:59:24","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=358086&#038;preview=true&#038;preview_id=358086"},"modified":"2025-09-16T08:57:02","modified_gmt":"2025-09-16T06:57:02","slug":"ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/","title":{"rendered":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield"},"content":{"rendered":"<p align=\"justify\"><em><strong>LIGUE DES CHAMPIONS 2022\/2023 &#8211; Dans une rencontre aller totalement folle o\u00f9 Liverpool a rapidement pris les devants avec deux buts, le Real Madrid a compl\u00e8tement renvers\u00e9 la situation, propuls\u00e9 par les doubl\u00e9s de Vin\u00edcius J\u00fanior et de Karim Benzema, respectivement dans le premier et second acte de cette confrontation remport\u00e9e par les Merengue (2-5).\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Le remake de la derni\u00e8re finale de <strong>Ligue des Champions<\/strong> qui s\u2019est d\u00e9roul\u00e9e au Stade de France a pris place \u00e0 Anfield. Les Reds, en difficult\u00e9 au huiti\u00e8me rang de Premier League, re\u00e7oivent le <strong>Real Madrid<\/strong>, dauphin du Bar\u00e7a en Liga. Une rencontre totalement folle puisque <strong>Liverpool<\/strong> ayant r\u00e9alis\u00e9 une entame parfaite en marquant rapidement et en doublant la mise, a \u00e9t\u00e9 totalement d\u00e9pass\u00e9 en fin de premi\u00e8re p\u00e9riode par la Maison Blanche, qui s\u2019est mise \u00e0 d\u00e9rouler d\u00e8s le d\u00e9but du second acte. Liverpool n&rsquo;a remport\u00e9 aucun de ses sept derniers duels face au Real Madrid en Coupe d&rsquo;Europe.<\/span><\/p>\n<h2 style=\"text-align: justify;\">Liverpool lance les hostilit\u00e9s<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La rencontre d\u00e9bute tr\u00e8s fort avec l\u2019ouverture du score liverpuldienne d\u00e8s la 4\u00e8me minute de jeu. Une situation o\u00f9 <strong>Darwin N\u00fa\u00f1ez<\/strong> h\u00e9rite d\u2019un ballon de <strong>Mohamed Salah<\/strong>. L&rsquo;Uruguayen s\u2019illustre magnifiquement d\u2019une talonnade du pied droit venant tromper la vigilance de <strong>Thibaut Courtois<\/strong> (1-0). <strong>N\u00fa\u00f1ez<\/strong> inscrit son quatri\u00e8me but cette saison dans la comp\u00e9tition. Liverpool \u00e9tablit une entame record avec ce but \u00e9tant le plus rapide de l\u2019histoire \u00e0 Anfield en C1. <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Marquer un but du talon face au Real Madrid en Ligue des Champions n\u2019est plus arriv\u00e9 depuis un certain <strong>Didier Drogba<\/strong> avec le maillot de Galatasaray, remontant au 9 avril 2013. Passeur d\u00e9cisif sur la r\u00e9alisation, <strong>Mohamed Salah<\/strong> s\u2019introduit du c\u00f4t\u00e9 droit et d\u00e9clenche une frappe de la patte gauche qui fr\u00f4le le cadre (12e). Deux minutes plus tard, l&rsquo;\u00c9gyptien trouve \u00e0 son tour le chemin des filets en profitant d\u2019une grosse erreur du portier madril\u00e8ne. Un contr\u00f4le totalement rat\u00e9 sur la passe de son co\u00e9quipier <strong>Dani Carvajal<\/strong> profitant au num\u00e9ro 11 de Liverpool pour prendre le large en doublant la mise (14e ; 2-0).\u00a0<\/span><\/p>\n<h2 style=\"text-align: justify;\">La remontada du Real Madrid<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Mais la Ligue des Champions est habitu\u00e9e aux rebondissements. L\u2019avance des Reds vient se r\u00e9duire gr\u00e2ce \u00e0 la pr\u00e9cision chirurgicale de<strong> Vin\u00edcius J\u00fanior<\/strong> avec une tentative enroul\u00e9e face \u00e0 trois d\u00e9fenseurs adverses et venant vaincre <strong>Alisson<\/strong> (21e ; 2-1). L\u2019attaquant br\u00e9silien marque pour la cinqui\u00e8me fois cette saison en Ligue des Champions. Le natif de S\u00e3o Gon\u00e7alo n\u2019est pas rassasi\u00e9 et vient trouver les ressources pour s\u2019offrir un doubl\u00e9. Bien aid\u00e9 par une erreur c\u00f4t\u00e9 gardien cette fois-ci de <strong>Alisson<\/strong> qui relance sur le buteur madril\u00e8ne \u00e0 qui, le doubl\u00e9 est offert sur un plateau. Ainsi que sa sixi\u00e8me r\u00e9alisation de la saison sur la sc\u00e8ne europ\u00e9enne (36e ; 2-2). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les erreurs de la part des deux gardiens sur le terrain se payent tr\u00e8s cher. Les compteurs sont remis \u00e0 \u00e9galit\u00e9 \u00e0 la fin du premier acte o\u00f9 tout aurait pu encore basculer. <strong>Trent Alexander-Arnold<\/strong> se montre \u00e0 son tour mais voit son opportunit\u00e9 capt\u00e9e par <strong>Thibaut Courtois<\/strong> (45e). Le danger change imm\u00e9diatement de camp avant la pause sur une situation o\u00f9 l\u2019homme du doubl\u00e9 centre en direction de<strong> Rodrygo<\/strong>, ce dernier se retrouve seul face \u00e0 la cage mais aper\u00e7oit le retour in extremis de <strong>Andrew Robertson<\/strong> pour tacler le ballon et lui donner la trajectoire du corner (45+1).\u00a0\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"in\">\u23f8\ufe0f DC: <a href=\"https:\/\/twitter.com\/LFC?ref_src=twsrc%5Etfw\">@LFC<\/a> 2-2 <a href=\"https:\/\/twitter.com\/realmadrid?ref_src=twsrc%5Etfw\">@RealMadrid<\/a><br \/>\n\u26bd Darwin 04, M. Salah 14&prime;; <a href=\"https:\/\/twitter.com\/vinijr?ref_src=twsrc%5Etfw\">@vinijr<\/a> 21&prime;, 36&prime;<a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/UhZwecsHgs\">pic.twitter.com\/UhZwecsHgs<\/a><\/p>\n<p>\u2014 Real Madrid C.F. (@realmadrid) <a href=\"https:\/\/twitter.com\/realmadrid\/status\/1628135294452043812?ref_src=twsrc%5Etfw\">February 21, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\">L\u2019\u00e9veil de Karim Benzema<\/h2>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">La seconde p\u00e9riode maintient son rythme spectaculaire et cette fois-ci c\u2019est en deux minutes que les filets tremblent. A son origine, un coup franc de <strong>Luka Modri\u0107<\/strong> trouve la t\u00eate de <strong>\u00c9der Milit\u00e3o<\/strong>, une action o\u00f9 <strong>Alisson<\/strong> reste fig\u00e9 sur sa ligne de but (47e ; 2-3). Le d\u00e9fenseur central br\u00e9silien inscrit son premier but cette saison dans la coupe aux grandes oreilles. Tout comme <strong>Karim Benzema<\/strong> d\u00e9bloquant son compteur \u00e0 l\u2019issue de cette confrontation (55e). Le Ballon d\u2019Or frappe de sa patte gauche et profite de la d\u00e9viation de <strong>Darwin N\u00fa\u00f1ez<\/strong>, premier buteur de ce match fou, dans son propre but avec cette trajectoire trompant la vigilance de <strong>Alisson<\/strong> (2-4). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">L\u2019attaquant fran\u00e7ais r\u00e9enclenche la machine \u00e0 buts et ne perd pas de temps \u00e0 maintenir la cadence retrouv\u00e9e. \u00c0 la 67\u00e8me minute, il profite du ballon transmis par <strong>Vin\u00edcius J\u00fanior<\/strong>, <strong>Karim Benzema<\/strong> vient vaincre d\u2019un crochet <strong>Alisson<\/strong> avanc\u00e9 de son but sur cette action, pour aboutir sur une frappe du gauche venant finir sa course dans les filets liverpuldiens pour la cinqui\u00e8me fois de suite (2-5). La Maison Blanche passe \u00e0 c\u00f4t\u00e9 de la soir\u00e9e parfaite suite \u00e0 la sortie sur blessure au niveau du bas du dos de <strong>Rodrygo<\/strong> (81e). <\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"font-weight: 400;\">Les Reds pensent obtenir un p\u00e9nalty dans le temps additionnel, ce qui n\u2019est pas de l\u2019avis de l\u2019arbitre. Une situation o\u00f9 <strong>Mohamed Salah<\/strong> est bouscul\u00e9 au point de p\u00e9nalty (90+2). Dans une rencontre o\u00f9 Liverpool a pris l\u2019avantage avec deux buts, le Real Madrid affirme son statut de tenant du titre face \u00e0 son ancien finaliste et prend une grande option dans la validation du ticket pour rejoindre les quarts de finale de la comp\u00e9tition.\u00a0<\/span><\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"in\">\ud83c\udfc1 FP: <a href=\"https:\/\/twitter.com\/LFC?ref_src=twsrc%5Etfw\">@LFC<\/a> 2-5 <a href=\"https:\/\/twitter.com\/realmadrid?ref_src=twsrc%5Etfw\">@RealMadrid<\/a><br \/>\n\u26bd Darwin 04, M. Salah 14&prime;; <a href=\"https:\/\/twitter.com\/vinijr?ref_src=twsrc%5Etfw\">@vinijr<\/a> 21&prime;, 36&prime;, <a href=\"https:\/\/twitter.com\/edermilitao?ref_src=twsrc%5Etfw\">@edermilitao<\/a> 47&prime;, <a href=\"https:\/\/twitter.com\/Benzema?ref_src=twsrc%5Etfw\">@Benzema<\/a> 55&prime;, 67&prime;<a href=\"https:\/\/twitter.com\/hashtag\/UCL?src=hash&amp;ref_src=twsrc%5Etfw\">#UCL<\/a> <a href=\"https:\/\/t.co\/rgcmSHQFy4\">pic.twitter.com\/rgcmSHQFy4<\/a><\/p>\n<p>\u2014 Real Madrid C.F. (@realmadrid) <a href=\"https:\/\/twitter.com\/realmadrid\/status\/1628151352764383236?ref_src=twsrc%5Etfw\">February 21, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>LIGUE DES CHAMPIONS 2022\/2023 &#8211; Dans une rencontre aller totalement folle o\u00f9 Liverpool a rapidement pris les devants avec deux buts, le Real Madrid a compl\u00e8tement renvers\u00e9 la situation, propuls\u00e9 par les doubl\u00e9s de Vin\u00edcius J\u00fanior et de Karim Benzema, respectivement dans le premier et second acte de cette confrontation remport\u00e9e par les Merengue (2-5).\u00a0<\/p>\n","protected":false},"author":62,"featured_media":358095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[47250],"tags":[16878,75,419,3120,521],"class_list":["post-358086","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ligue-des-champions-de-football","tag-breve","tag-football","tag-ligue-des-champions","tag-liverpool","tag-real-madrid"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield<\/title>\n<meta name=\"description\" content=\"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s&#039;impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield\" \/>\n<meta property=\"og:description\" content=\"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s&#039;impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-21T21:59:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-16T06:57:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Andr\u00e9a Lamy\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\"},\"author\":{\"name\":\"Andr\u00e9a Lamy\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31\"},\"headline\":\"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield\",\"datePublished\":\"2023-02-21T21:59:24+00:00\",\"dateModified\":\"2025-09-16T06:57:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\"},\"wordCount\":958,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png\",\"keywords\":[\"br\u00e8ve\",\"Football\",\"Ligue des champions\",\"Liverpool\",\"Real Madrid\"],\"articleSection\":[\"Ligue des Champions de football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\",\"name\":\"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png\",\"datePublished\":\"2023-02-21T21:59:24+00:00\",\"dateModified\":\"2025-09-16T06:57:02+00:00\",\"description\":\"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s'impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png\",\"width\":800,\"height\":445,\"caption\":\"Ligue des champions Le Real Madrid renverse Liverpool \u00e0 Anfield\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31\",\"name\":\"Andr\u00e9a Lamy\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg\",\"caption\":\"Andr\u00e9a Lamy\"},\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/andrea-lamy\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield","description":"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s'impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield","og_description":"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s'impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-02-21T21:59:24+00:00","article_modified_time":"2025-09-16T06:57:02+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png","type":"image\/png"}],"author":"Andr\u00e9a Lamy","twitter_card":"summary_large_image","twitter_title":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/"},"author":{"name":"Andr\u00e9a Lamy","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31"},"headline":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield","datePublished":"2023-02-21T21:59:24+00:00","dateModified":"2025-09-16T06:57:02+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/"},"wordCount":958,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png","keywords":["br\u00e8ve","Football","Ligue des champions","Liverpool","Real Madrid"],"articleSection":["Ligue des Champions de football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/","name":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png","datePublished":"2023-02-21T21:59:24+00:00","dateModified":"2025-09-16T06:57:02+00:00","description":"LIGUE DES CHAMPIONS 2022\/2023 - Le Real Madrid s'impos\u00e9 sur la pelouse de Liverpool ce mardi soir (2-5), en 8\u00e8me de finale aller.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Ligue-des-champions-Le-Real-Madrid-renverse-Liverpool-a-Anfield.png","width":800,"height":445,"caption":"Ligue des champions Le Real Madrid renverse Liverpool \u00e0 Anfield"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-des-champions-le-real-madrid-renverse-liverpool-a-anfield\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue des Champions : Le Real Madrid renverse Liverpool \u00e0 Anfield"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/5b73f4b55b8683f37e9f75d6dc039f31","name":"Andr\u00e9a Lamy","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2022\/03\/Andrea-150x150.jpg","caption":"Andr\u00e9a Lamy"},"url":"https:\/\/dicodusport.fr\/blog\/author\/andrea-lamy\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/358086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=358086"}],"version-history":[{"count":1,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/358086\/revisions"}],"predecessor-version":[{"id":611396,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/358086\/revisions\/611396"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/358095"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=358086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=358086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=358086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}