{"id":358143,"date":"2023-02-23T21:49:26","date_gmt":"2023-02-23T20:49:26","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=358143&#038;preview=true&#038;preview_id=358143"},"modified":"2023-02-23T22:01:40","modified_gmt":"2023-02-23T21:01:40","slug":"eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/","title":{"rendered":"Eurocoupe femmes : Larges victoires pour Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL en quarts de finale aller"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>EUROCOUPE FEMMES &#8211; Trois clubs fran\u00e7ais sont engag\u00e9s en quarts de finale dont deux qui s&rsquo;affrontaient. Villeneuve-d&rsquo;Ascq l&#8217;emporte \u00e0 domicile face \u00e0 Saragosse (84-68) tandis que l&rsquo;ASVEL n&rsquo;a laiss\u00e9 aucune chance \u00e0 Angers (88-58).<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Kennedy Burke<\/strong> r\u00e9pond au panier \u00e0 3 points de <strong>Leonie Fiebich<\/strong> et le match est lanc\u00e9. \u00c0 domicile, <strong>Villeneuve-d&rsquo;Ascq<\/strong> fait la course en t\u00eate et profite d&rsquo;un faible pourcentage au tir de <strong>Saragosse<\/strong> (27%). De +11 \u00e0 la fin du premier quart-temps, l&rsquo;<strong>ESBVA-LM<\/strong> ne cesse d&rsquo;accroitre son avance. Avec notamment un beau 60% d&rsquo;adresse \u00e0 3 points. Les <strong>Guerri\u00e8res<\/strong> rentrent aux vestiaires en menant 45-26. Plus adroites que leurs adversaires, elles imposent leur intensit\u00e9 et font preuve d&rsquo;anticipation pour dominer les d\u00e9bats.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\"><strong>Saragosse<\/strong> a montr\u00e9 un autre visage durant la seconde p\u00e9riode. Mais les Espagnoles partaient de trop loin. Port\u00e9 par une grande <strong>Kamiah Smalls<\/strong> (21 points, 8 rebonds, 9 passes d\u00e9cisives, 3 interceptions),<strong> Villeneuve-d&rsquo;Ascq<\/strong> s&rsquo;impose finalement 84-68.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Le match retour aura lieu en Espagne <strong>jeudi prochain \u00e0 20h<\/strong>. Avec en vue une demi-finale 100% fran\u00e7aise, vraisemblablement face \u00e0 Lyon.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">\u2694\ufe0f \ud835\udc15\ud835\udc08\ud835\udc02\ud835\udc13\ud835\udc0e\ud835\udc08\ud835\udc11\ud835\udc04 \u2694\ufe0f<\/p>\n<p>\ud83c\udfc6 <a href=\"https:\/\/twitter.com\/EuroCupWomen?ref_src=twsrc%5Etfw\">@EuroCupWomen<\/a><\/p>\n<p>\ud83d\udc49 Le r\u00e9sultat du match vous est propos\u00e9 par <a href=\"https:\/\/twitter.com\/maisonsarlogis?ref_src=twsrc%5Etfw\">@maisonsarlogis<\/a> Lille, constructeur de maisons individuelles sur-mesure en France.<\/p>\n<p>\ud835\udc14\ud835\udc0d \ud835\udc0f\ud835\udc08\ud835\udc04\ud835\udc03 \ud835\udc04\ud835\udc0d \ud835\udc03\ud835\udc04\ud835\udc0c\ud835\udc08-\ud835\udc05\ud835\udc08\ud835\udc0d\ud835\udc00\ud835\udc0b\ud835\udc04 !<\/p>\n<p>84\/68 \u2705<a href=\"https:\/\/twitter.com\/hashtag\/AllezLesGuerrieres?src=hash&amp;ref_src=twsrc%5Etfw\">#AllezLesGuerrieres<\/a> \ud83d\udd34\u26aa <a href=\"https:\/\/t.co\/3zpeOgC5Df\">pic.twitter.com\/3zpeOgC5Df<\/a><\/p>\n<p>\u2014 ESBVA-LM (@ESBVALM) <a href=\"https:\/\/twitter.com\/ESBVALM\/status\/1628860799899865090?ref_src=twsrc%5Etfw\">February 23, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 align=\"justify\">L&rsquo;ASVEL taille patron<\/h2>\n<p style=\"text-align: justify;\">En championnat, l&rsquo;<strong>ASVEL<\/strong> s&rsquo;\u00e9tait impos\u00e9e lors des deux rencontres face \u00e0 <strong>Angers<\/strong> (+17 et +11). Et en favori de la comp\u00e9tition, Lyon a d\u00e9roul\u00e9 son basket pour prendre 20 points d&rsquo;avance en milieu de deuxi\u00e8me quart-temps (35-15). Ainsi, l&rsquo;ASVEL rentre aux vestiaires avec un avantage cons\u00e9quent (54-29). Sous la pression de Lyon, Angers est catastrophique sous le panier (22% contre 77% \u00e0 2 points) en plus d&rsquo;\u00eatre d\u00e9pass\u00e9 par la vitesse des Lyonnaises.<\/p>\n<p style=\"text-align: justify;\">Au retour des vestiaires, Lyon enchaine les paniers et les grosses d\u00e9fenses. Le match tourne \u00e0 la d\u00e9monstration et les contre-attaques lyonnaises se multiplient. Une nouvelle fois, toutes les Lyonnaises ont pu avoir des minutes et se reposer. Avec une <strong>Sandrine Gruda<\/strong> qui monte en puissance depuis son retour \u00e0 la comp\u00e9tition en d\u00e9cembre (16 points \u00e0 88%, 4 rebonds),<strong> Lyon<\/strong> n&rsquo;a fait qu&rsquo;une bouch\u00e9e de l&rsquo;UFAB. L&rsquo;ASVEL s&rsquo;impose 88-58 et prend une option sur les demies.<\/p>\n<p>En excellente position, Lyon se d\u00e9placera \u00e0 Angers <strong>mercredi prochain (20h)<\/strong> pour valider sa place en demi-finales.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">\ud83d\udea8 When in doubt, leave it to <a href=\"https:\/\/twitter.com\/MarineJ5?ref_src=twsrc%5Etfw\">@MarineJ5<\/a> \u26a1\ud83d\udca8<br \/>\n<a href=\"https:\/\/twitter.com\/hashtag\/EuroCupWomen?src=hash&amp;ref_src=twsrc%5Etfw\">#EuroCupWomen<\/a> | <a href=\"https:\/\/twitter.com\/ASVEL_Feminin?ref_src=twsrc%5Etfw\">@ASVEL_Feminin<\/a> <a href=\"https:\/\/t.co\/MgkLyZPF8n\">pic.twitter.com\/MgkLyZPF8n<\/a><\/p>\n<p>\u2014 EuroCup Women (@EuroCupWomen) <a href=\"https:\/\/twitter.com\/EuroCupWomen\/status\/1628843963217240065?ref_src=twsrc%5Etfw\">February 23, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EUROCOUPE FEMMES &#8211; Trois clubs fran\u00e7ais sont engag\u00e9s en quarts de finale dont deux qui s&rsquo;affrontaient. Villeneuve-d&rsquo;Ascq l&#8217;emporte \u00e0 domicile face \u00e0 Saragosse tandis que l&rsquo;ASVEL n&rsquo;a laiss\u00e9 aucune chance \u00e0 Angers.<\/p>\n","protected":false},"author":12,"featured_media":358701,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2305],"tags":[174,16878,29871,24],"class_list":["post-358143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basket-ball","tag-basket","tag-breve","tag-eurocoupe-femmes","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Eurocoupe femmes : Larges victoires pour Villeneuve-d&#039;Ascq et l&#039;ASVEL en quarts de finale aller<\/title>\n<meta name=\"description\" content=\"EUROCOUPE FEMMES - Villeneuve-d&#039;Ascq l&#039;emporte \u00e0 domicile face \u00e0 Saragosse tandis que l&#039;ASVEL n&#039;a laiss\u00e9 aucune chance \u00e0 Angers.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Eurocoupe femmes : Larges victoires pour Villeneuve-d&#039;Ascq et l&#039;ASVEL en quarts de finale aller\" \/>\n<meta property=\"og:description\" content=\"EUROCOUPE FEMMES - Villeneuve-d&#039;Ascq l&#039;emporte \u00e0 domicile face \u00e0 Saragosse tandis que l&#039;ASVEL n&#039;a laiss\u00e9 aucune chance \u00e0 Angers.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-23T20:49:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-23T21:01:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Arlette Yeye\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Eurocoupe femmes : Larges victoires pour Villeneuve-d&#039;Ascq et l&#039;ASVEL en quarts de finale aller\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Shiclette94\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/\"},\"author\":{\"name\":\"Arlette Yeye\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\"},\"headline\":\"Eurocoupe femmes : Larges victoires pour Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL en quarts de finale aller\",\"datePublished\":\"2023-02-23T20:49:26+00:00\",\"dateModified\":\"2023-02-23T21:01:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/\"},\"wordCount\":418,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg\",\"keywords\":[\"basket\",\"br\u00e8ve\",\"EuroCoupe femmes\",\"sport\"],\"articleSection\":[\"Basket-ball\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/\",\"name\":\"Eurocoupe femmes : Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg\",\"datePublished\":\"2023-02-23T20:49:26+00:00\",\"dateModified\":\"2023-02-23T21:01:40+00:00\",\"description\":\"EUROCOUPE FEMMES - Villeneuve-d'Ascq l'emporte \u00e0 domicile face \u00e0 Saragosse tandis que l'ASVEL n'a laiss\u00e9 aucune chance \u00e0 Angers.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg\",\"width\":800,\"height\":445,\"caption\":\"Eurocoupe femmes Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Eurocoupe femmes : Larges victoires pour Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL en quarts de finale aller\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cce96fa88785bd8573e3d43078ac8c79\",\"name\":\"Arlette Yeye\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g\",\"caption\":\"Arlette Yeye\"},\"description\":\"Journaliste\\\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Shiclette94\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/arlette\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Eurocoupe femmes : Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller","description":"EUROCOUPE FEMMES - Villeneuve-d'Ascq l'emporte \u00e0 domicile face \u00e0 Saragosse tandis que l'ASVEL n'a laiss\u00e9 aucune chance \u00e0 Angers.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/","og_locale":"fr_FR","og_type":"article","og_title":"Eurocoupe femmes : Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller","og_description":"EUROCOUPE FEMMES - Villeneuve-d'Ascq l'emporte \u00e0 domicile face \u00e0 Saragosse tandis que l'ASVEL n'a laiss\u00e9 aucune chance \u00e0 Angers.","og_url":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-02-23T20:49:26+00:00","article_modified_time":"2023-02-23T21:01:40+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg","type":"image\/jpeg"}],"author":"Arlette Yeye","twitter_card":"summary_large_image","twitter_title":"Eurocoupe femmes : Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller","twitter_creator":"@https:\/\/twitter.com\/Shiclette94","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/"},"author":{"name":"Arlette Yeye","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79"},"headline":"Eurocoupe femmes : Larges victoires pour Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL en quarts de finale aller","datePublished":"2023-02-23T20:49:26+00:00","dateModified":"2023-02-23T21:01:40+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/"},"wordCount":418,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg","keywords":["basket","br\u00e8ve","EuroCoupe femmes","sport"],"articleSection":["Basket-ball"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/","url":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/","name":"Eurocoupe femmes : Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg","datePublished":"2023-02-23T20:49:26+00:00","dateModified":"2023-02-23T21:01:40+00:00","description":"EUROCOUPE FEMMES - Villeneuve-d'Ascq l'emporte \u00e0 domicile face \u00e0 Saragosse tandis que l'ASVEL n'a laiss\u00e9 aucune chance \u00e0 Angers.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/02\/Eurocoupe-femmes-Larges-victoires-pour-Villeneuve-dAscq-et-lASVEL-en-quarts-de-finale-aller.jpg","width":800,"height":445,"caption":"Eurocoupe femmes Larges victoires pour Villeneuve-d'Ascq et l'ASVEL en quarts de finale aller"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/eurocoupe-femmes-larges-victoires-pour-villeneuve-dascq-et-lasvel-en-quarts-de-finale-aller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Eurocoupe femmes : Larges victoires pour Villeneuve-d&rsquo;Ascq et l&rsquo;ASVEL en quarts de finale aller"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cce96fa88785bd8573e3d43078ac8c79","name":"Arlette Yeye","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7d26f160c87f008554ddbe248f64f15bce46c2c32725229b50e2a4ef42d38b9e?s=96&d=wp_user_avatar&r=g","caption":"Arlette Yeye"},"description":"Journaliste\/r\u00e9dactrice depuis septembre 2015 - Supportrice de Chelsea, j'ai pour sports de pr\u00e9dilection le handball, l'athl\u00e9tisme et le tennis. Si je tweete plus vite que mon ombre, vous pouvez aussi me retrouver les week-ends sur les playgrounds de Bruxelles pour un petit foot ou basket entre potes. Parcourir la France, l'Europe et plus si affinit\u00e9s pour suivre mes sportifs pr\u00e9f\u00e9r\u00e9s ? Mon kif ! Et c'est avec plaisir que je partage les r\u00e9sultats des sports populaires mais \u00e9galement plus confidentiels pour Dicodusport.","sameAs":["https:\/\/x.com\/https:\/\/twitter.com\/Shiclette94"],"url":"https:\/\/dicodusport.fr\/blog\/author\/arlette\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/358143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=358143"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/358143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/358701"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=358143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=358143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=358143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}