{"id":360442,"date":"2023-03-01T08:42:48","date_gmt":"2023-03-01T07:42:48","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=360442&#038;preview=true&#038;preview_id=360442"},"modified":"2023-03-01T09:23:09","modified_gmt":"2023-03-01T08:23:09","slug":"rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/","title":{"rendered":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>TOP 14 2022-2023 &#8211; De nouveau bless\u00e9 avec le XV de France il y a quelques semaines, Gabin Villi\u00e8re s&rsquo;est fait op\u00e9rer avec succ\u00e8s. L&rsquo;ailier varois pr\u00e9pare d\u00e9j\u00e0 son retour \u00e0 la comp\u00e9tition.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Sur <em>rctplay.tv<\/em>, la plateforme digitale du RC Toulon, <strong>Gabin<\/strong> <strong>Villi\u00e8re<\/strong> a d&rsquo;abord \u00e9voqu\u00e9 cette nouvelle p\u00e9riode loin des terrains. L&rsquo;ailier du <strong>XV de France<\/strong> a tr\u00e8s peu jou\u00e9 depuis plusieurs mois et s&rsquo;il confesse que ce n&rsquo;est pas le plus facile, il essaye de prendre les choses du bon c\u00f4t\u00e9.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">C\u2019est la faute \u00e0 pas de chance. C\u2019est \u00e7a qui est dur, car ce n\u2019est pas la premi\u00e8re fois. Mais voil\u00e0, c\u2019est sur moi que cela tombe \u00e0 nouveau. Je me suis fait op\u00e9rer. Elle s\u2019est bien pass\u00e9e gr\u00e2ce au chirurgien qui me suit depuis un certain moment. Maintenant, il faut avoir un peu de patience pour revenir en forme sur les terrains. C\u2019est un peu long pour l\u2019instant. Ce n\u2019est pas la meilleure p\u00e9riode. Au d\u00e9but, c\u2019est un peu dur car on ne peut rien faire. J\u2019en profite pour me reposer et r\u00e9fl\u00e9chir \u00e0 la suite.<\/p>\n<\/blockquote>\n<h2 style=\"text-align: justify;\">Villi\u00e8re, la Coupe du monde en ligne de mire<\/h2>\n<p style=\"text-align: justify;\">M\u00eame s&rsquo;il ne l&rsquo;\u00e9voque pas directement, <strong>Gabin<\/strong> <strong>Villi\u00e8re<\/strong> a toujours la <a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/rugby\/rugby-a-xv\/coupe-du-monde-de-rugby-2023\/\"><strong>Coupe<\/strong> <strong>du<\/strong> <strong>monde 2023<\/strong><\/a> en ligne de mire, en septembre prochain. Et s&rsquo;il ne veut pas griller les \u00e9tapes, il sait d\u00e9j\u00e0 quand il va revenir \u00e0 la comp\u00e9tition, dans moins de deux mois, s&rsquo;il n&rsquo;y a pas de complications d&rsquo;ici-l\u00e0.<\/p>\n<blockquote>\n<p style=\"text-align: justify;\">L&rsquo;objectif c&rsquo;est de revenir mi-avril, ou au plus tard fin avril. On va faire attention, les d\u00e9lais sont allong\u00e9s pour \u00eatre certain de revenir \u00e0 100%. L\u2019objectif est de ne pas mentir au groupe pour revenir avec toutes ses capacit\u00e9s.<\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">Titulaire \u00e0 l&rsquo;aile avec le <strong>XV de France<\/strong> avant sa blessure, <strong>Gabin<\/strong> <strong>Villi\u00e8re<\/strong> sera en concurrence avec <a href=\"https:\/\/dicodusport.fr\/blog\/ethan-dumortier-un-avenir-tout-trace-avec-les-bleus\/\"><strong>Ethan<\/strong> <strong>Dumortier<\/strong><\/a> pour la Coupe du monde. L&rsquo;ailier lyonnais a r\u00e9alis\u00e9 des performances plus qu&rsquo;int\u00e9ressantes depuis le d\u00e9but du Tournoi des 6 Nations. Ainsi, <strong>Fabien<\/strong> <strong>Galthi\u00e9<\/strong> aura un choix compliqu\u00e9 \u00e0 faire dans quelques mois.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Des nouvelles de <a href=\"https:\/\/twitter.com\/gabinvilliere?ref_src=twsrc%5Etfw\">@gabinvilliere<\/a> \ud83d\udd34\u26ab<\/p>\n<p>D\u00e9couvrez les premiers mots de l&rsquo;international fran\u00e7ais apr\u00e8s sa fracture du p\u00e9ron\u00e9 \ud83d\udcfd\u2935<\/p>\n<p>\u2014 RCT &#8211; RC Toulon (@RCTofficiel) <a href=\"https:\/\/twitter.com\/RCTofficiel\/status\/1630636450525110272?ref_src=twsrc%5Etfw\">February 28, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2022-2023 &#8211; De nouveau bless\u00e9 avec le XV de France il y a quelques semaines, Gabin Villi\u00e8re s&rsquo;est fait op\u00e9rer avec succ\u00e8s. L&rsquo;ailier varois pr\u00e9pare d\u00e9j\u00e0 son retour \u00e0 la comp\u00e9tition.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":360444,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129,47050],"tags":[16878,7679,3078,216],"class_list":["post-360442","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-breve","tag-gabin-villiere","tag-rc-toulon","tag-rct"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14<\/title>\n<meta name=\"description\" content=\"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s&#039;est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s&#039;est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-01T07:42:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-01T08:23:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14\",\"datePublished\":\"2023-03-01T07:42:48+00:00\",\"dateModified\":\"2023-03-01T08:23:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png\",\"keywords\":[\"br\u00e8ve\",\"Gabin Villi\u00e8re\",\"RC Toulon\",\"RCT\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\",\"name\":\"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png\",\"datePublished\":\"2023-03-01T07:42:48+00:00\",\"dateModified\":\"2023-03-01T08:23:09+00:00\",\"description\":\"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s'est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14","description":"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s'est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14","og_description":"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s'est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.","og_url":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-03-01T07:42:48+00:00","article_modified_time":"2023-03-01T08:23:09+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14","datePublished":"2023-03-01T07:42:48+00:00","dateModified":"2023-03-01T08:23:09+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png","keywords":["br\u00e8ve","Gabin Villi\u00e8re","RC Toulon","RCT"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/","name":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png","datePublished":"2023-03-01T07:42:48+00:00","dateModified":"2023-03-01T08:23:09+00:00","description":"TOP 14 2022-2023 - De nouveau bless\u00e9 avec le XV de France, Gabin Villi\u00e8re s'est fait op\u00e9rer avec succ\u00e8s et pr\u00e9pare d\u00e9j\u00e0 son retour.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/RC-Toulon-Gabin-Villiere-annonce-la-date-de-son-retour-en-Top-14.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/rc-toulon-gabin-villiere-annonce-la-date-de-son-retour-en-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"RC Toulon : Gabin Villi\u00e8re annonce la date de son retour en Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/360442","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=360442"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/360442\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/360444"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=360442"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=360442"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=360442"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}