{"id":360820,"date":"2023-03-02T08:33:45","date_gmt":"2023-03-02T07:33:45","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=360820&#038;preview=true&#038;preview_id=360820"},"modified":"2023-03-02T11:50:55","modified_gmt":"2023-03-02T10:50:55","slug":"mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/","title":{"rendered":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>MONDIAUX DE SNOWBOARDCROSS &#8211; Apr\u00e8s la d\u00e9ception de l&rsquo;\u00e9preuve individuelle hier, les Bleus, en l&rsquo;occurrence Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant le bronze.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">C&rsquo;\u00e9tait la soupe \u00e0 la grimace hier pour les Bleus. Sur les comp\u00e9titions individuelles, <a href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-deception-pour-lequipe-de-france\/\">seule Manon Petit-Lenoir s&rsquo;\u00e9tait hiss\u00e9e en finale pour terminer au pied du podium<\/a>. Ainsi, une r\u00e9action \u00e9tait attendue lors de l&rsquo;\u00e9preuve par \u00e9quipes, la France pr\u00e9sentant deux \u00e9quipages de qualit\u00e9 pour aller chercher un podium. Et c&rsquo;est exactement ce qu&rsquo;il s&rsquo;est pass\u00e9.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">C&rsquo;est la paire <strong>Chlo\u00e9 Trespeuch &#8211; Merlin Surget<\/strong> qui a d\u00e9croch\u00e9 la timbale, parvenant en finale. Les Bleus ont profit\u00e9 de la chute de l&rsquo;Am\u00e9ricain <strong>Baumgartner<\/strong> sur le premier run, ce qui leur assurait la m\u00e9daille tant qu&rsquo;ils restaient sur la piste. Mission accomplie par <strong>Chlo\u00e9 Trespeuch<\/strong>, m\u00eame si elle n&rsquo;a rien pu faire contre les \u00e9quipages anglais et autrichiens.<strong> Loan Bozzolo<\/strong> et <strong>Manon Petit-Lenoir,<\/strong> eux, ont but\u00e9 en demi-finales. Les snowboardeurs fran\u00e7ais terminent sur une bonne note, m\u00eame si c&rsquo;est l&rsquo;or qui \u00e9tait esp\u00e9r\u00e9.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">La joie du duo <a href=\"https:\/\/twitter.com\/TrespeuchChloe?ref_src=twsrc%5Etfw\">@TrespeuchChloe<\/a> \/ <a href=\"https:\/\/twitter.com\/hashtag\/MerlinSurget?src=hash&amp;ref_src=twsrc%5Etfw\">#MerlinSurget<\/a> \ud83c\uddeb\ud83c\uddf7 sur la 3e marche du podium du snowboard cross mixte \u00e0 <a href=\"https:\/\/twitter.com\/hashtag\/Bakuriani?src=hash&amp;ref_src=twsrc%5Etfw\">#Bakuriani<\/a> \ud83e\udd49<br \/>\nBravo pour la m\u00e9daille \ud83d\udc4f\ud83c\udffb<br \/>\n\u27a1\ufe0f<a href=\"https:\/\/twitter.com\/Eurosport_FR?ref_src=twsrc%5Etfw\">@Eurosport_FR<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/ChaletClub?src=hash&amp;ref_src=twsrc%5Etfw\">#ChaletClub<\/a> <a href=\"https:\/\/t.co\/EeZtnUIsRQ\">pic.twitter.com\/EeZtnUIsRQ<\/a><\/p>\n<p>\u2014 Chalet \u2744\ufe0f Club (@ChaletClub2021) <a href=\"https:\/\/twitter.com\/ChaletClub2021\/status\/1631201644720398337?ref_src=twsrc%5Etfw\">March 2, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>MONDIAUX DE SNOWBOARDCROSS &#8211; Apr\u00e8s la d\u00e9ception de l&rsquo;\u00e9preuve individuelle hier, les Bleus, en l&rsquo;occurrence Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.<\/p>\n","protected":false},"author":59,"featured_media":360879,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[10126],"tags":[16878,3022,24],"class_list":["post-360820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-snowboard","tag-breve","tag-snowboardcross","tag-sport"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes<\/title>\n<meta name=\"description\" content=\"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\" \/>\n<meta property=\"og:description\" content=\"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-02T07:33:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-02T10:50:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\",\"datePublished\":\"2023-03-02T07:33:45+00:00\",\"dateModified\":\"2023-03-02T10:50:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\"},\"wordCount\":241,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png\",\"keywords\":[\"br\u00e8ve\",\"snowboardcross\",\"sport\"],\"articleSection\":[\"Snowboard\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\",\"name\":\"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png\",\"datePublished\":\"2023-03-02T07:33:45+00:00\",\"dateModified\":\"2023-03-02T10:50:55+00:00\",\"description\":\"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png\",\"width\":800,\"height\":445,\"caption\":\"Mondiaux de snowboardcross Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\/\/www.facebook.com\/sebastien.gente\/\",\"https:\/\/www.instagram.com\/sebgente\/\",\"https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/\",\"https:\/\/x.com\/https:\/\/twitter.com\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes","description":"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/","og_locale":"fr_FR","og_type":"article","og_title":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes","og_description":"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.","og_url":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-03-02T07:33:45+00:00","article_modified_time":"2023-03-02T10:50:55+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes","datePublished":"2023-03-02T07:33:45+00:00","dateModified":"2023-03-02T10:50:55+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/"},"wordCount":241,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png","keywords":["br\u00e8ve","snowboardcross","sport"],"articleSection":["Snowboard"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/","url":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/","name":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png","datePublished":"2023-03-02T07:33:45+00:00","dateModified":"2023-03-02T10:50:55+00:00","description":"MONDIAUX DE SNOWBOARDCROSS - Chlo\u00e9 Trespeuch et Merlin Surget, se sont magnifiquement ressaisis en prenant\u00a0le bronze.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/03\/Mondiaux-de-snowboardcross-Chloe-Trespeuch-et-Merlin-Surget-prennent-le-bronze-par-equipes-1.png","width":800,"height":445,"caption":"Mondiaux de snowboardcross Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/mondiaux-de-snowboardcross-chloe-trespeuch-et-merlin-surget-prennent-le-bronze-par-equipes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Mondiaux de snowboardcross : Chlo\u00e9 Trespeuch et Merlin Surget prennent le bronze par \u00e9quipes"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/360820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=360820"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/360820\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/360879"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=360820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=360820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=360820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}