{"id":36279,"date":"2019-04-03T15:04:31","date_gmt":"2019-04-03T13:04:31","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=36279"},"modified":"2019-04-03T16:03:30","modified_gmt":"2019-04-03T14:03:30","slug":"ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/","title":{"rendered":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong><a href=\"https:\/\/www.estrepublicain.fr\/sport-franc-comtois\/2019\/04\/03\/fc-sochaux-le-president-wing-sang-li-vient-de-demissionner\" target=\"_blank\" rel=\"noopener\">Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d&rsquo;annoncer qu&rsquo;il quittait ses fonctions<\/a>, <a href=\"http:\/\/www.fcsochaux.fr\/fr\/index.html\" target=\"_blank\" rel=\"noopener\">l&rsquo;un des clubs embl\u00e9matiques du paysage footballistique fran\u00e7ais<\/a> traverse une p\u00e9riode plus que d\u00e9licate. A quelques journ\u00e9es de la fin du championnat, il en va de son maintien en Ligue 2 sur le court terme et de sa survie tout simplement \u00e0 long terme.<br \/>\n<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Un petit bol d&rsquo;air ! En ramenant les 3 points de leur d\u00e9placement en terres niortiaises (0-1) vendredi dernier, les hommes d&rsquo;Omar Daf respirent un peu et faute de sortir compl\u00e8tement la t\u00eate de l&rsquo;eau, s&rsquo;extirpent pour le moment de la zone rouge. Si les <em>Jaune et Bleu<\/em> restaient sur deux r\u00e9sultats positifs avec des matchs nuls respectivement face \u00e0 Troyes (0-0) et Metz (1-1), ils n&rsquo;avaient plus go\u00fbt\u00e9 \u00e0 la victoire depuis 2 mois ! Le club vit une crise sportive cette saison et\u00a0depuis sa descente en 2013-2014, il n&rsquo;a jamais sembl\u00e9 \u00eatre en mesure de retrouver l&rsquo;\u00e9lite. Comment ce club historique qui f\u00eatera cette ann\u00e9e ses 90 ans en est arriv\u00e9 \u00e0 ce stade ? Va-t-il se relever de cette situation et rebondir ?<\/p>\n<h1 style=\"text-align: justify;\">Une long\u00e9vit\u00e9 parmi l&rsquo;\u00e9lite fran\u00e7aise<\/h1>\n<p style=\"text-align: justify;\">66, c&rsquo;est le nombre d&rsquo;ann\u00e9es que le FC Sochaux-Montb\u00e9liard a pass\u00e9 au sein de la Divison 1 fran\u00e7aise, puis de la Ligue 1. C&rsquo;est ce qui en faisait jusqu&rsquo;en octobre 2016, le club le plus cap\u00e9 en termes de rencontres disput\u00e9es parmi l&rsquo;\u00e9lite, aujourd&rsquo;hui c&rsquo;est l&rsquo;Olympique de Marseille qui peut se targuer d&rsquo;occuper cette position. D&rsquo;un point de vue historique, il est clairement impossible de dissocier le FC Sochaux-Montb\u00e9liard et Peugeot, le club ayant vu le jour en 1928 par la volont\u00e9 de deux salari\u00e9s de la soci\u00e9t\u00e9 des Automobiles Peugeot, la marque au lion sera l&rsquo;actionnaire principal du club jusqu&rsquo;en 2015 avant de passer la main. Le club doubiste est l&rsquo;un des clubs fondateurs \u00e9galement de la premi\u00e8re division fran\u00e7aise, d&rsquo;o\u00f9 son importance dans le paysage footballistique national.<\/p>\n<h1 style=\"text-align: justify;\">Une formation pl\u00e9biscit\u00e9e, l&rsquo;Europe, puis le n\u00e9ant&#8230;<\/h1>\n<p style=\"text-align: justify;\">Si les d\u00e9buts du FCSM sont couronn\u00e9s de succ\u00e8s avec deux titres nationaux \u00e0 la cl\u00e9 en 1935 et 1938, par la suite, le club a plut\u00f4t c\u00f4toy\u00e9 le ventre mou du championnat r\u00e9ussissant quelques saisons de haut vol avec notamment une demi-finale de Coupe de l&rsquo;UEFA lors de la saison 80-81 sous l&rsquo;impulsion de leur attaquant vedette, un certain Patrick Revelli. Dans un pass\u00e9 proche, nous pouvons rappeler que le FC Sochaux Montb\u00e9liard a \u00e9t\u00e9 finaliste de la Coupe de la Ligue 2003 face \u00e0 l&rsquo;AS Monaco et vainqueur en 2004 face \u00e0 Nantes, avec notamment la fameuse tentative de panenka de Micka\u00ebl Landreau ou encore triomphant de l&rsquo;Olympique de Marseille en Coupe de France en 2007.<\/p>\n<p style=\"text-align: justify;\">Mais ce qui a fait \u00e9galement la renomm\u00e9e des r\u00e9sidents du stade Bonal est son centre de formation, reconnu comme l&rsquo;un des meilleurs de France et pourvoyeur de grands talents, dans une liste non exhaustive nous pouvons citer p\u00eale-m\u00eale des joueurs comme Jo\u00ebl Bats, Franck Silvestre, Franck Sauz\u00e9e, J\u00e9r\u00e9my Mathieu, Beno\u00eet Pedretti, J\u00e9r\u00e9my M\u00e9nez, Marvin Martin ou encore Bernard Genghini.<\/p>\n<div id=\"attachment_36401\" style=\"width: 1002px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36401\" class=\"size-full wp-image-36401\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/J\u00e9r\u00e9my-Menez-pur-produit-sochalien-AFP.jpg\" alt=\"\" width=\"992\" height=\"669\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/J\u00e9r\u00e9my-Menez-pur-produit-sochalien-AFP.jpg 992w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/J\u00e9r\u00e9my-Menez-pur-produit-sochalien-AFP-300x202.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/J\u00e9r\u00e9my-Menez-pur-produit-sochalien-AFP-768x518.jpg 768w\" sizes=\"auto, (max-width: 992px) 100vw, 992px\" \/><p id=\"caption-attachment-36401\" class=\"wp-caption-text\">J\u00e9r\u00e9my Menez, pur produit sochalien &#8211; AFP<\/p><\/div>\n<p style=\"text-align: justify;\">Si le club franc-comtois a donc connu des heures dor\u00e9es dans son pass\u00e9, il semble ne plus \u00eatre que l&rsquo;ombre de lui-m\u00eame depuis sa descente en Ligue 2 \u00e0 l&rsquo;issue de la saison 2013-2014, lors de la derni\u00e8re journ\u00e9e face \u00e0 Evian (0-3) et encore davantage depuis la fin de l&rsquo;histoire avec Peugeot en 2015. Plus qu&rsquo;un actionnaire, il s&rsquo;agissait pratiquement d&rsquo;une famille comme le rappelait Jean-Claude Plessis, pr\u00e9sident embl\u00e9matique du club de 1999 \u00e0 2008.<\/p>\n<h1 style=\"text-align: justify;\">A l&rsquo;heure chinoise, les Sochaliens font grise mine<\/h1>\n<p style=\"text-align: justify;\">Une page s&rsquo;est donc tourn\u00e9e en 2015 et le FC Sochaux allait tout comme le PSG et l&rsquo;AS Monaco passer sous pavillon \u00e9tranger. Ledus, filiale du groupe Tech Pro Technology avec \u00e0 sa t\u00eate Wing Sang Li, devait permettre de repartir sur des bases solides et envisager un retour en Ligue 1 sur le court terme. Si certains supporters se sont mis \u00e0 r\u00eaver de transferts gr\u00e2ce \u00e0 un apport financier du nouvel actionnaire, ils ont rapidement d\u00e9chant\u00e9, car depuis un peu plus de 3 ans d\u00e9sormais, ce rachat tourne au fiasco. Sur un plan sportif, les Sochaliens n&rsquo;ont jamais jou\u00e9 les premiers r\u00f4les pour l&rsquo;accession en Ligue 1, pire, ils ont d\u00fb lutter pour leur survie en Ligue 2, comme \u00e0 l&rsquo;heure actuelle donc.<\/p>\n<p style=\"text-align: justify;\">Bien que\u00a0le groupe soit sp\u00e9cialis\u00e9 dans le domaine de l&rsquo;\u00e9lectricit\u00e9 et notamment des ampoules LED, ce dernier ne semble jamais avoir effectu\u00e9 tous les branchements n\u00e9cessaires pour mettre en route leur projet sportif. Car si des investissements avaient \u00e9t\u00e9 promis, la strat\u00e9gie adopt\u00e9e a \u00e9t\u00e9 tout autre : d\u00e9part massif de joueurs d&rsquo;exp\u00e9rience, arriv\u00e9es de joueurs en fin de contrat, difficult\u00e9 \u00e0 faire ressortir des joueurs de la formation dans ce contexte. Mais alors quel est le but des investisseurs ? Si ces derniers sont venus en France, ce n&rsquo;est sans doute pas pour r\u00e9aliser des b\u00e9n\u00e9fices. Chose qui est pratiquement \u00e0 exclure dans le milieu du ballon rond, l&rsquo;id\u00e9e \u00e9tait plut\u00f4t de d\u00e9velopper les affaires du groupe dans l&rsquo;Hexagone, mais l\u00e0 encore, le r\u00e9sultat n&rsquo;est pas une r\u00e9ussite.<\/p>\n<div id=\"attachment_36402\" style=\"width: 970px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-36402\" class=\"wp-image-36402 size-full\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Wing-Sang-Li-f\u00e9licite-les-joueurs-sochaliens-AFP.jpg\" alt=\"\" width=\"960\" height=\"638\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Wing-Sang-Li-f\u00e9licite-les-joueurs-sochaliens-AFP.jpg 960w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Wing-Sang-Li-f\u00e9licite-les-joueurs-sochaliens-AFP-300x199.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Wing-Sang-Li-f\u00e9licite-les-joueurs-sochaliens-AFP-768x510.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><p id=\"caption-attachment-36402\" class=\"wp-caption-text\">Wing Sang Li f\u00e9licite les joueurs sochaliens &#8211; AFP<\/p><\/div>\n<p style=\"text-align: justify;\">La lubie de l&rsquo;homme d&rsquo;affaire semble tourner au cauchemar. Apr\u00e8s une premi\u00e8re menace du gendarme financier la DNCG de r\u00e9trogradation en National l&rsquo;an pass\u00e9, une d\u00e9cision similaire a \u00e9t\u00e9 prise cette ann\u00e9e face aux difficult\u00e9s financi\u00e8res rencontr\u00e9es par le club et son groupe d&rsquo;actionnaires et pourrait faire plonger le club en 5\u00e8me divison&#8230; Si ce sc\u00e9nario catastrophe se confirmait, cela serait synonyme de <em>\u00ab<\/em> <em>la mort du club\u00a0\u00bb<\/em> selon les mots de Cyril Perrin, s\u00e9nateur du Territoire de Belfort qui appelle <em>\u00ab<\/em> <em>de tous ses v\u0153ux comme les amoureux du club \u00e0 une vente du FCSM<\/em>. <em>\u00bb<\/em><\/p>\n<h1 style=\"text-align: justify;\">Wing Sang Li dit stop<\/h1>\n<p style=\"text-align: justify;\">Les v\u0153ux de Cyril Perrin vont-ils se r\u00e9aliser ? Toujours est-il qu&rsquo;aujourd&rsquo;hui, le propri\u00e9taire du FCSM Wing Sang Li a annonc\u00e9 qu&rsquo;il quittait son poste de directeur de Tech Pro Technology. Une d\u00e9cision qui prend effet \u00e0 compter du 2 avril. En attendant l&rsquo;annonce d&rsquo;un successeur, le club doubiste doit tout d&rsquo;abord se sauver sur le plan sportif, on esp\u00e8re pour ce dernier une issue plus radieuse que pour Grenoble, qui avait connu une r\u00e9trogradation en CFA 2 lors de la saison 2011 et qui \u00e9tait quant \u00e0 lui sous pavillon japonais.<\/p>\n<p><span class=\"nlaUco0gbqu3XNVWZYGeCxJLSK\"><\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\">\n<p lang=\"fr\" dir=\"ltr\">\ud83d\udd34 <a href=\"https:\/\/twitter.com\/hashtag\/Football?src=hash&amp;ref_src=twsrc%5Etfw\">#Football<\/a> FC Sochaux\u00a0: le pr\u00e9sident, Wing Sang Li, vient de d\u00e9missionner <a href=\"https:\/\/t.co\/ujwsMNSORx\">https:\/\/t.co\/ujwsMNSORx<\/a><\/p>\n<p>&mdash; L&#39;Est R\u00e9publicain (@lestrepublicain) <a href=\"https:\/\/twitter.com\/lestrepublicain\/status\/1113384714470141952?ref_src=twsrc%5Etfw\">April 3, 2019<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/span><\/p>\n<p><strong><em>Julien Corr\u00e9ia<br \/>\n<a href=\"https:\/\/www.facebook.com\/julien.correia.52\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><a href=\"https:\/\/twitter.com\/julienco_psg70\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d&rsquo;annoncer qu&rsquo;il quittait ses fonctions, l&rsquo;un des clubs embl\u00e9matiques du paysage footballistique fran\u00e7ais traverse une p\u00e9riode plus que d\u00e9licate. A quelques journ\u00e9es de la fin du championnat, il en va de son maintien en Ligue 2 sur le court terme et de sa survie tout simplement \u00e0 long terme. <\/p>\n","protected":false},"author":37,"featured_media":36403,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2,2301],"tags":[75,231],"class_list":["post-36279","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-football","tag-football","tag-ligue-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir<\/title>\n<meta name=\"description\" content=\"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d&#039;annoncer qu&#039;il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir\" \/>\n<meta property=\"og:description\" content=\"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d&#039;annoncer qu&#039;il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/julien.correia.52\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-03T13:04:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-03T14:03:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Julien Correia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/julienco_psg70\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\"},\"author\":{\"name\":\"Julien Correia\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239\"},\"headline\":\"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir\",\"datePublished\":\"2019-04-03T13:04:31+00:00\",\"dateModified\":\"2019-04-03T14:03:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\"},\"wordCount\":1183,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png\",\"keywords\":[\"Football\",\"ligue 2\"],\"articleSection\":[\"Actualit\u00e9s\",\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\",\"name\":\"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png\",\"datePublished\":\"2019-04-03T13:04:31+00:00\",\"dateModified\":\"2019-04-03T14:03:30+00:00\",\"description\":\"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d'annoncer qu'il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239\",\"name\":\"Julien Correia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg\",\"caption\":\"Julien Correia\"},\"description\":\"Journaliste\/r\u00e9dacteur depuis janvier 2019 - Tomb\u00e9 dans le monde du ballon rond \u00e9tant petit, j\u2019aurais pu devenir pro sans ces foutus ligaments crois\u00e9s. D\u00e9filant sur les champs (mais pas Elys\u00e9es) en 98, j\u2019ai \u00e9t\u00e9 berc\u00e9 par les exploits de Mister George, piqu\u00e9 par la technique du Snake, grandi avec Captain Rai et Ronnie, m\u00fbri avec Pauleta et Edi. Mais Ibracadabra, je suis d\u00e9sormais reconverti en runner\/traileur. Moins rapide que Bolt et moins endurant que Jornet, c\u2019est donc plume \u00e0 la main que je partage les exploits de ces athl\u00e8tes !\",\"sameAs\":[\"https:\/\/www.facebook.com\/julien.correia.52\",\"https:\/\/x.com\/https:\/\/twitter.com\/julienco_psg70\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/julien-c\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir","description":"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d'annoncer qu'il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/","og_locale":"fr_FR","og_type":"article","og_title":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir","og_description":"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d'annoncer qu'il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.","og_url":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/julien.correia.52","article_published_time":"2019-04-03T13:04:31+00:00","article_modified_time":"2019-04-03T14:03:30+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png","type":"image\/png"}],"author":"Julien Correia","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/julienco_psg70","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/"},"author":{"name":"Julien Correia","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239"},"headline":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir","datePublished":"2019-04-03T13:04:31+00:00","dateModified":"2019-04-03T14:03:30+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/"},"wordCount":1183,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png","keywords":["Football","ligue 2"],"articleSection":["Actualit\u00e9s","Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/","url":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/","name":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png","datePublished":"2019-04-03T13:04:31+00:00","dateModified":"2019-04-03T14:03:30+00:00","description":"Alors que Wing Sang Li, propri\u00e9taire du FCSM, vient d'annoncer qu'il quittait ses fonctions, le FC Sochaux traverse une p\u00e9riode plus que d\u00e9licate.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/FC-Sochaux-2019.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/ligue-2-les-lionceaux-du-fc-sochaux-veulent-encore-rugir\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Ligue 2 : les Lionceaux du FC Sochaux veulent encore rugir"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/0f73d157e4670e108e23009fa82f2239","name":"Julien Correia","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Julien-Correia-150x150.jpg","caption":"Julien Correia"},"description":"Journaliste\/r\u00e9dacteur depuis janvier 2019 - Tomb\u00e9 dans le monde du ballon rond \u00e9tant petit, j\u2019aurais pu devenir pro sans ces foutus ligaments crois\u00e9s. D\u00e9filant sur les champs (mais pas Elys\u00e9es) en 98, j\u2019ai \u00e9t\u00e9 berc\u00e9 par les exploits de Mister George, piqu\u00e9 par la technique du Snake, grandi avec Captain Rai et Ronnie, m\u00fbri avec Pauleta et Edi. Mais Ibracadabra, je suis d\u00e9sormais reconverti en runner\/traileur. Moins rapide que Bolt et moins endurant que Jornet, c\u2019est donc plume \u00e0 la main que je partage les exploits de ces athl\u00e8tes !","sameAs":["https:\/\/www.facebook.com\/julien.correia.52","https:\/\/x.com\/https:\/\/twitter.com\/julienco_psg70"],"url":"https:\/\/dicodusport.fr\/blog\/author\/julien-c\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/36279","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=36279"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/36279\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/36403"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=36279"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=36279"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=36279"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}