{"id":371061,"date":"2023-04-01T20:46:49","date_gmt":"2023-04-01T18:46:49","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=371061&#038;preview=true&#038;preview_id=371061"},"modified":"2023-04-01T23:13:24","modified_gmt":"2023-04-01T21:13:24","slug":"masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/","title":{"rendered":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>MASTERS 1000 ATP \/ WTA DE MIAMI &#8211; La finale \u00e9tait assur\u00e9e de consacrer un Tricolore, et c&rsquo;est \u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut, remportant son deuxi\u00e8me Masters 1000.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">La France \u00e9tait assur\u00e9e de figurer au palmar\u00e8s du Masters 1000 de Miami en 2023. En effet, deux Bleus se faisaient face en finale du double messieurs.<strong> \u00c9douard Roger-Vasselin,<\/strong> associ\u00e9 \u00e0 <strong>Santiago Gonzalez<\/strong>, visait un deuxi\u00e8me sacre dans cette cat\u00e9gorie, apr\u00e8s Cincinnati 2015. Mais en face, on trouvait <strong>Nicolas Mahut<\/strong>, qui faisait la paire avec <strong>Austin Krajicek<\/strong>. Le Tricolore visait un huiti\u00e8me troph\u00e9e en Masters 1000, et le deuxi\u00e8me \u00e0 Miami, apr\u00e8s celui de 2015 en compagnie de <strong>Pierre-Hugues Herbert<\/strong>.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Beaucoup de grands serveurs, et malgr\u00e9 une break de chaque c\u00f4t\u00e9, c&rsquo;est au tie-break que s&rsquo;est jou\u00e9 le premier set. La paire <strong>Roger-Vasselin \/ Gonzalez<\/strong> a parfaitement g\u00e9r\u00e9 le jeu d\u00e9cisif pour \u00e9merger en t\u00eate. Le deuxi\u00e8me set a \u00e9t\u00e9 tout aussi serr\u00e9, mais alors qu&rsquo;on se dirigeait vers un nouveau tie-break, le duo franco-mexicain a acc\u00e9l\u00e9r\u00e9 et conclu sur service adverse,<strong> 7-6 (4), 7-5,<\/strong> en 1 heure 45. Finaliste \u00e0 Indian Wells l&rsquo;an dernier, la paire <strong>Roger-Vasselin \/ Gonzalez<\/strong> gagne son plus grand troph\u00e9e ensemble, et le Fran\u00e7ais remporte son 25e titre en double en carri\u00e8re.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"en\">One of the most prestigious titles in tennis \ud83e\udd47\ud83c\udf34<a href=\"https:\/\/twitter.com\/gonzalezsanty?ref_src=twsrc%5Etfw\">@gonzalezsanty<\/a> \ud83e\udd1d <a href=\"https:\/\/twitter.com\/ERogerVasselin?ref_src=twsrc%5Etfw\">@ERogerVasselin<\/a> clinch doubles glory 7-6(4), 7-5 over Mahut\/Krajicek<a href=\"https:\/\/twitter.com\/MiamiOpen?ref_src=twsrc%5Etfw\">@MiamiOpen<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/MiamiOpen?src=hash&amp;ref_src=twsrc%5Etfw\">#MiamiOpen<\/a> <a href=\"https:\/\/t.co\/mn9EuRDTDq\">pic.twitter.com\/mn9EuRDTDq<\/a><\/p>\n<p>\u2014 ATP Tour (@atptour) <a href=\"https:\/\/twitter.com\/atptour\/status\/1642235264067067904?ref_src=twsrc%5Etfw\">April 1, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">\u00c0 lire aussi<\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-le-tableau-du-tournoi-de-double-hommes-2023\/\"><strong>Le tableau de double messieurs<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>MASTERS 1000 ATP \/ WTA DE MIAMI &#8211; La finale \u00e9tait assur\u00e9e de consacrer un Tricolore, et c&rsquo;est \u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut, remportant son deuxi\u00e8me Masters 1000.<\/p>\n","protected":false},"author":59,"featured_media":371142,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2302],"tags":[16878,22527],"class_list":["post-371061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tennis","tag-breve","tag-masters-1000-de-miami"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs<\/title>\n<meta name=\"description\" content=\"MASTERS 1000 ATP \/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\" \/>\n<meta property=\"og:description\" content=\"MASTERS 1000 ATP \/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/sebastien.gente\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-01T18:46:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-01T21:13:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"S\u00e9bastien Gente\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/globulo24\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/\"},\"author\":{\"name\":\"S\u00e9bastien Gente\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\"},\"headline\":\"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\",\"datePublished\":\"2023-04-01T18:46:49+00:00\",\"dateModified\":\"2023-04-01T21:13:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/\"},\"wordCount\":268,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png\",\"keywords\":[\"br\u00e8ve\",\"Masters 1000 de Miami\"],\"articleSection\":[\"Tennis\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/\",\"name\":\"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png\",\"datePublished\":\"2023-04-01T18:46:49+00:00\",\"dateModified\":\"2023-04-01T21:13:24+00:00\",\"description\":\"MASTERS 1000 ATP \\\/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png\",\"width\":800,\"height\":445,\"caption\":\"Masters 1000 de Miami \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/627966a6cde45dbd8c5e36ac85d783da\",\"name\":\"S\u00e9bastien Gente\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg\",\"caption\":\"S\u00e9bastien Gente\"},\"description\":\"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/sebastien.gente\\\/\",\"https:\\\/\\\/www.instagram.com\\\/sebgente\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/sbastien-gente-a29583169\\\/\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/globulo24\",\"SebastienGente\"],\"worksFor\":\"S\u00e9bastien GENTE\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/sebastiengente\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs","description":"MASTERS 1000 ATP \/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/","og_locale":"fr_FR","og_type":"article","og_title":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs","og_description":"MASTERS 1000 ATP \/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut","og_url":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/sebastien.gente\/","article_published_time":"2023-04-01T18:46:49+00:00","article_modified_time":"2023-04-01T21:13:24+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png","type":"image\/png"}],"author":"S\u00e9bastien Gente","twitter_card":"summary_large_image","twitter_title":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs","twitter_creator":"@https:\/\/twitter.com\/globulo24","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/"},"author":{"name":"S\u00e9bastien Gente","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da"},"headline":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs","datePublished":"2023-04-01T18:46:49+00:00","dateModified":"2023-04-01T21:13:24+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/"},"wordCount":268,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png","keywords":["br\u00e8ve","Masters 1000 de Miami"],"articleSection":["Tennis"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/","url":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/","name":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png","datePublished":"2023-04-01T18:46:49+00:00","dateModified":"2023-04-01T21:13:24+00:00","description":"MASTERS 1000 ATP \/ WTA DE MIAMI -\u00c9douard Roger-Vasselin, associ\u00e9 \u00e0 Santiago Gonzalez, qui a gagn\u00e9 son duel avec Nicolas Mahut","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Masters-1000-de-Miami-Edouard-Roger-Vasselin-sacre-en-double-messieurs.png","width":800,"height":445,"caption":"Masters 1000 de Miami \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/masters-1000-de-miami-edouard-roger-vasselin-sacre-en-double-messieurs\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Masters 1000 de Miami : \u00c9douard Roger-Vasselin sacr\u00e9 en double messieurs"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/627966a6cde45dbd8c5e36ac85d783da","name":"S\u00e9bastien Gente","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/09\/1510990_10205810251400683_4124423575079401707_n-150x150.jpg","caption":"S\u00e9bastien Gente"},"description":"John Stockton, Gianni Bugno, Zinedine Zidane, Steffi Graf, Frode Andresen, St\u00e9phane Stoecklin, Davis Kamoga, Primoz Peterka, Werner Schlager et Aur\u00e9lien Rougerie. Point commun entre ces sportifs? Ils m'ont fait r\u00eaver et ont berc\u00e9 mon adolescence. Je suis un fondu de sports et j'essaie de retranscrire ma passion \u00e0 travers mes articles. Originaire du P\u00e9rigord, ma passion pour les Girondins, les Jaunards et les Jazzmen transpire dans mes \u00e9crits. \u00c0 Dicodusport depuis 2021, je d\u00e9niche les sports m\u00e9connus dans lesquels la France brille, et il y en a !","sameAs":["https:\/\/www.facebook.com\/sebastien.gente\/","https:\/\/www.instagram.com\/sebgente\/","https:\/\/www.linkedin.com\/in\/sbastien-gente-a29583169\/","https:\/\/x.com\/https:\/\/twitter.com\/globulo24","SebastienGente"],"worksFor":"S\u00e9bastien GENTE","url":"https:\/\/dicodusport.fr\/blog\/author\/sebastiengente\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/371061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=371061"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/371061\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/371142"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=371061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=371061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=371061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}