{"id":37404,"date":"2019-04-18T17:13:25","date_gmt":"2019-04-18T15:13:25","guid":{"rendered":"http:\/\/dicodusport.fr\/blog\/?p=37404"},"modified":"2019-04-19T10:06:49","modified_gmt":"2019-04-19T08:06:49","slug":"les-dragons-catalans-pour-les-nuls","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/","title":{"rendered":"Les Dragons Catalans pour les nuls"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Les <a href=\"https:\/\/treizemondial.fr\/tag\/dragons-catalans\/\" target=\"_blank\" rel=\"noopener\">Dragons Catalans<\/a> sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais, bien qu&rsquo;\u00e9voluant en Angleterre. Pr\u00e9sentation de la franchise catalane qui est l&rsquo;une des meilleures \u00e9quipes europ\u00e9ennes.<\/strong><\/em><\/p>\n<h1 style=\"text-align: justify;\">Histoire<\/h1>\n<p style=\"text-align: justify;\">Tout commence en 2000, quand un certain Bernard Guasch r\u00eavait de Super League. L&rsquo;actuel pr\u00e9sident des Dragons Catalans a d\u00e9cid\u00e9 d&rsquo;unir deux clubs :\u00a0Saint-Est\u00e8ve et le XIII Catalan, pour former une seule entit\u00e9 capable de rivaliser avec les Anglais. Dans un premier temps, cette nouvelle formation prendra le nom d&rsquo;Union Treiziste Catalane. C&rsquo;est au moment de l&rsquo;introduction en Super League, en 2008, qu&rsquo;elle a pris le nom des Dragons Catalans. En 2019, la franchise perpignanaise joue sa 14\u00e8me saison dans la plus prestigieuse des comp\u00e9titions de rugby \u00e0 XIII de l&rsquo;h\u00e9misph\u00e8re nord.<\/p>\n<h1 style=\"text-align: justify;\">R\u00e9sultats \/ Palmar\u00e8s<\/h1>\n<p style=\"text-align: justify;\">Les Dragons Catalans n&rsquo;ont encore jamais gagn\u00e9 la Super League, mais ils ont atteint deux fois les demi-finales, en 2009 et 2014. Le mod\u00e8le de la Super League ressemble \u00e0 bon nombre de comp\u00e9titions dans d&rsquo;autres sports, comme le Top 14 ou la Pro A de basket, avec une phase r\u00e9guli\u00e8re et des phases finales. Chaque saison, les Dragons sont aussi engag\u00e9s dans la Challenge Cup, la coupe anglaise. En 2018, ils ont remport\u00e9 la comp\u00e9tition en battant en finale Warrington et sont devenus la premi\u00e8re \u00e9quipe non anglaise \u00e0 triompher. Ils avaient aussi atteint la finale en 2007, un an et demi apr\u00e8s leur arriv\u00e9e dans les comp\u00e9titions britanniques, mais s&rsquo;\u00e9taient inclin\u00e9s en finale.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-25225 aligncenter\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Dragons-Catalans-vainqueur-Challenge-Cup-2018-1024x576.jpg\" alt=\"\" width=\"1024\" height=\"576\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Dragons-Catalans-vainqueur-Challenge-Cup-2018-1024x576.jpg 1024w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Dragons-Catalans-vainqueur-Challenge-Cup-2018-1024x576-300x169.jpg 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2018\/09\/Dragons-Catalans-vainqueur-Challenge-Cup-2018-1024x576-768x432.jpg 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/p>\n<h1 style=\"text-align: justify;\">Structure du club \/ Budget<\/h1>\n<p style=\"text-align: justify;\">Le budget total du club pour la saison 2019 s&rsquo;\u00e9l\u00e8ve autour des 11 millions d&rsquo;euros et \u00e0 titre de comparaison, le plus petit budget du Top 14, Agen, avait comme budget 13,8 millions d&rsquo;euros pour cette saison 2018\/2019. En plus de l&rsquo;\u00e9quipe fanion qui \u00e9volue dans le championnat anglais, le club poss\u00e8de une \u00e9quipe fran\u00e7aise qui \u00e9volue dans le championnat hexagonal et qui est la tenante du titre en Coupe de France. Il y a aussi une \u00e9quipe Handi-Rugby, des f\u00e9minines et des \u00e9quipes dans toutes les cat\u00e9gories de jeunes, toutes \u00e9voluent au plus haut niveau.<\/p>\n<h1 style=\"text-align: justify;\">Saison 2019<\/h1>\n<p style=\"text-align: justify;\">Comme chaque ann\u00e9e civile, les saisons ne sont pas celles que l&rsquo;on voit habituellement en France dans les sports collectifs. Les Dragons Catalans sont engag\u00e9s en Super League, 12 \u00e9quipes sur la ligne de d\u00e9part avec les cinq premiers qualifi\u00e9s pour les playoffs \u00e0 la fin de <a href=\"https:\/\/treizemondial.fr\/calendrier-et-resultats-super-league\/\" target=\"_blank\" rel=\"noopener\">la phase r\u00e9guli\u00e8re, qui se d\u00e9coupe en 29 journ\u00e9es<\/a>. En plus de la Super League, les Dragons Catalans auront la Cup \u00e0 d\u00e9fendre, et ils affronteront une \u00e9quipe de 3\u00e8me division pour leur entr\u00e9e en lice en 8\u00e8me de finale. L&rsquo;effectif est compos\u00e9 des meilleurs joueurs fran\u00e7ais, mais aussi d&rsquo;\u00e9trangers qui ont \u00e9volu\u00e9 par le pass\u00e9 en NRL, le championnat australien ou en Super League, avec d&rsquo;autres \u00e9quipes.<\/p>\n<p style=\"text-align: justify;\"><em><strong>Nicolas Jacquemard<\/strong><br \/>\n<\/em><a style=\"color: #000000;\" href=\"https:\/\/twitter.com\/Nico_Jacquemard\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2908\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-twitter-150x150.png\" alt=\"\" width=\"39\" height=\"39\" \/><\/a><a style=\"color: #000000;\" href=\"https:\/\/www.facebook.com\/dicodusport\/\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2909\" src=\"http:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2017\/07\/logo-facebook-150x150.png\" alt=\"\" width=\"40\" height=\"40\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais, bien qu&rsquo;\u00e9voluant en Angleterre. Pr\u00e9sentation de la franchise catalane qui est l&rsquo;une des meilleures \u00e9quipes europ\u00e9ennes.<\/p>\n","protected":false},"author":1,"featured_media":37407,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[2,2303],"tags":[5690,2049,851,3795],"class_list":["post-37404","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-rugby","tag-dragons","tag-dragons-catalans","tag-rugby-a-xiii","tag-super-league"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Les Dragons Catalans pour les nuls<\/title>\n<meta name=\"description\" content=\"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l&#039;une des meilleures \u00e9quipes europ\u00e9ennes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Les Dragons Catalans pour les nuls\" \/>\n<meta property=\"og:description\" content=\"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l&#039;une des meilleures \u00e9quipes europ\u00e9ennes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-18T15:13:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-19T08:06:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Les Dragons Catalans pour les nuls\",\"datePublished\":\"2019-04-18T15:13:25+00:00\",\"dateModified\":\"2019-04-19T08:06:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/\"},\"wordCount\":501,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Dragons-Catalans-Pre\u0301sentation.png\",\"keywords\":[\"Dragons\",\"Dragons Catalans\",\"rugby \u00e0 XIII\",\"Super League\"],\"articleSection\":[\"Actualit\u00e9s\",\"Rugby\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#respond\"]}],\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/\",\"name\":\"Les Dragons Catalans pour les nuls\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Dragons-Catalans-Pre\u0301sentation.png\",\"datePublished\":\"2019-04-18T15:13:25+00:00\",\"dateModified\":\"2019-04-19T08:06:49+00:00\",\"description\":\"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l'une des meilleures \u00e9quipes europ\u00e9ennes.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Dragons-Catalans-Pre\u0301sentation.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/04\\\/Dragons-Catalans-Pre\u0301sentation.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/les-dragons-catalans-pour-les-nuls\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Dragons Catalans pour les nuls\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Les Dragons Catalans pour les nuls","description":"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l'une des meilleures \u00e9quipes europ\u00e9ennes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/","og_locale":"fr_FR","og_type":"article","og_title":"Les Dragons Catalans pour les nuls","og_description":"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l'une des meilleures \u00e9quipes europ\u00e9ennes.","og_url":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2019-04-18T15:13:25+00:00","article_modified_time":"2019-04-19T08:06:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Les Dragons Catalans pour les nuls","datePublished":"2019-04-18T15:13:25+00:00","dateModified":"2019-04-19T08:06:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/"},"wordCount":501,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png","keywords":["Dragons","Dragons Catalans","rugby \u00e0 XIII","Super League"],"articleSection":["Actualit\u00e9s","Rugby"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#respond"]}],"copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/","url":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/","name":"Les Dragons Catalans pour les nuls","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png","datePublished":"2019-04-18T15:13:25+00:00","dateModified":"2019-04-19T08:06:49+00:00","description":"Les Dragons Catalans sont la t\u00eate de proue du rugby \u00e0 XIII fran\u00e7ais. Pr\u00e9sentation de la franchise catalane qui est l'une des meilleures \u00e9quipes europ\u00e9ennes.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2019\/04\/Dragons-Catalans-Pre\u0301sentation.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/les-dragons-catalans-pour-les-nuls\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Les Dragons Catalans pour les nuls"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/37404","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=37404"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/37404\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/37407"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=37404"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=37404"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=37404"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}