{"id":375767,"date":"2023-04-22T19:43:27","date_gmt":"2023-04-22T17:43:27","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=375767&#038;preview=true&#038;preview_id=375767"},"modified":"2023-04-22T19:43:10","modified_gmt":"2023-04-22T17:43:10","slug":"gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/","title":{"rendered":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong><em><a href=\"https:\/\/dicodusport.fr\/blog\/actualites\/sports-de-combat\/boxe\/\">BOXE<\/a> &#8211; Gervonta Davis et Ryan Garcia s&rsquo;affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Le programme TV.\u00a0<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">Choc en vue ce week-end \u00e0 Las Vegas. <strong>Gervonta Davis<\/strong>\u00a0(28\u22120, 26 KO), 28 ans et\u00a0<strong>Ryan Garcia<\/strong> (23\u22120, 19 KO), 24 ans, s\u2019affrontent pour le choc des l\u00e9gers. Le combat aura lieu dans la nuit de samedi \u00e0 dimanche. Le premier cit\u00e9, pr\u00e9sent\u00e9 comme favori, a d\u00e9j\u00e0 combattu en 2023. Avec \u00e0 la cl\u00e9, une victoire par KO face au Dominicain <strong>Hector Luis Garcia<\/strong>. En mai 2022, pour son seul combat de l&rsquo;ann\u00e9e, <a href=\"https:\/\/dicodusport.fr\/blog\/boxe-poids-legers-gervonta-davis-intraitable-avec-rolando-romero\/\"><em>Le Tank<\/em> s&rsquo;\u00e9tait d\u00e9fait de son compatriote <strong>Rolando Romero<\/strong><\/a>, l\u00e0 aussi par KO.<\/p>\n<p style=\"text-align: justify;\">De son c\u00f4t\u00e9, <strong>Ryan Garcia<\/strong> est pr\u00e9sent\u00e9 comme l&rsquo;\u00e9toile montante de la cat\u00e9gorie des l\u00e9gers. Invaincu en 23 combats professionnels, <em>King Ry<\/em> a disput\u00e9 deux combats en 2022. En avril, il a d&rsquo;abord \u00e9cart\u00e9 le Ghan\u00e9en <strong>Emmanuel Tagoe<\/strong>, sur d\u00e9cision unanime des juges. En juillet, c&rsquo;est cette fois le Dominicain <strong>Javier Fortuna<\/strong> qui a subi la loi de Garcia, d\u00e9fait par KO.<\/p>\n<p style=\"text-align: justify;\">Lors de cette soir\u00e9e \u00e0 La Vegas, un co-main event sera propos\u00e9, avant le combat <strong>Davis vs Ryan<\/strong>. Le Cubain <strong>David Morell<\/strong> (8\u22120, 7 KO) d\u00e9fendra sa ceinture mondiale WBA des super moyens, face au Br\u00e9silien <strong>Yamaguchi Falcao<\/strong> (24\u22121\u22121, 10 KO). Le combat <strong>Davis vs Ryan<\/strong> sera diffus\u00e9 sur RMC Sport 1, via le Pass Combat.<\/p>\n<div class=\"vlp-link-container vlp-layout-article\"><a href=\"https:\/\/dicodusport.fr\/blog\/boxe-ryan-garcia-vs-gervonta-davis-choc-de-stars-chez-les-legers\/\" class=\"vlp-link\" title=\"Boxe : Ryan Garcia vs Gervonta Davis, choc de stars chez les l\u00e9gers\"><\/a><div class=\"vlp-layout-zone-side\"><div class=\"vlp-block-4 vlp-link-image\"><img loading=\"lazy\" decoding=\"async\" style=\"max-width: 800px;\" width=\"800\" height=\"445\" src=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Boxe-Ryan-Garcia-vs-Gervonta-Davis-choc-de-stars-chez-les-legers.png\" class=\"attachment-800x445 size-800x445\" alt=\"Boxe Ryan Garcia vs Gervonta Davis, choc de stars chez les l\u00e9gers\" srcset=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Boxe-Ryan-Garcia-vs-Gervonta-Davis-choc-de-stars-chez-les-legers.png 800w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Boxe-Ryan-Garcia-vs-Gervonta-Davis-choc-de-stars-chez-les-legers-300x167.png 300w, https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Boxe-Ryan-Garcia-vs-Gervonta-Davis-choc-de-stars-chez-les-legers-768x427.png 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><div class=\"vlp-layout-zone-main\"><div class=\"vlp-block-0 vlp-link-title\">Boxe : Ryan Garcia vs Gervonta Davis, choc de stars chez les l\u00e9gers<\/div><div class=\"vlp-block-1 vlp-link-summary\">BOXE - POIDS L\u00c9GERS - Samedi soir, les fans de boxe du monde entier auront les yeux riv\u00e9s sur un combat de stars. En effet, le duel opposera Gervonta Davis \u00e0 Ryan Garcia, deux t\u00eates d'affiche de la cat\u00e9gorie explosive des poids l\u00e9gers. \u00c0 Las Vegas, les deux jeunes puncheurs am\u00e9ricains sauront, sans aucun doute, assurer le spectacle.\u00a0<\/div><div class=\"vlp-block-2 vlp-link-button\">Lire l'article<\/div><div class=\"vlp-block-3 vlp-link-url\">dicodusport.fr<\/div><\/div><\/div>\n<h2 style=\"text-align: justify;\">Gervonta Davis vs Ryan Garcia &#8211; Le programme TV<\/h2>\n<h3 style=\"text-align: justify;\">Dimanche 23 avril 2023<\/h3>\n<p style=\"text-align: justify;\"><strong>RMC Sport 1<\/strong><\/p>\n<p style=\"text-align: justify;\">02h00 : R\u00e9union de Las Vegas avec le combat Davis vs Garcia<\/p>\n<h2 style=\"text-align: justify;\">Les autres combats de la soir\u00e9e de Las Vegas, le 22 avril 2023<\/h2>\n<p style=\"text-align: justify;\"><strong>Carte principale\u00a0:<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Gervonta Davis vs Ryan Garcia<\/li>\n<li style=\"text-align: justify;\">David Morrell Jr vs Yamaguchi Falcao<\/li>\n<li style=\"text-align: justify;\">Gabriel Rosado vs Bektemir Melikuziev<\/li>\n<li style=\"text-align: justify;\">Elijah Garcia vs Kevin Salgado<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><strong>Carte pr\u00e9liminaire :<\/strong><\/p>\n<ul>\n<li style=\"text-align: justify;\">Fiodor Czerkaszyn vs. Elias Espadas<\/li>\n<li style=\"text-align: justify;\">Vito Mielnicki Jr vs. Jose Charles<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOXE &#8211; Gervonta Davis et Ryan Garcia s&rsquo;affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Le programme TV.\u00a0<\/p>\n","protected":false},"author":4,"featured_media":375771,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[8672],"tags":[622,16878,20653,8799,13251],"class_list":["post-375767","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-boxe","tag-boxe","tag-breve","tag-gervonta-davis","tag-programme-tv","tag-ryan-garcia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV<\/title>\n<meta name=\"description\" content=\"BOXE - Gervonta Davis et Ryan Garcia s&#039;affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV\" \/>\n<meta property=\"og:description\" content=\"BOXE - Gervonta Davis et Ryan Garcia s&#039;affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-22T17:43:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV\",\"datePublished\":\"2023-04-22T17:43:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/\"},\"wordCount\":422,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"keywords\":[\"boxe\",\"br\u00e8ve\",\"Gervonta Davis\",\"Programme TV\",\"Ryan Garcia\"],\"articleSection\":[\"Boxe\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/\",\"name\":\"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"datePublished\":\"2023-04-22T17:43:27+00:00\",\"description\":\"BOXE - Gervonta Davis et Ryan Garcia s'affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png\",\"width\":800,\"height\":445,\"caption\":\"Gervonta Davis vs Ryan Garcia \u00c0 quelle heure et sur quelle cha\u00eene TV\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\\\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/florent.ostermann\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/FlOstermann\",\"admin\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/flo\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV","description":"BOXE - Gervonta Davis et Ryan Garcia s'affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_locale":"fr_FR","og_type":"article","og_title":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV","og_description":"BOXE - Gervonta Davis et Ryan Garcia s'affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-04-22T17:43:27+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV","datePublished":"2023-04-22T17:43:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/"},"wordCount":422,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png","keywords":["boxe","br\u00e8ve","Gervonta Davis","Programme TV","Ryan Garcia"],"articleSection":["Boxe"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/","url":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/","name":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png","datePublished":"2023-04-22T17:43:27+00:00","description":"BOXE - Gervonta Davis et Ryan Garcia s'affrontent ce samedi 22 avril \u00e0 Las Vegas (USA), pour un choc des stars chez les l\u00e9gers. Programme TV.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Gervonta-Davis-vs-Ryan-Garcia-A-quelle-heure-et-sur-quelle-chaine-TV.png","width":800,"height":445,"caption":"Gervonta Davis vs Ryan Garcia \u00c0 quelle heure et sur quelle cha\u00eene TV"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/gervonta-davis-vs-ryan-garcia-a-quelle-heure-et-sur-quelle-chaine-tv\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Gervonta Davis vs Ryan Garcia : \u00c0 quelle heure et sur quelle cha\u00eene TV"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/375767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=375767"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/375767\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/375771"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=375767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=375767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=375767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}