{"id":377092,"date":"2023-04-26T16:38:02","date_gmt":"2023-04-26T14:38:02","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=377092&#038;preview=true&#038;preview_id=377092"},"modified":"2023-04-26T19:28:49","modified_gmt":"2023-04-26T17:28:49","slug":"transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/","title":{"rendered":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>TOP 14 2023-2024 &#8211; Selon Rugbyrama, l&rsquo;ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Si les <strong>Jaunards<\/strong> ont vraiment r\u00e9ussi leur recrutement pour leur pack, c&rsquo;est pour le moment beaucoup plus compliqu\u00e9 pour la ligne de trois-quarts. <strong>Christophe<\/strong> <strong>Urios<\/strong>, satisfait du recrutement au niveau des avants, confirmait ce matin sur <em>France Bleu<\/em> que son club cherchait toujours au moins <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-lasm-clermont-veut-recruter-encore-plusieurs-joueurs\/\" target=\"_blank\" rel=\"noopener\">deux voire trois renforts pour sa ligne arri\u00e8re<\/a>. Mais pour le moment, peu de noms sortent du chapeau.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">La piste Benjamin Urdapilleta<\/h2>\n<p style=\"text-align: justify;\" align=\"justify\">Avec le d\u00e9part de <strong>Damian<\/strong> <strong>Penaud<\/strong>, l&rsquo;<strong>ASM Clermont<\/strong> cherche une pointure capable de faire des diff\u00e9rences. Mais <a href=\"https:\/\/dicodusport.fr\/blog\/transferts-un-cador-de-top-14-va-doubler-clermont-pour-signer-leicester-faingaanuku\/\" target=\"_blank\" rel=\"noopener\">ce ne sera pas <strong>Leicester Fainga\u2019anuku,<\/strong> qui devrait rejoindre le RC Toulon<\/a>. Si <strong>Alfred Parisien<\/strong> va bien rallier l&rsquo;Auvergne, le club de Top 14 cherche encore un ailier\/arri\u00e8re, mais aussi un centre capable de jouer \u00e0 l&rsquo;ouverture pour suppl\u00e9er le tandem Belleau-Plisson.<\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Selon nos confr\u00e8res, les <strong>Jaunards<\/strong> \u00e9tudient la possibilit\u00e9 de signer <strong>Benjamin<\/strong> <strong>Urdapilleta<\/strong>, ouvreur du <strong>Castres<\/strong> <strong>Olympique<\/strong>. L&rsquo;international argentin, qui se voit bien continuer encore une saison, est en fin de contrat avec le <strong>CO<\/strong>, qui lui proposerait seulement un contrat de joker Coupe du monde. L&rsquo;<strong>ASM Clermont<\/strong> pourrait donc lui proposer un nouveau challenge, m\u00eame si son profil n&rsquo;est pas forc\u00e9ment celui recherch\u00e9. Affaire \u00e0 suivre donc !<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Transferts &#8211; Clermont en qu\u00eate de trois-quarts, Benjamin Urdapilleta (Castres) pist\u00e9 ? <a href=\"https:\/\/t.co\/7zEp3nl44z\">https:\/\/t.co\/7zEp3nl44z<\/a><\/p>\n<p>\u2014 Cl\u00e9ment Labonne (@clement_labonne) <a href=\"https:\/\/twitter.com\/clement_labonne\/status\/1651225248308576276?ref_src=twsrc%5Etfw\">April 26, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOP 14 2023-2024 &#8211; Selon Rugbyrama, l&rsquo;ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":377095,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[9129,47050],"tags":[1208,30872,16878],"class_list":["post-377092","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","category-top-14","tag-asm-clermont","tag-benjamin-urdapilleta","tag-breve"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.0 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14<\/title>\n<meta name=\"description\" content=\"TOP 14 2023-2024 - Selon Rugbyrama, l&#039;ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14\" \/>\n<meta property=\"og:description\" content=\"TOP 14 2023-2024 - Selon Rugbyrama, l&#039;ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T14:38:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-26T17:28:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14\",\"datePublished\":\"2023-04-26T14:38:02+00:00\",\"dateModified\":\"2023-04-26T17:28:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/\"},\"wordCount\":261,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png\",\"keywords\":[\"ASM Clermont\",\"Benjamin Urdapilleta\",\"br\u00e8ve\"],\"articleSection\":[\"Rugby \u00e0 XV\",\"Top 14\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/\",\"name\":\"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png\",\"datePublished\":\"2023-04-26T14:38:02+00:00\",\"dateModified\":\"2023-04-26T17:28:49+00:00\",\"description\":\"TOP 14 2023-2024 - Selon Rugbyrama, l'ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2020\\\/06\\\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/dicodusport\",\"https:\\\/\\\/www.instagram.com\\\/dicodusport\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/#\\\/schema\\\/person\\\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/05\\\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/dicodusport\",\"https:\\\/\\\/x.com\\\/https:\\\/\\\/twitter.com\\\/Nico_Jacquemard\"],\"url\":\"https:\\\/\\\/dicodusport.fr\\\/blog\\\/author\\\/dicodusport\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14","description":"TOP 14 2023-2024 - Selon Rugbyrama, l'ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14","og_description":"TOP 14 2023-2024 - Selon Rugbyrama, l'ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-04-26T14:38:02+00:00","article_modified_time":"2023-04-26T17:28:49+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14","datePublished":"2023-04-26T14:38:02+00:00","dateModified":"2023-04-26T17:28:49+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/"},"wordCount":261,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png","keywords":["ASM Clermont","Benjamin Urdapilleta","br\u00e8ve"],"articleSection":["Rugby \u00e0 XV","Top 14"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/","name":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png","datePublished":"2023-04-26T14:38:02+00:00","dateModified":"2023-04-26T17:28:49+00:00","description":"TOP 14 2023-2024 - Selon Rugbyrama, l'ASM Clermont \u00e9tudie la possibilit\u00e9 de recruter Benjamin Urdapilleta pour la saison prochaine.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Benjamin-Urdapilleta-piste-par-une-grosse-ecurie-du-Top-14.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-benjamin-urdapilleta-piste-par-une-grosse-ecurie-du-top-14\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts : Benjamin Urdapilleta pist\u00e9 par une grosse \u00e9curie du Top 14"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=377092"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377092\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/377095"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=377092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=377092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=377092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}