{"id":377174,"date":"2023-04-26T23:00:47","date_gmt":"2023-04-26T21:00:47","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=377174&#038;preview=true&#038;preview_id=377174"},"modified":"2023-04-27T12:17:31","modified_gmt":"2023-04-27T10:17:31","slug":"premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/","title":{"rendered":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre"},"content":{"rendered":"<p align=\"justify\"><em><strong>PREMIER LEAGUE 2022-2023 &#8211; Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l&rsquo;Etihad Stadium (4-1). Une fess\u00e9e qui permet aux hommes de Pep Guardiola de revenir \u00e0 deux points de leur adversaire, plus que jamais fragile leader. Car City a deux matchs de retard. Kevin De Bruyne, deux fois, John Stones et Erling Haaland sont les buteurs. Rob Holding sauve l&rsquo;honneur en fin de match.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Il est toujours difficile de parler de finale dans un match de championnat. Surtout quand il reste des matchs \u00e0 jouer derri\u00e8re. Oui, cette Premier League approche de son \u00e9pilogue. Mais le football nous a r\u00e9serv\u00e9 tellement de surprises, qu&rsquo;on va bien se garder de tirer des conclusions d\u00e9finitives. On va donc rester focalis\u00e9 sur ce qu&rsquo;on a vu ce soir. \u00c0 savoir une d\u00e9monstration. Une nouvelle de Manchester City. Le champion en titre a domin\u00e9 son challenger Arsenal. Ce match \u00e9tait attendu. Les Gunners, surprise de la saison, pouvaient-ils damer le pion au maitre des cl\u00e9s ? Et bien la r\u00e9ponse a \u00e9t\u00e9 rapide. En moins de dix minutes, on a compris \u00e0 quelle sauce les hommes de <strong>Mikel Arteta<\/strong> allaient \u00eatre mang\u00e9s. Et de choc, il n&rsquo;aura \u00e9t\u00e9 que sur le papier. Mais pas sur le terrain ce mercredi soir.<\/p>\n<h2 style=\"text-align: justify;\">City a tordu Arsenal dans le premier acte<\/h2>\n<p style=\"text-align: justify;\">Car apr\u00e8s 45 minutes de jeu, Arsenal \u00e9tait men\u00e9 2-0 par les Citizens. Et c&rsquo;est presque flatteur pour les Gunners, tant ils ont \u00e9t\u00e9 \u00e9touff\u00e9s. Si Arsenal s&rsquo;en sort miraculeusement, dans une action confuse \u00e0 la suite d&rsquo;un rush de <strong>Jake Grealish<\/strong>, c&rsquo;\u00e9tait pour mieux craquer quatre minutes plus tard. Au terme d&rsquo;une action de grande classe par deux grands joueurs. <strong>Erling Haaland<\/strong> a fait parler sa capacit\u00e9 \u00e0 jouer collectif. Le Norv\u00e9gien en milieu de terrain lance <strong>Kevin De Bruyne<\/strong>. Qui perce la d\u00e9fense d&rsquo;Arsenal, avant de frapper \u00e0 l&rsquo;entr\u00e9e de la surface, au premier poteau sur la droite. Pour tromper un <strong>Aaron Ramsdale<\/strong> qui avait quelque peu anticip\u00e9 la frappe crois\u00e9e et qui n&rsquo;est pas exempt de tous reproches (1-0, 7e). On notera la capacit\u00e9 de l&rsquo;attaquant norv\u00e9gien \u00e0 se montrer collectif, disponible.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">KEVIN DE BRUYYYYYYNE !!! QUELLE ACTION \ud83e\udd2f<a href=\"https:\/\/twitter.com\/hashtag\/MCIARS?src=hash&amp;ref_src=twsrc%5Etfw\">#MCIARS<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/PremierLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#PremierLeague<\/a> <a href=\"https:\/\/t.co\/l6kX7DGjTr\">pic.twitter.com\/l6kX7DGjTr<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1651303043424452640?ref_src=twsrc%5Etfw\">April 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">Il a fait \u00e9voluer son jeu et a sans doute livr\u00e9 une de ses prestations les plus abouties. Il est tout proche de r\u00e9cidiver 20 minutes plus tard, la frappe de<strong> Kevin De Bruyne<\/strong> \u00e9tant finalement repouss\u00e9e par Ben White. Et pourtant,<strong> Erling Haaland<\/strong> a \u00e9t\u00e9 plus que maladroit devant le but, contrairement \u00e0 son habitude. Tombant sur un excellent <strong>Aaron Ramsdale<\/strong>, qui s&rsquo;est bien rattrap\u00e9 de son erreur inaugurale. Et qui a \u00e9t\u00e9 plusieurs fois d\u00e9cisif devant l&rsquo;attaquant de City. Que ce soit sur une frappe ras de terre (27e), une frappe angle ferm\u00e9 dans la gauche de la surface (32e), ou servi en retrait sur la gauche (42e). Entre-temps, il n&rsquo;avait pas trouv\u00e9 le cadre (36e).<\/p>\n<p style=\"text-align: justify;\">Et Arsenal dans tout cela ? Hormis une frappe de <strong>Thomas Partey<\/strong> &#8211; hors cadre &#8211; \u00e0 la suite d&rsquo;un beau service de Bukayo Saka, c&rsquo;est le n\u00e9ant (34e). \u00c9touff\u00e9 par Manchester City, Arsenal craque avant la mi-temps. <strong>Kevin De Bruyne<\/strong> enroule son coup franc pour <strong>John Stones<\/strong> qui place sa t\u00eate victorieusement. D&rsquo;abord refus\u00e9, le but est finalement accord\u00e9 apr\u00e8s v\u00e9rification de la VAR (2-0, 45+2). 16e passe d\u00e9cisive du Belge cette saison, impliqu\u00e9 directement dans tous les buts ce soir.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Et John Stones double la mise pour Manchester City \u26a1\ufe0f<\/p>\n<p>Que c&rsquo;est dur pour Arsenal&#8230;<a href=\"https:\/\/twitter.com\/hashtag\/MCIARS?src=hash&amp;ref_src=twsrc%5Etfw\">#MCIARS<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/PremierLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#PremierLeague<\/a> <a href=\"https:\/\/t.co\/OCnzE9sxzG\">pic.twitter.com\/OCnzE9sxzG<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1651314679241666562?ref_src=twsrc%5Etfw\">April 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<h2>Haaland &#8211; De Bruyne : La connexion gagnante ce soir<\/h2>\n<p style=\"text-align: justify;\"><strong>Erling Haaland<\/strong> a cependant bien failli \u00eatre frustr\u00e9 de son match. Car pour un attaquant, marquer est dans son ADN et longtemps, il n&rsquo;a pu soigner ses statistiques. Ce n&rsquo;est pas faute d&rsquo;avoir eu d&rsquo;autres cartouches ce soir. \u00c0 l&rsquo;image d&rsquo;un nouveau duel perdu sur <strong>Aaron Ramsdale<\/strong> (53e). Mais le Norv\u00e9gien a \u00e9t\u00e9 tr\u00e8s grand ce soir. Peut-\u00eatre encore plus pr\u00e9cieux pour son \u00e9quipe que dans un r\u00f4le de pur finisseur. Car c&rsquo;est lui qui d\u00e9livre un second caviar pour son meneur <strong>Kevin De Bruyne<\/strong>. Et le Belge a le pied chaud ce soir, pour glisser un petit ballon hors de port\u00e9e du gardien d&rsquo;Arsenal (3-0, 54e). Mais ne nous trompons pas. <strong>Erling Haaland<\/strong> a montr\u00e9 qu&rsquo;un attaquant pouvait faire un grand match. Et la r\u00e9compense viendra finalement presque au moment o\u00f9 on ne s&rsquo;y attendait plus.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">Quand l&rsquo;Etihad Stadium se met \u00e0 trembler \ud83d\udd35<\/p>\n<p>Manchester City m\u00e8ne 3-0 contre Arsenal ! \ud83e\udd76<a href=\"https:\/\/twitter.com\/hashtag\/MCIARS?src=hash&amp;ref_src=twsrc%5Etfw\">#MCIARS<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/PremierLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#PremierLeague<\/a> <a href=\"https:\/\/t.co\/h6np34FsjJ\">pic.twitter.com\/h6np34FsjJ<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1651320580455510031?ref_src=twsrc%5Etfw\">April 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p style=\"text-align: justify;\">La derni\u00e8re demi-heure ne restera pas dans les annales du football anglais et europ\u00e9en. Mais l&rsquo;essentiel \u00e9tait fait. Et ce n&rsquo;est pas le but de <strong>Rob Holding<\/strong>, qui vient sauver l&rsquo;honneur des Gunners, qui changera la donne (3-1, 87e). Et s\u00fbrement que Manchester City, une fois le travail fait et bien fait ce mercredi soir, avait quelque peu la t\u00eate dans les \u00e9toiles. Celles de la Ligue des Champions et d&rsquo;un choc qui se profile face au Real Madrid en demi-finales. Car cette comp\u00e9tition lui \u00e9chappe encore. Mais au vu de ce qu&rsquo;on a aper\u00e7u ce soir, 2023 pourrait bien \u00eatre la bonne ann\u00e9e pour les Citizens.<\/p>\n<p style=\"text-align: justify;\">Et ils l&rsquo;aborderont avec un <strong>Erling Haaland<\/strong> en pleine confiance. Le Norv\u00e9gien s&rsquo;offre un but tellement m\u00e9rit\u00e9 en fin de match. Afin d&rsquo;apporter un peu plus de statistiques \u00e0 son match immense (4-1, 90+4). C&rsquo;est son 33e but cette saison en Premier League. Parti pour affoler tous les records. Score final 4-1. City est dans les r\u00e9tros d&rsquo;Arsenal, avec deux matchs en retard encore \u00e0 jouer.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"fr\">UNE VICTOIRE DE CITY NE SERAIT PAS COMPL\u00c8TE SANS UN BUT DE HAALAND \ud83d\udca5<\/p>\n<p>Et avec les cheveux d\u00e9tach\u00e9s en prime \ud83e\udddd\ud83c\udffb\u200d\u2642\ufe0f<a href=\"https:\/\/twitter.com\/hashtag\/MCIARS?src=hash&amp;ref_src=twsrc%5Etfw\">#MCIARS<\/a> | <a href=\"https:\/\/twitter.com\/hashtag\/PremierLeague?src=hash&amp;ref_src=twsrc%5Etfw\">#PremierLeague<\/a> <a href=\"https:\/\/t.co\/VGPEeaYZpA\">pic.twitter.com\/VGPEeaYZpA<\/a><\/p>\n<p>\u2014 CANAL+ Foot (@CanalplusFoot) <a href=\"https:\/\/twitter.com\/CanalplusFoot\/status\/1651330617450328065?ref_src=twsrc%5Etfw\">April 26, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>PREMIER LEAGUE 2022-2023 &#8211; Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l&rsquo;Etihad Stadium (4-1). Une fess\u00e9e qui permet aux hommes de Pep Guardiola de revenir \u00e0 deux points de leur adversaire, plus que jamais fragile leader. Car City a deux matchs de retard. Kevin De Bruyne, deux fois, John Stones et Erling Haaland sont les buteurs. Rob Holding sauve l&rsquo;honneur en fin de match.<\/p>\n","protected":false},"author":83,"featured_media":377213,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[2301],"tags":[3434,16878,75,3169],"class_list":["post-377174","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-football","tag-arsenal","tag-breve","tag-football","tag-manchester-city"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre<\/title>\n<meta name=\"description\" content=\"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l&#039;Etihad Stadium (4-1).\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre\" \/>\n<meta property=\"og:description\" content=\"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l&#039;Etihad Stadium (4-1).\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-26T21:00:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T10:17:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Etienne Goursaud\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre\" \/>\n<meta name=\"twitter:creator\" content=\"@dicodusport\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\"},\"author\":{\"name\":\"Etienne Goursaud\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\"},\"headline\":\"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre\",\"datePublished\":\"2023-04-26T21:00:47+00:00\",\"dateModified\":\"2023-04-27T10:17:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\"},\"wordCount\":1049,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png\",\"keywords\":[\"Arsenal\",\"br\u00e8ve\",\"Football\",\"Manchester City\"],\"articleSection\":[\"Football\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\",\"name\":\"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png\",\"datePublished\":\"2023-04-26T21:00:47+00:00\",\"dateModified\":\"2023-04-27T10:17:31+00:00\",\"description\":\"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l'Etihad Stadium (4-1).\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png\",\"width\":800,\"height\":445,\"caption\":\"Premier League (J33) - City atomise Arsenal et prend une option sur le titre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13\",\"name\":\"Etienne Goursaud\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg\",\"caption\":\"Etienne Goursaud\"},\"description\":\"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.\",\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre","description":"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l'Etihad Stadium (4-1).","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/","og_locale":"fr_FR","og_type":"article","og_title":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre","og_description":"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l'Etihad Stadium (4-1).","og_url":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-04-26T21:00:47+00:00","article_modified_time":"2023-04-27T10:17:31+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png","type":"image\/png"}],"author":"Etienne Goursaud","twitter_card":"summary_large_image","twitter_title":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre","twitter_creator":"@dicodusport","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/"},"author":{"name":"Etienne Goursaud","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13"},"headline":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre","datePublished":"2023-04-26T21:00:47+00:00","dateModified":"2023-04-27T10:17:31+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/"},"wordCount":1049,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png","keywords":["Arsenal","br\u00e8ve","Football","Manchester City"],"articleSection":["Football"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/","url":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/","name":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png","datePublished":"2023-04-26T21:00:47+00:00","dateModified":"2023-04-27T10:17:31+00:00","description":"PREMIER LEAGUE 2022-2023 - Manchester City a donn\u00e9 la le\u00e7on \u00e0 Arsenal, ce mercredi soir, \u00e0 l'Etihad Stadium (4-1).","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Premier-League-J33-City-atomise-Arsenal-et-prend-une-option-sur-le-titre.png","width":800,"height":445,"caption":"Premier League (J33) - City atomise Arsenal et prend une option sur le titre"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/premier-league-j33-manchester-city-assomme-arsenal-et-prend-une-option-sur-le-titre\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Premier League (J33) : Manchester City assomme Arsenal et prend une option sur le titre"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/d603dd7da31fb2b46c82b9835a77ec13","name":"Etienne Goursaud","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/12\/410122264_10231602061736049_5565839791558026645_n-150x150.jpg","caption":"Etienne Goursaud"},"description":"Journaliste et amoureux de sport. Ancien footballeur reconverti athl\u00e8te quand ses muscles le laissent tranquille. \u00c9lev\u00e9 \u00e0 la sauce des exploits de Thomas Voeckler en 2004, du dernier essai de l\u00e9gende de Eunice Barber \u00e0 la longueur lors des championnats du monde d'athl\u00e9tisme de 2003 mais aussi Zidane, Omeyer et Titou Lamaison.","url":"https:\/\/dicodusport.fr\/blog\/author\/etienne-goursaud\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/83"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=377174"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377174\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/377213"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=377174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=377174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=377174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}