{"id":377327,"date":"2023-04-27T17:24:34","date_gmt":"2023-04-27T15:24:34","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=377327&#038;preview=true&#038;preview_id=377327"},"modified":"2023-04-27T17:35:25","modified_gmt":"2023-04-27T15:35:25","slug":"tour-de-romandie-2023-classement-2eme-etape","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/","title":{"rendered":"Tour de Romandie 2023 &#8211; Classement 2\u00e8me \u00e9tape"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>TOUR DE ROMANDIE 2023 &#8211; D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du <a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-parcours-et-favoris\/\">Tour de Romandie 2023<\/a>, disput\u00e9e ce jeudi 27 avril entre <span class=\"red\">Morteau et <\/span><span class=\"red\">La Chaux-de-Fonds <\/span><span class=\"red fw400\">(162.7 km)<\/span><\/strong>.<strong> Le Tour de Romandie est la 20\u00e8me \u00e9preuve du <a href=\"https:\/\/dicodusport.fr\/blog\/cyclisme-world-tour-2023-calendrier-et-resultats\/\">calendrier World Tour 2023<\/a>.<\/strong><\/em><\/p>\n<div class=\"su-table su-table-alternate\">\n<table style=\"width: 800px;border-collapse: collapse\" border=\"1\">\n<tbody>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\">\ud83c\udfc6<\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>COUREURS<\/strong><\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>TEMPS \/ \u00c9CART<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">1.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\">\ud83c\uddec\ud83c\udde7 ETHAN HAYTER<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">INEOS GRENADIERS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>3h55m20s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">2.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddea\ud83c\uddf8 JUAN AYUSO<\/strong><br \/>\n<span style=\"font-size: 0.8em\">UAE TEAM EMIRATES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">3.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddeb\ud83c\uddf7 ROMAIN BARDET<br \/>\n<\/strong><span style=\"font-size: 0.8em\">TEAM DSM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">4.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9 MATTEO SOBRERO<\/strong><\/span><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">TEAM\u00a0 JAYCO ALULA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">5.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddec\ud83c\udde7 OSCAR ONLEY<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM DSM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">6.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">\ud83c\udde6\ud83c\uddfa HARRY SWEENY<br \/>\n<\/strong><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">LOTTO DSTNY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">7.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong style=\"font-size: 14.4px\"><strong>\ud83c\udde7\ud83c\uddea <\/strong>KOBE GOOSSENS<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.8em\">INTERMARCH\u00c9 &#8211; CIRCUS &#8211; WANTY<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">8.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\udde9\ud83c\uddf0 MAGNUS CORT NIELSEN<br \/>\n<\/strong><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">EF EDUCATION &#8211; EASYPOST<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">9.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><b><strong>\ud83c\uddf3\ud83c\uddff <\/strong>FINN FISHER-BLACK<br \/>\n<\/b><span style=\"font-size: 0.8em\">UAE TEAM EMIRATES<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr style=\"height: 24px\">\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">10.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddfa<\/strong> NICK SCHULTZ<br \/>\n<\/strong><span style=\"font-size: 0.8em\">ISRAEL &#8211; PREMIER TECH<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">11.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\uddfa\ud83c\uddf8 MATTEO JORGENSON<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">12.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong><span style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7 CL\u00c9MENT CHAMPOUSSIN<\/span><\/strong><br \/>\n<span style=\"font-size: 0.8em\">TEAM ARK\u00c9A-SAMSIC<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">13.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\uddf3\ud83c\uddf4 TOBIAS FOSS<\/strong><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">TEAM JUMBO VISMA<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">14.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddee\ud83c\uddf9<\/strong><\/span> DAMIANO CARUSO<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">BAHRAIN VICTORIOUS<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">15.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 0.9em\">\ud83c\udde6\ud83c\uddf9 GREGOR MUHLBERGER<\/strong><br \/>\n<span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">16.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\"><span style=\"font-size: 0.9em\"><strong><strong style=\"font-size: 0.9em\">\ud83c\uddeb\ud83c\uddf7<\/strong><\/strong><\/span> KENNY ELISSONDE<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">TREK &#8211; SEGAFREDO<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">17.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">\ud83c\uddf5\ud83c\uddf9 NELSON OLIVEIRA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">18.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\udde8\ud83c\udded YANNIS VOISARD<\/strong><br \/>\n<span style=\"font-size: 0.8em\">TUDOR PRO CYCLING TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">19.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><strong style=\"font-size: 14.4px\">\ud83c\udde8\ud83c\uddf4 HAROLD TEJADA<\/strong><br style=\"font-size: 14.4px\" \/><span style=\"font-size: 0.9em\"><span style=\"font-size: 0.8em\">ASTANA QAZAQSTAN TEAM<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"border-color: #ebebeb;text-align: center;width: 80px;vertical-align: middle\"><span style=\"font-size: 0.9em\">20.<\/span><\/td>\n<td style=\"border-color: #ebebeb;height: 24px;text-align: center;width: 500px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\ud83c\uddfa\ud83c\uddf8 WILLIAM BARTA<\/strong><br \/>\n<span style=\"font-size: 0.8em\">MOVISTAR<\/span><\/span><\/td>\n<td style=\"border-color: #ebebeb;text-align: center;width: 220px;vertical-align: middle\"><span style=\"font-size: 0.9em\"><strong>\u00e0 0s<\/strong><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<h2 style=\"text-align: justify;\"><strong>\u00c0 lire aussi<\/strong><\/h2>\n<ul>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/www.procyclingstats.com\/race\/tour-de-romandie\/2023\/stage-2\"><strong>Le classement complet de la 2\u00e8me \u00e9tape<\/strong><\/a><\/li>\n<li style=\"text-align: justify;\"><a href=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-general\/\" target=\"_blank\" rel=\"noopener\"><strong>Le classement g\u00e9n\u00e9ral du Tour de Romandie<\/strong><\/a><\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>TOUR DE ROMANDIE 2023 &#8211; D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril entre Morteau et La Chaux-de-Fonds (162.7 km). Le Tour de Romandie est la 20\u00e8me \u00e9preuve du calendrier World Tour 2023.<\/p>\n","protected":false},"author":4,"featured_media":377334,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[46994],"tags":[16878,7747],"class_list":["post-377327","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cyclisme-sur-route","tag-breve","tag-tour-de-romandie"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape<\/title>\n<meta name=\"description\" content=\"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape\" \/>\n<meta property=\"og:description\" content=\"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/florent.ostermann\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-27T15:24:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-27T15:35:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"670\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Flo Ostermann\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/FlOstermann\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\"},\"author\":{\"name\":\"Flo Ostermann\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\"},\"headline\":\"Tour de Romandie 2023 &#8211; Classement 2\u00e8me \u00e9tape\",\"datePublished\":\"2023-04-27T15:24:34+00:00\",\"dateModified\":\"2023-04-27T15:35:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\"},\"wordCount\":188,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png\",\"keywords\":[\"br\u00e8ve\",\"Tour de Romandie\"],\"articleSection\":[\"Cyclisme sur route\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\",\"name\":\"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png\",\"datePublished\":\"2023-04-27T15:24:34+00:00\",\"dateModified\":\"2023-04-27T15:35:25+00:00\",\"description\":\"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png\",\"width\":1200,\"height\":670,\"caption\":\"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tour de Romandie 2023 &#8211; Classement 2\u00e8me \u00e9tape\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a\",\"name\":\"Flo Ostermann\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg\",\"caption\":\"Flo Ostermann\"},\"description\":\"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !\",\"sameAs\":[\"https:\/\/www.facebook.com\/florent.ostermann\",\"https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann\",\"admin\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/flo\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape","description":"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/","og_locale":"fr_FR","og_type":"article","og_title":"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape","og_description":"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.","og_url":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/florent.ostermann","article_published_time":"2023-04-27T15:24:34+00:00","article_modified_time":"2023-04-27T15:35:25+00:00","og_image":[{"width":1200,"height":670,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png","type":"image\/png"}],"author":"Flo Ostermann","twitter_card":"summary_large_image","twitter_title":"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape","twitter_creator":"@https:\/\/twitter.com\/FlOstermann","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/"},"author":{"name":"Flo Ostermann","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a"},"headline":"Tour de Romandie 2023 &#8211; Classement 2\u00e8me \u00e9tape","datePublished":"2023-04-27T15:24:34+00:00","dateModified":"2023-04-27T15:35:25+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/"},"wordCount":188,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png","keywords":["br\u00e8ve","Tour de Romandie"],"articleSection":["Cyclisme sur route"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/","url":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/","name":"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png","datePublished":"2023-04-27T15:24:34+00:00","dateModified":"2023-04-27T15:35:25+00:00","description":"TOUR DE ROMANDIE 2023 - D\u00e9couvrez le classement de la 2\u00e8me \u00e9tape (top 20) du Tour de Romandie 2023, disput\u00e9e ce jeudi 27 avril.","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Tour-de-Romandie-2023-Classement-2eme-etape-1.png","width":1200,"height":670,"caption":"Tour de Romandie 2023 - Classement 2\u00e8me \u00e9tape"},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/tour-de-romandie-2023-classement-2eme-etape\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Tour de Romandie 2023 &#8211; Classement 2\u00e8me \u00e9tape"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/cb02af4c173ce4a653b55e9baf388d4a","name":"Flo Ostermann","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Flo-Ostermann-150x150.jpg","caption":"Flo Ostermann"},"description":"Journaliste\/R\u00e9dacteur depuis septembre 2015 - Mes premiers souvenirs dans le sport ? Les envol\u00e9es du Stade Toulousain et les duels Villeneuve-Schumacher et H\u00e4kkinen-Schumacher \u00e0 la fin des ann\u00e9es 90, la Coupe du monde de football en 1998, l\u2019exploit du XV de France face aux All Blacks en 1999, mais aussi Richard C\u0153ur de Lion qui vole sur les montagnes du Tour de France. Bien parti pour devenir professeur d\u2019EPS, les \u00e9v\u00e9nements de la vie (et la flemme d\u2019animer des s\u00e9ances de 3x500 m\u00e8tres toute ma vie) m\u2019ont conduit \u00e0 revoir mes plans. Me voil\u00e0 depuis fin 2017 sur Dicodusport, m\u00e9dia gr\u00e2ce (et pour) lequel je partage ma passion : le sport dans tous ses \u00e9tats. Le tout accompagn\u00e9 par les fous furieux et folles furieuses cit\u00e9s sur cette page !","sameAs":["https:\/\/www.facebook.com\/florent.ostermann","https:\/\/x.com\/https:\/\/twitter.com\/FlOstermann","admin"],"url":"https:\/\/dicodusport.fr\/blog\/author\/flo\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377327","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=377327"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377327\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/377334"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=377327"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=377327"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=377327"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}