{"id":377760,"date":"2023-04-29T08:20:58","date_gmt":"2023-04-29T06:20:58","guid":{"rendered":"https:\/\/dicodusport.fr\/blog\/?p=377760&#038;preview=true&#038;preview_id=377760"},"modified":"2023-04-29T11:11:21","modified_gmt":"2023-04-29T09:11:21","slug":"transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise","status":"publish","type":"post","link":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/","title":{"rendered":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise"},"content":{"rendered":"<p style=\"text-align: justify;\" align=\"justify\"><em><strong>RUGBY \u00c0 XV &#8211; Selon <a href=\"https:\/\/www.rugbyrama.fr\/2023\/04\/28\/transferts-pro-d2-vannes-hamish-bain-arrive-nicolas-freitas-nest-pas-conserve-11164846.php\" target=\"_blank\" rel=\"nofollow noopener\">Rugbyrama<\/a>, Hamish Bain va s&rsquo;engager avec Vannes alors que Nicolas Freitas n&rsquo;est lui pas conserv\u00e9 pour la saison prochaine.\u00a0<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\" align=\"justify\">Pour le moment quatri\u00e8me, <strong>Vannes<\/strong> est s\u00fbr de jouer les phases finales de <strong>Pro<\/strong> <strong>D2,<\/strong> mais ne sait pas encore s&rsquo;il y aura encore un match \u00e0 domicile. Le club breton peut encore terminer deuxi\u00e8me et se qualifier pour une demi-finale \u00e0 la maison, mais aussi sixi\u00e8me et barragiste \u00e0 l&rsquo;ext\u00e9rieur avec plus aucune rencontre \u00e0 domicile. Le suspense est entier de la deuxi\u00e8me \u00e0 la sixi\u00e8me place \u00e0 80 minutes de la fin de la phase r\u00e9guli\u00e8re.<\/p>\n<h2 style=\"text-align: justify;\" align=\"justify\">Nicolas Freitas pas conserv\u00e9<\/h2>\n<p style=\"text-align: justify;\">Apr\u00e8s une saison derni\u00e8re cauchemar, Vannes a donc l&rsquo;occasion de monter en <strong>Top<\/strong> <strong>14<\/strong> d\u00e8s cette saison et certains joueurs ont profit\u00e9 de ce dernier match de la phase r\u00e9guli\u00e8re pour faire leurs adieux au public. Et selon nos confr\u00e8res, si un d\u00e9part est act\u00e9 pour bon nombre d&rsquo;entre eux depuis plusieurs semaines, <strong>Nicolas<\/strong> <strong>Freitas<\/strong> ne devrait pas \u00eatre conserv\u00e9 par ses dirigeants. Le centre uruguayen de 29 ans est arriv\u00e9 en 2021 en <strong>Bretagne<\/strong> et a encha\u00een\u00e9 les performances de qualit\u00e9 cette saison avec pas moins de 21 feuilles de match.<\/p>\n<p style=\"text-align: justify;\">Si l&rsquo;homme aux 12 s\u00e9lections avec l&rsquo;<strong>Uruguay<\/strong> est sur le d\u00e9part, <strong>Vannes<\/strong> serait en passe de signer le rempla\u00e7ant d&rsquo;<a href=\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-ewan-johnson-sur-le-depart-joe-edwards-dans-lattente\/\" target=\"_blank\" rel=\"noopener\"><strong>Ewan Johnson,<\/strong> qui s&rsquo;est engag\u00e9 pour plusieurs saisons avec <\/a><strong><a href=\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-ewan-johnson-sur-le-depart-joe-edwards-dans-lattente\/\" target=\"_blank\" rel=\"noopener\">Oyonnax<\/a>. Hamish<\/strong> <strong>Bain<\/strong>, deuxi\u00e8me ligne \u00e9cossais de 25 ans, serait proche de s&rsquo;engager avec le club de <strong>Pro<\/strong> <strong>D2<\/strong>. Il a notamment port\u00e9 le maillot des Glasgow Warriors pendant deux ans et sera la deuxi\u00e8me recrue du club \u00e0 ce poste apr\u00e8s <strong>Anton<\/strong> <strong>Bresler<\/strong>.<\/p>\n<blockquote class=\"twitter-tweet\">\n<p dir=\"ltr\" lang=\"es\">Nicolas Freitas \ud83c\uddfa\ud83c\uddfe <a href=\"https:\/\/twitter.com\/RugbyClubVannes?ref_src=twsrc%5Etfw\">@RugbyClubVannes<\/a> <a href=\"https:\/\/t.co\/nrp7MPI5yU\">pic.twitter.com\/nrp7MPI5yU<\/a><\/p>\n<p>\u2014 Somos Deporte (@SomosDeporte_uy) <a href=\"https:\/\/twitter.com\/SomosDeporte_uy\/status\/1614037067079483393?ref_src=twsrc%5Etfw\">January 13, 2023<\/a><\/p><\/blockquote>\n<p style=\"text-align: justify;\"><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>RUGBY \u00c0 XV &#8211; Selon Rugbyrama, Hamish Bain va s&rsquo;engager avec Vannes alors que Nicolas Freitas n&rsquo;est lui pas conserv\u00e9 pour la saison prochaine.\u00a0<\/p>\n","protected":false},"author":1,"featured_media":377761,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_daextam_enable_autolinks":"","footnotes":""},"categories":[9129],"tags":[16878,1839,10224,110],"class_list":["post-377760","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rugby-a-xv","tag-breve","tag-pro-d2","tag-rc-vannes","tag-rugby-a-xv"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v26.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise<\/title>\n<meta name=\"description\" content=\"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s&#039;engager avec Vannes alors que Nicolas Freitas n&#039;est lui pas conserv\u00e9 pour la saison prochaine.\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise\" \/>\n<meta property=\"og:description\" content=\"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s&#039;engager avec Vannes alors que Nicolas Freitas n&#039;est lui pas conserv\u00e9 pour la saison prochaine.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\" \/>\n<meta property=\"og:site_name\" content=\"Dicodusport\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/dicodusport\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-29T06:20:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-04-29T09:11:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Nicolas Jacquemard\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise\" \/>\n<meta name=\"twitter:creator\" content=\"@https:\/\/twitter.com\/Nico_Jacquemard\" \/>\n<meta name=\"twitter:site\" content=\"@dicodusport\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\"},\"author\":{\"name\":\"Nicolas Jacquemard\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\"},\"headline\":\"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise\",\"datePublished\":\"2023-04-29T06:20:58+00:00\",\"dateModified\":\"2023-04-29T09:11:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\"},\"wordCount\":316,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png\",\"keywords\":[\"br\u00e8ve\",\"Pro D2\",\"RC Vannes\",\"Rugby \u00e0 XV\"],\"articleSection\":[\"Rugby \u00e0 XV\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#respond\"]}],\"copyrightYear\":\"2023\",\"copyrightHolder\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\",\"name\":\"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise\",\"isPartOf\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png\",\"datePublished\":\"2023-04-29T06:20:58+00:00\",\"dateModified\":\"2023-04-29T09:11:21+00:00\",\"description\":\"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s'engager avec Vannes alors que Nicolas Freitas n'est lui pas conserv\u00e9 pour la saison prochaine.\u00a0\",\"breadcrumb\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/dicodusport.fr\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#website\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"name\":\"Dicodusport\",\"description\":\"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive\",\"publisher\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"NewsMediaOrganization\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#organization\",\"name\":\"Dicodusport\",\"url\":\"https:\/\/dicodusport.fr\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png\",\"width\":512,\"height\":512,\"caption\":\"Dicodusport\"},\"image\":{\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/dicodusport\",\"https:\/\/www.instagram.com\/dicodusport\/\",\"https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w\"],\"description\":\"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.\",\"email\":\"bonjour@dicodusport.fr\",\"legalName\":\"DICODUSPORT\",\"foundingDate\":\"2018-01-14\",\"vatID\":\"FR71834470973\",\"taxID\":\"83447097300043\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1\",\"maxValue\":\"10\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191\",\"name\":\"Nicolas Jacquemard\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"contentUrl\":\"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg\",\"caption\":\"Nicolas Jacquemard\"},\"description\":\"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.\",\"sameAs\":[\"https:\/\/www.facebook.com\/dicodusport\",\"https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard\"],\"url\":\"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise","description":"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s'engager avec Vannes alors que Nicolas Freitas n'est lui pas conserv\u00e9 pour la saison prochaine.\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/","og_locale":"fr_FR","og_type":"article","og_title":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise","og_description":"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s'engager avec Vannes alors que Nicolas Freitas n'est lui pas conserv\u00e9 pour la saison prochaine.\u00a0","og_url":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/","og_site_name":"Dicodusport","article_publisher":"https:\/\/www.facebook.com\/dicodusport","article_author":"https:\/\/www.facebook.com\/dicodusport","article_published_time":"2023-04-29T06:20:58+00:00","article_modified_time":"2023-04-29T09:11:21+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png","type":"image\/png"}],"author":"Nicolas Jacquemard","twitter_card":"summary_large_image","twitter_title":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise","twitter_creator":"@https:\/\/twitter.com\/Nico_Jacquemard","twitter_site":"@dicodusport","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#article","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/"},"author":{"name":"Nicolas Jacquemard","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191"},"headline":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise","datePublished":"2023-04-29T06:20:58+00:00","dateModified":"2023-04-29T09:11:21+00:00","mainEntityOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/"},"wordCount":316,"commentCount":0,"publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png","keywords":["br\u00e8ve","Pro D2","RC Vannes","Rugby \u00e0 XV"],"articleSection":["Rugby \u00e0 XV"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#respond"]}],"copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"}},{"@type":"WebPage","@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/","url":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/","name":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise","isPartOf":{"@id":"https:\/\/dicodusport.fr\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage"},"thumbnailUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png","datePublished":"2023-04-29T06:20:58+00:00","dateModified":"2023-04-29T09:11:21+00:00","description":"RUGBY \u00c0 XV - Selon Rugbyrama, Hamish Bain va s'engager avec Vannes alors que Nicolas Freitas n'est lui pas conserv\u00e9 pour la saison prochaine.\u00a0","breadcrumb":{"@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#primaryimage","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2023\/04\/Transferts-Vannes-Une-arrivee-en-2eme-ligne-et-un-depart-surprise.png","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/dicodusport.fr\/blog\/transferts-vannes-une-arrivee-en-2eme-ligne-et-un-depart-surprise\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/dicodusport.fr\/blog\/"},{"@type":"ListItem","position":2,"name":"Transferts Vannes : Une arriv\u00e9e en 2\u00e8me ligne et un d\u00e9part surprise"}]},{"@type":"WebSite","@id":"https:\/\/dicodusport.fr\/blog\/#website","url":"https:\/\/dicodusport.fr\/blog\/","name":"Dicodusport","description":"L&#039;encyclop\u00e9die de l&#039;actualit\u00e9 sportive","publisher":{"@id":"https:\/\/dicodusport.fr\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dicodusport.fr\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"NewsMediaOrganization","@id":"https:\/\/dicodusport.fr\/blog\/#organization","name":"Dicodusport","url":"https:\/\/dicodusport.fr\/blog\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2020\/06\/cropped-LOGO-DICODUSPORT-2020-SANS-FOND-SANS-TEXTE.png","width":512,"height":512,"caption":"Dicodusport"},"image":{"@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/dicodusport","https:\/\/www.instagram.com\/dicodusport\/","https:\/\/www.youtube.com\/channel\/UC7V2KZ5sd3htJivAbA4ZG3w"],"description":"Dicodusport est l'encyclop\u00e9die de l'actualit\u00e9 sportive.","email":"bonjour@dicodusport.fr","legalName":"DICODUSPORT","foundingDate":"2018-01-14","vatID":"FR71834470973","taxID":"83447097300043","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1","maxValue":"10"}},{"@type":"Person","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/55dcb50ad410894e431ed812bbb70191","name":"Nicolas Jacquemard","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dicodusport.fr\/blog\/#\/schema\/person\/image\/","url":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","contentUrl":"https:\/\/dicodusport.fr\/blog\/wp-content\/uploads\/2021\/05\/Nicolas-Jacquemard-150x150.jpeg","caption":"Nicolas Jacquemard"},"description":"Passionn\u00e9 de sport et entrepreneur depuis mes 18 ans, la cr\u00e9ation de Dicodusport m'a sembl\u00e9 \u00e9vidente pour participer \u00e0 la m\u00e9diatisation d'un plus grand nombre de sports. Le chemin est long mais avec une \u00e9quipe des plus motiv\u00e9es et les Jeux Olympiques de Paris 2024 en point de mire, nous y arriverons ! Journaliste dans le monde du sport depuis plus de 5 ans, je traite aussi bien de football, de rugby, de biathlon que de cyclisme.","sameAs":["https:\/\/www.facebook.com\/dicodusport","https:\/\/x.com\/https:\/\/twitter.com\/Nico_Jacquemard"],"url":"https:\/\/dicodusport.fr\/blog\/author\/dicodusport\/"}]}},"_links":{"self":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377760","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/comments?post=377760"}],"version-history":[{"count":0,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/posts\/377760\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media\/377761"}],"wp:attachment":[{"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/media?parent=377760"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/categories?post=377760"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dicodusport.fr\/blog\/wp-json\/wp\/v2\/tags?post=377760"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}